{"id":87376,"date":"2023-02-16T14:54:53","date_gmt":"2023-02-16T20:54:53","guid":{"rendered":"https:\/\/canal7slp.tv\/2023\/?p=87376"},"modified":"2023-02-16T14:54:53","modified_gmt":"2023-02-16T20:54:53","slug":"nascar-mexico-2023-tendra-dos-fechas-en-la-capital-potosina","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2023\/nascar-mexico-2023-tendra-dos-fechas-en-la-capital-potosina\/","title":{"rendered":"NASCAR M\u00e9xico 2023 tendr\u00e1 dos fechas en la capital potosina"},"content":{"rendered":"<p style=\"text-align: justify;\">SLP.- NASCAR M\u00e9xico dio a conocer el calendario oficial 2023, en donde tendr\u00e1 dos fechas puntuables de la temporada 2023 en San Luis Potos\u00ed.<\/p>\n<p style=\"text-align: justify;\">El calendario cuenta con doce fechas las cuales se desarrollaran en ocho ciudades diferentes, entre las que se encuentra San Luis Potos\u00ed, Quer\u00e9taro, Puebla y Chihuahua los cuales recibir\u00e1n dos fechas.<\/p>\n<p style=\"text-align: justify;\">La temporada arranca los d\u00edas 25 y 26 de marzo en Tuxtla Guti\u00e9rrez, Chiapas, mientras que la segunda fecha llega al s\u00faper \u00f3valo potosino de la carretera a Rioverde los d\u00edas 15 y 16 de abril.<\/p>\n<p style=\"text-align: justify;\">En mayo llega la tercera fecha los d\u00edas 12 y 13 en Chihuahua, y 27 y 28 en Quer\u00e9taro.<br \/>\nEl 10 y 11 de junio llega a Aguascalientes con la quinta jornada y en julio 8 y 9 en Puebla mientras que a Monterrey 22 y 23, correspondientes a las jornadas seis y siete.<\/p>\n<p style=\"text-align: justify;\">Los d\u00edas 12 y 13 de agosto, siendo la octava fecha puntuable regresa a San Luis Potos\u00ed.<br \/>\nEn septiembre, el 9 y 10 en Quer\u00e9taro la novena jornada, y 22 y 23 en Chihuahua la d\u00e9cima.<\/p>\n<p style=\"text-align: justify;\">Los d\u00edas 21 y 22 de octubre en Puebla, la onceava, y 11 y 12 de noviembre en la Ciudad de M\u00e9xico la doceava y \u00faltima.<\/p>\n<p style=\"text-align: justify;\">Hacer menci\u00f3n que en cada una de las fechas se tendr\u00e1 actividad en tres categor\u00edas: Estelar, Challenge y Truck&#8217;s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SLP.- NASCAR M\u00e9xico dio a conocer el calendario oficial 2023, en donde tendr\u00e1 dos fechas puntuables de la temporada 2023 en San Luis Potos\u00ed. El calendario cuenta con doce fechas las cuales se desarrollaran en ocho ciudades diferentes, entre las que se encuentra San Luis Potos\u00ed, Quer\u00e9taro, Puebla y Chihuahua los cuales recibir\u00e1n dos fechas. La temporada arranca los d\u00edas 25 y 26 de marzo en Tuxtla Guti\u00e9rrez, Chiapas, mientras que la segunda fecha llega al s\u00faper \u00f3valo potosino de la carretera a Rioverde los d\u00edas 15 y 16 de abril. En mayo llega la tercera fecha los d\u00edas 12 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":87383,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"footnotes":""},"categories":[7,5],"tags":[],"class_list":["post-87376","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-deportes","category-destacadas","post_format-post-format-video","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NASCAR M\u00e9xico 2023 tendr\u00e1 dos fechas en la capital potosina - Canal 7 SLP - 2023<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2023\/nascar-mexico-2023-tendra-dos-fechas-en-la-capital-potosina\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NASCAR M\u00e9xico 2023 tendr\u00e1 dos fechas en la capital potosina - Canal 7 SLP - 2023\" \/>\n<meta property=\"og:description\" content=\"SLP.- NASCAR M\u00e9xico dio a conocer el calendario oficial 2023, en donde tendr\u00e1 dos fechas puntuables de la temporada 2023 en San Luis Potos\u00ed. El calendario cuenta con doce fechas las cuales se desarrollaran en ocho ciudades diferentes, entre las que se encuentra San Luis Potos\u00ed, Quer\u00e9taro, Puebla y Chihuahua los cuales recibir\u00e1n dos fechas. La temporada arranca los d\u00edas 25 y 26 de marzo en Tuxtla Guti\u00e9rrez, Chiapas, mientras que la segunda fecha llega al s\u00faper \u00f3valo potosino de la carretera a Rioverde los d\u00edas 15 y 16 de abril. En mayo llega la tercera fecha los d\u00edas 12 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2023\/nascar-mexico-2023-tendra-dos-fechas-en-la-capital-potosina\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2023\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanalsiete\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-16T20:54:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2023\/02\/Froi02Nascar.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"888\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/nascar-mexico-2023-tendra-dos-fechas-en-la-capital-potosina\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/nascar-mexico-2023-tendra-dos-fechas-en-la-capital-potosina\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#\\\/schema\\\/person\\\/639c424e3584069003b11ae813915da6\"},\"headline\":\"NASCAR M\u00e9xico 2023 tendr\u00e1 dos fechas en la capital potosina\",\"datePublished\":\"2023-02-16T20:54:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/nascar-mexico-2023-tendra-dos-fechas-en-la-capital-potosina\\\/\"},\"wordCount\":228,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/nascar-mexico-2023-tendra-dos-fechas-en-la-capital-potosina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Froi02Nascar.jpg\",\"articleSection\":[\"DEPORTES\",\"DESTACADAS\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/nascar-mexico-2023-tendra-dos-fechas-en-la-capital-potosina\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/nascar-mexico-2023-tendra-dos-fechas-en-la-capital-potosina\\\/\",\"name\":\"NASCAR M\u00e9xico 2023 tendr\u00e1 dos fechas en la capital potosina - Canal 7 SLP - 2023\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/nascar-mexico-2023-tendra-dos-fechas-en-la-capital-potosina\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/nascar-mexico-2023-tendra-dos-fechas-en-la-capital-potosina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Froi02Nascar.jpg\",\"datePublished\":\"2023-02-16T20:54:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/nascar-mexico-2023-tendra-dos-fechas-en-la-capital-potosina\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/nascar-mexico-2023-tendra-dos-fechas-en-la-capital-potosina\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/nascar-mexico-2023-tendra-dos-fechas-en-la-capital-potosina\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Froi02Nascar.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Froi02Nascar.jpg\",\"width\":888,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/nascar-mexico-2023-tendra-dos-fechas-en-la-capital-potosina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NASCAR M\u00e9xico 2023 tendr\u00e1 dos fechas en la capital potosina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanalsiete\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#\\\/schema\\\/person\\\/639c424e3584069003b11ae813915da6\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NASCAR M\u00e9xico 2023 tendr\u00e1 dos fechas en la capital potosina - Canal 7 SLP - 2023","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2023\/nascar-mexico-2023-tendra-dos-fechas-en-la-capital-potosina\/","og_locale":"es_ES","og_type":"article","og_title":"NASCAR M\u00e9xico 2023 tendr\u00e1 dos fechas en la capital potosina - Canal 7 SLP - 2023","og_description":"SLP.- NASCAR M\u00e9xico dio a conocer el calendario oficial 2023, en donde tendr\u00e1 dos fechas puntuables de la temporada 2023 en San Luis Potos\u00ed. El calendario cuenta con doce fechas las cuales se desarrollaran en ocho ciudades diferentes, entre las que se encuentra San Luis Potos\u00ed, Quer\u00e9taro, Puebla y Chihuahua los cuales recibir\u00e1n dos fechas. La temporada arranca los d\u00edas 25 y 26 de marzo en Tuxtla Guti\u00e9rrez, Chiapas, mientras que la segunda fecha llega al s\u00faper \u00f3valo potosino de la carretera a Rioverde los d\u00edas 15 y 16 de abril. En mayo llega la tercera fecha los d\u00edas 12 [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2023\/nascar-mexico-2023-tendra-dos-fechas-en-la-capital-potosina\/","og_site_name":"Canal 7 SLP - 2023","article_publisher":"https:\/\/www.facebook.com\/noticieroscanalsiete","article_published_time":"2023-02-16T20:54:53+00:00","og_image":[{"width":888,"height":500,"url":"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2023\/02\/Froi02Nascar.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2023\/nascar-mexico-2023-tendra-dos-fechas-en-la-capital-potosina\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2023\/nascar-mexico-2023-tendra-dos-fechas-en-la-capital-potosina\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2023\/#\/schema\/person\/639c424e3584069003b11ae813915da6"},"headline":"NASCAR M\u00e9xico 2023 tendr\u00e1 dos fechas en la capital potosina","datePublished":"2023-02-16T20:54:53+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2023\/nascar-mexico-2023-tendra-dos-fechas-en-la-capital-potosina\/"},"wordCount":228,"publisher":{"@id":"https:\/\/canal7slp.tv\/2023\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2023\/nascar-mexico-2023-tendra-dos-fechas-en-la-capital-potosina\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2023\/02\/Froi02Nascar.jpg","articleSection":["DEPORTES","DESTACADAS"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2023\/nascar-mexico-2023-tendra-dos-fechas-en-la-capital-potosina\/","url":"https:\/\/canal7slp.tv\/2023\/nascar-mexico-2023-tendra-dos-fechas-en-la-capital-potosina\/","name":"NASCAR M\u00e9xico 2023 tendr\u00e1 dos fechas en la capital potosina - Canal 7 SLP - 2023","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2023\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2023\/nascar-mexico-2023-tendra-dos-fechas-en-la-capital-potosina\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2023\/nascar-mexico-2023-tendra-dos-fechas-en-la-capital-potosina\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2023\/02\/Froi02Nascar.jpg","datePublished":"2023-02-16T20:54:53+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2023\/nascar-mexico-2023-tendra-dos-fechas-en-la-capital-potosina\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2023\/nascar-mexico-2023-tendra-dos-fechas-en-la-capital-potosina\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2023\/nascar-mexico-2023-tendra-dos-fechas-en-la-capital-potosina\/#primaryimage","url":"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2023\/02\/Froi02Nascar.jpg","contentUrl":"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2023\/02\/Froi02Nascar.jpg","width":888,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2023\/nascar-mexico-2023-tendra-dos-fechas-en-la-capital-potosina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2023\/"},{"@type":"ListItem","position":2,"name":"NASCAR M\u00e9xico 2023 tendr\u00e1 dos fechas en la capital potosina"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2023\/#website","url":"https:\/\/canal7slp.tv\/2023\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2023\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2023\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2023\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2023\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2023\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2023\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanalsiete","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2023\/#\/schema\/person\/639c424e3584069003b11ae813915da6","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2023\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/posts\/87376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/comments?post=87376"}],"version-history":[{"count":2,"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/posts\/87376\/revisions"}],"predecessor-version":[{"id":87384,"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/posts\/87376\/revisions\/87384"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/media\/87383"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/media?parent=87376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/categories?post=87376"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/tags?post=87376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}