{"id":84718,"date":"2023-01-21T17:48:51","date_gmt":"2023-01-21T23:48:51","guid":{"rendered":"https:\/\/canal7slp.tv\/2023\/?p=84718"},"modified":"2023-01-21T17:48:51","modified_gmt":"2023-01-21T23:48:51","slug":"en-michoacan-sicarios-atropellan-a-comandante-del-65-batallon-de-infanteria","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2023\/en-michoacan-sicarios-atropellan-a-comandante-del-65-batallon-de-infanteria\/","title":{"rendered":"En Michoac\u00e1n, sicarios atropellan a comandante del 65 Batall\u00f3n de Infanter\u00eda"},"content":{"rendered":"<p style=\"text-align: justify;\">Coalcoman.- En la sierra Madre del Sur, el coronel del Ej\u00e9rcito Mexicano y comandante del 65 Batall\u00f3n de Infanter\u00eda en Coalcom\u00e1n, H\u00e9ctor Miguel Vargas Carrillo muri\u00f3 atropellado por un \u00abcami\u00f3n monstruo\u201d al ser emboscado con sus escoltas por un grupo de sicarios.<\/p>\n<p style=\"text-align: justify;\">Fuentes de la 43 Zona Militar, confirmaron que el mando militar fue emboscado la tarde-noche de ayer por sicarios que utilizaron varios camiones con blindaje artesanal conocidos como \u00abmonstruos\u00bb, cuando con sus escoltas realizaba un operativo de reconocimiento por el poblado de Maguey Verde, en Coalcom\u00e1n.<\/p>\n<p style=\"text-align: justify;\">El coronel y sus escoltas repelieron el ataque, desat\u00e1ndose un enfrentamiento que dej\u00f3 un militar herido y un civil lesionado, \u00e9ste \u00faltimo, vecino de la zona.<\/p>\n<p style=\"text-align: justify;\">Sin embargo, el comandante del Batall\u00f3n fue atropellado por un cami\u00f3n con blindaje artesanal, provoc\u00e1ndole diversas lesiones en t\u00f3rax, f\u00e9mur y otras partes del cuerpo, por lo que fue \u00abextra\u00eddo\u201d del lugar por un helic\u00f3ptero que lo traslad\u00f3 al hospital militar de la 44 Zona Militar, donde se confirm\u00f3 su deceso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Coalcoman.- En la sierra Madre del Sur, el coronel del Ej\u00e9rcito Mexicano y comandante del 65 Batall\u00f3n de Infanter\u00eda en Coalcom\u00e1n, H\u00e9ctor Miguel Vargas Carrillo muri\u00f3 atropellado por un \u00abcami\u00f3n monstruo\u201d al ser emboscado con sus escoltas por un grupo de sicarios. Fuentes de la 43 Zona Militar, confirmaron que el mando militar fue emboscado la tarde-noche de ayer por sicarios que utilizaron varios camiones con blindaje artesanal conocidos como \u00abmonstruos\u00bb, cuando con sus escoltas realizaba un operativo de reconocimiento por el poblado de Maguey Verde, en Coalcom\u00e1n. El coronel y sus escoltas repelieron el ataque, desat\u00e1ndose un enfrentamiento que [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":84734,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[],"class_list":["post-84718","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>En Michoac\u00e1n, sicarios atropellan a comandante del 65 Batall\u00f3n de Infanter\u00eda - Canal 7 SLP - 2023<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2023\/en-michoacan-sicarios-atropellan-a-comandante-del-65-batallon-de-infanteria\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En Michoac\u00e1n, sicarios atropellan a comandante del 65 Batall\u00f3n de Infanter\u00eda - Canal 7 SLP - 2023\" \/>\n<meta property=\"og:description\" content=\"Coalcoman.- En la sierra Madre del Sur, el coronel del Ej\u00e9rcito Mexicano y comandante del 65 Batall\u00f3n de Infanter\u00eda en Coalcom\u00e1n, H\u00e9ctor Miguel Vargas Carrillo muri\u00f3 atropellado por un \u00abcami\u00f3n monstruo\u201d al ser emboscado con sus escoltas por un grupo de sicarios. Fuentes de la 43 Zona Militar, confirmaron que el mando militar fue emboscado la tarde-noche de ayer por sicarios que utilizaron varios camiones con blindaje artesanal conocidos como \u00abmonstruos\u00bb, cuando con sus escoltas realizaba un operativo de reconocimiento por el poblado de Maguey Verde, en Coalcom\u00e1n. El coronel y sus escoltas repelieron el ataque, desat\u00e1ndose un enfrentamiento que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2023\/en-michoacan-sicarios-atropellan-a-comandante-del-65-batallon-de-infanteria\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2023\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanalsiete\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-21T23:48:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2023\/01\/05-16.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"769\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/en-michoacan-sicarios-atropellan-a-comandante-del-65-batallon-de-infanteria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/en-michoacan-sicarios-atropellan-a-comandante-del-65-batallon-de-infanteria\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#\\\/schema\\\/person\\\/639c424e3584069003b11ae813915da6\"},\"headline\":\"En Michoac\u00e1n, sicarios atropellan a comandante del 65 Batall\u00f3n de Infanter\u00eda\",\"datePublished\":\"2023-01-21T23:48:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/en-michoacan-sicarios-atropellan-a-comandante-del-65-batallon-de-infanteria\\\/\"},\"wordCount\":191,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/en-michoacan-sicarios-atropellan-a-comandante-del-65-batallon-de-infanteria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/05-16.jpg\",\"articleSection\":[\"NACIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/en-michoacan-sicarios-atropellan-a-comandante-del-65-batallon-de-infanteria\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/en-michoacan-sicarios-atropellan-a-comandante-del-65-batallon-de-infanteria\\\/\",\"name\":\"En Michoac\u00e1n, sicarios atropellan a comandante del 65 Batall\u00f3n de Infanter\u00eda - Canal 7 SLP - 2023\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/en-michoacan-sicarios-atropellan-a-comandante-del-65-batallon-de-infanteria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/en-michoacan-sicarios-atropellan-a-comandante-del-65-batallon-de-infanteria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/05-16.jpg\",\"datePublished\":\"2023-01-21T23:48:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/en-michoacan-sicarios-atropellan-a-comandante-del-65-batallon-de-infanteria\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/en-michoacan-sicarios-atropellan-a-comandante-del-65-batallon-de-infanteria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/en-michoacan-sicarios-atropellan-a-comandante-del-65-batallon-de-infanteria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/05-16.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/05-16.jpg\",\"width\":1280,\"height\":769},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/en-michoacan-sicarios-atropellan-a-comandante-del-65-batallon-de-infanteria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En Michoac\u00e1n, sicarios atropellan a comandante del 65 Batall\u00f3n de Infanter\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanalsiete\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#\\\/schema\\\/person\\\/639c424e3584069003b11ae813915da6\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En Michoac\u00e1n, sicarios atropellan a comandante del 65 Batall\u00f3n de Infanter\u00eda - Canal 7 SLP - 2023","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2023\/en-michoacan-sicarios-atropellan-a-comandante-del-65-batallon-de-infanteria\/","og_locale":"es_ES","og_type":"article","og_title":"En Michoac\u00e1n, sicarios atropellan a comandante del 65 Batall\u00f3n de Infanter\u00eda - Canal 7 SLP - 2023","og_description":"Coalcoman.- En la sierra Madre del Sur, el coronel del Ej\u00e9rcito Mexicano y comandante del 65 Batall\u00f3n de Infanter\u00eda en Coalcom\u00e1n, H\u00e9ctor Miguel Vargas Carrillo muri\u00f3 atropellado por un \u00abcami\u00f3n monstruo\u201d al ser emboscado con sus escoltas por un grupo de sicarios. Fuentes de la 43 Zona Militar, confirmaron que el mando militar fue emboscado la tarde-noche de ayer por sicarios que utilizaron varios camiones con blindaje artesanal conocidos como \u00abmonstruos\u00bb, cuando con sus escoltas realizaba un operativo de reconocimiento por el poblado de Maguey Verde, en Coalcom\u00e1n. El coronel y sus escoltas repelieron el ataque, desat\u00e1ndose un enfrentamiento que [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2023\/en-michoacan-sicarios-atropellan-a-comandante-del-65-batallon-de-infanteria\/","og_site_name":"Canal 7 SLP - 2023","article_publisher":"https:\/\/www.facebook.com\/noticieroscanalsiete","article_published_time":"2023-01-21T23:48:51+00:00","og_image":[{"width":1280,"height":769,"url":"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2023\/01\/05-16.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2023\/en-michoacan-sicarios-atropellan-a-comandante-del-65-batallon-de-infanteria\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2023\/en-michoacan-sicarios-atropellan-a-comandante-del-65-batallon-de-infanteria\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2023\/#\/schema\/person\/639c424e3584069003b11ae813915da6"},"headline":"En Michoac\u00e1n, sicarios atropellan a comandante del 65 Batall\u00f3n de Infanter\u00eda","datePublished":"2023-01-21T23:48:51+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2023\/en-michoacan-sicarios-atropellan-a-comandante-del-65-batallon-de-infanteria\/"},"wordCount":191,"publisher":{"@id":"https:\/\/canal7slp.tv\/2023\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2023\/en-michoacan-sicarios-atropellan-a-comandante-del-65-batallon-de-infanteria\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2023\/01\/05-16.jpg","articleSection":["NACIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2023\/en-michoacan-sicarios-atropellan-a-comandante-del-65-batallon-de-infanteria\/","url":"https:\/\/canal7slp.tv\/2023\/en-michoacan-sicarios-atropellan-a-comandante-del-65-batallon-de-infanteria\/","name":"En Michoac\u00e1n, sicarios atropellan a comandante del 65 Batall\u00f3n de Infanter\u00eda - Canal 7 SLP - 2023","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2023\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2023\/en-michoacan-sicarios-atropellan-a-comandante-del-65-batallon-de-infanteria\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2023\/en-michoacan-sicarios-atropellan-a-comandante-del-65-batallon-de-infanteria\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2023\/01\/05-16.jpg","datePublished":"2023-01-21T23:48:51+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2023\/en-michoacan-sicarios-atropellan-a-comandante-del-65-batallon-de-infanteria\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2023\/en-michoacan-sicarios-atropellan-a-comandante-del-65-batallon-de-infanteria\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2023\/en-michoacan-sicarios-atropellan-a-comandante-del-65-batallon-de-infanteria\/#primaryimage","url":"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2023\/01\/05-16.jpg","contentUrl":"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2023\/01\/05-16.jpg","width":1280,"height":769},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2023\/en-michoacan-sicarios-atropellan-a-comandante-del-65-batallon-de-infanteria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2023\/"},{"@type":"ListItem","position":2,"name":"En Michoac\u00e1n, sicarios atropellan a comandante del 65 Batall\u00f3n de Infanter\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2023\/#website","url":"https:\/\/canal7slp.tv\/2023\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2023\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2023\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2023\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2023\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2023\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2023\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanalsiete","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2023\/#\/schema\/person\/639c424e3584069003b11ae813915da6","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2023\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/posts\/84718","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/comments?post=84718"}],"version-history":[{"count":2,"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/posts\/84718\/revisions"}],"predecessor-version":[{"id":84740,"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/posts\/84718\/revisions\/84740"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/media\/84734"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/media?parent=84718"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/categories?post=84718"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/tags?post=84718"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}