{"id":103260,"date":"2023-08-03T17:33:21","date_gmt":"2023-08-03T23:33:21","guid":{"rendered":"https:\/\/canal7slp.tv\/2023\/?p=103260"},"modified":"2023-08-03T17:33:21","modified_gmt":"2023-08-03T23:33:21","slug":"llaman-a-registrarse-para-seleccion-de-candidato-del-frente-amplio-por-mexico","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2023\/llaman-a-registrarse-para-seleccion-de-candidato-del-frente-amplio-por-mexico\/","title":{"rendered":"Llaman a registrarse para selecci\u00f3n de candidato del Frente Amplio por M\u00e9xico"},"content":{"rendered":"<p style=\"text-align: justify;\">SLP.- Los integrantes del Comit\u00e9 Organizador Estatal del Frente Amplio Por M\u00e9xico hicieron un llamado a registrarse en el padr\u00f3n y de esta manera, participar en el proceso para seleccionar al candidato de la coalici\u00f3n \u201cVa Por M\u00e9xico\u201da la presidencia de la rep\u00fablica.<\/p>\n<p style=\"text-align: justify;\">Mnauel Aranda integrante tambi\u00e9n de este comit\u00e9 organizador detall\u00f3 las etapas que deber\u00e1n de seguirse en este proceso en donde 3n un principio se registraron 33 aspirantes y ahora, solo quedan 12.<\/p>\n<p style=\"text-align: justify;\">Cabe se\u00f1alar que en este mes de Agosto se vencen los plazos para el registro ya que el nombre del aspirante \u00f3 candidato ganador, deber\u00e1 darse a conocer el pr\u00f3ximo 3 de Septiembre.<\/p>\n<p style=\"text-align: justify;\">Cabe recordar que cada uno de los 12 aspirantes deber\u00e1n de reunir 150 mil firmas de simpatizantes registrados en la plataforma, y avanzar en cada una las etapas de este proceso<\/p>\n<p>Por: Claudio Ibarra<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SLP.- Los integrantes del Comit\u00e9 Organizador Estatal del Frente Amplio Por M\u00e9xico hicieron un llamado a registrarse en el padr\u00f3n y de esta manera, participar en el proceso para seleccionar al candidato de la coalici\u00f3n \u201cVa Por M\u00e9xico\u201da la presidencia de la rep\u00fablica. Mnauel Aranda integrante tambi\u00e9n de este comit\u00e9 organizador detall\u00f3 las etapas que deber\u00e1n de seguirse en este proceso en donde 3n un principio se registraron 33 aspirantes y ahora, solo quedan 12. Cabe se\u00f1alar que en este mes de Agosto se vencen los plazos para el registro ya que el nombre del aspirante \u00f3 candidato ganador, deber\u00e1 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":103282,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"footnotes":""},"categories":[5,45],"tags":[],"class_list":["post-103260","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-destacadas","category-localesyregionales","post_format-post-format-video","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Llaman a registrarse para selecci\u00f3n de candidato del Frente Amplio por M\u00e9xico - Canal 7 SLP - 2023<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2023\/llaman-a-registrarse-para-seleccion-de-candidato-del-frente-amplio-por-mexico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Llaman a registrarse para selecci\u00f3n de candidato del Frente Amplio por M\u00e9xico - Canal 7 SLP - 2023\" \/>\n<meta property=\"og:description\" content=\"SLP.- Los integrantes del Comit\u00e9 Organizador Estatal del Frente Amplio Por M\u00e9xico hicieron un llamado a registrarse en el padr\u00f3n y de esta manera, participar en el proceso para seleccionar al candidato de la coalici\u00f3n \u201cVa Por M\u00e9xico\u201da la presidencia de la rep\u00fablica. Mnauel Aranda integrante tambi\u00e9n de este comit\u00e9 organizador detall\u00f3 las etapas que deber\u00e1n de seguirse en este proceso en donde 3n un principio se registraron 33 aspirantes y ahora, solo quedan 12. Cabe se\u00f1alar que en este mes de Agosto se vencen los plazos para el registro ya que el nombre del aspirante \u00f3 candidato ganador, deber\u00e1 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2023\/llaman-a-registrarse-para-seleccion-de-candidato-del-frente-amplio-por-mexico\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2023\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanalsiete\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-03T23:33:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2023\/08\/Claudio02RegistroFAM.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/llaman-a-registrarse-para-seleccion-de-candidato-del-frente-amplio-por-mexico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/llaman-a-registrarse-para-seleccion-de-candidato-del-frente-amplio-por-mexico\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#\\\/schema\\\/person\\\/639c424e3584069003b11ae813915da6\"},\"headline\":\"Llaman a registrarse para selecci\u00f3n de candidato del Frente Amplio por M\u00e9xico\",\"datePublished\":\"2023-08-03T23:33:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/llaman-a-registrarse-para-seleccion-de-candidato-del-frente-amplio-por-mexico\\\/\"},\"wordCount\":162,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/llaman-a-registrarse-para-seleccion-de-candidato-del-frente-amplio-por-mexico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Claudio02RegistroFAM.jpg\",\"articleSection\":[\"DESTACADAS\",\"LOCALES Y REGIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/llaman-a-registrarse-para-seleccion-de-candidato-del-frente-amplio-por-mexico\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/llaman-a-registrarse-para-seleccion-de-candidato-del-frente-amplio-por-mexico\\\/\",\"name\":\"Llaman a registrarse para selecci\u00f3n de candidato del Frente Amplio por M\u00e9xico - Canal 7 SLP - 2023\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/llaman-a-registrarse-para-seleccion-de-candidato-del-frente-amplio-por-mexico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/llaman-a-registrarse-para-seleccion-de-candidato-del-frente-amplio-por-mexico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Claudio02RegistroFAM.jpg\",\"datePublished\":\"2023-08-03T23:33:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/llaman-a-registrarse-para-seleccion-de-candidato-del-frente-amplio-por-mexico\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/llaman-a-registrarse-para-seleccion-de-candidato-del-frente-amplio-por-mexico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/llaman-a-registrarse-para-seleccion-de-candidato-del-frente-amplio-por-mexico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Claudio02RegistroFAM.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Claudio02RegistroFAM.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/llaman-a-registrarse-para-seleccion-de-candidato-del-frente-amplio-por-mexico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Llaman a registrarse para selecci\u00f3n de candidato del Frente Amplio por M\u00e9xico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanalsiete\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#\\\/schema\\\/person\\\/639c424e3584069003b11ae813915da6\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Llaman a registrarse para selecci\u00f3n de candidato del Frente Amplio por M\u00e9xico - Canal 7 SLP - 2023","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2023\/llaman-a-registrarse-para-seleccion-de-candidato-del-frente-amplio-por-mexico\/","og_locale":"es_ES","og_type":"article","og_title":"Llaman a registrarse para selecci\u00f3n de candidato del Frente Amplio por M\u00e9xico - Canal 7 SLP - 2023","og_description":"SLP.- Los integrantes del Comit\u00e9 Organizador Estatal del Frente Amplio Por M\u00e9xico hicieron un llamado a registrarse en el padr\u00f3n y de esta manera, participar en el proceso para seleccionar al candidato de la coalici\u00f3n \u201cVa Por M\u00e9xico\u201da la presidencia de la rep\u00fablica. Mnauel Aranda integrante tambi\u00e9n de este comit\u00e9 organizador detall\u00f3 las etapas que deber\u00e1n de seguirse en este proceso en donde 3n un principio se registraron 33 aspirantes y ahora, solo quedan 12. Cabe se\u00f1alar que en este mes de Agosto se vencen los plazos para el registro ya que el nombre del aspirante \u00f3 candidato ganador, deber\u00e1 [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2023\/llaman-a-registrarse-para-seleccion-de-candidato-del-frente-amplio-por-mexico\/","og_site_name":"Canal 7 SLP - 2023","article_publisher":"https:\/\/www.facebook.com\/noticieroscanalsiete","article_published_time":"2023-08-03T23:33:21+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2023\/08\/Claudio02RegistroFAM.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2023\/llaman-a-registrarse-para-seleccion-de-candidato-del-frente-amplio-por-mexico\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2023\/llaman-a-registrarse-para-seleccion-de-candidato-del-frente-amplio-por-mexico\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2023\/#\/schema\/person\/639c424e3584069003b11ae813915da6"},"headline":"Llaman a registrarse para selecci\u00f3n de candidato del Frente Amplio por M\u00e9xico","datePublished":"2023-08-03T23:33:21+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2023\/llaman-a-registrarse-para-seleccion-de-candidato-del-frente-amplio-por-mexico\/"},"wordCount":162,"publisher":{"@id":"https:\/\/canal7slp.tv\/2023\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2023\/llaman-a-registrarse-para-seleccion-de-candidato-del-frente-amplio-por-mexico\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2023\/08\/Claudio02RegistroFAM.jpg","articleSection":["DESTACADAS","LOCALES Y REGIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2023\/llaman-a-registrarse-para-seleccion-de-candidato-del-frente-amplio-por-mexico\/","url":"https:\/\/canal7slp.tv\/2023\/llaman-a-registrarse-para-seleccion-de-candidato-del-frente-amplio-por-mexico\/","name":"Llaman a registrarse para selecci\u00f3n de candidato del Frente Amplio por M\u00e9xico - Canal 7 SLP - 2023","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2023\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2023\/llaman-a-registrarse-para-seleccion-de-candidato-del-frente-amplio-por-mexico\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2023\/llaman-a-registrarse-para-seleccion-de-candidato-del-frente-amplio-por-mexico\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2023\/08\/Claudio02RegistroFAM.jpg","datePublished":"2023-08-03T23:33:21+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2023\/llaman-a-registrarse-para-seleccion-de-candidato-del-frente-amplio-por-mexico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2023\/llaman-a-registrarse-para-seleccion-de-candidato-del-frente-amplio-por-mexico\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2023\/llaman-a-registrarse-para-seleccion-de-candidato-del-frente-amplio-por-mexico\/#primaryimage","url":"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2023\/08\/Claudio02RegistroFAM.jpg","contentUrl":"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2023\/08\/Claudio02RegistroFAM.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2023\/llaman-a-registrarse-para-seleccion-de-candidato-del-frente-amplio-por-mexico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2023\/"},{"@type":"ListItem","position":2,"name":"Llaman a registrarse para selecci\u00f3n de candidato del Frente Amplio por M\u00e9xico"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2023\/#website","url":"https:\/\/canal7slp.tv\/2023\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2023\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2023\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2023\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2023\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2023\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2023\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanalsiete","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2023\/#\/schema\/person\/639c424e3584069003b11ae813915da6","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2023\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/posts\/103260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/comments?post=103260"}],"version-history":[{"count":3,"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/posts\/103260\/revisions"}],"predecessor-version":[{"id":103283,"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/posts\/103260\/revisions\/103283"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/media\/103282"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/media?parent=103260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/categories?post=103260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/tags?post=103260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}