{"id":103238,"date":"2023-08-03T16:35:50","date_gmt":"2023-08-03T22:35:50","guid":{"rendered":"https:\/\/canal7slp.tv\/2023\/?p=103238"},"modified":"2023-08-03T16:35:50","modified_gmt":"2023-08-03T22:35:50","slug":"autotanques-asegurados-con-hidrocarburos-provienen-de-tamaulipas","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2023\/autotanques-asegurados-con-hidrocarburos-provienen-de-tamaulipas\/","title":{"rendered":"Autotanques asegurados con hidrocarburos provienen de Tamaulipas"},"content":{"rendered":"<p style=\"text-align: justify;\">SLP.- El titular de la Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana a nivel estatal, Guzmar \u00c1ngel Gonz\u00e1lez Castillo, inform\u00f3 que los aseguramientos de autotanques con hidrocarburos de procedencia il\u00edcita que se han registrado en el estado, provienen de Tamaulipas.<\/p>\n<p style=\"text-align: justify;\">Sin embargo, aclar\u00f3 que este tipo de eventos, son atendidos por los cuerpos de seguridad que tiene la federaci\u00f3n en la entidad.<\/p>\n<p style=\"text-align: justify;\">\u00abEstamos observando que la mayor\u00eda viene de procedencia de Tamaulipas los recorridos han sido por carreteras federales pero no hemos tenido aseguramientos, han sido m\u00ednimos, pero realmente los tractocamiones y estos autotanques vienen directamente por la Guardia Nacional\u00bb, dijo.<\/p>\n<p style=\"text-align: justify;\">Agreg\u00f3 que desde la dependencia se mantiene una coordinaci\u00f3n con la Guardia Nacional y el Ej\u00e9rcito Mexicano, por lo que reconoci\u00f3 las medidas de seguridad que se han tomado en ese sentido.<\/p>\n<p style=\"text-align: justify;\">Aunado a ello, Gonz\u00e1lez Castillo anunci\u00f3 que en los pr\u00f3ximos d\u00edas se emitir\u00e1 un informe sobre las acciones y resultados que ha tenido la Divisi\u00f3n Caminos de la Guardia Civil.<\/p>\n<p style=\"text-align: justify;\">\u00abSe va a hacer un resumen y ustedes tendr\u00e1n conocimiento, se les va a proporcionar manejando cantidades aseguradas as\u00ed como los montos que representaban para la delincuencia organizada; la Fiscal\u00eda General de la Rep\u00fablica directamente con la Guardia Nacional son quienes est\u00e1n atendiendo esto\u00bb, insisti\u00f3.<\/p>\n<p>Por: Jos\u00e9 Luis V\u00e1zquez<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SLP.- El titular de la Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana a nivel estatal, Guzmar \u00c1ngel Gonz\u00e1lez Castillo, inform\u00f3 que los aseguramientos de autotanques con hidrocarburos de procedencia il\u00edcita que se han registrado en el estado, provienen de Tamaulipas. Sin embargo, aclar\u00f3 que este tipo de eventos, son atendidos por los cuerpos de seguridad que tiene la federaci\u00f3n en la entidad. \u00abEstamos observando que la mayor\u00eda viene de procedencia de Tamaulipas los recorridos han sido por carreteras federales pero no hemos tenido aseguramientos, han sido m\u00ednimos, pero realmente los tractocamiones y estos autotanques vienen directamente por la Guardia Nacional\u00bb, dijo. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":103266,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"footnotes":""},"categories":[5,45],"tags":[],"class_list":["post-103238","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-destacadas","category-localesyregionales","post_format-post-format-video","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Autotanques asegurados con hidrocarburos provienen de Tamaulipas - Canal 7 SLP - 2023<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2023\/autotanques-asegurados-con-hidrocarburos-provienen-de-tamaulipas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Autotanques asegurados con hidrocarburos provienen de Tamaulipas - Canal 7 SLP - 2023\" \/>\n<meta property=\"og:description\" content=\"SLP.- El titular de la Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana a nivel estatal, Guzmar \u00c1ngel Gonz\u00e1lez Castillo, inform\u00f3 que los aseguramientos de autotanques con hidrocarburos de procedencia il\u00edcita que se han registrado en el estado, provienen de Tamaulipas. Sin embargo, aclar\u00f3 que este tipo de eventos, son atendidos por los cuerpos de seguridad que tiene la federaci\u00f3n en la entidad. \u00abEstamos observando que la mayor\u00eda viene de procedencia de Tamaulipas los recorridos han sido por carreteras federales pero no hemos tenido aseguramientos, han sido m\u00ednimos, pero realmente los tractocamiones y estos autotanques vienen directamente por la Guardia Nacional\u00bb, dijo. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2023\/autotanques-asegurados-con-hidrocarburos-provienen-de-tamaulipas\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2023\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanalsiete\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-03T22:35:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2023\/08\/Vazquez01SSPCHidrocarburos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/autotanques-asegurados-con-hidrocarburos-provienen-de-tamaulipas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/autotanques-asegurados-con-hidrocarburos-provienen-de-tamaulipas\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#\\\/schema\\\/person\\\/639c424e3584069003b11ae813915da6\"},\"headline\":\"Autotanques asegurados con hidrocarburos provienen de Tamaulipas\",\"datePublished\":\"2023-08-03T22:35:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/autotanques-asegurados-con-hidrocarburos-provienen-de-tamaulipas\\\/\"},\"wordCount\":237,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/autotanques-asegurados-con-hidrocarburos-provienen-de-tamaulipas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Vazquez01SSPCHidrocarburos.jpg\",\"articleSection\":[\"DESTACADAS\",\"LOCALES Y REGIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/autotanques-asegurados-con-hidrocarburos-provienen-de-tamaulipas\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/autotanques-asegurados-con-hidrocarburos-provienen-de-tamaulipas\\\/\",\"name\":\"Autotanques asegurados con hidrocarburos provienen de Tamaulipas - Canal 7 SLP - 2023\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/autotanques-asegurados-con-hidrocarburos-provienen-de-tamaulipas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/autotanques-asegurados-con-hidrocarburos-provienen-de-tamaulipas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Vazquez01SSPCHidrocarburos.jpg\",\"datePublished\":\"2023-08-03T22:35:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/autotanques-asegurados-con-hidrocarburos-provienen-de-tamaulipas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/autotanques-asegurados-con-hidrocarburos-provienen-de-tamaulipas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/autotanques-asegurados-con-hidrocarburos-provienen-de-tamaulipas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Vazquez01SSPCHidrocarburos.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Vazquez01SSPCHidrocarburos.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/autotanques-asegurados-con-hidrocarburos-provienen-de-tamaulipas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Autotanques asegurados con hidrocarburos provienen de Tamaulipas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanalsiete\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#\\\/schema\\\/person\\\/639c424e3584069003b11ae813915da6\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Autotanques asegurados con hidrocarburos provienen de Tamaulipas - Canal 7 SLP - 2023","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2023\/autotanques-asegurados-con-hidrocarburos-provienen-de-tamaulipas\/","og_locale":"es_ES","og_type":"article","og_title":"Autotanques asegurados con hidrocarburos provienen de Tamaulipas - Canal 7 SLP - 2023","og_description":"SLP.- El titular de la Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana a nivel estatal, Guzmar \u00c1ngel Gonz\u00e1lez Castillo, inform\u00f3 que los aseguramientos de autotanques con hidrocarburos de procedencia il\u00edcita que se han registrado en el estado, provienen de Tamaulipas. Sin embargo, aclar\u00f3 que este tipo de eventos, son atendidos por los cuerpos de seguridad que tiene la federaci\u00f3n en la entidad. \u00abEstamos observando que la mayor\u00eda viene de procedencia de Tamaulipas los recorridos han sido por carreteras federales pero no hemos tenido aseguramientos, han sido m\u00ednimos, pero realmente los tractocamiones y estos autotanques vienen directamente por la Guardia Nacional\u00bb, dijo. [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2023\/autotanques-asegurados-con-hidrocarburos-provienen-de-tamaulipas\/","og_site_name":"Canal 7 SLP - 2023","article_publisher":"https:\/\/www.facebook.com\/noticieroscanalsiete","article_published_time":"2023-08-03T22:35:50+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2023\/08\/Vazquez01SSPCHidrocarburos.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2023\/autotanques-asegurados-con-hidrocarburos-provienen-de-tamaulipas\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2023\/autotanques-asegurados-con-hidrocarburos-provienen-de-tamaulipas\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2023\/#\/schema\/person\/639c424e3584069003b11ae813915da6"},"headline":"Autotanques asegurados con hidrocarburos provienen de Tamaulipas","datePublished":"2023-08-03T22:35:50+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2023\/autotanques-asegurados-con-hidrocarburos-provienen-de-tamaulipas\/"},"wordCount":237,"publisher":{"@id":"https:\/\/canal7slp.tv\/2023\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2023\/autotanques-asegurados-con-hidrocarburos-provienen-de-tamaulipas\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2023\/08\/Vazquez01SSPCHidrocarburos.jpg","articleSection":["DESTACADAS","LOCALES Y REGIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2023\/autotanques-asegurados-con-hidrocarburos-provienen-de-tamaulipas\/","url":"https:\/\/canal7slp.tv\/2023\/autotanques-asegurados-con-hidrocarburos-provienen-de-tamaulipas\/","name":"Autotanques asegurados con hidrocarburos provienen de Tamaulipas - Canal 7 SLP - 2023","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2023\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2023\/autotanques-asegurados-con-hidrocarburos-provienen-de-tamaulipas\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2023\/autotanques-asegurados-con-hidrocarburos-provienen-de-tamaulipas\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2023\/08\/Vazquez01SSPCHidrocarburos.jpg","datePublished":"2023-08-03T22:35:50+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2023\/autotanques-asegurados-con-hidrocarburos-provienen-de-tamaulipas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2023\/autotanques-asegurados-con-hidrocarburos-provienen-de-tamaulipas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2023\/autotanques-asegurados-con-hidrocarburos-provienen-de-tamaulipas\/#primaryimage","url":"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2023\/08\/Vazquez01SSPCHidrocarburos.jpg","contentUrl":"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2023\/08\/Vazquez01SSPCHidrocarburos.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2023\/autotanques-asegurados-con-hidrocarburos-provienen-de-tamaulipas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2023\/"},{"@type":"ListItem","position":2,"name":"Autotanques asegurados con hidrocarburos provienen de Tamaulipas"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2023\/#website","url":"https:\/\/canal7slp.tv\/2023\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2023\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2023\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2023\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2023\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2023\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2023\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanalsiete","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2023\/#\/schema\/person\/639c424e3584069003b11ae813915da6","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2023\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/posts\/103238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/comments?post=103238"}],"version-history":[{"count":2,"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/posts\/103238\/revisions"}],"predecessor-version":[{"id":103267,"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/posts\/103238\/revisions\/103267"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/media\/103266"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/media?parent=103238"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/categories?post=103238"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/tags?post=103238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}