{"id":102640,"date":"2023-07-28T18:11:51","date_gmt":"2023-07-29T00:11:51","guid":{"rendered":"https:\/\/canal7slp.tv\/2023\/?p=102640"},"modified":"2023-07-28T18:11:51","modified_gmt":"2023-07-29T00:11:51","slug":"retiran-libros-de-texto-de-escuelas-de-guanajuato-tras-amparo-de-padres-de-familia","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2023\/retiran-libros-de-texto-de-escuelas-de-guanajuato-tras-amparo-de-padres-de-familia\/","title":{"rendered":"Retiran libros de texto de escuelas de Guanajuato tras amparo de padres de familia"},"content":{"rendered":"<p style=\"text-align: justify;\">Le\u00f3n.- Una remesa de libros de texto gratuito fue retirada de varias escuelas de primaria en Le\u00f3n, Guanajuato, por mandato de un juzgado federal en un juicio de amparo que promovi\u00f3 la Uni\u00f3n Nacional de Padres de Familia.<\/p>\n<p style=\"text-align: justify;\">Los libros hab\u00edan sido repartidos por la delegaci\u00f3n regional de la Secretar\u00eda de Educaci\u00f3n de Guanajuato en varios planteles de Le\u00f3n, y d\u00edas despu\u00e9s retornaron a las bodegas.<\/p>\n<p style=\"text-align: justify;\">La Secretar\u00eda de Educaci\u00f3n de Guanajuato (SEG) se\u00f1al\u00f3 que esos libros \u00abson regresados al almac\u00e9n regional hasta en tanto se completen las entregas por parte de la Secretar\u00eda de Educaci\u00f3n P\u00fablica (SEP) y se brinde la certeza legal en cuanto a la distribuci\u00f3n\u00bb.<\/p>\n<p style=\"text-align: justify;\">La SEP ha enviado menos del 40% de los libros asignados a Guanajuato para el ciclo escolar 2023-2024. La dependencia no dio detalles sobre la acci\u00f3n legal de los padres de familia por la violaci\u00f3n a sus derechos fundamentales en el tema de educaci\u00f3n, no obstante que representantes de padres de familia han denunciado que los libros de texto supuestamente tienen errores y contenidos ideol\u00f3gicos.<\/p>\n<p style=\"text-align: justify;\">El Presidente Andr\u00e9s Manuel L\u00f3pez Obrador asegur\u00f3 que existen opositores porque son nuevos contenidos que buscan que la educaci\u00f3n tenga dimensi\u00f3n social, human\u00edstica y cient\u00edfica que se hab\u00eda perdido en el periodo neoliberal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le\u00f3n.- Una remesa de libros de texto gratuito fue retirada de varias escuelas de primaria en Le\u00f3n, Guanajuato, por mandato de un juzgado federal en un juicio de amparo que promovi\u00f3 la Uni\u00f3n Nacional de Padres de Familia. Los libros hab\u00edan sido repartidos por la delegaci\u00f3n regional de la Secretar\u00eda de Educaci\u00f3n de Guanajuato en varios planteles de Le\u00f3n, y d\u00edas despu\u00e9s retornaron a las bodegas. La Secretar\u00eda de Educaci\u00f3n de Guanajuato (SEG) se\u00f1al\u00f3 que esos libros \u00abson regresados al almac\u00e9n regional hasta en tanto se completen las entregas por parte de la Secretar\u00eda de Educaci\u00f3n P\u00fablica (SEP) y se [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":102655,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[],"class_list":["post-102640","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Retiran libros de texto de escuelas de Guanajuato tras amparo de padres de familia - Canal 7 SLP - 2023<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2023\/retiran-libros-de-texto-de-escuelas-de-guanajuato-tras-amparo-de-padres-de-familia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Retiran libros de texto de escuelas de Guanajuato tras amparo de padres de familia - Canal 7 SLP - 2023\" \/>\n<meta property=\"og:description\" content=\"Le\u00f3n.- Una remesa de libros de texto gratuito fue retirada de varias escuelas de primaria en Le\u00f3n, Guanajuato, por mandato de un juzgado federal en un juicio de amparo que promovi\u00f3 la Uni\u00f3n Nacional de Padres de Familia. Los libros hab\u00edan sido repartidos por la delegaci\u00f3n regional de la Secretar\u00eda de Educaci\u00f3n de Guanajuato en varios planteles de Le\u00f3n, y d\u00edas despu\u00e9s retornaron a las bodegas. La Secretar\u00eda de Educaci\u00f3n de Guanajuato (SEG) se\u00f1al\u00f3 que esos libros \u00abson regresados al almac\u00e9n regional hasta en tanto se completen las entregas por parte de la Secretar\u00eda de Educaci\u00f3n P\u00fablica (SEP) y se [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2023\/retiran-libros-de-texto-de-escuelas-de-guanajuato-tras-amparo-de-padres-de-familia\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2023\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanalsiete\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-29T00:11:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2023\/07\/06-19.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"387\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/retiran-libros-de-texto-de-escuelas-de-guanajuato-tras-amparo-de-padres-de-familia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/retiran-libros-de-texto-de-escuelas-de-guanajuato-tras-amparo-de-padres-de-familia\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#\\\/schema\\\/person\\\/639c424e3584069003b11ae813915da6\"},\"headline\":\"Retiran libros de texto de escuelas de Guanajuato tras amparo de padres de familia\",\"datePublished\":\"2023-07-29T00:11:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/retiran-libros-de-texto-de-escuelas-de-guanajuato-tras-amparo-de-padres-de-familia\\\/\"},\"wordCount\":250,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/retiran-libros-de-texto-de-escuelas-de-guanajuato-tras-amparo-de-padres-de-familia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/06-19.jpg\",\"articleSection\":[\"NACIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/retiran-libros-de-texto-de-escuelas-de-guanajuato-tras-amparo-de-padres-de-familia\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/retiran-libros-de-texto-de-escuelas-de-guanajuato-tras-amparo-de-padres-de-familia\\\/\",\"name\":\"Retiran libros de texto de escuelas de Guanajuato tras amparo de padres de familia - Canal 7 SLP - 2023\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/retiran-libros-de-texto-de-escuelas-de-guanajuato-tras-amparo-de-padres-de-familia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/retiran-libros-de-texto-de-escuelas-de-guanajuato-tras-amparo-de-padres-de-familia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/06-19.jpg\",\"datePublished\":\"2023-07-29T00:11:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/retiran-libros-de-texto-de-escuelas-de-guanajuato-tras-amparo-de-padres-de-familia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/retiran-libros-de-texto-de-escuelas-de-guanajuato-tras-amparo-de-padres-de-familia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/retiran-libros-de-texto-de-escuelas-de-guanajuato-tras-amparo-de-padres-de-familia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/06-19.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/06-19.jpg\",\"width\":720,\"height\":387},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/retiran-libros-de-texto-de-escuelas-de-guanajuato-tras-amparo-de-padres-de-familia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retiran libros de texto de escuelas de Guanajuato tras amparo de padres de familia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanalsiete\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#\\\/schema\\\/person\\\/639c424e3584069003b11ae813915da6\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Retiran libros de texto de escuelas de Guanajuato tras amparo de padres de familia - Canal 7 SLP - 2023","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2023\/retiran-libros-de-texto-de-escuelas-de-guanajuato-tras-amparo-de-padres-de-familia\/","og_locale":"es_ES","og_type":"article","og_title":"Retiran libros de texto de escuelas de Guanajuato tras amparo de padres de familia - Canal 7 SLP - 2023","og_description":"Le\u00f3n.- Una remesa de libros de texto gratuito fue retirada de varias escuelas de primaria en Le\u00f3n, Guanajuato, por mandato de un juzgado federal en un juicio de amparo que promovi\u00f3 la Uni\u00f3n Nacional de Padres de Familia. Los libros hab\u00edan sido repartidos por la delegaci\u00f3n regional de la Secretar\u00eda de Educaci\u00f3n de Guanajuato en varios planteles de Le\u00f3n, y d\u00edas despu\u00e9s retornaron a las bodegas. La Secretar\u00eda de Educaci\u00f3n de Guanajuato (SEG) se\u00f1al\u00f3 que esos libros \u00abson regresados al almac\u00e9n regional hasta en tanto se completen las entregas por parte de la Secretar\u00eda de Educaci\u00f3n P\u00fablica (SEP) y se [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2023\/retiran-libros-de-texto-de-escuelas-de-guanajuato-tras-amparo-de-padres-de-familia\/","og_site_name":"Canal 7 SLP - 2023","article_publisher":"https:\/\/www.facebook.com\/noticieroscanalsiete","article_published_time":"2023-07-29T00:11:51+00:00","og_image":[{"width":720,"height":387,"url":"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2023\/07\/06-19.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2023\/retiran-libros-de-texto-de-escuelas-de-guanajuato-tras-amparo-de-padres-de-familia\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2023\/retiran-libros-de-texto-de-escuelas-de-guanajuato-tras-amparo-de-padres-de-familia\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2023\/#\/schema\/person\/639c424e3584069003b11ae813915da6"},"headline":"Retiran libros de texto de escuelas de Guanajuato tras amparo de padres de familia","datePublished":"2023-07-29T00:11:51+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2023\/retiran-libros-de-texto-de-escuelas-de-guanajuato-tras-amparo-de-padres-de-familia\/"},"wordCount":250,"publisher":{"@id":"https:\/\/canal7slp.tv\/2023\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2023\/retiran-libros-de-texto-de-escuelas-de-guanajuato-tras-amparo-de-padres-de-familia\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2023\/07\/06-19.jpg","articleSection":["NACIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2023\/retiran-libros-de-texto-de-escuelas-de-guanajuato-tras-amparo-de-padres-de-familia\/","url":"https:\/\/canal7slp.tv\/2023\/retiran-libros-de-texto-de-escuelas-de-guanajuato-tras-amparo-de-padres-de-familia\/","name":"Retiran libros de texto de escuelas de Guanajuato tras amparo de padres de familia - Canal 7 SLP - 2023","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2023\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2023\/retiran-libros-de-texto-de-escuelas-de-guanajuato-tras-amparo-de-padres-de-familia\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2023\/retiran-libros-de-texto-de-escuelas-de-guanajuato-tras-amparo-de-padres-de-familia\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2023\/07\/06-19.jpg","datePublished":"2023-07-29T00:11:51+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2023\/retiran-libros-de-texto-de-escuelas-de-guanajuato-tras-amparo-de-padres-de-familia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2023\/retiran-libros-de-texto-de-escuelas-de-guanajuato-tras-amparo-de-padres-de-familia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2023\/retiran-libros-de-texto-de-escuelas-de-guanajuato-tras-amparo-de-padres-de-familia\/#primaryimage","url":"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2023\/07\/06-19.jpg","contentUrl":"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2023\/07\/06-19.jpg","width":720,"height":387},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2023\/retiran-libros-de-texto-de-escuelas-de-guanajuato-tras-amparo-de-padres-de-familia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2023\/"},{"@type":"ListItem","position":2,"name":"Retiran libros de texto de escuelas de Guanajuato tras amparo de padres de familia"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2023\/#website","url":"https:\/\/canal7slp.tv\/2023\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2023\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2023\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2023\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2023\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2023\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2023\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanalsiete","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2023\/#\/schema\/person\/639c424e3584069003b11ae813915da6","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2023\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/posts\/102640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/comments?post=102640"}],"version-history":[{"count":3,"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/posts\/102640\/revisions"}],"predecessor-version":[{"id":102707,"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/posts\/102640\/revisions\/102707"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/media\/102655"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/media?parent=102640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/categories?post=102640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/tags?post=102640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}