{"id":101040,"date":"2023-07-11T19:58:43","date_gmt":"2023-07-12T01:58:43","guid":{"rendered":"https:\/\/canal7slp.tv\/2023\/?p=101040"},"modified":"2023-07-11T19:58:43","modified_gmt":"2023-07-12T01:58:43","slug":"impulsa-secretaria-de-turismo-subasta-de-payasos-en-el-centro-historico","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2023\/impulsa-secretaria-de-turismo-subasta-de-payasos-en-el-centro-historico\/","title":{"rendered":"Impulsa Secretar\u00eda de Turismo \u00abSubasta de Payasos\u00bb en el Centro Hist\u00f3rico"},"content":{"rendered":"<p style=\"text-align: justify;\">SLP.- Durante tres d\u00edas, del 24 al 27 de Julio la capital potosina ser\u00e1 sede del evento denominado \u201cSubasta de Payasos\u201d y en el que capacita a quienes se dedican a este oficio, pero tambi\u00e9n a quienes quieran ejercerlo, como un preparativo al Congreso Nacional de Payasos que se realiza a\u00f1os tras a\u00f1o.<\/p>\n<p style=\"text-align: justify;\">Se espera la asistencia de cientos de payasos que igual vendr\u00e1n de otros estados de la rep\u00fablica pero tambi\u00e9n del extranjero<\/p>\n<p style=\"text-align: justify;\">Afirm\u00f3 que ser payasos no solo es llegar a la burla \u00f3 a la ofensa adem\u00e1s de no solo pintarse la cara sino maquillarse de manera que provoque risas.<\/p>\n<p style=\"text-align: justify;\">Y es que el payaso \u201cTurin Kokito\u201d afirm\u00f3 que hay quienes se burlan de los defectos de las personas pero que un verdadero payaso, es aquel que provoca sonrisas con base a un humor sano y no a las burlas.<br \/>\nEn este evento habr\u00e1 tambi\u00e9n talleres de magia, baby shower, comedia y musicalizaci\u00f3n para aprender a manejar instrumentos.<\/p>\n<p style=\"text-align: justify;\">Otras de las actividades que habr\u00e1 en esta Subasta de Payasos ser\u00e1 una comparsa que se llevar\u00e1 a cabo por las calles del Centro Hist\u00f3rico, a partir de las 11 de la ma\u00f1ana llegando a Palacio Municipal adem\u00e1s de un concurso de comedia.<\/p>\n<p>Por: Claudio Ibarra<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SLP.- Durante tres d\u00edas, del 24 al 27 de Julio la capital potosina ser\u00e1 sede del evento denominado \u201cSubasta de Payasos\u201d y en el que capacita a quienes se dedican a este oficio, pero tambi\u00e9n a quienes quieran ejercerlo, como un preparativo al Congreso Nacional de Payasos que se realiza a\u00f1os tras a\u00f1o. Se espera la asistencia de cientos de payasos que igual vendr\u00e1n de otros estados de la rep\u00fablica pero tambi\u00e9n del extranjero Afirm\u00f3 que ser payasos no solo es llegar a la burla \u00f3 a la ofensa adem\u00e1s de no solo pintarse la cara sino maquillarse de manera [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":101073,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"footnotes":""},"categories":[5,45],"tags":[],"class_list":["post-101040","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-destacadas","category-localesyregionales","post_format-post-format-video","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Impulsa Secretar\u00eda de Turismo &quot;Subasta de Payasos&quot; en el Centro Hist\u00f3rico - Canal 7 SLP - 2023<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2023\/impulsa-secretaria-de-turismo-subasta-de-payasos-en-el-centro-historico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Impulsa Secretar\u00eda de Turismo &quot;Subasta de Payasos&quot; en el Centro Hist\u00f3rico - Canal 7 SLP - 2023\" \/>\n<meta property=\"og:description\" content=\"SLP.- Durante tres d\u00edas, del 24 al 27 de Julio la capital potosina ser\u00e1 sede del evento denominado \u201cSubasta de Payasos\u201d y en el que capacita a quienes se dedican a este oficio, pero tambi\u00e9n a quienes quieran ejercerlo, como un preparativo al Congreso Nacional de Payasos que se realiza a\u00f1os tras a\u00f1o. Se espera la asistencia de cientos de payasos que igual vendr\u00e1n de otros estados de la rep\u00fablica pero tambi\u00e9n del extranjero Afirm\u00f3 que ser payasos no solo es llegar a la burla \u00f3 a la ofensa adem\u00e1s de no solo pintarse la cara sino maquillarse de manera [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2023\/impulsa-secretaria-de-turismo-subasta-de-payasos-en-el-centro-historico\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2023\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanalsiete\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-12T01:58:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2023\/07\/Claudio0Payasos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/impulsa-secretaria-de-turismo-subasta-de-payasos-en-el-centro-historico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/impulsa-secretaria-de-turismo-subasta-de-payasos-en-el-centro-historico\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#\\\/schema\\\/person\\\/639c424e3584069003b11ae813915da6\"},\"headline\":\"Impulsa Secretar\u00eda de Turismo \u00abSubasta de Payasos\u00bb en el Centro Hist\u00f3rico\",\"datePublished\":\"2023-07-12T01:58:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/impulsa-secretaria-de-turismo-subasta-de-payasos-en-el-centro-historico\\\/\"},\"wordCount\":230,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/impulsa-secretaria-de-turismo-subasta-de-payasos-en-el-centro-historico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Claudio0Payasos.jpg\",\"articleSection\":[\"DESTACADAS\",\"LOCALES Y REGIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/impulsa-secretaria-de-turismo-subasta-de-payasos-en-el-centro-historico\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/impulsa-secretaria-de-turismo-subasta-de-payasos-en-el-centro-historico\\\/\",\"name\":\"Impulsa Secretar\u00eda de Turismo \\\"Subasta de Payasos\\\" en el Centro Hist\u00f3rico - Canal 7 SLP - 2023\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/impulsa-secretaria-de-turismo-subasta-de-payasos-en-el-centro-historico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/impulsa-secretaria-de-turismo-subasta-de-payasos-en-el-centro-historico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Claudio0Payasos.jpg\",\"datePublished\":\"2023-07-12T01:58:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/impulsa-secretaria-de-turismo-subasta-de-payasos-en-el-centro-historico\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/impulsa-secretaria-de-turismo-subasta-de-payasos-en-el-centro-historico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/impulsa-secretaria-de-turismo-subasta-de-payasos-en-el-centro-historico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Claudio0Payasos.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Claudio0Payasos.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/impulsa-secretaria-de-turismo-subasta-de-payasos-en-el-centro-historico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Impulsa Secretar\u00eda de Turismo &#8220;Subasta de Payasos&#8221; en el Centro Hist\u00f3rico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanalsiete\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/#\\\/schema\\\/person\\\/639c424e3584069003b11ae813915da6\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2023\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Impulsa Secretar\u00eda de Turismo \"Subasta de Payasos\" en el Centro Hist\u00f3rico - Canal 7 SLP - 2023","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2023\/impulsa-secretaria-de-turismo-subasta-de-payasos-en-el-centro-historico\/","og_locale":"es_ES","og_type":"article","og_title":"Impulsa Secretar\u00eda de Turismo \"Subasta de Payasos\" en el Centro Hist\u00f3rico - Canal 7 SLP - 2023","og_description":"SLP.- Durante tres d\u00edas, del 24 al 27 de Julio la capital potosina ser\u00e1 sede del evento denominado \u201cSubasta de Payasos\u201d y en el que capacita a quienes se dedican a este oficio, pero tambi\u00e9n a quienes quieran ejercerlo, como un preparativo al Congreso Nacional de Payasos que se realiza a\u00f1os tras a\u00f1o. Se espera la asistencia de cientos de payasos que igual vendr\u00e1n de otros estados de la rep\u00fablica pero tambi\u00e9n del extranjero Afirm\u00f3 que ser payasos no solo es llegar a la burla \u00f3 a la ofensa adem\u00e1s de no solo pintarse la cara sino maquillarse de manera [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2023\/impulsa-secretaria-de-turismo-subasta-de-payasos-en-el-centro-historico\/","og_site_name":"Canal 7 SLP - 2023","article_publisher":"https:\/\/www.facebook.com\/noticieroscanalsiete","article_published_time":"2023-07-12T01:58:43+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2023\/07\/Claudio0Payasos.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2023\/impulsa-secretaria-de-turismo-subasta-de-payasos-en-el-centro-historico\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2023\/impulsa-secretaria-de-turismo-subasta-de-payasos-en-el-centro-historico\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2023\/#\/schema\/person\/639c424e3584069003b11ae813915da6"},"headline":"Impulsa Secretar\u00eda de Turismo \u00abSubasta de Payasos\u00bb en el Centro Hist\u00f3rico","datePublished":"2023-07-12T01:58:43+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2023\/impulsa-secretaria-de-turismo-subasta-de-payasos-en-el-centro-historico\/"},"wordCount":230,"publisher":{"@id":"https:\/\/canal7slp.tv\/2023\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2023\/impulsa-secretaria-de-turismo-subasta-de-payasos-en-el-centro-historico\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2023\/07\/Claudio0Payasos.jpg","articleSection":["DESTACADAS","LOCALES Y REGIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2023\/impulsa-secretaria-de-turismo-subasta-de-payasos-en-el-centro-historico\/","url":"https:\/\/canal7slp.tv\/2023\/impulsa-secretaria-de-turismo-subasta-de-payasos-en-el-centro-historico\/","name":"Impulsa Secretar\u00eda de Turismo \"Subasta de Payasos\" en el Centro Hist\u00f3rico - Canal 7 SLP - 2023","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2023\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2023\/impulsa-secretaria-de-turismo-subasta-de-payasos-en-el-centro-historico\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2023\/impulsa-secretaria-de-turismo-subasta-de-payasos-en-el-centro-historico\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2023\/07\/Claudio0Payasos.jpg","datePublished":"2023-07-12T01:58:43+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2023\/impulsa-secretaria-de-turismo-subasta-de-payasos-en-el-centro-historico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2023\/impulsa-secretaria-de-turismo-subasta-de-payasos-en-el-centro-historico\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2023\/impulsa-secretaria-de-turismo-subasta-de-payasos-en-el-centro-historico\/#primaryimage","url":"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2023\/07\/Claudio0Payasos.jpg","contentUrl":"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2023\/07\/Claudio0Payasos.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2023\/impulsa-secretaria-de-turismo-subasta-de-payasos-en-el-centro-historico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2023\/"},{"@type":"ListItem","position":2,"name":"Impulsa Secretar\u00eda de Turismo &#8220;Subasta de Payasos&#8221; en el Centro Hist\u00f3rico"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2023\/#website","url":"https:\/\/canal7slp.tv\/2023\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2023\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2023\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2023\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2023\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2023\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2023\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2023\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanalsiete","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2023\/#\/schema\/person\/639c424e3584069003b11ae813915da6","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2023\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/posts\/101040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/comments?post=101040"}],"version-history":[{"count":2,"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/posts\/101040\/revisions"}],"predecessor-version":[{"id":101074,"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/posts\/101040\/revisions\/101074"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/media\/101073"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/media?parent=101040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/categories?post=101040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2023\/wp-json\/wp\/v2\/tags?post=101040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}