{"id":81713,"date":"2022-12-21T17:06:35","date_gmt":"2022-12-21T23:06:35","guid":{"rendered":"https:\/\/canal7slp.tv\/2022\/?p=81713"},"modified":"2022-12-21T17:48:02","modified_gmt":"2022-12-21T23:48:02","slug":"irrumpen-ladrones-en-vivienda-y-golpean-a-mascotas-con-un-bate-de-beisbol-con-clavos","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2022\/irrumpen-ladrones-en-vivienda-y-golpean-a-mascotas-con-un-bate-de-beisbol-con-clavos\/","title":{"rendered":"Irrumpen ladrones en vivienda y golpean a mascotas con un bate de b\u00e9isbol con clavos"},"content":{"rendered":"<p>Rioverde.-<\/p>\n<p>Por: X\u00f3chitl Morales<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rioverde.- Por: X\u00f3chitl Morales<\/p>\n","protected":false},"author":2,"featured_media":81714,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"footnotes":""},"categories":[5,43],"tags":[],"class_list":["post-81713","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-destacadas","category-interior","post_format-post-format-video","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Irrumpen ladrones en vivienda y golpean a mascotas con un bate de b\u00e9isbol con clavos - Canal 7 SLP - 2022<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2022\/irrumpen-ladrones-en-vivienda-y-golpean-a-mascotas-con-un-bate-de-beisbol-con-clavos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Irrumpen ladrones en vivienda y golpean a mascotas con un bate de b\u00e9isbol con clavos - Canal 7 SLP - 2022\" \/>\n<meta property=\"og:description\" content=\"Rioverde.- Por: X\u00f3chitl Morales\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2022\/irrumpen-ladrones-en-vivienda-y-golpean-a-mascotas-con-un-bate-de-beisbol-con-clavos\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2022\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanalsiete\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-21T23:06:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-21T23:48:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/12\/Xochi01Mascotas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/irrumpen-ladrones-en-vivienda-y-golpean-a-mascotas-con-un-bate-de-beisbol-con-clavos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/irrumpen-ladrones-en-vivienda-y-golpean-a-mascotas-con-un-bate-de-beisbol-con-clavos\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/person\\\/429704152a21f5f856ce29aa69a238da\"},\"headline\":\"Irrumpen ladrones en vivienda y golpean a mascotas con un bate de b\u00e9isbol con clavos\",\"datePublished\":\"2022-12-21T23:06:35+00:00\",\"dateModified\":\"2022-12-21T23:48:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/irrumpen-ladrones-en-vivienda-y-golpean-a-mascotas-con-un-bate-de-beisbol-con-clavos\\\/\"},\"wordCount\":22,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/irrumpen-ladrones-en-vivienda-y-golpean-a-mascotas-con-un-bate-de-beisbol-con-clavos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Xochi01Mascotas.jpg\",\"articleSection\":[\"DESTACADAS\",\"INTERIOR DEL ESTADO\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/irrumpen-ladrones-en-vivienda-y-golpean-a-mascotas-con-un-bate-de-beisbol-con-clavos\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/irrumpen-ladrones-en-vivienda-y-golpean-a-mascotas-con-un-bate-de-beisbol-con-clavos\\\/\",\"name\":\"Irrumpen ladrones en vivienda y golpean a mascotas con un bate de b\u00e9isbol con clavos - Canal 7 SLP - 2022\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/irrumpen-ladrones-en-vivienda-y-golpean-a-mascotas-con-un-bate-de-beisbol-con-clavos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/irrumpen-ladrones-en-vivienda-y-golpean-a-mascotas-con-un-bate-de-beisbol-con-clavos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Xochi01Mascotas.jpg\",\"datePublished\":\"2022-12-21T23:06:35+00:00\",\"dateModified\":\"2022-12-21T23:48:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/irrumpen-ladrones-en-vivienda-y-golpean-a-mascotas-con-un-bate-de-beisbol-con-clavos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/irrumpen-ladrones-en-vivienda-y-golpean-a-mascotas-con-un-bate-de-beisbol-con-clavos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/irrumpen-ladrones-en-vivienda-y-golpean-a-mascotas-con-un-bate-de-beisbol-con-clavos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Xochi01Mascotas.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Xochi01Mascotas.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/irrumpen-ladrones-en-vivienda-y-golpean-a-mascotas-con-un-bate-de-beisbol-con-clavos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Irrumpen ladrones en vivienda y golpean a mascotas con un bate de b\u00e9isbol con clavos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanalsiete\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/person\\\/429704152a21f5f856ce29aa69a238da\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Irrumpen ladrones en vivienda y golpean a mascotas con un bate de b\u00e9isbol con clavos - Canal 7 SLP - 2022","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2022\/irrumpen-ladrones-en-vivienda-y-golpean-a-mascotas-con-un-bate-de-beisbol-con-clavos\/","og_locale":"es_ES","og_type":"article","og_title":"Irrumpen ladrones en vivienda y golpean a mascotas con un bate de b\u00e9isbol con clavos - Canal 7 SLP - 2022","og_description":"Rioverde.- Por: X\u00f3chitl Morales","og_url":"https:\/\/canal7slp.tv\/2022\/irrumpen-ladrones-en-vivienda-y-golpean-a-mascotas-con-un-bate-de-beisbol-con-clavos\/","og_site_name":"Canal 7 SLP - 2022","article_publisher":"https:\/\/www.facebook.com\/noticieroscanalsiete","article_published_time":"2022-12-21T23:06:35+00:00","article_modified_time":"2022-12-21T23:48:02+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/12\/Xochi01Mascotas.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2022\/irrumpen-ladrones-en-vivienda-y-golpean-a-mascotas-con-un-bate-de-beisbol-con-clavos\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2022\/irrumpen-ladrones-en-vivienda-y-golpean-a-mascotas-con-un-bate-de-beisbol-con-clavos\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/person\/429704152a21f5f856ce29aa69a238da"},"headline":"Irrumpen ladrones en vivienda y golpean a mascotas con un bate de b\u00e9isbol con clavos","datePublished":"2022-12-21T23:06:35+00:00","dateModified":"2022-12-21T23:48:02+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2022\/irrumpen-ladrones-en-vivienda-y-golpean-a-mascotas-con-un-bate-de-beisbol-con-clavos\/"},"wordCount":22,"publisher":{"@id":"https:\/\/canal7slp.tv\/2022\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2022\/irrumpen-ladrones-en-vivienda-y-golpean-a-mascotas-con-un-bate-de-beisbol-con-clavos\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/12\/Xochi01Mascotas.jpg","articleSection":["DESTACADAS","INTERIOR DEL ESTADO"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2022\/irrumpen-ladrones-en-vivienda-y-golpean-a-mascotas-con-un-bate-de-beisbol-con-clavos\/","url":"https:\/\/canal7slp.tv\/2022\/irrumpen-ladrones-en-vivienda-y-golpean-a-mascotas-con-un-bate-de-beisbol-con-clavos\/","name":"Irrumpen ladrones en vivienda y golpean a mascotas con un bate de b\u00e9isbol con clavos - Canal 7 SLP - 2022","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2022\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2022\/irrumpen-ladrones-en-vivienda-y-golpean-a-mascotas-con-un-bate-de-beisbol-con-clavos\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2022\/irrumpen-ladrones-en-vivienda-y-golpean-a-mascotas-con-un-bate-de-beisbol-con-clavos\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/12\/Xochi01Mascotas.jpg","datePublished":"2022-12-21T23:06:35+00:00","dateModified":"2022-12-21T23:48:02+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2022\/irrumpen-ladrones-en-vivienda-y-golpean-a-mascotas-con-un-bate-de-beisbol-con-clavos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2022\/irrumpen-ladrones-en-vivienda-y-golpean-a-mascotas-con-un-bate-de-beisbol-con-clavos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2022\/irrumpen-ladrones-en-vivienda-y-golpean-a-mascotas-con-un-bate-de-beisbol-con-clavos\/#primaryimage","url":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/12\/Xochi01Mascotas.jpg","contentUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/12\/Xochi01Mascotas.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2022\/irrumpen-ladrones-en-vivienda-y-golpean-a-mascotas-con-un-bate-de-beisbol-con-clavos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2022\/"},{"@type":"ListItem","position":2,"name":"Irrumpen ladrones en vivienda y golpean a mascotas con un bate de b\u00e9isbol con clavos"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2022\/#website","url":"https:\/\/canal7slp.tv\/2022\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2022\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2022\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2022\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2022\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanalsiete","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/person\/429704152a21f5f856ce29aa69a238da","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2022\/author\/edicionweb\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts\/81713","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/comments?post=81713"}],"version-history":[{"count":3,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts\/81713\/revisions"}],"predecessor-version":[{"id":81733,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts\/81713\/revisions\/81733"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/media\/81714"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/media?parent=81713"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/categories?post=81713"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/tags?post=81713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}