{"id":80699,"date":"2022-12-09T14:08:11","date_gmt":"2022-12-09T20:08:11","guid":{"rendered":"https:\/\/canal7slp.tv\/2022\/?p=80699"},"modified":"2022-12-09T14:08:11","modified_gmt":"2022-12-09T20:08:11","slug":"atletico-de-san-luis-cae-ante-deportivo-moron-en-argentina-en-partido-de-pretemporada","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2022\/atletico-de-san-luis-cae-ante-deportivo-moron-en-argentina-en-partido-de-pretemporada\/","title":{"rendered":"Atl\u00e9tico de San Luis cae ante Deportivo Moro\u0301n en Argentina en partido de pretemporada"},"content":{"rendered":"<p style=\"text-align: justify;\">SLP.- Como parte de su pretemporada por Argentina Atl\u00e9tico de San Luis se enfrento al Deportivo Moro\u0301n.<\/p>\n<p style=\"text-align: justify;\">Al minuto 2, Gasto\u0301n Gonza\u0301lez tomo\u0301 la pelota fuera del \u00e1rea y con un potente disparo, anoto\u0301 el primer gol del partido dejando a Barovero sin oportunidad. Al 15\u2019, Bayk se fue al frente y remato\u0301 con fuerza mandando la pelota por arriba del arco de Barovero.<\/p>\n<p style=\"text-align: justify;\">Al 21\u2019, Atl\u00e9tico de San Luis tuvo la m\u00e1s clara cuando Dieter Villalpando robo\u0301 el esf\u00e9rico para asistir a Jhon Murillo quien en el \u00e1rea, intento\u0301 empatar el partido con un tiro cruzado que se fue por un costado de la porter\u00eda.<\/p>\n<p style=\"text-align: justify;\">Al 45\u2019, nuevamente los potosinos lo intentaron siendo Sabin Merino quien disparo\u0301 desde fuera del \u00e1rea obligando al arquero Galv\u00e1n a mandar la pelota al tiro de esquina.<\/p>\n<p style=\"text-align: justify;\">Un minuto m\u00e1s tarde, apareci\u00f3\u0301 Jhon Murillo con un tiro que se estrello\u0301 en las manos del guardameta.<\/p>\n<p style=\"text-align: justify;\">En el segundo tiempo, la primera fue para el Deportivo Moro\u0301n con Tob\u00edas Zarate quien mando\u0301 un potente cabezazo que se fue por un costado.<\/p>\n<p style=\"text-align: justify;\">Al 81 \u0301, Facundo L\u00f3pez cobro\u0301 un tiro libre que fue directo al arco y David Ochoa apareci\u00f3\u0301 para evitar el peligro.<\/p>\n<p style=\"text-align: justify;\">En los minutos finales, al 91 \u0301, Gonzalo Salega marco\u0301 el segundo gol del encuentro cuando tras un pase de Gonzalo Berterame, se encontr\u00f3\u0301 solo frente al portero Ochoa y no perdono\u0301.<\/p>\n<p style=\"text-align: justify;\">De esta manera, Deportivo Moro\u0301n se quedo\u0301 con la Copa de la Amistad Internacional.<\/p>\n<p style=\"text-align: justify;\">Por otra parte el cuadro potosino ha realizado un cambio en su itinerario y es que este domingo 11 de diciembre en punto de las 7:00 am, Atl\u00e9tico de San Luis se enfrentar\u00e1 a las reservas de Atl\u00e9tico de Lan\u00fas en el Centro Alto rendimiento.<\/p>\n<p style=\"text-align: justify;\">Atl\u00e9tico Lan\u00fas se ha destacado por grandes jugadores que han pasado por el equipo de reservas, siendo algunos de estos Eduardo Salvio, Carlos Izquierdos, Gustavo G\u00f3mez, Lautaro Acosta, Guido Pizarro y Agust\u00edn Marches\u00edn<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SLP.- Como parte de su pretemporada por Argentina Atl\u00e9tico de San Luis se enfrento al Deportivo Moro\u0301n. Al minuto 2, Gasto\u0301n Gonza\u0301lez tomo\u0301 la pelota fuera del \u00e1rea y con un potente disparo, anoto\u0301 el primer gol del partido dejando a Barovero sin oportunidad. Al 15\u2019, Bayk se fue al frente y remato\u0301 con fuerza mandando la pelota por arriba del arco de Barovero. Al 21\u2019, Atl\u00e9tico de San Luis tuvo la m\u00e1s clara cuando Dieter Villalpando robo\u0301 el esf\u00e9rico para asistir a Jhon Murillo quien en el \u00e1rea, intento\u0301 empatar el partido con un tiro cruzado que se fue [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":80706,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"footnotes":""},"categories":[7,5],"tags":[],"class_list":["post-80699","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-deportes","category-destacadas","post_format-post-format-video","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Atl\u00e9tico de San Luis cae ante Deportivo Moro\u0301n en Argentina en partido de pretemporada - Canal 7 SLP - 2022<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2022\/atletico-de-san-luis-cae-ante-deportivo-moron-en-argentina-en-partido-de-pretemporada\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Atl\u00e9tico de San Luis cae ante Deportivo Moro\u0301n en Argentina en partido de pretemporada - Canal 7 SLP - 2022\" \/>\n<meta property=\"og:description\" content=\"SLP.- Como parte de su pretemporada por Argentina Atl\u00e9tico de San Luis se enfrento al Deportivo Moro\u0301n. Al minuto 2, Gasto\u0301n Gonza\u0301lez tomo\u0301 la pelota fuera del \u00e1rea y con un potente disparo, anoto\u0301 el primer gol del partido dejando a Barovero sin oportunidad. Al 15\u2019, Bayk se fue al frente y remato\u0301 con fuerza mandando la pelota por arriba del arco de Barovero. Al 21\u2019, Atl\u00e9tico de San Luis tuvo la m\u00e1s clara cuando Dieter Villalpando robo\u0301 el esf\u00e9rico para asistir a Jhon Murillo quien en el \u00e1rea, intento\u0301 empatar el partido con un tiro cruzado que se fue [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2022\/atletico-de-san-luis-cae-ante-deportivo-moron-en-argentina-en-partido-de-pretemporada\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2022\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanalsiete\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-09T20:08:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/12\/Froi01Atletico-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"888\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/atletico-de-san-luis-cae-ante-deportivo-moron-en-argentina-en-partido-de-pretemporada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/atletico-de-san-luis-cae-ante-deportivo-moron-en-argentina-en-partido-de-pretemporada\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/person\\\/429704152a21f5f856ce29aa69a238da\"},\"headline\":\"Atl\u00e9tico de San Luis cae ante Deportivo Moro\u0301n en Argentina en partido de pretemporada\",\"datePublished\":\"2022-12-09T20:08:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/atletico-de-san-luis-cae-ante-deportivo-moron-en-argentina-en-partido-de-pretemporada\\\/\"},\"wordCount\":352,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/atletico-de-san-luis-cae-ante-deportivo-moron-en-argentina-en-partido-de-pretemporada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Froi01Atletico-1.jpg\",\"articleSection\":[\"DEPORTES\",\"DESTACADAS\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/atletico-de-san-luis-cae-ante-deportivo-moron-en-argentina-en-partido-de-pretemporada\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/atletico-de-san-luis-cae-ante-deportivo-moron-en-argentina-en-partido-de-pretemporada\\\/\",\"name\":\"Atl\u00e9tico de San Luis cae ante Deportivo Moro\u0301n en Argentina en partido de pretemporada - Canal 7 SLP - 2022\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/atletico-de-san-luis-cae-ante-deportivo-moron-en-argentina-en-partido-de-pretemporada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/atletico-de-san-luis-cae-ante-deportivo-moron-en-argentina-en-partido-de-pretemporada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Froi01Atletico-1.jpg\",\"datePublished\":\"2022-12-09T20:08:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/atletico-de-san-luis-cae-ante-deportivo-moron-en-argentina-en-partido-de-pretemporada\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/atletico-de-san-luis-cae-ante-deportivo-moron-en-argentina-en-partido-de-pretemporada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/atletico-de-san-luis-cae-ante-deportivo-moron-en-argentina-en-partido-de-pretemporada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Froi01Atletico-1.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Froi01Atletico-1.jpg\",\"width\":888,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/atletico-de-san-luis-cae-ante-deportivo-moron-en-argentina-en-partido-de-pretemporada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Atl\u00e9tico de San Luis cae ante Deportivo Moro\u0301n en Argentina en partido de pretemporada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanalsiete\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/person\\\/429704152a21f5f856ce29aa69a238da\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Atl\u00e9tico de San Luis cae ante Deportivo Moro\u0301n en Argentina en partido de pretemporada - Canal 7 SLP - 2022","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2022\/atletico-de-san-luis-cae-ante-deportivo-moron-en-argentina-en-partido-de-pretemporada\/","og_locale":"es_ES","og_type":"article","og_title":"Atl\u00e9tico de San Luis cae ante Deportivo Moro\u0301n en Argentina en partido de pretemporada - Canal 7 SLP - 2022","og_description":"SLP.- Como parte de su pretemporada por Argentina Atl\u00e9tico de San Luis se enfrento al Deportivo Moro\u0301n. Al minuto 2, Gasto\u0301n Gonza\u0301lez tomo\u0301 la pelota fuera del \u00e1rea y con un potente disparo, anoto\u0301 el primer gol del partido dejando a Barovero sin oportunidad. Al 15\u2019, Bayk se fue al frente y remato\u0301 con fuerza mandando la pelota por arriba del arco de Barovero. Al 21\u2019, Atl\u00e9tico de San Luis tuvo la m\u00e1s clara cuando Dieter Villalpando robo\u0301 el esf\u00e9rico para asistir a Jhon Murillo quien en el \u00e1rea, intento\u0301 empatar el partido con un tiro cruzado que se fue [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2022\/atletico-de-san-luis-cae-ante-deportivo-moron-en-argentina-en-partido-de-pretemporada\/","og_site_name":"Canal 7 SLP - 2022","article_publisher":"https:\/\/www.facebook.com\/noticieroscanalsiete","article_published_time":"2022-12-09T20:08:11+00:00","og_image":[{"width":888,"height":500,"url":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/12\/Froi01Atletico-1.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2022\/atletico-de-san-luis-cae-ante-deportivo-moron-en-argentina-en-partido-de-pretemporada\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2022\/atletico-de-san-luis-cae-ante-deportivo-moron-en-argentina-en-partido-de-pretemporada\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/person\/429704152a21f5f856ce29aa69a238da"},"headline":"Atl\u00e9tico de San Luis cae ante Deportivo Moro\u0301n en Argentina en partido de pretemporada","datePublished":"2022-12-09T20:08:11+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2022\/atletico-de-san-luis-cae-ante-deportivo-moron-en-argentina-en-partido-de-pretemporada\/"},"wordCount":352,"publisher":{"@id":"https:\/\/canal7slp.tv\/2022\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2022\/atletico-de-san-luis-cae-ante-deportivo-moron-en-argentina-en-partido-de-pretemporada\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/12\/Froi01Atletico-1.jpg","articleSection":["DEPORTES","DESTACADAS"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2022\/atletico-de-san-luis-cae-ante-deportivo-moron-en-argentina-en-partido-de-pretemporada\/","url":"https:\/\/canal7slp.tv\/2022\/atletico-de-san-luis-cae-ante-deportivo-moron-en-argentina-en-partido-de-pretemporada\/","name":"Atl\u00e9tico de San Luis cae ante Deportivo Moro\u0301n en Argentina en partido de pretemporada - Canal 7 SLP - 2022","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2022\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2022\/atletico-de-san-luis-cae-ante-deportivo-moron-en-argentina-en-partido-de-pretemporada\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2022\/atletico-de-san-luis-cae-ante-deportivo-moron-en-argentina-en-partido-de-pretemporada\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/12\/Froi01Atletico-1.jpg","datePublished":"2022-12-09T20:08:11+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2022\/atletico-de-san-luis-cae-ante-deportivo-moron-en-argentina-en-partido-de-pretemporada\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2022\/atletico-de-san-luis-cae-ante-deportivo-moron-en-argentina-en-partido-de-pretemporada\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2022\/atletico-de-san-luis-cae-ante-deportivo-moron-en-argentina-en-partido-de-pretemporada\/#primaryimage","url":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/12\/Froi01Atletico-1.jpg","contentUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/12\/Froi01Atletico-1.jpg","width":888,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2022\/atletico-de-san-luis-cae-ante-deportivo-moron-en-argentina-en-partido-de-pretemporada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2022\/"},{"@type":"ListItem","position":2,"name":"Atl\u00e9tico de San Luis cae ante Deportivo Moro\u0301n en Argentina en partido de pretemporada"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2022\/#website","url":"https:\/\/canal7slp.tv\/2022\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2022\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2022\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2022\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2022\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanalsiete","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/person\/429704152a21f5f856ce29aa69a238da","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2022\/author\/edicionweb\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts\/80699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/comments?post=80699"}],"version-history":[{"count":3,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts\/80699\/revisions"}],"predecessor-version":[{"id":80708,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts\/80699\/revisions\/80708"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/media\/80706"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/media?parent=80699"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/categories?post=80699"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/tags?post=80699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}