{"id":79347,"date":"2022-11-24T19:33:33","date_gmt":"2022-11-25T01:33:33","guid":{"rendered":"https:\/\/canal7slp.tv\/2022\/?p=79347"},"modified":"2022-11-24T19:33:33","modified_gmt":"2022-11-25T01:33:33","slug":"con-mayor-presupuesto-considera-gobernador-que-en-real-de-catorce-podrian-resolverse-problemas-arrastrados-durante-anos","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2022\/con-mayor-presupuesto-considera-gobernador-que-en-real-de-catorce-podrian-resolverse-problemas-arrastrados-durante-anos\/","title":{"rendered":"Con mayor presupuesto, considera gobernador que en Real de Catorce podr\u00edan resolverse problemas arrastrados durante a\u00f1os."},"content":{"rendered":"<p style=\"text-align: justify;\">Real de Catorce.-\u00a0 En entrevista, el Gobernador del Estado, Ricardo Gallardo Cardona, fue cuestionado en torno a las problem\u00e1ticas que se han suscitado en el municipio de Catorce, donde se ha se\u00f1alado una falta de servicio m\u00e9dico y presuntos abusos policiacos por parte de la seguridad p\u00fablica municipal.<\/p>\n<p style=\"text-align: justify;\">\u201cYa platiqu\u00e9 con la Presidenta para que puedan atender eso, nosotros ya nos comprometimos a darle m\u00e1s presupuesto a Real de Catorce, un 18 por ciento, para que puedan hacerle frente a las obligaciones que tienen como municipios, si bien es cierto, es un municipio que ha recibido muy poco dinero, en esta administraci\u00f3n, en dos a\u00f1os ha recibido un 25 por ciento a la participaci\u00f3n, es un incremento muy importante que le puede hacer frente a muchas obligaciones que hoy no est\u00e1n atendi\u00e9ndose como es el tema m\u00e9dico y el transporte local que tienen ellos\u201d, dijo.<\/p>\n<p style=\"text-align: justify;\">Para el Gobernador del Estado, las problem\u00e1ticas de Catorce se vienen arrastrando desde anteriores administraciones, \u201cno bueno, no vamos a poder hablar de desatenciones por parte del municipio, creo que es un vicio de muchos a\u00f1os, que se tiene que corregir y que nosotros tenemos que abonar a que se corrija\u201d.<\/p>\n<p style=\"text-align: justify;\">Gallardo Cardona se pronunci\u00f3 sobre los problemas de seguridad que han ocurrido en el municipio de Guadalc\u00e1zar, en el altiplano potosino, \u201cestamos metidos todos, fuerza federal, estatal y municipal, se dej\u00f3 ah\u00ed crecer mucho la delincuencia en ese municipio, sin embargo, hemos tenido intervenciones importantes, vamos a seguir, no nos vamos a ir hasta que Guadalc\u00e1zar quede limpio\u201d.<\/p>\n<p>Por: Jes\u00fas Valencia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Real de Catorce.-\u00a0 En entrevista, el Gobernador del Estado, Ricardo Gallardo Cardona, fue cuestionado en torno a las problem\u00e1ticas que se han suscitado en el municipio de Catorce, donde se ha se\u00f1alado una falta de servicio m\u00e9dico y presuntos abusos policiacos por parte de la seguridad p\u00fablica municipal. \u201cYa platiqu\u00e9 con la Presidenta para que puedan atender eso, nosotros ya nos comprometimos a darle m\u00e1s presupuesto a Real de Catorce, un 18 por ciento, para que puedan hacerle frente a las obligaciones que tienen como municipios, si bien es cierto, es un municipio que ha recibido muy poco dinero, en [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":79348,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"footnotes":""},"categories":[5,510,43],"tags":[],"class_list":["post-79347","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-destacadas","category-gobedoslp","category-interior","post_format-post-format-video","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Con mayor presupuesto, considera gobernador que en Real de Catorce podr\u00edan resolverse problemas arrastrados durante a\u00f1os. - Canal 7 SLP - 2022<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2022\/con-mayor-presupuesto-considera-gobernador-que-en-real-de-catorce-podrian-resolverse-problemas-arrastrados-durante-anos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Con mayor presupuesto, considera gobernador que en Real de Catorce podr\u00edan resolverse problemas arrastrados durante a\u00f1os. - Canal 7 SLP - 2022\" \/>\n<meta property=\"og:description\" content=\"Real de Catorce.-\u00a0 En entrevista, el Gobernador del Estado, Ricardo Gallardo Cardona, fue cuestionado en torno a las problem\u00e1ticas que se han suscitado en el municipio de Catorce, donde se ha se\u00f1alado una falta de servicio m\u00e9dico y presuntos abusos policiacos por parte de la seguridad p\u00fablica municipal. \u201cYa platiqu\u00e9 con la Presidenta para que puedan atender eso, nosotros ya nos comprometimos a darle m\u00e1s presupuesto a Real de Catorce, un 18 por ciento, para que puedan hacerle frente a las obligaciones que tienen como municipios, si bien es cierto, es un municipio que ha recibido muy poco dinero, en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2022\/con-mayor-presupuesto-considera-gobernador-que-en-real-de-catorce-podrian-resolverse-problemas-arrastrados-durante-anos\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2022\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanalsiete\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-25T01:33:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/11\/Valencia01CatorceProblemas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"909\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/con-mayor-presupuesto-considera-gobernador-que-en-real-de-catorce-podrian-resolverse-problemas-arrastrados-durante-anos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/con-mayor-presupuesto-considera-gobernador-que-en-real-de-catorce-podrian-resolverse-problemas-arrastrados-durante-anos\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/person\\\/429704152a21f5f856ce29aa69a238da\"},\"headline\":\"Con mayor presupuesto, considera gobernador que en Real de Catorce podr\u00edan resolverse problemas arrastrados durante a\u00f1os.\",\"datePublished\":\"2022-11-25T01:33:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/con-mayor-presupuesto-considera-gobernador-que-en-real-de-catorce-podrian-resolverse-problemas-arrastrados-durante-anos\\\/\"},\"wordCount\":290,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/con-mayor-presupuesto-considera-gobernador-que-en-real-de-catorce-podrian-resolverse-problemas-arrastrados-durante-anos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Valencia01CatorceProblemas.jpg\",\"articleSection\":[\"DESTACADAS\",\"GOBEDOSLP\",\"INTERIOR DEL ESTADO\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/con-mayor-presupuesto-considera-gobernador-que-en-real-de-catorce-podrian-resolverse-problemas-arrastrados-durante-anos\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/con-mayor-presupuesto-considera-gobernador-que-en-real-de-catorce-podrian-resolverse-problemas-arrastrados-durante-anos\\\/\",\"name\":\"Con mayor presupuesto, considera gobernador que en Real de Catorce podr\u00edan resolverse problemas arrastrados durante a\u00f1os. - Canal 7 SLP - 2022\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/con-mayor-presupuesto-considera-gobernador-que-en-real-de-catorce-podrian-resolverse-problemas-arrastrados-durante-anos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/con-mayor-presupuesto-considera-gobernador-que-en-real-de-catorce-podrian-resolverse-problemas-arrastrados-durante-anos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Valencia01CatorceProblemas.jpg\",\"datePublished\":\"2022-11-25T01:33:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/con-mayor-presupuesto-considera-gobernador-que-en-real-de-catorce-podrian-resolverse-problemas-arrastrados-durante-anos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/con-mayor-presupuesto-considera-gobernador-que-en-real-de-catorce-podrian-resolverse-problemas-arrastrados-durante-anos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/con-mayor-presupuesto-considera-gobernador-que-en-real-de-catorce-podrian-resolverse-problemas-arrastrados-durante-anos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Valencia01CatorceProblemas.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Valencia01CatorceProblemas.jpg\",\"width\":909,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/con-mayor-presupuesto-considera-gobernador-que-en-real-de-catorce-podrian-resolverse-problemas-arrastrados-durante-anos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Con mayor presupuesto, considera gobernador que en Real de Catorce podr\u00edan resolverse problemas arrastrados durante a\u00f1os.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanalsiete\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/person\\\/429704152a21f5f856ce29aa69a238da\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Con mayor presupuesto, considera gobernador que en Real de Catorce podr\u00edan resolverse problemas arrastrados durante a\u00f1os. - Canal 7 SLP - 2022","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2022\/con-mayor-presupuesto-considera-gobernador-que-en-real-de-catorce-podrian-resolverse-problemas-arrastrados-durante-anos\/","og_locale":"es_ES","og_type":"article","og_title":"Con mayor presupuesto, considera gobernador que en Real de Catorce podr\u00edan resolverse problemas arrastrados durante a\u00f1os. - Canal 7 SLP - 2022","og_description":"Real de Catorce.-\u00a0 En entrevista, el Gobernador del Estado, Ricardo Gallardo Cardona, fue cuestionado en torno a las problem\u00e1ticas que se han suscitado en el municipio de Catorce, donde se ha se\u00f1alado una falta de servicio m\u00e9dico y presuntos abusos policiacos por parte de la seguridad p\u00fablica municipal. \u201cYa platiqu\u00e9 con la Presidenta para que puedan atender eso, nosotros ya nos comprometimos a darle m\u00e1s presupuesto a Real de Catorce, un 18 por ciento, para que puedan hacerle frente a las obligaciones que tienen como municipios, si bien es cierto, es un municipio que ha recibido muy poco dinero, en [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2022\/con-mayor-presupuesto-considera-gobernador-que-en-real-de-catorce-podrian-resolverse-problemas-arrastrados-durante-anos\/","og_site_name":"Canal 7 SLP - 2022","article_publisher":"https:\/\/www.facebook.com\/noticieroscanalsiete","article_published_time":"2022-11-25T01:33:33+00:00","og_image":[{"width":909,"height":500,"url":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/11\/Valencia01CatorceProblemas.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2022\/con-mayor-presupuesto-considera-gobernador-que-en-real-de-catorce-podrian-resolverse-problemas-arrastrados-durante-anos\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2022\/con-mayor-presupuesto-considera-gobernador-que-en-real-de-catorce-podrian-resolverse-problemas-arrastrados-durante-anos\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/person\/429704152a21f5f856ce29aa69a238da"},"headline":"Con mayor presupuesto, considera gobernador que en Real de Catorce podr\u00edan resolverse problemas arrastrados durante a\u00f1os.","datePublished":"2022-11-25T01:33:33+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2022\/con-mayor-presupuesto-considera-gobernador-que-en-real-de-catorce-podrian-resolverse-problemas-arrastrados-durante-anos\/"},"wordCount":290,"publisher":{"@id":"https:\/\/canal7slp.tv\/2022\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2022\/con-mayor-presupuesto-considera-gobernador-que-en-real-de-catorce-podrian-resolverse-problemas-arrastrados-durante-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/11\/Valencia01CatorceProblemas.jpg","articleSection":["DESTACADAS","GOBEDOSLP","INTERIOR DEL ESTADO"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2022\/con-mayor-presupuesto-considera-gobernador-que-en-real-de-catorce-podrian-resolverse-problemas-arrastrados-durante-anos\/","url":"https:\/\/canal7slp.tv\/2022\/con-mayor-presupuesto-considera-gobernador-que-en-real-de-catorce-podrian-resolverse-problemas-arrastrados-durante-anos\/","name":"Con mayor presupuesto, considera gobernador que en Real de Catorce podr\u00edan resolverse problemas arrastrados durante a\u00f1os. - Canal 7 SLP - 2022","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2022\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2022\/con-mayor-presupuesto-considera-gobernador-que-en-real-de-catorce-podrian-resolverse-problemas-arrastrados-durante-anos\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2022\/con-mayor-presupuesto-considera-gobernador-que-en-real-de-catorce-podrian-resolverse-problemas-arrastrados-durante-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/11\/Valencia01CatorceProblemas.jpg","datePublished":"2022-11-25T01:33:33+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2022\/con-mayor-presupuesto-considera-gobernador-que-en-real-de-catorce-podrian-resolverse-problemas-arrastrados-durante-anos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2022\/con-mayor-presupuesto-considera-gobernador-que-en-real-de-catorce-podrian-resolverse-problemas-arrastrados-durante-anos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2022\/con-mayor-presupuesto-considera-gobernador-que-en-real-de-catorce-podrian-resolverse-problemas-arrastrados-durante-anos\/#primaryimage","url":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/11\/Valencia01CatorceProblemas.jpg","contentUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/11\/Valencia01CatorceProblemas.jpg","width":909,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2022\/con-mayor-presupuesto-considera-gobernador-que-en-real-de-catorce-podrian-resolverse-problemas-arrastrados-durante-anos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2022\/"},{"@type":"ListItem","position":2,"name":"Con mayor presupuesto, considera gobernador que en Real de Catorce podr\u00edan resolverse problemas arrastrados durante a\u00f1os."}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2022\/#website","url":"https:\/\/canal7slp.tv\/2022\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2022\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2022\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2022\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2022\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanalsiete","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/person\/429704152a21f5f856ce29aa69a238da","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2022\/author\/edicionweb\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts\/79347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/comments?post=79347"}],"version-history":[{"count":1,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts\/79347\/revisions"}],"predecessor-version":[{"id":79349,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts\/79347\/revisions\/79349"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/media\/79348"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/media?parent=79347"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/categories?post=79347"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/tags?post=79347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}