{"id":79075,"date":"2022-11-22T16:42:36","date_gmt":"2022-11-22T22:42:36","guid":{"rendered":"https:\/\/canal7slp.tv\/2022\/?p=79075"},"modified":"2022-11-22T16:42:36","modified_gmt":"2022-11-22T22:42:36","slug":"al-alza-homicidios-dolosos-en-mexico","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2022\/al-alza-homicidios-dolosos-en-mexico\/","title":{"rendered":"Al alza homicidios dolosos en M\u00e9xico"},"content":{"rendered":"<ul style=\"text-align: justify;\">\n<li>Promedio anual sube 2.29%<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">M\u00e9xico.- El n\u00famero de homicidios dolosos en M\u00e9xico increment\u00f3 un 2.29 por ciento anual en el mes de octubre pasado, con lo que alcanz\u00f3 los 2 mil 766 asesinatos y se convierte en el segundo mes m\u00e1s violento de 2022 hasta ahora, as\u00ed lo inform\u00f3 este martes la Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana (SSPC).<\/p>\n<p style=\"text-align: justify;\">De acuerdo con los datos del pasado mes de octubre se comparan con los 2 mil 704 homicidios del mismo mes de 2021, y tambi\u00e9n implican un incremento mensual del 4.57 por ciento frente a los 2 mil 645 asesinatos de septiembre pasado.<\/p>\n<p style=\"text-align: justify;\">Los homicidios registrados en octubre se encuentran s\u00f3lo por debajo de los 2 mil 827 reportados en mayo pasado, el mes con m\u00e1s v\u00edctimas en lo que va de 2022, esto de acuerdo con la informaci\u00f3n que exhibi\u00f3 Rosa Icela Rodr\u00edguez, secretaria de Seguridad y Protecci\u00f3n Ciudadana, en la \u201cma\u00f1anera\u201d de este martes desde Palacio Nacional.<\/p>\n<p style=\"text-align: justify;\">Con estas cifras, se contabiliz\u00f3 un total de 26 mil 119 v\u00edctimas de asesinato, una media de 86 diarias, en los primeros 10 meses de 2022, una disminuci\u00f3n de 7.1 por ciento frente al periodo de enero a octubre de 2021, cuando se registraron 28 mil 110, un promedio diario de 92.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Promedio anual sube 2.29% M\u00e9xico.- El n\u00famero de homicidios dolosos en M\u00e9xico increment\u00f3 un 2.29 por ciento anual en el mes de octubre pasado, con lo que alcanz\u00f3 los 2 mil 766 asesinatos y se convierte en el segundo mes m\u00e1s violento de 2022 hasta ahora, as\u00ed lo inform\u00f3 este martes la Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana (SSPC). De acuerdo con los datos del pasado mes de octubre se comparan con los 2 mil 704 homicidios del mismo mes de 2021, y tambi\u00e9n implican un incremento mensual del 4.57 por ciento frente a los 2 mil 645 asesinatos de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":79087,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[],"class_list":["post-79075","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Al alza homicidios dolosos en M\u00e9xico - Canal 7 SLP - 2022<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2022\/al-alza-homicidios-dolosos-en-mexico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Al alza homicidios dolosos en M\u00e9xico - Canal 7 SLP - 2022\" \/>\n<meta property=\"og:description\" content=\"Promedio anual sube 2.29% M\u00e9xico.- El n\u00famero de homicidios dolosos en M\u00e9xico increment\u00f3 un 2.29 por ciento anual en el mes de octubre pasado, con lo que alcanz\u00f3 los 2 mil 766 asesinatos y se convierte en el segundo mes m\u00e1s violento de 2022 hasta ahora, as\u00ed lo inform\u00f3 este martes la Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana (SSPC). De acuerdo con los datos del pasado mes de octubre se comparan con los 2 mil 704 homicidios del mismo mes de 2021, y tambi\u00e9n implican un incremento mensual del 4.57 por ciento frente a los 2 mil 645 asesinatos de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2022\/al-alza-homicidios-dolosos-en-mexico\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2022\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanalsiete\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-22T22:42:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/11\/01-19.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/al-alza-homicidios-dolosos-en-mexico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/al-alza-homicidios-dolosos-en-mexico\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/person\\\/429704152a21f5f856ce29aa69a238da\"},\"headline\":\"Al alza homicidios dolosos en M\u00e9xico\",\"datePublished\":\"2022-11-22T22:42:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/al-alza-homicidios-dolosos-en-mexico\\\/\"},\"wordCount\":210,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/al-alza-homicidios-dolosos-en-mexico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/01-19.jpg\",\"articleSection\":[\"NACIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/al-alza-homicidios-dolosos-en-mexico\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/al-alza-homicidios-dolosos-en-mexico\\\/\",\"name\":\"Al alza homicidios dolosos en M\u00e9xico - Canal 7 SLP - 2022\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/al-alza-homicidios-dolosos-en-mexico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/al-alza-homicidios-dolosos-en-mexico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/01-19.jpg\",\"datePublished\":\"2022-11-22T22:42:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/al-alza-homicidios-dolosos-en-mexico\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/al-alza-homicidios-dolosos-en-mexico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/al-alza-homicidios-dolosos-en-mexico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/01-19.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/01-19.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/al-alza-homicidios-dolosos-en-mexico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Al alza homicidios dolosos en M\u00e9xico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanalsiete\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/person\\\/429704152a21f5f856ce29aa69a238da\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Al alza homicidios dolosos en M\u00e9xico - Canal 7 SLP - 2022","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2022\/al-alza-homicidios-dolosos-en-mexico\/","og_locale":"es_ES","og_type":"article","og_title":"Al alza homicidios dolosos en M\u00e9xico - Canal 7 SLP - 2022","og_description":"Promedio anual sube 2.29% M\u00e9xico.- El n\u00famero de homicidios dolosos en M\u00e9xico increment\u00f3 un 2.29 por ciento anual en el mes de octubre pasado, con lo que alcanz\u00f3 los 2 mil 766 asesinatos y se convierte en el segundo mes m\u00e1s violento de 2022 hasta ahora, as\u00ed lo inform\u00f3 este martes la Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana (SSPC). De acuerdo con los datos del pasado mes de octubre se comparan con los 2 mil 704 homicidios del mismo mes de 2021, y tambi\u00e9n implican un incremento mensual del 4.57 por ciento frente a los 2 mil 645 asesinatos de [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2022\/al-alza-homicidios-dolosos-en-mexico\/","og_site_name":"Canal 7 SLP - 2022","article_publisher":"https:\/\/www.facebook.com\/noticieroscanalsiete","article_published_time":"2022-11-22T22:42:36+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/11\/01-19.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2022\/al-alza-homicidios-dolosos-en-mexico\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2022\/al-alza-homicidios-dolosos-en-mexico\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/person\/429704152a21f5f856ce29aa69a238da"},"headline":"Al alza homicidios dolosos en M\u00e9xico","datePublished":"2022-11-22T22:42:36+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2022\/al-alza-homicidios-dolosos-en-mexico\/"},"wordCount":210,"publisher":{"@id":"https:\/\/canal7slp.tv\/2022\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2022\/al-alza-homicidios-dolosos-en-mexico\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/11\/01-19.jpg","articleSection":["NACIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2022\/al-alza-homicidios-dolosos-en-mexico\/","url":"https:\/\/canal7slp.tv\/2022\/al-alza-homicidios-dolosos-en-mexico\/","name":"Al alza homicidios dolosos en M\u00e9xico - Canal 7 SLP - 2022","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2022\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2022\/al-alza-homicidios-dolosos-en-mexico\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2022\/al-alza-homicidios-dolosos-en-mexico\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/11\/01-19.jpg","datePublished":"2022-11-22T22:42:36+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2022\/al-alza-homicidios-dolosos-en-mexico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2022\/al-alza-homicidios-dolosos-en-mexico\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2022\/al-alza-homicidios-dolosos-en-mexico\/#primaryimage","url":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/11\/01-19.jpg","contentUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/11\/01-19.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2022\/al-alza-homicidios-dolosos-en-mexico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2022\/"},{"@type":"ListItem","position":2,"name":"Al alza homicidios dolosos en M\u00e9xico"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2022\/#website","url":"https:\/\/canal7slp.tv\/2022\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2022\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2022\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2022\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2022\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanalsiete","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/person\/429704152a21f5f856ce29aa69a238da","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2022\/author\/edicionweb\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts\/79075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/comments?post=79075"}],"version-history":[{"count":2,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts\/79075\/revisions"}],"predecessor-version":[{"id":79098,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts\/79075\/revisions\/79098"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/media\/79087"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/media?parent=79075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/categories?post=79075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/tags?post=79075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}