{"id":76906,"date":"2022-10-28T13:33:18","date_gmt":"2022-10-28T19:33:18","guid":{"rendered":"https:\/\/canal7slp.tv\/2022\/?p=76906"},"modified":"2022-10-28T13:33:18","modified_gmt":"2022-10-28T19:33:18","slug":"primera-edicion-de-carrera-con-causa-se-llevara-a-cabo-el-proximo-6-de-noviembre","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2022\/primera-edicion-de-carrera-con-causa-se-llevara-a-cabo-el-proximo-6-de-noviembre\/","title":{"rendered":"Primera edici\u00f3n de Carrera con Causa se llevar\u00e1 a cabo el pr\u00f3ximo 6 de noviembre."},"content":{"rendered":"<p style=\"text-align: justify;\">SLP.- Ser\u00e1 el domingo 6 de noviembre cuando se llevar\u00e1 a cabo la primera edici\u00f3n de la Carrera Recreativa con Causa, la cual es organizada por la asociaci\u00f3n Econectando AC, Dr. Sonrisas AC. y Ayudando al Pr\u00f3jimo, quienes dedicar\u00e1n los recursos obtenidos a las diferentes labores altruistas.<\/p>\n<p style=\"text-align: justify;\">La carrera competencia tendr\u00e1 salida y meta en el jard\u00edn de Tequis y dar\u00e1 inicio en punto de las 9 y media de la ma\u00f1ana, teniendo un recorrido de 5 kil\u00f3metros, la premiaci\u00f3n ser\u00e1 en especie para las categor\u00edas previstas, que son varonil y femenil de 18 a\u00f1os en adelante, as\u00ed como la juvenil mixta, que es de 12 a 17 a\u00f1os.<\/p>\n<p style=\"text-align: justify;\">Durante el evento, se contar\u00e1 con diez stands con causa, en donde se tendr\u00e1 a la venta comida, as\u00ed como diversos art\u00edculos, los cuales ser\u00e1n manejados por familiares de ni\u00f1as y ni\u00f1os, que padecen enfermedades cr\u00f3nicas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SLP.- Ser\u00e1 el domingo 6 de noviembre cuando se llevar\u00e1 a cabo la primera edici\u00f3n de la Carrera Recreativa con Causa, la cual es organizada por la asociaci\u00f3n Econectando AC, Dr. Sonrisas AC. y Ayudando al Pr\u00f3jimo, quienes dedicar\u00e1n los recursos obtenidos a las diferentes labores altruistas. La carrera competencia tendr\u00e1 salida y meta en el jard\u00edn de Tequis y dar\u00e1 inicio en punto de las 9 y media de la ma\u00f1ana, teniendo un recorrido de 5 kil\u00f3metros, la premiaci\u00f3n ser\u00e1 en especie para las categor\u00edas previstas, que son varonil y femenil de 18 a\u00f1os en adelante, as\u00ed como la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":76914,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"footnotes":""},"categories":[7,5],"tags":[],"class_list":["post-76906","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-deportes","category-destacadas","post_format-post-format-video","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Primera edici\u00f3n de Carrera con Causa se llevar\u00e1 a cabo el pr\u00f3ximo 6 de noviembre. - Canal 7 SLP - 2022<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2022\/primera-edicion-de-carrera-con-causa-se-llevara-a-cabo-el-proximo-6-de-noviembre\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Primera edici\u00f3n de Carrera con Causa se llevar\u00e1 a cabo el pr\u00f3ximo 6 de noviembre. - Canal 7 SLP - 2022\" \/>\n<meta property=\"og:description\" content=\"SLP.- Ser\u00e1 el domingo 6 de noviembre cuando se llevar\u00e1 a cabo la primera edici\u00f3n de la Carrera Recreativa con Causa, la cual es organizada por la asociaci\u00f3n Econectando AC, Dr. Sonrisas AC. y Ayudando al Pr\u00f3jimo, quienes dedicar\u00e1n los recursos obtenidos a las diferentes labores altruistas. La carrera competencia tendr\u00e1 salida y meta en el jard\u00edn de Tequis y dar\u00e1 inicio en punto de las 9 y media de la ma\u00f1ana, teniendo un recorrido de 5 kil\u00f3metros, la premiaci\u00f3n ser\u00e1 en especie para las categor\u00edas previstas, que son varonil y femenil de 18 a\u00f1os en adelante, as\u00ed como la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2022\/primera-edicion-de-carrera-con-causa-se-llevara-a-cabo-el-proximo-6-de-noviembre\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2022\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanalsiete\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-28T19:33:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/10\/Froi03Carrera-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"888\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/primera-edicion-de-carrera-con-causa-se-llevara-a-cabo-el-proximo-6-de-noviembre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/primera-edicion-de-carrera-con-causa-se-llevara-a-cabo-el-proximo-6-de-noviembre\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/person\\\/429704152a21f5f856ce29aa69a238da\"},\"headline\":\"Primera edici\u00f3n de Carrera con Causa se llevar\u00e1 a cabo el pr\u00f3ximo 6 de noviembre.\",\"datePublished\":\"2022-10-28T19:33:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/primera-edicion-de-carrera-con-causa-se-llevara-a-cabo-el-proximo-6-de-noviembre\\\/\"},\"wordCount\":172,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/primera-edicion-de-carrera-con-causa-se-llevara-a-cabo-el-proximo-6-de-noviembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Froi03Carrera-1.jpg\",\"articleSection\":[\"DEPORTES\",\"DESTACADAS\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/primera-edicion-de-carrera-con-causa-se-llevara-a-cabo-el-proximo-6-de-noviembre\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/primera-edicion-de-carrera-con-causa-se-llevara-a-cabo-el-proximo-6-de-noviembre\\\/\",\"name\":\"Primera edici\u00f3n de Carrera con Causa se llevar\u00e1 a cabo el pr\u00f3ximo 6 de noviembre. - Canal 7 SLP - 2022\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/primera-edicion-de-carrera-con-causa-se-llevara-a-cabo-el-proximo-6-de-noviembre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/primera-edicion-de-carrera-con-causa-se-llevara-a-cabo-el-proximo-6-de-noviembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Froi03Carrera-1.jpg\",\"datePublished\":\"2022-10-28T19:33:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/primera-edicion-de-carrera-con-causa-se-llevara-a-cabo-el-proximo-6-de-noviembre\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/primera-edicion-de-carrera-con-causa-se-llevara-a-cabo-el-proximo-6-de-noviembre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/primera-edicion-de-carrera-con-causa-se-llevara-a-cabo-el-proximo-6-de-noviembre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Froi03Carrera-1.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Froi03Carrera-1.jpg\",\"width\":888,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/primera-edicion-de-carrera-con-causa-se-llevara-a-cabo-el-proximo-6-de-noviembre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Primera edici\u00f3n de Carrera con Causa se llevar\u00e1 a cabo el pr\u00f3ximo 6 de noviembre.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanalsiete\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/person\\\/429704152a21f5f856ce29aa69a238da\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Primera edici\u00f3n de Carrera con Causa se llevar\u00e1 a cabo el pr\u00f3ximo 6 de noviembre. - Canal 7 SLP - 2022","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2022\/primera-edicion-de-carrera-con-causa-se-llevara-a-cabo-el-proximo-6-de-noviembre\/","og_locale":"es_ES","og_type":"article","og_title":"Primera edici\u00f3n de Carrera con Causa se llevar\u00e1 a cabo el pr\u00f3ximo 6 de noviembre. - Canal 7 SLP - 2022","og_description":"SLP.- Ser\u00e1 el domingo 6 de noviembre cuando se llevar\u00e1 a cabo la primera edici\u00f3n de la Carrera Recreativa con Causa, la cual es organizada por la asociaci\u00f3n Econectando AC, Dr. Sonrisas AC. y Ayudando al Pr\u00f3jimo, quienes dedicar\u00e1n los recursos obtenidos a las diferentes labores altruistas. La carrera competencia tendr\u00e1 salida y meta en el jard\u00edn de Tequis y dar\u00e1 inicio en punto de las 9 y media de la ma\u00f1ana, teniendo un recorrido de 5 kil\u00f3metros, la premiaci\u00f3n ser\u00e1 en especie para las categor\u00edas previstas, que son varonil y femenil de 18 a\u00f1os en adelante, as\u00ed como la [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2022\/primera-edicion-de-carrera-con-causa-se-llevara-a-cabo-el-proximo-6-de-noviembre\/","og_site_name":"Canal 7 SLP - 2022","article_publisher":"https:\/\/www.facebook.com\/noticieroscanalsiete","article_published_time":"2022-10-28T19:33:18+00:00","og_image":[{"width":888,"height":500,"url":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/10\/Froi03Carrera-1.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2022\/primera-edicion-de-carrera-con-causa-se-llevara-a-cabo-el-proximo-6-de-noviembre\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2022\/primera-edicion-de-carrera-con-causa-se-llevara-a-cabo-el-proximo-6-de-noviembre\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/person\/429704152a21f5f856ce29aa69a238da"},"headline":"Primera edici\u00f3n de Carrera con Causa se llevar\u00e1 a cabo el pr\u00f3ximo 6 de noviembre.","datePublished":"2022-10-28T19:33:18+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2022\/primera-edicion-de-carrera-con-causa-se-llevara-a-cabo-el-proximo-6-de-noviembre\/"},"wordCount":172,"publisher":{"@id":"https:\/\/canal7slp.tv\/2022\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2022\/primera-edicion-de-carrera-con-causa-se-llevara-a-cabo-el-proximo-6-de-noviembre\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/10\/Froi03Carrera-1.jpg","articleSection":["DEPORTES","DESTACADAS"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2022\/primera-edicion-de-carrera-con-causa-se-llevara-a-cabo-el-proximo-6-de-noviembre\/","url":"https:\/\/canal7slp.tv\/2022\/primera-edicion-de-carrera-con-causa-se-llevara-a-cabo-el-proximo-6-de-noviembre\/","name":"Primera edici\u00f3n de Carrera con Causa se llevar\u00e1 a cabo el pr\u00f3ximo 6 de noviembre. - Canal 7 SLP - 2022","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2022\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2022\/primera-edicion-de-carrera-con-causa-se-llevara-a-cabo-el-proximo-6-de-noviembre\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2022\/primera-edicion-de-carrera-con-causa-se-llevara-a-cabo-el-proximo-6-de-noviembre\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/10\/Froi03Carrera-1.jpg","datePublished":"2022-10-28T19:33:18+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2022\/primera-edicion-de-carrera-con-causa-se-llevara-a-cabo-el-proximo-6-de-noviembre\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2022\/primera-edicion-de-carrera-con-causa-se-llevara-a-cabo-el-proximo-6-de-noviembre\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2022\/primera-edicion-de-carrera-con-causa-se-llevara-a-cabo-el-proximo-6-de-noviembre\/#primaryimage","url":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/10\/Froi03Carrera-1.jpg","contentUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/10\/Froi03Carrera-1.jpg","width":888,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2022\/primera-edicion-de-carrera-con-causa-se-llevara-a-cabo-el-proximo-6-de-noviembre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2022\/"},{"@type":"ListItem","position":2,"name":"Primera edici\u00f3n de Carrera con Causa se llevar\u00e1 a cabo el pr\u00f3ximo 6 de noviembre."}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2022\/#website","url":"https:\/\/canal7slp.tv\/2022\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2022\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2022\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2022\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2022\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanalsiete","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/person\/429704152a21f5f856ce29aa69a238da","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2022\/author\/edicionweb\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts\/76906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/comments?post=76906"}],"version-history":[{"count":2,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts\/76906\/revisions"}],"predecessor-version":[{"id":76915,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts\/76906\/revisions\/76915"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/media\/76914"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/media?parent=76906"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/categories?post=76906"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/tags?post=76906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}