{"id":73879,"date":"2022-09-25T16:19:28","date_gmt":"2022-09-25T22:19:28","guid":{"rendered":"https:\/\/canal7slp.tv\/2022\/?p=73879"},"modified":"2022-09-25T16:19:28","modified_gmt":"2022-09-25T22:19:28","slug":"autoridades-detienen-a-dueno-de-la-mina-el-pinabete","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2022\/autoridades-detienen-a-dueno-de-la-mina-el-pinabete\/","title":{"rendered":"Autoridades detienen a due\u00f1o de la mina \u201cEl Pinabete\u201d"},"content":{"rendered":"<p style=\"text-align: justify;\">Sabinas.- Cristian Sol\u00eds, due\u00f1o de la mina \u201cEl Pinabete\u201d, fue detenido en el municipio de Sabinas, Coahuila.<\/p>\n<p style=\"text-align: justify;\">Esto, debido a su probable responsabilidad en el delito federal previsto en la Ley General de Bienes Nacionales.<\/p>\n<p style=\"text-align: justify;\">La Fiscal\u00eda General de la Rep\u00fablica (FGR), detall\u00f3 que el imputado presuntamente explotaba de manera il\u00edcita un bien perteneciente a la Naci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">\u201cPersonal de la Polic\u00eda Federal Ministerial (PFM) de la Agencia de Investigaci\u00f3n Criminal (AIC), detuvo a Cristian \u00abS\u00bb, en la calle Cananea Agujita, Colonia Cosedores y fue puesto a disposici\u00f3n del Juez de Control adscrito al Centro de Justicia Penal Federal con residencia en Torre\u00f3n, Coahuila\u201d, puntualiz\u00f3 la FGR.<\/p>\n<p style=\"text-align: justify;\">Cabe se\u00f1alar que el Ministerio P\u00fablico Federal (MPF), lo present\u00f3 en la audiencia, formul\u00f3 imputaci\u00f3n y solicit\u00f3 vinculaci\u00f3n a proceso.<\/p>\n<p style=\"text-align: justify;\">Como resultado de la audiencia inicial, la defensa se acogi\u00f3 a la duplicidad del t\u00e9rmino para que el Juez resuelva sobre la situaci\u00f3n jur\u00eddica y continuar con la audiencia el pr\u00f3ximo 29 de septiembre.<\/p>\n<p style=\"text-align: justify;\">El Juez dict\u00f3 prisi\u00f3n preventiva, que deber\u00e1 cumplir en el Centro Federal de Readaptaci\u00f3n Social n\u00famero 18 de Ramos Arizpe, Coahuila.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sabinas.- Cristian Sol\u00eds, due\u00f1o de la mina \u201cEl Pinabete\u201d, fue detenido en el municipio de Sabinas, Coahuila. Esto, debido a su probable responsabilidad en el delito federal previsto en la Ley General de Bienes Nacionales. La Fiscal\u00eda General de la Rep\u00fablica (FGR), detall\u00f3 que el imputado presuntamente explotaba de manera il\u00edcita un bien perteneciente a la Naci\u00f3n. \u201cPersonal de la Polic\u00eda Federal Ministerial (PFM) de la Agencia de Investigaci\u00f3n Criminal (AIC), detuvo a Cristian \u00abS\u00bb, en la calle Cananea Agujita, Colonia Cosedores y fue puesto a disposici\u00f3n del Juez de Control adscrito al Centro de Justicia Penal Federal con residencia [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":73889,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[],"class_list":["post-73879","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Autoridades detienen a due\u00f1o de la mina \u201cEl Pinabete\u201d - Canal 7 SLP - 2022<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2022\/autoridades-detienen-a-dueno-de-la-mina-el-pinabete\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Autoridades detienen a due\u00f1o de la mina \u201cEl Pinabete\u201d - Canal 7 SLP - 2022\" \/>\n<meta property=\"og:description\" content=\"Sabinas.- Cristian Sol\u00eds, due\u00f1o de la mina \u201cEl Pinabete\u201d, fue detenido en el municipio de Sabinas, Coahuila. Esto, debido a su probable responsabilidad en el delito federal previsto en la Ley General de Bienes Nacionales. La Fiscal\u00eda General de la Rep\u00fablica (FGR), detall\u00f3 que el imputado presuntamente explotaba de manera il\u00edcita un bien perteneciente a la Naci\u00f3n. \u201cPersonal de la Polic\u00eda Federal Ministerial (PFM) de la Agencia de Investigaci\u00f3n Criminal (AIC), detuvo a Cristian \u00abS\u00bb, en la calle Cananea Agujita, Colonia Cosedores y fue puesto a disposici\u00f3n del Juez de Control adscrito al Centro de Justicia Penal Federal con residencia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2022\/autoridades-detienen-a-dueno-de-la-mina-el-pinabete\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2022\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanalsiete\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-25T22:19:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/09\/04-21.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1140\" \/>\n\t<meta property=\"og:image:height\" content=\"712\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/autoridades-detienen-a-dueno-de-la-mina-el-pinabete\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/autoridades-detienen-a-dueno-de-la-mina-el-pinabete\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/person\\\/429704152a21f5f856ce29aa69a238da\"},\"headline\":\"Autoridades detienen a due\u00f1o de la mina \u201cEl Pinabete\u201d\",\"datePublished\":\"2022-09-25T22:19:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/autoridades-detienen-a-dueno-de-la-mina-el-pinabete\\\/\"},\"wordCount\":211,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/autoridades-detienen-a-dueno-de-la-mina-el-pinabete\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/04-21.jpg\",\"articleSection\":[\"NACIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/autoridades-detienen-a-dueno-de-la-mina-el-pinabete\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/autoridades-detienen-a-dueno-de-la-mina-el-pinabete\\\/\",\"name\":\"Autoridades detienen a due\u00f1o de la mina \u201cEl Pinabete\u201d - Canal 7 SLP - 2022\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/autoridades-detienen-a-dueno-de-la-mina-el-pinabete\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/autoridades-detienen-a-dueno-de-la-mina-el-pinabete\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/04-21.jpg\",\"datePublished\":\"2022-09-25T22:19:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/autoridades-detienen-a-dueno-de-la-mina-el-pinabete\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/autoridades-detienen-a-dueno-de-la-mina-el-pinabete\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/autoridades-detienen-a-dueno-de-la-mina-el-pinabete\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/04-21.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/04-21.jpg\",\"width\":1140,\"height\":712},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/autoridades-detienen-a-dueno-de-la-mina-el-pinabete\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Autoridades detienen a due\u00f1o de la mina \u201cEl Pinabete\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanalsiete\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/person\\\/429704152a21f5f856ce29aa69a238da\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Autoridades detienen a due\u00f1o de la mina \u201cEl Pinabete\u201d - Canal 7 SLP - 2022","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2022\/autoridades-detienen-a-dueno-de-la-mina-el-pinabete\/","og_locale":"es_ES","og_type":"article","og_title":"Autoridades detienen a due\u00f1o de la mina \u201cEl Pinabete\u201d - Canal 7 SLP - 2022","og_description":"Sabinas.- Cristian Sol\u00eds, due\u00f1o de la mina \u201cEl Pinabete\u201d, fue detenido en el municipio de Sabinas, Coahuila. Esto, debido a su probable responsabilidad en el delito federal previsto en la Ley General de Bienes Nacionales. La Fiscal\u00eda General de la Rep\u00fablica (FGR), detall\u00f3 que el imputado presuntamente explotaba de manera il\u00edcita un bien perteneciente a la Naci\u00f3n. \u201cPersonal de la Polic\u00eda Federal Ministerial (PFM) de la Agencia de Investigaci\u00f3n Criminal (AIC), detuvo a Cristian \u00abS\u00bb, en la calle Cananea Agujita, Colonia Cosedores y fue puesto a disposici\u00f3n del Juez de Control adscrito al Centro de Justicia Penal Federal con residencia [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2022\/autoridades-detienen-a-dueno-de-la-mina-el-pinabete\/","og_site_name":"Canal 7 SLP - 2022","article_publisher":"https:\/\/www.facebook.com\/noticieroscanalsiete","article_published_time":"2022-09-25T22:19:28+00:00","og_image":[{"width":1140,"height":712,"url":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/09\/04-21.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2022\/autoridades-detienen-a-dueno-de-la-mina-el-pinabete\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2022\/autoridades-detienen-a-dueno-de-la-mina-el-pinabete\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/person\/429704152a21f5f856ce29aa69a238da"},"headline":"Autoridades detienen a due\u00f1o de la mina \u201cEl Pinabete\u201d","datePublished":"2022-09-25T22:19:28+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2022\/autoridades-detienen-a-dueno-de-la-mina-el-pinabete\/"},"wordCount":211,"publisher":{"@id":"https:\/\/canal7slp.tv\/2022\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2022\/autoridades-detienen-a-dueno-de-la-mina-el-pinabete\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/09\/04-21.jpg","articleSection":["NACIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2022\/autoridades-detienen-a-dueno-de-la-mina-el-pinabete\/","url":"https:\/\/canal7slp.tv\/2022\/autoridades-detienen-a-dueno-de-la-mina-el-pinabete\/","name":"Autoridades detienen a due\u00f1o de la mina \u201cEl Pinabete\u201d - Canal 7 SLP - 2022","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2022\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2022\/autoridades-detienen-a-dueno-de-la-mina-el-pinabete\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2022\/autoridades-detienen-a-dueno-de-la-mina-el-pinabete\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/09\/04-21.jpg","datePublished":"2022-09-25T22:19:28+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2022\/autoridades-detienen-a-dueno-de-la-mina-el-pinabete\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2022\/autoridades-detienen-a-dueno-de-la-mina-el-pinabete\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2022\/autoridades-detienen-a-dueno-de-la-mina-el-pinabete\/#primaryimage","url":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/09\/04-21.jpg","contentUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/09\/04-21.jpg","width":1140,"height":712},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2022\/autoridades-detienen-a-dueno-de-la-mina-el-pinabete\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2022\/"},{"@type":"ListItem","position":2,"name":"Autoridades detienen a due\u00f1o de la mina \u201cEl Pinabete\u201d"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2022\/#website","url":"https:\/\/canal7slp.tv\/2022\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2022\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2022\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2022\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2022\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanalsiete","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/person\/429704152a21f5f856ce29aa69a238da","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2022\/author\/edicionweb\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts\/73879","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/comments?post=73879"}],"version-history":[{"count":2,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts\/73879\/revisions"}],"predecessor-version":[{"id":73892,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts\/73879\/revisions\/73892"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/media\/73889"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/media?parent=73879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/categories?post=73879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/tags?post=73879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}