{"id":73725,"date":"2022-09-23T17:08:02","date_gmt":"2022-09-23T23:08:02","guid":{"rendered":"https:\/\/canal7slp.tv\/2022\/?p=73725"},"modified":"2022-09-23T17:08:02","modified_gmt":"2022-09-23T23:08:02","slug":"con-auditoria-en-puerta-exdirigente-de-morena-afirma-que-rendicion-de-cuentas-recae-en-el-comite-nacional-del-partido","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2022\/con-auditoria-en-puerta-exdirigente-de-morena-afirma-que-rendicion-de-cuentas-recae-en-el-comite-nacional-del-partido\/","title":{"rendered":"Con auditor\u00eda en puerta, exdirigente de MORENA afirma que rendici\u00f3n de cuentas recae en el Comit\u00e9 Nacional del partido."},"content":{"rendered":"<ul>\n<li>Sergio Serrano se\u00f1ala a Yeidckol Polevnsky y Mario Delgado.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">SLP.- En d\u00edas pasado el presidente del Consejo Estatal de MORENA Carlos Arreola afirm\u00f3 que la nueva dirigencia estatal de este partido, iniciar\u00e1n una auditor\u00eda a la anterior dirigencia al afirmar que expresidente Sergio Serrano Soriano no rindi\u00f3 cuentas claras sobre los manejos financieros de este partido.<\/p>\n<p style=\"text-align: justify;\">Cuestionado al respecto, Serrano Soriano dijo sentirse tranquilo al decir que en todo caso a quien se le debe de pedir cuentas en este tema, es a la Secretar\u00eda de Finanzas del Comit\u00e9 Ejecutivo Nacional de Morena, y concretamente a la exdirigente Yeidckol Polevnsky Gurwitz pero tambi\u00e9n a su actual presidente Mario Delgado Carrillo, al afirmar que son ellos los que llevan el control de gastos en cada una de las sedes estatales.<\/p>\n<p style=\"text-align: justify;\">En este contexto, Serrano Soriano, quien estuvo al frente de este partido durante 7 a\u00f1os, revel\u00f3 que los exintegrantes del Comit\u00e9 Ejecutivo Estatal dejaron de percibir recursos durante varios a\u00f1os, con el prop\u00f3sito de reunir 15 millones de pesos, para adquirir un inmueble propio.<\/p>\n<p style=\"text-align: justify;\">Sin embargo, asegur\u00f3 que no se logr\u00f3 este objetivo pero de los recursos que se reunieron para este fin a la fecha no se sabe nada de ellos.<\/p>\n<p>Por: Claudio Ibarra<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sergio Serrano se\u00f1ala a Yeidckol Polevnsky y Mario Delgado. SLP.- En d\u00edas pasado el presidente del Consejo Estatal de MORENA Carlos Arreola afirm\u00f3 que la nueva dirigencia estatal de este partido, iniciar\u00e1n una auditor\u00eda a la anterior dirigencia al afirmar que expresidente Sergio Serrano Soriano no rindi\u00f3 cuentas claras sobre los manejos financieros de este partido. Cuestionado al respecto, Serrano Soriano dijo sentirse tranquilo al decir que en todo caso a quien se le debe de pedir cuentas en este tema, es a la Secretar\u00eda de Finanzas del Comit\u00e9 Ejecutivo Nacional de Morena, y concretamente a la exdirigente Yeidckol Polevnsky [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":73759,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"footnotes":""},"categories":[5,45],"tags":[],"class_list":["post-73725","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-destacadas","category-localesyregionales","post_format-post-format-video","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Con auditor\u00eda en puerta, exdirigente de MORENA afirma que rendici\u00f3n de cuentas recae en el Comit\u00e9 Nacional del partido. - Canal 7 SLP - 2022<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2022\/con-auditoria-en-puerta-exdirigente-de-morena-afirma-que-rendicion-de-cuentas-recae-en-el-comite-nacional-del-partido\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Con auditor\u00eda en puerta, exdirigente de MORENA afirma que rendici\u00f3n de cuentas recae en el Comit\u00e9 Nacional del partido. - Canal 7 SLP - 2022\" \/>\n<meta property=\"og:description\" content=\"Sergio Serrano se\u00f1ala a Yeidckol Polevnsky y Mario Delgado. SLP.- En d\u00edas pasado el presidente del Consejo Estatal de MORENA Carlos Arreola afirm\u00f3 que la nueva dirigencia estatal de este partido, iniciar\u00e1n una auditor\u00eda a la anterior dirigencia al afirmar que expresidente Sergio Serrano Soriano no rindi\u00f3 cuentas claras sobre los manejos financieros de este partido. Cuestionado al respecto, Serrano Soriano dijo sentirse tranquilo al decir que en todo caso a quien se le debe de pedir cuentas en este tema, es a la Secretar\u00eda de Finanzas del Comit\u00e9 Ejecutivo Nacional de Morena, y concretamente a la exdirigente Yeidckol Polevnsky [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2022\/con-auditoria-en-puerta-exdirigente-de-morena-afirma-que-rendicion-de-cuentas-recae-en-el-comite-nacional-del-partido\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2022\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanalsiete\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-23T23:08:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/09\/Claudio04Auditoria.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"888\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/con-auditoria-en-puerta-exdirigente-de-morena-afirma-que-rendicion-de-cuentas-recae-en-el-comite-nacional-del-partido\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/con-auditoria-en-puerta-exdirigente-de-morena-afirma-que-rendicion-de-cuentas-recae-en-el-comite-nacional-del-partido\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/person\\\/429704152a21f5f856ce29aa69a238da\"},\"headline\":\"Con auditor\u00eda en puerta, exdirigente de MORENA afirma que rendici\u00f3n de cuentas recae en el Comit\u00e9 Nacional del partido.\",\"datePublished\":\"2022-09-23T23:08:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/con-auditoria-en-puerta-exdirigente-de-morena-afirma-que-rendicion-de-cuentas-recae-en-el-comite-nacional-del-partido\\\/\"},\"wordCount\":233,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/con-auditoria-en-puerta-exdirigente-de-morena-afirma-que-rendicion-de-cuentas-recae-en-el-comite-nacional-del-partido\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Claudio04Auditoria.jpg\",\"articleSection\":[\"DESTACADAS\",\"LOCALES Y REGIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/con-auditoria-en-puerta-exdirigente-de-morena-afirma-que-rendicion-de-cuentas-recae-en-el-comite-nacional-del-partido\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/con-auditoria-en-puerta-exdirigente-de-morena-afirma-que-rendicion-de-cuentas-recae-en-el-comite-nacional-del-partido\\\/\",\"name\":\"Con auditor\u00eda en puerta, exdirigente de MORENA afirma que rendici\u00f3n de cuentas recae en el Comit\u00e9 Nacional del partido. - Canal 7 SLP - 2022\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/con-auditoria-en-puerta-exdirigente-de-morena-afirma-que-rendicion-de-cuentas-recae-en-el-comite-nacional-del-partido\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/con-auditoria-en-puerta-exdirigente-de-morena-afirma-que-rendicion-de-cuentas-recae-en-el-comite-nacional-del-partido\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Claudio04Auditoria.jpg\",\"datePublished\":\"2022-09-23T23:08:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/con-auditoria-en-puerta-exdirigente-de-morena-afirma-que-rendicion-de-cuentas-recae-en-el-comite-nacional-del-partido\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/con-auditoria-en-puerta-exdirigente-de-morena-afirma-que-rendicion-de-cuentas-recae-en-el-comite-nacional-del-partido\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/con-auditoria-en-puerta-exdirigente-de-morena-afirma-que-rendicion-de-cuentas-recae-en-el-comite-nacional-del-partido\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Claudio04Auditoria.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Claudio04Auditoria.jpg\",\"width\":888,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/con-auditoria-en-puerta-exdirigente-de-morena-afirma-que-rendicion-de-cuentas-recae-en-el-comite-nacional-del-partido\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Con auditor\u00eda en puerta, exdirigente de MORENA afirma que rendici\u00f3n de cuentas recae en el Comit\u00e9 Nacional del partido.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanalsiete\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/person\\\/429704152a21f5f856ce29aa69a238da\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Con auditor\u00eda en puerta, exdirigente de MORENA afirma que rendici\u00f3n de cuentas recae en el Comit\u00e9 Nacional del partido. - Canal 7 SLP - 2022","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2022\/con-auditoria-en-puerta-exdirigente-de-morena-afirma-que-rendicion-de-cuentas-recae-en-el-comite-nacional-del-partido\/","og_locale":"es_ES","og_type":"article","og_title":"Con auditor\u00eda en puerta, exdirigente de MORENA afirma que rendici\u00f3n de cuentas recae en el Comit\u00e9 Nacional del partido. - Canal 7 SLP - 2022","og_description":"Sergio Serrano se\u00f1ala a Yeidckol Polevnsky y Mario Delgado. SLP.- En d\u00edas pasado el presidente del Consejo Estatal de MORENA Carlos Arreola afirm\u00f3 que la nueva dirigencia estatal de este partido, iniciar\u00e1n una auditor\u00eda a la anterior dirigencia al afirmar que expresidente Sergio Serrano Soriano no rindi\u00f3 cuentas claras sobre los manejos financieros de este partido. Cuestionado al respecto, Serrano Soriano dijo sentirse tranquilo al decir que en todo caso a quien se le debe de pedir cuentas en este tema, es a la Secretar\u00eda de Finanzas del Comit\u00e9 Ejecutivo Nacional de Morena, y concretamente a la exdirigente Yeidckol Polevnsky [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2022\/con-auditoria-en-puerta-exdirigente-de-morena-afirma-que-rendicion-de-cuentas-recae-en-el-comite-nacional-del-partido\/","og_site_name":"Canal 7 SLP - 2022","article_publisher":"https:\/\/www.facebook.com\/noticieroscanalsiete","article_published_time":"2022-09-23T23:08:02+00:00","og_image":[{"width":888,"height":500,"url":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/09\/Claudio04Auditoria.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2022\/con-auditoria-en-puerta-exdirigente-de-morena-afirma-que-rendicion-de-cuentas-recae-en-el-comite-nacional-del-partido\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2022\/con-auditoria-en-puerta-exdirigente-de-morena-afirma-que-rendicion-de-cuentas-recae-en-el-comite-nacional-del-partido\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/person\/429704152a21f5f856ce29aa69a238da"},"headline":"Con auditor\u00eda en puerta, exdirigente de MORENA afirma que rendici\u00f3n de cuentas recae en el Comit\u00e9 Nacional del partido.","datePublished":"2022-09-23T23:08:02+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2022\/con-auditoria-en-puerta-exdirigente-de-morena-afirma-que-rendicion-de-cuentas-recae-en-el-comite-nacional-del-partido\/"},"wordCount":233,"publisher":{"@id":"https:\/\/canal7slp.tv\/2022\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2022\/con-auditoria-en-puerta-exdirigente-de-morena-afirma-que-rendicion-de-cuentas-recae-en-el-comite-nacional-del-partido\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/09\/Claudio04Auditoria.jpg","articleSection":["DESTACADAS","LOCALES Y REGIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2022\/con-auditoria-en-puerta-exdirigente-de-morena-afirma-que-rendicion-de-cuentas-recae-en-el-comite-nacional-del-partido\/","url":"https:\/\/canal7slp.tv\/2022\/con-auditoria-en-puerta-exdirigente-de-morena-afirma-que-rendicion-de-cuentas-recae-en-el-comite-nacional-del-partido\/","name":"Con auditor\u00eda en puerta, exdirigente de MORENA afirma que rendici\u00f3n de cuentas recae en el Comit\u00e9 Nacional del partido. - Canal 7 SLP - 2022","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2022\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2022\/con-auditoria-en-puerta-exdirigente-de-morena-afirma-que-rendicion-de-cuentas-recae-en-el-comite-nacional-del-partido\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2022\/con-auditoria-en-puerta-exdirigente-de-morena-afirma-que-rendicion-de-cuentas-recae-en-el-comite-nacional-del-partido\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/09\/Claudio04Auditoria.jpg","datePublished":"2022-09-23T23:08:02+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2022\/con-auditoria-en-puerta-exdirigente-de-morena-afirma-que-rendicion-de-cuentas-recae-en-el-comite-nacional-del-partido\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2022\/con-auditoria-en-puerta-exdirigente-de-morena-afirma-que-rendicion-de-cuentas-recae-en-el-comite-nacional-del-partido\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2022\/con-auditoria-en-puerta-exdirigente-de-morena-afirma-que-rendicion-de-cuentas-recae-en-el-comite-nacional-del-partido\/#primaryimage","url":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/09\/Claudio04Auditoria.jpg","contentUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/09\/Claudio04Auditoria.jpg","width":888,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2022\/con-auditoria-en-puerta-exdirigente-de-morena-afirma-que-rendicion-de-cuentas-recae-en-el-comite-nacional-del-partido\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2022\/"},{"@type":"ListItem","position":2,"name":"Con auditor\u00eda en puerta, exdirigente de MORENA afirma que rendici\u00f3n de cuentas recae en el Comit\u00e9 Nacional del partido."}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2022\/#website","url":"https:\/\/canal7slp.tv\/2022\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2022\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2022\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2022\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2022\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanalsiete","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/person\/429704152a21f5f856ce29aa69a238da","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2022\/author\/edicionweb\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts\/73725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/comments?post=73725"}],"version-history":[{"count":4,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts\/73725\/revisions"}],"predecessor-version":[{"id":73760,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts\/73725\/revisions\/73760"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/media\/73759"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/media?parent=73725"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/categories?post=73725"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/tags?post=73725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}