{"id":72983,"date":"2022-09-16T03:42:52","date_gmt":"2022-09-16T09:42:52","guid":{"rendered":"https:\/\/canal7slp.tv\/2022\/?p=72983"},"modified":"2022-09-16T03:42:52","modified_gmt":"2022-09-16T09:42:52","slug":"miles-de-personas-conmemoraron-en-el-centro-historico-de-slp-el-aniversario-212-de-la-independencia-de-mexico","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2022\/miles-de-personas-conmemoraron-en-el-centro-historico-de-slp-el-aniversario-212-de-la-independencia-de-mexico\/","title":{"rendered":"Miles de personas conmemoraron en el Centro Hist\u00f3rico de SLP el aniversario 212 de la Independencia de M\u00e9xico."},"content":{"rendered":"<p style=\"text-align: justify;\">SLP.- Este jueves se celebr\u00f3 en San Luis Potos\u00ed el 212 aniversario del Grito de la Independencia luego de dos a\u00f1os de pandemia por Covid-19 en los que no se permit\u00eda realizar este tipo de eventos, al menos no con la presencia de cientos de personas que ahora s\u00ed se dieron cita a las afueras de Palacio de Gobierno, el mismo estuvo encabezado por el mandatario estatal, Jos\u00e9 Ricardo Gallardo Cardona.<\/p>\n<p style=\"text-align: justify;\">\u00abMuy contentos de celebrar el grito con la familia, estoy con todos mis hijos porque todo en familia se hace mejor, es un grito muy familiar, todas las familias potosinas acuden a la plaza para volver a retomar actividades, tenemos dos a\u00f1os sin un grito, yo creo que hoy es important\u00edsimo, un d\u00eda muy bueno para San Luis Potos\u00ed, volver a resaltar las tradiciones mexicanas y que mejor que hacerlo en esta Plaza memorable de la Plaza de Armas \u00ab<\/p>\n<p style=\"text-align: justify;\">Todo comenz\u00f3 en punto de las ocho de la noche con una verbena en la que se registraron largas filas de espera y donde se ofrecieron antojitos mexicanos totalmente gratuitos para las familias potosinas que se dieron cita a esta festividad.<\/p>\n<p style=\"text-align: justify;\">\u00abLo hicimos siempre en Soledad, cada a\u00f1o era algo muy natural en los otros, hoy no pod\u00eda faltar aqu\u00ed en la Plaza de Armas esta verbena popular para la gente, trajimos comida suficiente, ojal\u00e1 que la gente la disfrute: taquitos rojos, molletes, tostadas, elotes, todo lo va a poder disfrutar la gente, es momento de que convivamos con ellas y hoy es un d\u00eda muy importante para M\u00e9xico y para San Luis Potos\u00ed\u00bb, a\u00f1adi\u00f3.<\/p>\n<p style=\"text-align: justify;\">El protocolo de celebraci\u00f3n inici\u00f3 pasadas las 11 de la noche en el sal\u00f3n de recepciones del Palacio de Gobierno donde el ejecutivo recibi\u00f3 el l\u00e1baro patrio a manos de la escolta del ej\u00e9rcito mexicano; despu\u00e9s se dirigi\u00f3 al balc\u00f3n que da hacia el Jard\u00edn Hidalgo para dar el grito mexicano de independencia.<\/p>\n<p style=\"text-align: justify;\">\u00abPotosinas y potosinos: \u00a1Vivan los h\u00e9roes que nos dieron Patria y Libertad!, \u00a1Viva Miguel Hidalgo!, \u00a1Viva Morelos!, \u00a1Viva Josefa Ortiz de Dom\u00ednguez!, \u00a1Viva Vicente Guerrero!, \u00a1Viva Juan Aldama!, \u00a1Viva Ignacio Allende!, \u00a1Viva el potosino Mariano Jim\u00e9nez!, \u00a1Vivan las comunidades ind\u00edgenas de San Luis Potos\u00ed!, \u00a1Viva los adultos mayores!, \u00a1 Viva las familias potosinas!, \u00a1Viva los ni\u00f1os de San Luis Potos\u00ed!, \u00a1Viva la Huasteca Potosina!, \u00a1Viva la Zona Media!, \u00a1Viva el Altiplano!, \u00a1Viva la Zona Centro!, \u00a1Viva San Luis Potos\u00ed!, \u00a1Viva M\u00e9xico!, \u00a1Viva M\u00e9xico!, \u00a1Viva M\u00e9xico!\u00bb<\/p>\n<p style=\"text-align: justify;\">Enseguida, el mandatario toc\u00f3 la campana haciendo alusi\u00f3n a la de Dolores, onde\u00f3 la bandera nacional y se enton\u00f3 el Himno Nacional; posteriormente se dio comienzo a los fuegos pirot\u00e9cnicos cuyos colores representaron a M\u00e9xico.<\/p>\n<p style=\"text-align: justify;\">Todo culmin\u00f3 con la presentaci\u00f3n del grupo \u00abHuracanes del Norte\u00bb, quienes tocaron sus canciones m\u00e1s conocidas.<\/p>\n<p style=\"text-align: justify;\">Al evento tambi\u00e9n acudi\u00f3 la presidenta del Sistema DIF Estatal, Ruth Gonz\u00e1lez Silva; la presidenta del Supremo Tribunal de Justicia, Olga Regina Garc\u00eda L\u00f3pez y el secretario general, Guadalupe Torres S\u00e1nchez.<\/p>\n<p>Por: Jos\u00e9 Luis V\u00e1zquez<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SLP.- Este jueves se celebr\u00f3 en San Luis Potos\u00ed el 212 aniversario del Grito de la Independencia luego de dos a\u00f1os de pandemia por Covid-19 en los que no se permit\u00eda realizar este tipo de eventos, al menos no con la presencia de cientos de personas que ahora s\u00ed se dieron cita a las afueras de Palacio de Gobierno, el mismo estuvo encabezado por el mandatario estatal, Jos\u00e9 Ricardo Gallardo Cardona. \u00abMuy contentos de celebrar el grito con la familia, estoy con todos mis hijos porque todo en familia se hace mejor, es un grito muy familiar, todas las familias [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":72987,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"footnotes":""},"categories":[5,45],"tags":[],"class_list":["post-72983","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-destacadas","category-localesyregionales","post_format-post-format-video","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Miles de personas conmemoraron en el Centro Hist\u00f3rico de SLP el aniversario 212 de la Independencia de M\u00e9xico. - Canal 7 SLP - 2022<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2022\/miles-de-personas-conmemoraron-en-el-centro-historico-de-slp-el-aniversario-212-de-la-independencia-de-mexico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Miles de personas conmemoraron en el Centro Hist\u00f3rico de SLP el aniversario 212 de la Independencia de M\u00e9xico. - Canal 7 SLP - 2022\" \/>\n<meta property=\"og:description\" content=\"SLP.- Este jueves se celebr\u00f3 en San Luis Potos\u00ed el 212 aniversario del Grito de la Independencia luego de dos a\u00f1os de pandemia por Covid-19 en los que no se permit\u00eda realizar este tipo de eventos, al menos no con la presencia de cientos de personas que ahora s\u00ed se dieron cita a las afueras de Palacio de Gobierno, el mismo estuvo encabezado por el mandatario estatal, Jos\u00e9 Ricardo Gallardo Cardona. \u00abMuy contentos de celebrar el grito con la familia, estoy con todos mis hijos porque todo en familia se hace mejor, es un grito muy familiar, todas las familias [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2022\/miles-de-personas-conmemoraron-en-el-centro-historico-de-slp-el-aniversario-212-de-la-independencia-de-mexico\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2022\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanalsiete\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-16T09:42:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/09\/VazquezGrito.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"888\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/miles-de-personas-conmemoraron-en-el-centro-historico-de-slp-el-aniversario-212-de-la-independencia-de-mexico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/miles-de-personas-conmemoraron-en-el-centro-historico-de-slp-el-aniversario-212-de-la-independencia-de-mexico\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/person\\\/429704152a21f5f856ce29aa69a238da\"},\"headline\":\"Miles de personas conmemoraron en el Centro Hist\u00f3rico de SLP el aniversario 212 de la Independencia de M\u00e9xico.\",\"datePublished\":\"2022-09-16T09:42:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/miles-de-personas-conmemoraron-en-el-centro-historico-de-slp-el-aniversario-212-de-la-independencia-de-mexico\\\/\"},\"wordCount\":542,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/miles-de-personas-conmemoraron-en-el-centro-historico-de-slp-el-aniversario-212-de-la-independencia-de-mexico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/VazquezGrito.jpg\",\"articleSection\":[\"DESTACADAS\",\"LOCALES Y REGIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/miles-de-personas-conmemoraron-en-el-centro-historico-de-slp-el-aniversario-212-de-la-independencia-de-mexico\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/miles-de-personas-conmemoraron-en-el-centro-historico-de-slp-el-aniversario-212-de-la-independencia-de-mexico\\\/\",\"name\":\"Miles de personas conmemoraron en el Centro Hist\u00f3rico de SLP el aniversario 212 de la Independencia de M\u00e9xico. - Canal 7 SLP - 2022\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/miles-de-personas-conmemoraron-en-el-centro-historico-de-slp-el-aniversario-212-de-la-independencia-de-mexico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/miles-de-personas-conmemoraron-en-el-centro-historico-de-slp-el-aniversario-212-de-la-independencia-de-mexico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/VazquezGrito.jpg\",\"datePublished\":\"2022-09-16T09:42:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/miles-de-personas-conmemoraron-en-el-centro-historico-de-slp-el-aniversario-212-de-la-independencia-de-mexico\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/miles-de-personas-conmemoraron-en-el-centro-historico-de-slp-el-aniversario-212-de-la-independencia-de-mexico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/miles-de-personas-conmemoraron-en-el-centro-historico-de-slp-el-aniversario-212-de-la-independencia-de-mexico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/VazquezGrito.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/VazquezGrito.jpg\",\"width\":888,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/miles-de-personas-conmemoraron-en-el-centro-historico-de-slp-el-aniversario-212-de-la-independencia-de-mexico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Miles de personas conmemoraron en el Centro Hist\u00f3rico de SLP el aniversario 212 de la Independencia de M\u00e9xico.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanalsiete\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/person\\\/429704152a21f5f856ce29aa69a238da\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Miles de personas conmemoraron en el Centro Hist\u00f3rico de SLP el aniversario 212 de la Independencia de M\u00e9xico. - Canal 7 SLP - 2022","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2022\/miles-de-personas-conmemoraron-en-el-centro-historico-de-slp-el-aniversario-212-de-la-independencia-de-mexico\/","og_locale":"es_ES","og_type":"article","og_title":"Miles de personas conmemoraron en el Centro Hist\u00f3rico de SLP el aniversario 212 de la Independencia de M\u00e9xico. - Canal 7 SLP - 2022","og_description":"SLP.- Este jueves se celebr\u00f3 en San Luis Potos\u00ed el 212 aniversario del Grito de la Independencia luego de dos a\u00f1os de pandemia por Covid-19 en los que no se permit\u00eda realizar este tipo de eventos, al menos no con la presencia de cientos de personas que ahora s\u00ed se dieron cita a las afueras de Palacio de Gobierno, el mismo estuvo encabezado por el mandatario estatal, Jos\u00e9 Ricardo Gallardo Cardona. \u00abMuy contentos de celebrar el grito con la familia, estoy con todos mis hijos porque todo en familia se hace mejor, es un grito muy familiar, todas las familias [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2022\/miles-de-personas-conmemoraron-en-el-centro-historico-de-slp-el-aniversario-212-de-la-independencia-de-mexico\/","og_site_name":"Canal 7 SLP - 2022","article_publisher":"https:\/\/www.facebook.com\/noticieroscanalsiete","article_published_time":"2022-09-16T09:42:52+00:00","og_image":[{"width":888,"height":500,"url":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/09\/VazquezGrito.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2022\/miles-de-personas-conmemoraron-en-el-centro-historico-de-slp-el-aniversario-212-de-la-independencia-de-mexico\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2022\/miles-de-personas-conmemoraron-en-el-centro-historico-de-slp-el-aniversario-212-de-la-independencia-de-mexico\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/person\/429704152a21f5f856ce29aa69a238da"},"headline":"Miles de personas conmemoraron en el Centro Hist\u00f3rico de SLP el aniversario 212 de la Independencia de M\u00e9xico.","datePublished":"2022-09-16T09:42:52+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2022\/miles-de-personas-conmemoraron-en-el-centro-historico-de-slp-el-aniversario-212-de-la-independencia-de-mexico\/"},"wordCount":542,"publisher":{"@id":"https:\/\/canal7slp.tv\/2022\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2022\/miles-de-personas-conmemoraron-en-el-centro-historico-de-slp-el-aniversario-212-de-la-independencia-de-mexico\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/09\/VazquezGrito.jpg","articleSection":["DESTACADAS","LOCALES Y REGIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2022\/miles-de-personas-conmemoraron-en-el-centro-historico-de-slp-el-aniversario-212-de-la-independencia-de-mexico\/","url":"https:\/\/canal7slp.tv\/2022\/miles-de-personas-conmemoraron-en-el-centro-historico-de-slp-el-aniversario-212-de-la-independencia-de-mexico\/","name":"Miles de personas conmemoraron en el Centro Hist\u00f3rico de SLP el aniversario 212 de la Independencia de M\u00e9xico. - Canal 7 SLP - 2022","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2022\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2022\/miles-de-personas-conmemoraron-en-el-centro-historico-de-slp-el-aniversario-212-de-la-independencia-de-mexico\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2022\/miles-de-personas-conmemoraron-en-el-centro-historico-de-slp-el-aniversario-212-de-la-independencia-de-mexico\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/09\/VazquezGrito.jpg","datePublished":"2022-09-16T09:42:52+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2022\/miles-de-personas-conmemoraron-en-el-centro-historico-de-slp-el-aniversario-212-de-la-independencia-de-mexico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2022\/miles-de-personas-conmemoraron-en-el-centro-historico-de-slp-el-aniversario-212-de-la-independencia-de-mexico\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2022\/miles-de-personas-conmemoraron-en-el-centro-historico-de-slp-el-aniversario-212-de-la-independencia-de-mexico\/#primaryimage","url":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/09\/VazquezGrito.jpg","contentUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/09\/VazquezGrito.jpg","width":888,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2022\/miles-de-personas-conmemoraron-en-el-centro-historico-de-slp-el-aniversario-212-de-la-independencia-de-mexico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2022\/"},{"@type":"ListItem","position":2,"name":"Miles de personas conmemoraron en el Centro Hist\u00f3rico de SLP el aniversario 212 de la Independencia de M\u00e9xico."}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2022\/#website","url":"https:\/\/canal7slp.tv\/2022\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2022\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2022\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2022\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2022\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanalsiete","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/person\/429704152a21f5f856ce29aa69a238da","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2022\/author\/edicionweb\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts\/72983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/comments?post=72983"}],"version-history":[{"count":2,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts\/72983\/revisions"}],"predecessor-version":[{"id":72985,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts\/72983\/revisions\/72985"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/media\/72987"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/media?parent=72983"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/categories?post=72983"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/tags?post=72983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}