{"id":71762,"date":"2022-09-02T17:21:32","date_gmt":"2022-09-02T23:21:32","guid":{"rendered":"https:\/\/canal7slp.tv\/2022\/?p=71762"},"modified":"2022-09-02T17:21:32","modified_gmt":"2022-09-02T23:21:32","slug":"impulsa-secretaria-de-cultura-ejercicio-del-periodismo-en-el-marco-de-la-culminacion-del-festival-internacional-de-danza-contemporanea-lila-lopez","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2022\/impulsa-secretaria-de-cultura-ejercicio-del-periodismo-en-el-marco-de-la-culminacion-del-festival-internacional-de-danza-contemporanea-lila-lopez\/","title":{"rendered":"Impulsa Secretar\u00eda de Cultura ejercicio del periodismo, en el marco de la culminaci\u00f3n del Festival Internacional de Danza Contempor\u00e1nea \u00abLila L\u00f3pez\u00bb."},"content":{"rendered":"<p style=\"text-align: justify;\">SLP.- En el marco de la culminaci\u00f3n del Festival Internacional de Danza \u201c Lila L\u00f3pez\u201d la Secretar\u00eda de Cultura entreg\u00f3 los reconocimientos del Premio de Periodismo Cultural \u201cLuis Bruno Ruiz\u201d.<\/p>\n<p style=\"text-align: justify;\">El objetivo de esta convocatoria fue el de fomentar el ejercicio del periodismo cultural especializado en danza contempor\u00e1nea y generar espacios de visibilidad en este g\u00e9nero period\u00edstico, mismo que hab\u00eda sido suspendido desde hace tiempo.<\/p>\n<p style=\"text-align: justify;\">Cabe se\u00f1alar que en este Festival Internacional de Danza \u201cLila L\u00f3pez\u201d asistieron 9 mil personas con aforos reducidos por la contingencia sanitaria.<\/p>\n<p style=\"text-align: justify;\">Asimismo, se realizaron 31 presentaciones al p\u00fablico en general, participaron 25 compa\u00f1\u00edas danc\u00edsticas, 320 artistas, se llevaron a cabo 10 actividades acad\u00e9micas, 6 concursos, premios y competencias adem\u00e1s de 3 exposiciones.<\/p>\n<p style=\"text-align: justify;\">Igualmente, se llevaron 6 funciones en espacios abiertos y 5 municipios fueron atendidos en el tema de la descentralizaci\u00f3n de la cultura en el estado.<\/p>\n<p>Por: Claudio Ibarra<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SLP.- En el marco de la culminaci\u00f3n del Festival Internacional de Danza \u201c Lila L\u00f3pez\u201d la Secretar\u00eda de Cultura entreg\u00f3 los reconocimientos del Premio de Periodismo Cultural \u201cLuis Bruno Ruiz\u201d. El objetivo de esta convocatoria fue el de fomentar el ejercicio del periodismo cultural especializado en danza contempor\u00e1nea y generar espacios de visibilidad en este g\u00e9nero period\u00edstico, mismo que hab\u00eda sido suspendido desde hace tiempo. Cabe se\u00f1alar que en este Festival Internacional de Danza \u201cLila L\u00f3pez\u201d asistieron 9 mil personas con aforos reducidos por la contingencia sanitaria. Asimismo, se realizaron 31 presentaciones al p\u00fablico en general, participaron 25 compa\u00f1\u00edas danc\u00edsticas, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":71778,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"footnotes":""},"categories":[5,45],"tags":[],"class_list":["post-71762","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-destacadas","category-localesyregionales","post_format-post-format-video","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Impulsa Secretar\u00eda de Cultura ejercicio del periodismo, en el marco de la culminaci\u00f3n del Festival Internacional de Danza Contempor\u00e1nea &quot;Lila L\u00f3pez&quot;. - Canal 7 SLP - 2022<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2022\/impulsa-secretaria-de-cultura-ejercicio-del-periodismo-en-el-marco-de-la-culminacion-del-festival-internacional-de-danza-contemporanea-lila-lopez\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Impulsa Secretar\u00eda de Cultura ejercicio del periodismo, en el marco de la culminaci\u00f3n del Festival Internacional de Danza Contempor\u00e1nea &quot;Lila L\u00f3pez&quot;. - Canal 7 SLP - 2022\" \/>\n<meta property=\"og:description\" content=\"SLP.- En el marco de la culminaci\u00f3n del Festival Internacional de Danza \u201c Lila L\u00f3pez\u201d la Secretar\u00eda de Cultura entreg\u00f3 los reconocimientos del Premio de Periodismo Cultural \u201cLuis Bruno Ruiz\u201d. El objetivo de esta convocatoria fue el de fomentar el ejercicio del periodismo cultural especializado en danza contempor\u00e1nea y generar espacios de visibilidad en este g\u00e9nero period\u00edstico, mismo que hab\u00eda sido suspendido desde hace tiempo. Cabe se\u00f1alar que en este Festival Internacional de Danza \u201cLila L\u00f3pez\u201d asistieron 9 mil personas con aforos reducidos por la contingencia sanitaria. Asimismo, se realizaron 31 presentaciones al p\u00fablico en general, participaron 25 compa\u00f1\u00edas danc\u00edsticas, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2022\/impulsa-secretaria-de-cultura-ejercicio-del-periodismo-en-el-marco-de-la-culminacion-del-festival-internacional-de-danza-contemporanea-lila-lopez\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2022\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanalsiete\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-02T23:21:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/09\/Claudio01Culturales.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"888\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/impulsa-secretaria-de-cultura-ejercicio-del-periodismo-en-el-marco-de-la-culminacion-del-festival-internacional-de-danza-contemporanea-lila-lopez\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/impulsa-secretaria-de-cultura-ejercicio-del-periodismo-en-el-marco-de-la-culminacion-del-festival-internacional-de-danza-contemporanea-lila-lopez\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/person\\\/429704152a21f5f856ce29aa69a238da\"},\"headline\":\"Impulsa Secretar\u00eda de Cultura ejercicio del periodismo, en el marco de la culminaci\u00f3n del Festival Internacional de Danza Contempor\u00e1nea \u00abLila L\u00f3pez\u00bb.\",\"datePublished\":\"2022-09-02T23:21:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/impulsa-secretaria-de-cultura-ejercicio-del-periodismo-en-el-marco-de-la-culminacion-del-festival-internacional-de-danza-contemporanea-lila-lopez\\\/\"},\"wordCount\":177,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/impulsa-secretaria-de-cultura-ejercicio-del-periodismo-en-el-marco-de-la-culminacion-del-festival-internacional-de-danza-contemporanea-lila-lopez\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Claudio01Culturales.jpg\",\"articleSection\":[\"DESTACADAS\",\"LOCALES Y REGIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/impulsa-secretaria-de-cultura-ejercicio-del-periodismo-en-el-marco-de-la-culminacion-del-festival-internacional-de-danza-contemporanea-lila-lopez\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/impulsa-secretaria-de-cultura-ejercicio-del-periodismo-en-el-marco-de-la-culminacion-del-festival-internacional-de-danza-contemporanea-lila-lopez\\\/\",\"name\":\"Impulsa Secretar\u00eda de Cultura ejercicio del periodismo, en el marco de la culminaci\u00f3n del Festival Internacional de Danza Contempor\u00e1nea \\\"Lila L\u00f3pez\\\". - Canal 7 SLP - 2022\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/impulsa-secretaria-de-cultura-ejercicio-del-periodismo-en-el-marco-de-la-culminacion-del-festival-internacional-de-danza-contemporanea-lila-lopez\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/impulsa-secretaria-de-cultura-ejercicio-del-periodismo-en-el-marco-de-la-culminacion-del-festival-internacional-de-danza-contemporanea-lila-lopez\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Claudio01Culturales.jpg\",\"datePublished\":\"2022-09-02T23:21:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/impulsa-secretaria-de-cultura-ejercicio-del-periodismo-en-el-marco-de-la-culminacion-del-festival-internacional-de-danza-contemporanea-lila-lopez\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/impulsa-secretaria-de-cultura-ejercicio-del-periodismo-en-el-marco-de-la-culminacion-del-festival-internacional-de-danza-contemporanea-lila-lopez\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/impulsa-secretaria-de-cultura-ejercicio-del-periodismo-en-el-marco-de-la-culminacion-del-festival-internacional-de-danza-contemporanea-lila-lopez\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Claudio01Culturales.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Claudio01Culturales.jpg\",\"width\":888,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/impulsa-secretaria-de-cultura-ejercicio-del-periodismo-en-el-marco-de-la-culminacion-del-festival-internacional-de-danza-contemporanea-lila-lopez\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Impulsa Secretar\u00eda de Cultura ejercicio del periodismo, en el marco de la culminaci\u00f3n del Festival Internacional de Danza Contempor\u00e1nea &#8220;Lila L\u00f3pez&#8221;.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanalsiete\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/person\\\/429704152a21f5f856ce29aa69a238da\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Impulsa Secretar\u00eda de Cultura ejercicio del periodismo, en el marco de la culminaci\u00f3n del Festival Internacional de Danza Contempor\u00e1nea \"Lila L\u00f3pez\". - Canal 7 SLP - 2022","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2022\/impulsa-secretaria-de-cultura-ejercicio-del-periodismo-en-el-marco-de-la-culminacion-del-festival-internacional-de-danza-contemporanea-lila-lopez\/","og_locale":"es_ES","og_type":"article","og_title":"Impulsa Secretar\u00eda de Cultura ejercicio del periodismo, en el marco de la culminaci\u00f3n del Festival Internacional de Danza Contempor\u00e1nea \"Lila L\u00f3pez\". - Canal 7 SLP - 2022","og_description":"SLP.- En el marco de la culminaci\u00f3n del Festival Internacional de Danza \u201c Lila L\u00f3pez\u201d la Secretar\u00eda de Cultura entreg\u00f3 los reconocimientos del Premio de Periodismo Cultural \u201cLuis Bruno Ruiz\u201d. El objetivo de esta convocatoria fue el de fomentar el ejercicio del periodismo cultural especializado en danza contempor\u00e1nea y generar espacios de visibilidad en este g\u00e9nero period\u00edstico, mismo que hab\u00eda sido suspendido desde hace tiempo. Cabe se\u00f1alar que en este Festival Internacional de Danza \u201cLila L\u00f3pez\u201d asistieron 9 mil personas con aforos reducidos por la contingencia sanitaria. Asimismo, se realizaron 31 presentaciones al p\u00fablico en general, participaron 25 compa\u00f1\u00edas danc\u00edsticas, [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2022\/impulsa-secretaria-de-cultura-ejercicio-del-periodismo-en-el-marco-de-la-culminacion-del-festival-internacional-de-danza-contemporanea-lila-lopez\/","og_site_name":"Canal 7 SLP - 2022","article_publisher":"https:\/\/www.facebook.com\/noticieroscanalsiete","article_published_time":"2022-09-02T23:21:32+00:00","og_image":[{"width":888,"height":500,"url":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/09\/Claudio01Culturales.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2022\/impulsa-secretaria-de-cultura-ejercicio-del-periodismo-en-el-marco-de-la-culminacion-del-festival-internacional-de-danza-contemporanea-lila-lopez\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2022\/impulsa-secretaria-de-cultura-ejercicio-del-periodismo-en-el-marco-de-la-culminacion-del-festival-internacional-de-danza-contemporanea-lila-lopez\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/person\/429704152a21f5f856ce29aa69a238da"},"headline":"Impulsa Secretar\u00eda de Cultura ejercicio del periodismo, en el marco de la culminaci\u00f3n del Festival Internacional de Danza Contempor\u00e1nea \u00abLila L\u00f3pez\u00bb.","datePublished":"2022-09-02T23:21:32+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2022\/impulsa-secretaria-de-cultura-ejercicio-del-periodismo-en-el-marco-de-la-culminacion-del-festival-internacional-de-danza-contemporanea-lila-lopez\/"},"wordCount":177,"publisher":{"@id":"https:\/\/canal7slp.tv\/2022\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2022\/impulsa-secretaria-de-cultura-ejercicio-del-periodismo-en-el-marco-de-la-culminacion-del-festival-internacional-de-danza-contemporanea-lila-lopez\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/09\/Claudio01Culturales.jpg","articleSection":["DESTACADAS","LOCALES Y REGIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2022\/impulsa-secretaria-de-cultura-ejercicio-del-periodismo-en-el-marco-de-la-culminacion-del-festival-internacional-de-danza-contemporanea-lila-lopez\/","url":"https:\/\/canal7slp.tv\/2022\/impulsa-secretaria-de-cultura-ejercicio-del-periodismo-en-el-marco-de-la-culminacion-del-festival-internacional-de-danza-contemporanea-lila-lopez\/","name":"Impulsa Secretar\u00eda de Cultura ejercicio del periodismo, en el marco de la culminaci\u00f3n del Festival Internacional de Danza Contempor\u00e1nea \"Lila L\u00f3pez\". - Canal 7 SLP - 2022","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2022\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2022\/impulsa-secretaria-de-cultura-ejercicio-del-periodismo-en-el-marco-de-la-culminacion-del-festival-internacional-de-danza-contemporanea-lila-lopez\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2022\/impulsa-secretaria-de-cultura-ejercicio-del-periodismo-en-el-marco-de-la-culminacion-del-festival-internacional-de-danza-contemporanea-lila-lopez\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/09\/Claudio01Culturales.jpg","datePublished":"2022-09-02T23:21:32+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2022\/impulsa-secretaria-de-cultura-ejercicio-del-periodismo-en-el-marco-de-la-culminacion-del-festival-internacional-de-danza-contemporanea-lila-lopez\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2022\/impulsa-secretaria-de-cultura-ejercicio-del-periodismo-en-el-marco-de-la-culminacion-del-festival-internacional-de-danza-contemporanea-lila-lopez\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2022\/impulsa-secretaria-de-cultura-ejercicio-del-periodismo-en-el-marco-de-la-culminacion-del-festival-internacional-de-danza-contemporanea-lila-lopez\/#primaryimage","url":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/09\/Claudio01Culturales.jpg","contentUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/09\/Claudio01Culturales.jpg","width":888,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2022\/impulsa-secretaria-de-cultura-ejercicio-del-periodismo-en-el-marco-de-la-culminacion-del-festival-internacional-de-danza-contemporanea-lila-lopez\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2022\/"},{"@type":"ListItem","position":2,"name":"Impulsa Secretar\u00eda de Cultura ejercicio del periodismo, en el marco de la culminaci\u00f3n del Festival Internacional de Danza Contempor\u00e1nea &#8220;Lila L\u00f3pez&#8221;."}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2022\/#website","url":"https:\/\/canal7slp.tv\/2022\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2022\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2022\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2022\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2022\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanalsiete","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/person\/429704152a21f5f856ce29aa69a238da","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2022\/author\/edicionweb\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts\/71762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/comments?post=71762"}],"version-history":[{"count":4,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts\/71762\/revisions"}],"predecessor-version":[{"id":71781,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts\/71762\/revisions\/71781"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/media\/71778"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/media?parent=71762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/categories?post=71762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/tags?post=71762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}