{"id":70989,"date":"2022-08-26T16:26:47","date_gmt":"2022-08-26T22:26:47","guid":{"rendered":"https:\/\/canal7slp.tv\/2022\/?p=70989"},"modified":"2022-08-26T16:26:47","modified_gmt":"2022-08-26T22:26:47","slug":"mexico-supera-los-siete-millones-de-casos-de-covid-19","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2022\/mexico-supera-los-siete-millones-de-casos-de-covid-19\/","title":{"rendered":"M\u00e9xico supera los siete millones de casos de COVID-19"},"content":{"rendered":"<p style=\"text-align: justify;\">M\u00e9xico.- La Secretar\u00eda de Salud (Ssa), inform\u00f3 que al corte del 25 de agosto, se reportaron 7 mil 281 contagios de COVID-19, lo que sum\u00f3 7 millones 001 mil 590 infecciones totales desde el inicio de la pandemia.<\/p>\n<p style=\"text-align: justify;\">Asimismo, se suman 64 nuevas defunciones por la enfermedad, lo que da un acumulado de 329 mil 289 fallecidos.<\/p>\n<p style=\"text-align: justify;\">La dependencia detall\u00f3 que de la distribuci\u00f3n de los casos estimados por los grupos de edad seleccionados y semanas epidemiol\u00f3gicas del 2020, 2021 y 2022, en las \u00faltimas cinco semanas, la mayor parte de los casos est\u00e1n presentes en los grupos de 18 a 29 a\u00f1os, seguido del grupo de 30 a 39 a\u00f1os y 40 a 49 a\u00f1os.<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s expuso que de los casos confirmados acumulados por entidad de residencia, las diez primeras entidades que acumulan el mayor n\u00famero de casos son: Ciudad de M\u00e9xico, Estado de M\u00e9xico, Nuevo Le\u00f3n, Guanajuato, Jalisco, San Luis Potos\u00ed, Veracruz, Tabasco, Puebla y Sonora, que en conjunto conforman el 64% de todos los casos acumulados registrados en el pa\u00eds.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e9xico.- La Secretar\u00eda de Salud (Ssa), inform\u00f3 que al corte del 25 de agosto, se reportaron 7 mil 281 contagios de COVID-19, lo que sum\u00f3 7 millones 001 mil 590 infecciones totales desde el inicio de la pandemia. Asimismo, se suman 64 nuevas defunciones por la enfermedad, lo que da un acumulado de 329 mil 289 fallecidos. La dependencia detall\u00f3 que de la distribuci\u00f3n de los casos estimados por los grupos de edad seleccionados y semanas epidemiol\u00f3gicas del 2020, 2021 y 2022, en las \u00faltimas cinco semanas, la mayor parte de los casos est\u00e1n presentes en los grupos de 18 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":71001,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,46],"tags":[],"class_list":["post-70989","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-covid-19","category-nacional","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00e9xico supera los siete millones de casos de COVID-19 - Canal 7 SLP - 2022<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2022\/mexico-supera-los-siete-millones-de-casos-de-covid-19\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e9xico supera los siete millones de casos de COVID-19 - Canal 7 SLP - 2022\" \/>\n<meta property=\"og:description\" content=\"M\u00e9xico.- La Secretar\u00eda de Salud (Ssa), inform\u00f3 que al corte del 25 de agosto, se reportaron 7 mil 281 contagios de COVID-19, lo que sum\u00f3 7 millones 001 mil 590 infecciones totales desde el inicio de la pandemia. Asimismo, se suman 64 nuevas defunciones por la enfermedad, lo que da un acumulado de 329 mil 289 fallecidos. La dependencia detall\u00f3 que de la distribuci\u00f3n de los casos estimados por los grupos de edad seleccionados y semanas epidemiol\u00f3gicas del 2020, 2021 y 2022, en las \u00faltimas cinco semanas, la mayor parte de los casos est\u00e1n presentes en los grupos de 18 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2022\/mexico-supera-los-siete-millones-de-casos-de-covid-19\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2022\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanalsiete\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-26T22:26:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/08\/03-3.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"838\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/mexico-supera-los-siete-millones-de-casos-de-covid-19\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/mexico-supera-los-siete-millones-de-casos-de-covid-19\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/person\\\/429704152a21f5f856ce29aa69a238da\"},\"headline\":\"M\u00e9xico supera los siete millones de casos de COVID-19\",\"datePublished\":\"2022-08-26T22:26:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/mexico-supera-los-siete-millones-de-casos-de-covid-19\\\/\"},\"wordCount\":179,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/mexico-supera-los-siete-millones-de-casos-de-covid-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/03-3.jpeg\",\"articleSection\":[\"COVID-19\",\"NACIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/mexico-supera-los-siete-millones-de-casos-de-covid-19\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/mexico-supera-los-siete-millones-de-casos-de-covid-19\\\/\",\"name\":\"M\u00e9xico supera los siete millones de casos de COVID-19 - Canal 7 SLP - 2022\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/mexico-supera-los-siete-millones-de-casos-de-covid-19\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/mexico-supera-los-siete-millones-de-casos-de-covid-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/03-3.jpeg\",\"datePublished\":\"2022-08-26T22:26:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/mexico-supera-los-siete-millones-de-casos-de-covid-19\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/mexico-supera-los-siete-millones-de-casos-de-covid-19\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/mexico-supera-los-siete-millones-de-casos-de-covid-19\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/03-3.jpeg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/03-3.jpeg\",\"width\":1280,\"height\":838,\"caption\":\"CIUDAD DE M\u00c9XICO, 14ENERO2022.- CIUDAD DE M\u00c9XICO, 14ENERO2022.- En el Hospital General Regional No. 1 Dr. Carlos Mac Gregor S\u00e1nchez contin\u00faan las filas para practicarse pruebas Covid-19 tras el alza de casos registrados las \u00faltimas semanas. FOTO: EDGAR NEGRETE\\\/CUARTOSCURO.COM\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/mexico-supera-los-siete-millones-de-casos-de-covid-19\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e9xico supera los siete millones de casos de COVID-19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanalsiete\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/person\\\/429704152a21f5f856ce29aa69a238da\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e9xico supera los siete millones de casos de COVID-19 - Canal 7 SLP - 2022","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2022\/mexico-supera-los-siete-millones-de-casos-de-covid-19\/","og_locale":"es_ES","og_type":"article","og_title":"M\u00e9xico supera los siete millones de casos de COVID-19 - Canal 7 SLP - 2022","og_description":"M\u00e9xico.- La Secretar\u00eda de Salud (Ssa), inform\u00f3 que al corte del 25 de agosto, se reportaron 7 mil 281 contagios de COVID-19, lo que sum\u00f3 7 millones 001 mil 590 infecciones totales desde el inicio de la pandemia. Asimismo, se suman 64 nuevas defunciones por la enfermedad, lo que da un acumulado de 329 mil 289 fallecidos. La dependencia detall\u00f3 que de la distribuci\u00f3n de los casos estimados por los grupos de edad seleccionados y semanas epidemiol\u00f3gicas del 2020, 2021 y 2022, en las \u00faltimas cinco semanas, la mayor parte de los casos est\u00e1n presentes en los grupos de 18 [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2022\/mexico-supera-los-siete-millones-de-casos-de-covid-19\/","og_site_name":"Canal 7 SLP - 2022","article_publisher":"https:\/\/www.facebook.com\/noticieroscanalsiete","article_published_time":"2022-08-26T22:26:47+00:00","og_image":[{"width":1280,"height":838,"url":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/08\/03-3.jpeg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2022\/mexico-supera-los-siete-millones-de-casos-de-covid-19\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2022\/mexico-supera-los-siete-millones-de-casos-de-covid-19\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/person\/429704152a21f5f856ce29aa69a238da"},"headline":"M\u00e9xico supera los siete millones de casos de COVID-19","datePublished":"2022-08-26T22:26:47+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2022\/mexico-supera-los-siete-millones-de-casos-de-covid-19\/"},"wordCount":179,"publisher":{"@id":"https:\/\/canal7slp.tv\/2022\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2022\/mexico-supera-los-siete-millones-de-casos-de-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/08\/03-3.jpeg","articleSection":["COVID-19","NACIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2022\/mexico-supera-los-siete-millones-de-casos-de-covid-19\/","url":"https:\/\/canal7slp.tv\/2022\/mexico-supera-los-siete-millones-de-casos-de-covid-19\/","name":"M\u00e9xico supera los siete millones de casos de COVID-19 - Canal 7 SLP - 2022","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2022\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2022\/mexico-supera-los-siete-millones-de-casos-de-covid-19\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2022\/mexico-supera-los-siete-millones-de-casos-de-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/08\/03-3.jpeg","datePublished":"2022-08-26T22:26:47+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2022\/mexico-supera-los-siete-millones-de-casos-de-covid-19\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2022\/mexico-supera-los-siete-millones-de-casos-de-covid-19\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2022\/mexico-supera-los-siete-millones-de-casos-de-covid-19\/#primaryimage","url":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/08\/03-3.jpeg","contentUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/08\/03-3.jpeg","width":1280,"height":838,"caption":"CIUDAD DE M\u00c9XICO, 14ENERO2022.- CIUDAD DE M\u00c9XICO, 14ENERO2022.- En el Hospital General Regional No. 1 Dr. Carlos Mac Gregor S\u00e1nchez contin\u00faan las filas para practicarse pruebas Covid-19 tras el alza de casos registrados las \u00faltimas semanas. FOTO: EDGAR NEGRETE\/CUARTOSCURO.COM"},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2022\/mexico-supera-los-siete-millones-de-casos-de-covid-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2022\/"},{"@type":"ListItem","position":2,"name":"M\u00e9xico supera los siete millones de casos de COVID-19"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2022\/#website","url":"https:\/\/canal7slp.tv\/2022\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2022\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2022\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2022\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2022\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanalsiete","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/person\/429704152a21f5f856ce29aa69a238da","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2022\/author\/edicionweb\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts\/70989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/comments?post=70989"}],"version-history":[{"count":1,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts\/70989\/revisions"}],"predecessor-version":[{"id":70995,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts\/70989\/revisions\/70995"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/media\/71001"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/media?parent=70989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/categories?post=70989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/tags?post=70989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}