{"id":69906,"date":"2022-08-16T17:04:22","date_gmt":"2022-08-16T23:04:22","guid":{"rendered":"https:\/\/canal7slp.tv\/2022\/?p=69906"},"modified":"2022-08-16T17:04:22","modified_gmt":"2022-08-16T23:04:22","slug":"autoridades-de-ciudad-fernandez-realizaron-la-reapertura-de-la-biblioteca-adolfo-lopez-mateos","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2022\/autoridades-de-ciudad-fernandez-realizaron-la-reapertura-de-la-biblioteca-adolfo-lopez-mateos\/","title":{"rendered":"Autoridades de Ciudad Fern\u00e1ndez realizaron la reapertura de la biblioteca \u00abAdolfo L\u00f3pez Mateos\u00bb."},"content":{"rendered":"<p>Ciudad Fern\u00e1ndez.-<\/p>\n<p>Por: X\u00f3chitl Morales<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ciudad Fern\u00e1ndez.- Por: X\u00f3chitl Morales<\/p>\n","protected":false},"author":2,"featured_media":69907,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"footnotes":""},"categories":[5,43],"tags":[],"class_list":["post-69906","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-destacadas","category-interior","post_format-post-format-video","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Autoridades de Ciudad Fern\u00e1ndez realizaron la reapertura de la biblioteca &quot;Adolfo L\u00f3pez Mateos&quot;. - Canal 7 SLP - 2022<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2022\/autoridades-de-ciudad-fernandez-realizaron-la-reapertura-de-la-biblioteca-adolfo-lopez-mateos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Autoridades de Ciudad Fern\u00e1ndez realizaron la reapertura de la biblioteca &quot;Adolfo L\u00f3pez Mateos&quot;. - Canal 7 SLP - 2022\" \/>\n<meta property=\"og:description\" content=\"Ciudad Fern\u00e1ndez.- Por: X\u00f3chitl Morales\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2022\/autoridades-de-ciudad-fernandez-realizaron-la-reapertura-de-la-biblioteca-adolfo-lopez-mateos\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2022\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanalsiete\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-16T23:04:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/08\/Xochi02Biblioteca.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"888\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/autoridades-de-ciudad-fernandez-realizaron-la-reapertura-de-la-biblioteca-adolfo-lopez-mateos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/autoridades-de-ciudad-fernandez-realizaron-la-reapertura-de-la-biblioteca-adolfo-lopez-mateos\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/person\\\/429704152a21f5f856ce29aa69a238da\"},\"headline\":\"Autoridades de Ciudad Fern\u00e1ndez realizaron la reapertura de la biblioteca \u00abAdolfo L\u00f3pez Mateos\u00bb.\",\"datePublished\":\"2022-08-16T23:04:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/autoridades-de-ciudad-fernandez-realizaron-la-reapertura-de-la-biblioteca-adolfo-lopez-mateos\\\/\"},\"wordCount\":23,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/autoridades-de-ciudad-fernandez-realizaron-la-reapertura-de-la-biblioteca-adolfo-lopez-mateos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Xochi02Biblioteca.jpg\",\"articleSection\":[\"DESTACADAS\",\"INTERIOR DEL ESTADO\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/autoridades-de-ciudad-fernandez-realizaron-la-reapertura-de-la-biblioteca-adolfo-lopez-mateos\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/autoridades-de-ciudad-fernandez-realizaron-la-reapertura-de-la-biblioteca-adolfo-lopez-mateos\\\/\",\"name\":\"Autoridades de Ciudad Fern\u00e1ndez realizaron la reapertura de la biblioteca \\\"Adolfo L\u00f3pez Mateos\\\". - Canal 7 SLP - 2022\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/autoridades-de-ciudad-fernandez-realizaron-la-reapertura-de-la-biblioteca-adolfo-lopez-mateos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/autoridades-de-ciudad-fernandez-realizaron-la-reapertura-de-la-biblioteca-adolfo-lopez-mateos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Xochi02Biblioteca.jpg\",\"datePublished\":\"2022-08-16T23:04:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/autoridades-de-ciudad-fernandez-realizaron-la-reapertura-de-la-biblioteca-adolfo-lopez-mateos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/autoridades-de-ciudad-fernandez-realizaron-la-reapertura-de-la-biblioteca-adolfo-lopez-mateos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/autoridades-de-ciudad-fernandez-realizaron-la-reapertura-de-la-biblioteca-adolfo-lopez-mateos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Xochi02Biblioteca.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Xochi02Biblioteca.jpg\",\"width\":888,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/autoridades-de-ciudad-fernandez-realizaron-la-reapertura-de-la-biblioteca-adolfo-lopez-mateos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Autoridades de Ciudad Fern\u00e1ndez realizaron la reapertura de la biblioteca &#8220;Adolfo L\u00f3pez Mateos&#8221;.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanalsiete\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/person\\\/429704152a21f5f856ce29aa69a238da\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Autoridades de Ciudad Fern\u00e1ndez realizaron la reapertura de la biblioteca \"Adolfo L\u00f3pez Mateos\". - Canal 7 SLP - 2022","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2022\/autoridades-de-ciudad-fernandez-realizaron-la-reapertura-de-la-biblioteca-adolfo-lopez-mateos\/","og_locale":"es_ES","og_type":"article","og_title":"Autoridades de Ciudad Fern\u00e1ndez realizaron la reapertura de la biblioteca \"Adolfo L\u00f3pez Mateos\". - Canal 7 SLP - 2022","og_description":"Ciudad Fern\u00e1ndez.- Por: X\u00f3chitl Morales","og_url":"https:\/\/canal7slp.tv\/2022\/autoridades-de-ciudad-fernandez-realizaron-la-reapertura-de-la-biblioteca-adolfo-lopez-mateos\/","og_site_name":"Canal 7 SLP - 2022","article_publisher":"https:\/\/www.facebook.com\/noticieroscanalsiete","article_published_time":"2022-08-16T23:04:22+00:00","og_image":[{"width":888,"height":500,"url":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/08\/Xochi02Biblioteca.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2022\/autoridades-de-ciudad-fernandez-realizaron-la-reapertura-de-la-biblioteca-adolfo-lopez-mateos\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2022\/autoridades-de-ciudad-fernandez-realizaron-la-reapertura-de-la-biblioteca-adolfo-lopez-mateos\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/person\/429704152a21f5f856ce29aa69a238da"},"headline":"Autoridades de Ciudad Fern\u00e1ndez realizaron la reapertura de la biblioteca \u00abAdolfo L\u00f3pez Mateos\u00bb.","datePublished":"2022-08-16T23:04:22+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2022\/autoridades-de-ciudad-fernandez-realizaron-la-reapertura-de-la-biblioteca-adolfo-lopez-mateos\/"},"wordCount":23,"publisher":{"@id":"https:\/\/canal7slp.tv\/2022\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2022\/autoridades-de-ciudad-fernandez-realizaron-la-reapertura-de-la-biblioteca-adolfo-lopez-mateos\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/08\/Xochi02Biblioteca.jpg","articleSection":["DESTACADAS","INTERIOR DEL ESTADO"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2022\/autoridades-de-ciudad-fernandez-realizaron-la-reapertura-de-la-biblioteca-adolfo-lopez-mateos\/","url":"https:\/\/canal7slp.tv\/2022\/autoridades-de-ciudad-fernandez-realizaron-la-reapertura-de-la-biblioteca-adolfo-lopez-mateos\/","name":"Autoridades de Ciudad Fern\u00e1ndez realizaron la reapertura de la biblioteca \"Adolfo L\u00f3pez Mateos\". - Canal 7 SLP - 2022","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2022\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2022\/autoridades-de-ciudad-fernandez-realizaron-la-reapertura-de-la-biblioteca-adolfo-lopez-mateos\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2022\/autoridades-de-ciudad-fernandez-realizaron-la-reapertura-de-la-biblioteca-adolfo-lopez-mateos\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/08\/Xochi02Biblioteca.jpg","datePublished":"2022-08-16T23:04:22+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2022\/autoridades-de-ciudad-fernandez-realizaron-la-reapertura-de-la-biblioteca-adolfo-lopez-mateos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2022\/autoridades-de-ciudad-fernandez-realizaron-la-reapertura-de-la-biblioteca-adolfo-lopez-mateos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2022\/autoridades-de-ciudad-fernandez-realizaron-la-reapertura-de-la-biblioteca-adolfo-lopez-mateos\/#primaryimage","url":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/08\/Xochi02Biblioteca.jpg","contentUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/08\/Xochi02Biblioteca.jpg","width":888,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2022\/autoridades-de-ciudad-fernandez-realizaron-la-reapertura-de-la-biblioteca-adolfo-lopez-mateos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2022\/"},{"@type":"ListItem","position":2,"name":"Autoridades de Ciudad Fern\u00e1ndez realizaron la reapertura de la biblioteca &#8220;Adolfo L\u00f3pez Mateos&#8221;."}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2022\/#website","url":"https:\/\/canal7slp.tv\/2022\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2022\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2022\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2022\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2022\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanalsiete","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/person\/429704152a21f5f856ce29aa69a238da","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2022\/author\/edicionweb\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts\/69906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/comments?post=69906"}],"version-history":[{"count":1,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts\/69906\/revisions"}],"predecessor-version":[{"id":69908,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts\/69906\/revisions\/69908"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/media\/69907"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/media?parent=69906"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/categories?post=69906"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/tags?post=69906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}