{"id":69261,"date":"2022-08-10T16:52:58","date_gmt":"2022-08-10T22:52:58","guid":{"rendered":"https:\/\/canal7slp.tv\/2022\/?p=69261"},"modified":"2022-08-10T16:52:58","modified_gmt":"2022-08-10T22:52:58","slug":"cabildo-de-sgs-abordara-en-proximos-meses-la-desincorporacion-del-interapas","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2022\/cabildo-de-sgs-abordara-en-proximos-meses-la-desincorporacion-del-interapas\/","title":{"rendered":"Cabildo de SGS abordar\u00e1 en pr\u00f3ximos meses la desincorporaci\u00f3n del Interapas."},"content":{"rendered":"<p style=\"text-align: justify;\">SGS.- La alcaldesa de Soledad de Graciano S\u00e1nchez, Leonor Noyola Cervantes, inform\u00f3 que ser\u00eda en el pr\u00f3ximo mes de septiembre cuando se presente ante los integrantes de cabildo el proyecto de desincorporaci\u00f3n del Interapas, para posteriormente ser dictaminado y se analice en Congreso del Estado de San Luis Potos\u00ed.<\/p>\n<p style=\"text-align: justify;\">Indic\u00f3 que en el mes de octubre o noviembre se tendr\u00eda ya un panorama m\u00e1s general luego ser cuestionada sobre el recurso que se necesita para poder operar de manera aut\u00f3noma el servicio del agua potable.<\/p>\n<p style=\"text-align: justify;\">\u201cAhorita lo estamos trabajando, es un proyecto que traemos en an\u00e1lisis, en estudio, desde un inicio de la administraci\u00f3n y si fuera necesario pues claro que lo vamos a solicitar a qui\u00e9n sea\u201d, dijo al respecto.<\/p>\n<p style=\"text-align: justify;\">Noyola Cervantes asegur\u00f3 que con la desincorporaci\u00f3n del municipio tambi\u00e9n se beneficiar\u00e1 a la capital potosina pues la carga de trabajo en el organismo operador se reducir\u00e1 notablemente.<\/p>\n<p style=\"text-align: justify;\">\u201cEs para mejorar todo Soledad y capital, si ahorita el Interapas se encuentra deteriorado en cuesti\u00f3n econ\u00f3mica, nosotros nos haremos cargo de Soledad para que San Luis capital, no tenga esa problem\u00e1tica del desabasto del agua\u201d, agreg\u00f3.<\/p>\n<p style=\"text-align: justify;\">La funcionaria explic\u00f3 que actualmente se analizan los costos que todo lo que conlleva esta separaci\u00f3n, sin embargo, destac\u00f3 que la demarcaci\u00f3n cuenta con al menos 35 pozos de agua que abastecer\u00edan a la poblaci\u00f3n soledense.<\/p>\n<p>Por: Jos\u00e9 Luis V\u00e1zquez<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SGS.- La alcaldesa de Soledad de Graciano S\u00e1nchez, Leonor Noyola Cervantes, inform\u00f3 que ser\u00eda en el pr\u00f3ximo mes de septiembre cuando se presente ante los integrantes de cabildo el proyecto de desincorporaci\u00f3n del Interapas, para posteriormente ser dictaminado y se analice en Congreso del Estado de San Luis Potos\u00ed. Indic\u00f3 que en el mes de octubre o noviembre se tendr\u00eda ya un panorama m\u00e1s general luego ser cuestionada sobre el recurso que se necesita para poder operar de manera aut\u00f3noma el servicio del agua potable. \u201cAhorita lo estamos trabajando, es un proyecto que traemos en an\u00e1lisis, en estudio, desde un [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":69294,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"footnotes":""},"categories":[512,5,45],"tags":[],"class_list":["post-69261","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-ayosgs","category-destacadas","category-localesyregionales","post_format-post-format-video","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cabildo de SGS abordar\u00e1 en pr\u00f3ximos meses la desincorporaci\u00f3n del Interapas. - Canal 7 SLP - 2022<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2022\/cabildo-de-sgs-abordara-en-proximos-meses-la-desincorporacion-del-interapas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cabildo de SGS abordar\u00e1 en pr\u00f3ximos meses la desincorporaci\u00f3n del Interapas. - Canal 7 SLP - 2022\" \/>\n<meta property=\"og:description\" content=\"SGS.- La alcaldesa de Soledad de Graciano S\u00e1nchez, Leonor Noyola Cervantes, inform\u00f3 que ser\u00eda en el pr\u00f3ximo mes de septiembre cuando se presente ante los integrantes de cabildo el proyecto de desincorporaci\u00f3n del Interapas, para posteriormente ser dictaminado y se analice en Congreso del Estado de San Luis Potos\u00ed. Indic\u00f3 que en el mes de octubre o noviembre se tendr\u00eda ya un panorama m\u00e1s general luego ser cuestionada sobre el recurso que se necesita para poder operar de manera aut\u00f3noma el servicio del agua potable. \u201cAhorita lo estamos trabajando, es un proyecto que traemos en an\u00e1lisis, en estudio, desde un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2022\/cabildo-de-sgs-abordara-en-proximos-meses-la-desincorporacion-del-interapas\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2022\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanalsiete\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-10T22:52:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/08\/Vazquez04SGSInterapas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"888\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/cabildo-de-sgs-abordara-en-proximos-meses-la-desincorporacion-del-interapas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/cabildo-de-sgs-abordara-en-proximos-meses-la-desincorporacion-del-interapas\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/person\\\/429704152a21f5f856ce29aa69a238da\"},\"headline\":\"Cabildo de SGS abordar\u00e1 en pr\u00f3ximos meses la desincorporaci\u00f3n del Interapas.\",\"datePublished\":\"2022-08-10T22:52:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/cabildo-de-sgs-abordara-en-proximos-meses-la-desincorporacion-del-interapas\\\/\"},\"wordCount\":259,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/cabildo-de-sgs-abordara-en-proximos-meses-la-desincorporacion-del-interapas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Vazquez04SGSInterapas.jpg\",\"articleSection\":[\"AYOSGS\",\"DESTACADAS\",\"LOCALES Y REGIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/cabildo-de-sgs-abordara-en-proximos-meses-la-desincorporacion-del-interapas\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/cabildo-de-sgs-abordara-en-proximos-meses-la-desincorporacion-del-interapas\\\/\",\"name\":\"Cabildo de SGS abordar\u00e1 en pr\u00f3ximos meses la desincorporaci\u00f3n del Interapas. - Canal 7 SLP - 2022\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/cabildo-de-sgs-abordara-en-proximos-meses-la-desincorporacion-del-interapas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/cabildo-de-sgs-abordara-en-proximos-meses-la-desincorporacion-del-interapas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Vazquez04SGSInterapas.jpg\",\"datePublished\":\"2022-08-10T22:52:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/cabildo-de-sgs-abordara-en-proximos-meses-la-desincorporacion-del-interapas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/cabildo-de-sgs-abordara-en-proximos-meses-la-desincorporacion-del-interapas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/cabildo-de-sgs-abordara-en-proximos-meses-la-desincorporacion-del-interapas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Vazquez04SGSInterapas.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Vazquez04SGSInterapas.jpg\",\"width\":888,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/cabildo-de-sgs-abordara-en-proximos-meses-la-desincorporacion-del-interapas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cabildo de SGS abordar\u00e1 en pr\u00f3ximos meses la desincorporaci\u00f3n del Interapas.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanalsiete\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/person\\\/429704152a21f5f856ce29aa69a238da\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cabildo de SGS abordar\u00e1 en pr\u00f3ximos meses la desincorporaci\u00f3n del Interapas. - Canal 7 SLP - 2022","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2022\/cabildo-de-sgs-abordara-en-proximos-meses-la-desincorporacion-del-interapas\/","og_locale":"es_ES","og_type":"article","og_title":"Cabildo de SGS abordar\u00e1 en pr\u00f3ximos meses la desincorporaci\u00f3n del Interapas. - Canal 7 SLP - 2022","og_description":"SGS.- La alcaldesa de Soledad de Graciano S\u00e1nchez, Leonor Noyola Cervantes, inform\u00f3 que ser\u00eda en el pr\u00f3ximo mes de septiembre cuando se presente ante los integrantes de cabildo el proyecto de desincorporaci\u00f3n del Interapas, para posteriormente ser dictaminado y se analice en Congreso del Estado de San Luis Potos\u00ed. Indic\u00f3 que en el mes de octubre o noviembre se tendr\u00eda ya un panorama m\u00e1s general luego ser cuestionada sobre el recurso que se necesita para poder operar de manera aut\u00f3noma el servicio del agua potable. \u201cAhorita lo estamos trabajando, es un proyecto que traemos en an\u00e1lisis, en estudio, desde un [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2022\/cabildo-de-sgs-abordara-en-proximos-meses-la-desincorporacion-del-interapas\/","og_site_name":"Canal 7 SLP - 2022","article_publisher":"https:\/\/www.facebook.com\/noticieroscanalsiete","article_published_time":"2022-08-10T22:52:58+00:00","og_image":[{"width":888,"height":500,"url":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/08\/Vazquez04SGSInterapas.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2022\/cabildo-de-sgs-abordara-en-proximos-meses-la-desincorporacion-del-interapas\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2022\/cabildo-de-sgs-abordara-en-proximos-meses-la-desincorporacion-del-interapas\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/person\/429704152a21f5f856ce29aa69a238da"},"headline":"Cabildo de SGS abordar\u00e1 en pr\u00f3ximos meses la desincorporaci\u00f3n del Interapas.","datePublished":"2022-08-10T22:52:58+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2022\/cabildo-de-sgs-abordara-en-proximos-meses-la-desincorporacion-del-interapas\/"},"wordCount":259,"publisher":{"@id":"https:\/\/canal7slp.tv\/2022\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2022\/cabildo-de-sgs-abordara-en-proximos-meses-la-desincorporacion-del-interapas\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/08\/Vazquez04SGSInterapas.jpg","articleSection":["AYOSGS","DESTACADAS","LOCALES Y REGIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2022\/cabildo-de-sgs-abordara-en-proximos-meses-la-desincorporacion-del-interapas\/","url":"https:\/\/canal7slp.tv\/2022\/cabildo-de-sgs-abordara-en-proximos-meses-la-desincorporacion-del-interapas\/","name":"Cabildo de SGS abordar\u00e1 en pr\u00f3ximos meses la desincorporaci\u00f3n del Interapas. - Canal 7 SLP - 2022","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2022\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2022\/cabildo-de-sgs-abordara-en-proximos-meses-la-desincorporacion-del-interapas\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2022\/cabildo-de-sgs-abordara-en-proximos-meses-la-desincorporacion-del-interapas\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/08\/Vazquez04SGSInterapas.jpg","datePublished":"2022-08-10T22:52:58+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2022\/cabildo-de-sgs-abordara-en-proximos-meses-la-desincorporacion-del-interapas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2022\/cabildo-de-sgs-abordara-en-proximos-meses-la-desincorporacion-del-interapas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2022\/cabildo-de-sgs-abordara-en-proximos-meses-la-desincorporacion-del-interapas\/#primaryimage","url":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/08\/Vazquez04SGSInterapas.jpg","contentUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/08\/Vazquez04SGSInterapas.jpg","width":888,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2022\/cabildo-de-sgs-abordara-en-proximos-meses-la-desincorporacion-del-interapas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2022\/"},{"@type":"ListItem","position":2,"name":"Cabildo de SGS abordar\u00e1 en pr\u00f3ximos meses la desincorporaci\u00f3n del Interapas."}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2022\/#website","url":"https:\/\/canal7slp.tv\/2022\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2022\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2022\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2022\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2022\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanalsiete","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/person\/429704152a21f5f856ce29aa69a238da","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2022\/author\/edicionweb\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts\/69261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/comments?post=69261"}],"version-history":[{"count":3,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts\/69261\/revisions"}],"predecessor-version":[{"id":69295,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts\/69261\/revisions\/69295"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/media\/69294"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/media?parent=69261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/categories?post=69261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/tags?post=69261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}