{"id":65868,"date":"2022-07-07T12:10:49","date_gmt":"2022-07-07T18:10:49","guid":{"rendered":"https:\/\/canal7slp.tv\/2022\/?p=65868"},"modified":"2022-07-07T12:10:49","modified_gmt":"2022-07-07T18:10:49","slug":"este-viernes-inicia-en-san-luis-potosi-la-segunda-fase-de-vacunacion-contra-covid-19-en-ninas-y-ninos","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2022\/este-viernes-inicia-en-san-luis-potosi-la-segunda-fase-de-vacunacion-contra-covid-19-en-ninas-y-ninos\/","title":{"rendered":"Este viernes inicia en San Luis Potos\u00ed la segunda fase de vacunaci\u00f3n contra COVID-19 en ni\u00f1as y ni\u00f1os"},"content":{"rendered":"<p style=\"text-align: justify;\">SLP.-\u00a0La delegada del Instituto Mexicano del Seguro Social en San Luis Potos\u00ed, Mar\u00eda Guadalupe Garrido Rojano, inform\u00f3 que este viernes iniciar\u00e1 la segunda fase de vacunaci\u00f3n contra la covid-19 en ni\u00f1as y ni\u00f1os.<\/p>\n<p style=\"text-align: justify;\">\u00abContinuando con la etapa de vacunaci\u00f3n pedi\u00e1trica debemos comentar que vamos ahora con las ni\u00f1as y ni\u00f1os de 5 a 8 a\u00f1os, esta jornada dar\u00e1 inicio a partir del viernes 8 de julio, continuaremos el lunes 11, el martes 12 y el mi\u00e9rcoles 13 de julio<\/p>\n<p style=\"text-align: justify;\">Como en las pasadas jornadas de vacunaci\u00f3n, se seguir\u00e1 un sistema de orden alfab\u00e9tico, es decir, que dependiendo de la primera letra del apellido paterno del peque\u00f1o, se asignar\u00e1 un d\u00eda espec\u00edfico para acudir por sus respectivas dosis.<\/p>\n<p style=\"text-align: justify;\">\u00abLos ni\u00f1os van a acudir con sus pap\u00e1s el viernes 8, los de las letras: A, D, G, J, M, P, S, V; el lunes 11 con la letra: B, E, H, K, N, \u00d1, Q, T, W; el martes 12 de julio las letras: C, F, I, LL, O, R, U, X, Y, Z; y el mi\u00e9rcoles 13 de julio son las personas que no pudieron acudir en el d\u00eda que les correspond\u00eda\u00bb, detall\u00f3.<\/p>\n<p style=\"text-align: justify;\">En ese sentido, las autoridades informaron que se habilitar\u00e1n un total de siete sedes de vacunaci\u00f3n en la Zona Metropolitana, cuyo horario de atenci\u00f3n ser\u00e1 de 9 de la ma\u00f1ana a 5 de la tarde.<\/p>\n<p style=\"text-align: justify;\">Los documentos a presentar son la hoja de registro ante el portal del Gobierno Federales, el documento se obtiene a trav\u00e9s de la p\u00e1gina: mivacuna.salud.gob.mx; tambi\u00e9n deber\u00e1n presentarse con la CURP actualizada de la ni\u00f1a o ni\u00f1o.<\/p>\n<p style=\"text-align: justify;\">\u00abEs importante mencionar que por favor antes de ir hablen con los ni\u00f1os, expl\u00edquenles de qu\u00e9 se trata la vacunaci\u00f3n con el fin de generar confianza y que de esta manera colabore tranquilamente para que la vacunaci\u00f3n o causa estr\u00e9s a la o el menor\u00bb, agreg\u00f3.<\/p>\n<p style=\"text-align: justify;\">Se tiene que informar al personal de Salud si su hijo o hija tiene alguna alergia; por otro lado, se pide que las y los peque\u00f1os vayan desayunados y bien hidratados.<\/p>\n<p style=\"text-align: justify;\">\u00abLas misma recomendaciones que con los adultos es que despu\u00e9s de la aplicaci\u00f3n de la vacuna deben esperar de 15 a 30 minutos para una observaci\u00f3n m\u00e9dica y en caso de presentar alguna reacci\u00f3n ser\u00e1 atendido de forma inmediata\u00bb, indic\u00f3.<\/p>\n<p style=\"text-align: justify;\">Aunado a ello, se menciona el consultar con el profesional de su hija o hijo para ver si se puede aplicar un analg\u00e9sico que no contenga aspirina y otras medidas que puedan tomar en casa para que el o la menor se sienta m\u00e1s. c\u00f3moda<\/p>\n<p style=\"text-align: justify;\">\u00abNo se recomienda la administraci\u00f3n de analg\u00e9sicos antes de la vacunaci\u00f3n con el fin de intentar evitar los efectos secundarios y recibir el comprobante de vacunaci\u00f3n&#8230; Por favor, que vayan con la confianza de que sus ni\u00f1os van a ser bien tratados por el personal de salud, todos est\u00e1n capacitados para la aplicaci\u00f3n de esta vacuna a las y los ni\u00f1os\u00bb, termin\u00f3<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SLP.-\u00a0La delegada del Instituto Mexicano del Seguro Social en San Luis Potos\u00ed, Mar\u00eda Guadalupe Garrido Rojano, inform\u00f3 que este viernes iniciar\u00e1 la segunda fase de vacunaci\u00f3n contra la covid-19 en ni\u00f1as y ni\u00f1os. \u00abContinuando con la etapa de vacunaci\u00f3n pedi\u00e1trica debemos comentar que vamos ahora con las ni\u00f1as y ni\u00f1os de 5 a 8 a\u00f1os, esta jornada dar\u00e1 inicio a partir del viernes 8 de julio, continuaremos el lunes 11, el martes 12 y el mi\u00e9rcoles 13 de julio Como en las pasadas jornadas de vacunaci\u00f3n, se seguir\u00e1 un sistema de orden alfab\u00e9tico, es decir, que dependiendo de la primera [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":65869,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[45],"tags":[],"class_list":["post-65868","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-localesyregionales","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Este viernes inicia en San Luis Potos\u00ed la segunda fase de vacunaci\u00f3n contra COVID-19 en ni\u00f1as y ni\u00f1os - Canal 7 SLP - 2022<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2022\/este-viernes-inicia-en-san-luis-potosi-la-segunda-fase-de-vacunacion-contra-covid-19-en-ninas-y-ninos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Este viernes inicia en San Luis Potos\u00ed la segunda fase de vacunaci\u00f3n contra COVID-19 en ni\u00f1as y ni\u00f1os - Canal 7 SLP - 2022\" \/>\n<meta property=\"og:description\" content=\"SLP.-\u00a0La delegada del Instituto Mexicano del Seguro Social en San Luis Potos\u00ed, Mar\u00eda Guadalupe Garrido Rojano, inform\u00f3 que este viernes iniciar\u00e1 la segunda fase de vacunaci\u00f3n contra la covid-19 en ni\u00f1as y ni\u00f1os. \u00abContinuando con la etapa de vacunaci\u00f3n pedi\u00e1trica debemos comentar que vamos ahora con las ni\u00f1as y ni\u00f1os de 5 a 8 a\u00f1os, esta jornada dar\u00e1 inicio a partir del viernes 8 de julio, continuaremos el lunes 11, el martes 12 y el mi\u00e9rcoles 13 de julio Como en las pasadas jornadas de vacunaci\u00f3n, se seguir\u00e1 un sistema de orden alfab\u00e9tico, es decir, que dependiendo de la primera [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2022\/este-viernes-inicia-en-san-luis-potosi-la-segunda-fase-de-vacunacion-contra-covid-19-en-ninas-y-ninos\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2022\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanalsiete\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-07T18:10:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/07\/ssalud.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"415\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/este-viernes-inicia-en-san-luis-potosi-la-segunda-fase-de-vacunacion-contra-covid-19-en-ninas-y-ninos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/este-viernes-inicia-en-san-luis-potosi-la-segunda-fase-de-vacunacion-contra-covid-19-en-ninas-y-ninos\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/person\\\/429704152a21f5f856ce29aa69a238da\"},\"headline\":\"Este viernes inicia en San Luis Potos\u00ed la segunda fase de vacunaci\u00f3n contra COVID-19 en ni\u00f1as y ni\u00f1os\",\"datePublished\":\"2022-07-07T18:10:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/este-viernes-inicia-en-san-luis-potosi-la-segunda-fase-de-vacunacion-contra-covid-19-en-ninas-y-ninos\\\/\"},\"wordCount\":551,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/este-viernes-inicia-en-san-luis-potosi-la-segunda-fase-de-vacunacion-contra-covid-19-en-ninas-y-ninos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/ssalud.jpg\",\"articleSection\":[\"LOCALES Y REGIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/este-viernes-inicia-en-san-luis-potosi-la-segunda-fase-de-vacunacion-contra-covid-19-en-ninas-y-ninos\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/este-viernes-inicia-en-san-luis-potosi-la-segunda-fase-de-vacunacion-contra-covid-19-en-ninas-y-ninos\\\/\",\"name\":\"Este viernes inicia en San Luis Potos\u00ed la segunda fase de vacunaci\u00f3n contra COVID-19 en ni\u00f1as y ni\u00f1os - Canal 7 SLP - 2022\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/este-viernes-inicia-en-san-luis-potosi-la-segunda-fase-de-vacunacion-contra-covid-19-en-ninas-y-ninos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/este-viernes-inicia-en-san-luis-potosi-la-segunda-fase-de-vacunacion-contra-covid-19-en-ninas-y-ninos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/ssalud.jpg\",\"datePublished\":\"2022-07-07T18:10:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/este-viernes-inicia-en-san-luis-potosi-la-segunda-fase-de-vacunacion-contra-covid-19-en-ninas-y-ninos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/este-viernes-inicia-en-san-luis-potosi-la-segunda-fase-de-vacunacion-contra-covid-19-en-ninas-y-ninos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/este-viernes-inicia-en-san-luis-potosi-la-segunda-fase-de-vacunacion-contra-covid-19-en-ninas-y-ninos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/ssalud.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/ssalud.jpg\",\"width\":720,\"height\":415},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/este-viernes-inicia-en-san-luis-potosi-la-segunda-fase-de-vacunacion-contra-covid-19-en-ninas-y-ninos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Este viernes inicia en San Luis Potos\u00ed la segunda fase de vacunaci\u00f3n contra COVID-19 en ni\u00f1as y ni\u00f1os\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanalsiete\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/#\\\/schema\\\/person\\\/429704152a21f5f856ce29aa69a238da\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2022\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Este viernes inicia en San Luis Potos\u00ed la segunda fase de vacunaci\u00f3n contra COVID-19 en ni\u00f1as y ni\u00f1os - Canal 7 SLP - 2022","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2022\/este-viernes-inicia-en-san-luis-potosi-la-segunda-fase-de-vacunacion-contra-covid-19-en-ninas-y-ninos\/","og_locale":"es_ES","og_type":"article","og_title":"Este viernes inicia en San Luis Potos\u00ed la segunda fase de vacunaci\u00f3n contra COVID-19 en ni\u00f1as y ni\u00f1os - Canal 7 SLP - 2022","og_description":"SLP.-\u00a0La delegada del Instituto Mexicano del Seguro Social en San Luis Potos\u00ed, Mar\u00eda Guadalupe Garrido Rojano, inform\u00f3 que este viernes iniciar\u00e1 la segunda fase de vacunaci\u00f3n contra la covid-19 en ni\u00f1as y ni\u00f1os. \u00abContinuando con la etapa de vacunaci\u00f3n pedi\u00e1trica debemos comentar que vamos ahora con las ni\u00f1as y ni\u00f1os de 5 a 8 a\u00f1os, esta jornada dar\u00e1 inicio a partir del viernes 8 de julio, continuaremos el lunes 11, el martes 12 y el mi\u00e9rcoles 13 de julio Como en las pasadas jornadas de vacunaci\u00f3n, se seguir\u00e1 un sistema de orden alfab\u00e9tico, es decir, que dependiendo de la primera [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2022\/este-viernes-inicia-en-san-luis-potosi-la-segunda-fase-de-vacunacion-contra-covid-19-en-ninas-y-ninos\/","og_site_name":"Canal 7 SLP - 2022","article_publisher":"https:\/\/www.facebook.com\/noticieroscanalsiete","article_published_time":"2022-07-07T18:10:49+00:00","og_image":[{"width":720,"height":415,"url":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/07\/ssalud.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2022\/este-viernes-inicia-en-san-luis-potosi-la-segunda-fase-de-vacunacion-contra-covid-19-en-ninas-y-ninos\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2022\/este-viernes-inicia-en-san-luis-potosi-la-segunda-fase-de-vacunacion-contra-covid-19-en-ninas-y-ninos\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/person\/429704152a21f5f856ce29aa69a238da"},"headline":"Este viernes inicia en San Luis Potos\u00ed la segunda fase de vacunaci\u00f3n contra COVID-19 en ni\u00f1as y ni\u00f1os","datePublished":"2022-07-07T18:10:49+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2022\/este-viernes-inicia-en-san-luis-potosi-la-segunda-fase-de-vacunacion-contra-covid-19-en-ninas-y-ninos\/"},"wordCount":551,"publisher":{"@id":"https:\/\/canal7slp.tv\/2022\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2022\/este-viernes-inicia-en-san-luis-potosi-la-segunda-fase-de-vacunacion-contra-covid-19-en-ninas-y-ninos\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/07\/ssalud.jpg","articleSection":["LOCALES Y REGIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2022\/este-viernes-inicia-en-san-luis-potosi-la-segunda-fase-de-vacunacion-contra-covid-19-en-ninas-y-ninos\/","url":"https:\/\/canal7slp.tv\/2022\/este-viernes-inicia-en-san-luis-potosi-la-segunda-fase-de-vacunacion-contra-covid-19-en-ninas-y-ninos\/","name":"Este viernes inicia en San Luis Potos\u00ed la segunda fase de vacunaci\u00f3n contra COVID-19 en ni\u00f1as y ni\u00f1os - Canal 7 SLP - 2022","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2022\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2022\/este-viernes-inicia-en-san-luis-potosi-la-segunda-fase-de-vacunacion-contra-covid-19-en-ninas-y-ninos\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2022\/este-viernes-inicia-en-san-luis-potosi-la-segunda-fase-de-vacunacion-contra-covid-19-en-ninas-y-ninos\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/07\/ssalud.jpg","datePublished":"2022-07-07T18:10:49+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2022\/este-viernes-inicia-en-san-luis-potosi-la-segunda-fase-de-vacunacion-contra-covid-19-en-ninas-y-ninos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2022\/este-viernes-inicia-en-san-luis-potosi-la-segunda-fase-de-vacunacion-contra-covid-19-en-ninas-y-ninos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2022\/este-viernes-inicia-en-san-luis-potosi-la-segunda-fase-de-vacunacion-contra-covid-19-en-ninas-y-ninos\/#primaryimage","url":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/07\/ssalud.jpg","contentUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2022\/07\/ssalud.jpg","width":720,"height":415},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2022\/este-viernes-inicia-en-san-luis-potosi-la-segunda-fase-de-vacunacion-contra-covid-19-en-ninas-y-ninos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2022\/"},{"@type":"ListItem","position":2,"name":"Este viernes inicia en San Luis Potos\u00ed la segunda fase de vacunaci\u00f3n contra COVID-19 en ni\u00f1as y ni\u00f1os"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2022\/#website","url":"https:\/\/canal7slp.tv\/2022\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2022\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2022\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2022\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2022\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2022\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanalsiete","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2022\/#\/schema\/person\/429704152a21f5f856ce29aa69a238da","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2022\/author\/edicionweb\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts\/65868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/comments?post=65868"}],"version-history":[{"count":1,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts\/65868\/revisions"}],"predecessor-version":[{"id":65870,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/posts\/65868\/revisions\/65870"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/media\/65869"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/media?parent=65868"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/categories?post=65868"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2022\/wp-json\/wp\/v2\/tags?post=65868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}