{"id":5095,"date":"2021-02-21T15:39:40","date_gmt":"2021-02-21T21:39:40","guid":{"rendered":"https:\/\/canal7slp.tv\/2021\/?p=5095"},"modified":"2021-02-21T15:39:40","modified_gmt":"2021-02-21T21:39:40","slug":"admiten-amparo-contra-orden-de-aprehension-de-garcia-luna","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2021\/admiten-amparo-contra-orden-de-aprehension-de-garcia-luna\/","title":{"rendered":"Admiten amparo contra orden de aprehensi\u00f3n de Garc\u00eda Luna"},"content":{"rendered":"<p style=\"text-align: justify;\">M\u00e9xico.- La titular del Juzgado D\u00e9cimo Sexto de Distrito de Amparo en Materia Penal admiti\u00f3 la demanda de amparo que interpuso Genaro Garc\u00eda Luna el pasado 16 de febrero contra la orden de aprehensi\u00f3n en su contra por el delito de enriquecimiento il\u00edcito.<\/p>\n<p style=\"text-align: justify;\">La Juez Federal, no concedi\u00f3 la suspensi\u00f3n provisional a Garc\u00eda Luna, preso en Estados Unidos por presuntos nexos con el C\u00e1rtel de Sinaloa, ya que no la solicit\u00f3 en su demanda de garant\u00edas.<\/p>\n<p style=\"text-align: justify;\">\u00abSe admite la demanda de amparo. No ha lugar a ordenar la tramitaci\u00f3n del incidente de suspensi\u00f3n, toda vez que de la certificaci\u00f3n de cuenta se advierte que \u00e9ste no fue expresamente solicitado\u00bb, determin\u00f3 en la resoluci\u00f3n del expediente 78\/2021.<\/p>\n<p style=\"text-align: justify;\">La juez fij\u00f3 como fecha para la audiencia el 29 de marzo y dio un plazo de 15 d\u00edas para que las autoridades rindan su informe justificado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e9xico.- La titular del Juzgado D\u00e9cimo Sexto de Distrito de Amparo en Materia Penal admiti\u00f3 la demanda de amparo que interpuso Genaro Garc\u00eda Luna el pasado 16 de febrero contra la orden de aprehensi\u00f3n en su contra por el delito de enriquecimiento il\u00edcito. La Juez Federal, no concedi\u00f3 la suspensi\u00f3n provisional a Garc\u00eda Luna, preso en Estados Unidos por presuntos nexos con el C\u00e1rtel de Sinaloa, ya que no la solicit\u00f3 en su demanda de garant\u00edas. \u00abSe admite la demanda de amparo. No ha lugar a ordenar la tramitaci\u00f3n del incidente de suspensi\u00f3n, toda vez que de la certificaci\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5109,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[],"class_list":["post-5095","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Admiten amparo contra orden de aprehensi\u00f3n de Garc\u00eda Luna - Canal 7 SLP - 2021<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2021\/admiten-amparo-contra-orden-de-aprehension-de-garcia-luna\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Admiten amparo contra orden de aprehensi\u00f3n de Garc\u00eda Luna - Canal 7 SLP - 2021\" \/>\n<meta property=\"og:description\" content=\"M\u00e9xico.- La titular del Juzgado D\u00e9cimo Sexto de Distrito de Amparo en Materia Penal admiti\u00f3 la demanda de amparo que interpuso Genaro Garc\u00eda Luna el pasado 16 de febrero contra la orden de aprehensi\u00f3n en su contra por el delito de enriquecimiento il\u00edcito. La Juez Federal, no concedi\u00f3 la suspensi\u00f3n provisional a Garc\u00eda Luna, preso en Estados Unidos por presuntos nexos con el C\u00e1rtel de Sinaloa, ya que no la solicit\u00f3 en su demanda de garant\u00edas. \u00abSe admite la demanda de amparo. No ha lugar a ordenar la tramitaci\u00f3n del incidente de suspensi\u00f3n, toda vez que de la certificaci\u00f3n de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2021\/admiten-amparo-contra-orden-de-aprehension-de-garcia-luna\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2021\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanalsiete\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-21T21:39:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/02\/05-18.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/admiten-amparo-contra-orden-de-aprehension-de-garcia-luna\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/admiten-amparo-contra-orden-de-aprehension-de-garcia-luna\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#\\\/schema\\\/person\\\/28a12b0491d3b6f41a854d062961bdc7\"},\"headline\":\"Admiten amparo contra orden de aprehensi\u00f3n de Garc\u00eda Luna\",\"datePublished\":\"2021-02-21T21:39:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/admiten-amparo-contra-orden-de-aprehension-de-garcia-luna\\\/\"},\"wordCount\":165,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/admiten-amparo-contra-orden-de-aprehension-de-garcia-luna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/05-18.jpg\",\"articleSection\":[\"NACIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/admiten-amparo-contra-orden-de-aprehension-de-garcia-luna\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/admiten-amparo-contra-orden-de-aprehension-de-garcia-luna\\\/\",\"name\":\"Admiten amparo contra orden de aprehensi\u00f3n de Garc\u00eda Luna - Canal 7 SLP - 2021\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/admiten-amparo-contra-orden-de-aprehension-de-garcia-luna\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/admiten-amparo-contra-orden-de-aprehension-de-garcia-luna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/05-18.jpg\",\"datePublished\":\"2021-02-21T21:39:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/admiten-amparo-contra-orden-de-aprehension-de-garcia-luna\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/admiten-amparo-contra-orden-de-aprehension-de-garcia-luna\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/admiten-amparo-contra-orden-de-aprehension-de-garcia-luna\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/05-18.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/05-18.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/admiten-amparo-contra-orden-de-aprehension-de-garcia-luna\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Admiten amparo contra orden de aprehensi\u00f3n de Garc\u00eda Luna\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanalsiete\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#\\\/schema\\\/person\\\/28a12b0491d3b6f41a854d062961bdc7\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Admiten amparo contra orden de aprehensi\u00f3n de Garc\u00eda Luna - Canal 7 SLP - 2021","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2021\/admiten-amparo-contra-orden-de-aprehension-de-garcia-luna\/","og_locale":"es_ES","og_type":"article","og_title":"Admiten amparo contra orden de aprehensi\u00f3n de Garc\u00eda Luna - Canal 7 SLP - 2021","og_description":"M\u00e9xico.- La titular del Juzgado D\u00e9cimo Sexto de Distrito de Amparo en Materia Penal admiti\u00f3 la demanda de amparo que interpuso Genaro Garc\u00eda Luna el pasado 16 de febrero contra la orden de aprehensi\u00f3n en su contra por el delito de enriquecimiento il\u00edcito. La Juez Federal, no concedi\u00f3 la suspensi\u00f3n provisional a Garc\u00eda Luna, preso en Estados Unidos por presuntos nexos con el C\u00e1rtel de Sinaloa, ya que no la solicit\u00f3 en su demanda de garant\u00edas. \u00abSe admite la demanda de amparo. No ha lugar a ordenar la tramitaci\u00f3n del incidente de suspensi\u00f3n, toda vez que de la certificaci\u00f3n de [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2021\/admiten-amparo-contra-orden-de-aprehension-de-garcia-luna\/","og_site_name":"Canal 7 SLP - 2021","article_publisher":"https:\/\/www.facebook.com\/noticieroscanalsiete","article_published_time":"2021-02-21T21:39:40+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/02\/05-18.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2021\/admiten-amparo-contra-orden-de-aprehension-de-garcia-luna\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2021\/admiten-amparo-contra-orden-de-aprehension-de-garcia-luna\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2021\/#\/schema\/person\/28a12b0491d3b6f41a854d062961bdc7"},"headline":"Admiten amparo contra orden de aprehensi\u00f3n de Garc\u00eda Luna","datePublished":"2021-02-21T21:39:40+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2021\/admiten-amparo-contra-orden-de-aprehension-de-garcia-luna\/"},"wordCount":165,"publisher":{"@id":"https:\/\/canal7slp.tv\/2021\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2021\/admiten-amparo-contra-orden-de-aprehension-de-garcia-luna\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/02\/05-18.jpg","articleSection":["NACIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2021\/admiten-amparo-contra-orden-de-aprehension-de-garcia-luna\/","url":"https:\/\/canal7slp.tv\/2021\/admiten-amparo-contra-orden-de-aprehension-de-garcia-luna\/","name":"Admiten amparo contra orden de aprehensi\u00f3n de Garc\u00eda Luna - Canal 7 SLP - 2021","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2021\/admiten-amparo-contra-orden-de-aprehension-de-garcia-luna\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2021\/admiten-amparo-contra-orden-de-aprehension-de-garcia-luna\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/02\/05-18.jpg","datePublished":"2021-02-21T21:39:40+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2021\/admiten-amparo-contra-orden-de-aprehension-de-garcia-luna\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2021\/admiten-amparo-contra-orden-de-aprehension-de-garcia-luna\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2021\/admiten-amparo-contra-orden-de-aprehension-de-garcia-luna\/#primaryimage","url":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/02\/05-18.jpg","contentUrl":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/02\/05-18.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2021\/admiten-amparo-contra-orden-de-aprehension-de-garcia-luna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2021\/"},{"@type":"ListItem","position":2,"name":"Admiten amparo contra orden de aprehensi\u00f3n de Garc\u00eda Luna"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2021\/#website","url":"https:\/\/canal7slp.tv\/2021\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2021\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2021\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2021\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2021\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2021\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanalsiete","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2021\/#\/schema\/person\/28a12b0491d3b6f41a854d062961bdc7","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2021\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/posts\/5095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/comments?post=5095"}],"version-history":[{"count":1,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/posts\/5095\/revisions"}],"predecessor-version":[{"id":5101,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/posts\/5095\/revisions\/5101"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/media\/5109"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/media?parent=5095"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/categories?post=5095"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/tags?post=5095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}