{"id":45578,"date":"2021-12-14T21:43:08","date_gmt":"2021-12-15T03:43:08","guid":{"rendered":"https:\/\/canal7slp.tv\/2021\/?p=45578"},"modified":"2021-12-14T21:43:08","modified_gmt":"2021-12-15T03:43:08","slug":"legisladores-aprueban-incremento-a-la-tarifa-del-servicio-de-agua-potable-para-uso-industrial-y-comercial","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2021\/legisladores-aprueban-incremento-a-la-tarifa-del-servicio-de-agua-potable-para-uso-industrial-y-comercial\/","title":{"rendered":"Legisladores aprueban incremento a la tarifa del servicio de agua potable para uso industrial y comercial."},"content":{"rendered":"<p style=\"text-align: justify;\">SLP.- Con 24 votos a favor, una abstenci\u00f3n y dos votos en contra en Sesi\u00f3n Ordinaria del Pleno diputados del Congreso aprobaron un incremento del 6.9 por ciento a la tarifa del agua potable para usuarios industriales y comerciales, tal como se hab\u00eda acordado en comisiones.<\/p>\n<p style=\"text-align: justify;\">Sin embargo, la tarifa para usuarios dom\u00e9sticos se mantiene igual pero se advirti\u00f3 que tendr\u00e1 actualizaciones de acuerdo a los niveles de inflaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Asimismo, en esta iniciativa se implementa el programa \u201cCuenta Nueva y Borr\u00f3n\u201d para la eliminaci\u00f3n de adeudos anteriores a usuarios morosos, siempre y cuando est\u00e9n al corriente en el pago puntual de seis bimestres continuos.<\/p>\n<p style=\"text-align: justify;\">Sin embargo, la diputada del Partido Redes Sociales Progresistas Gabriela Mart\u00ednez L\u00e1rraga se inconform\u00f3 al decir que el incremento a los grandes usuarios, impactar\u00e1 al sector productivo y por ende, con el incremento de precios en bienes y servicios al consumidor final.<\/p>\n<p style=\"text-align: justify;\">El incremento a las tarifas industriales y comerciales fueron aprobadas en paquete para 21 organismos operadores del agua potable en el estado.<\/p>\n<p style=\"text-align: justify;\">Asimismo, en esta Sesi\u00f3n del Congreso se aprob\u00f3 la Ley de Ingresos Municipales misma que se aprob\u00f3 por mayor\u00eda con 25 votos a favor, una abstenci\u00f3n y 1 voto en contra, expidi\u00e9ndose los decretos para las leyes de ingresos para el ejercicio 2022 de los 58\u00a0 ayuntamientos del Estado.<\/p>\n<p style=\"text-align: justify;\">Tambi\u00e9n se conform\u00f3 la Comisi\u00f3n de Diputados para la Reforma Pol\u00edtico-Electoral del Estado y para la Diputaci\u00f3n Permanente y para lo cual, se les tom\u00f3 la respectiva protesta.<\/p>\n<p style=\"text-align: justify;\">Cabe se\u00f1alar que la Diputaci\u00f3n Permanente estar\u00e1 en funciones durante el periodo de receso del Congreso y que ser\u00e1 del 15 de Diciembre de este a\u00f1o y hasta el 31 de Enero de 2022.<\/p>\n<p style=\"text-align: justify;\">Por: Claudio Ibarra<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SLP.- Con 24 votos a favor, una abstenci\u00f3n y dos votos en contra en Sesi\u00f3n Ordinaria del Pleno diputados del Congreso aprobaron un incremento del 6.9 por ciento a la tarifa del agua potable para usuarios industriales y comerciales, tal como se hab\u00eda acordado en comisiones. Sin embargo, la tarifa para usuarios dom\u00e9sticos se mantiene igual pero se advirti\u00f3 que tendr\u00e1 actualizaciones de acuerdo a los niveles de inflaci\u00f3n. Asimismo, en esta iniciativa se implementa el programa \u201cCuenta Nueva y Borr\u00f3n\u201d para la eliminaci\u00f3n de adeudos anteriores a usuarios morosos, siempre y cuando est\u00e9n al corriente en el pago puntual [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":45602,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"footnotes":""},"categories":[3,5,45],"tags":[53],"class_list":["post-45578","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-congreso","category-destacadas","category-localesyregionales","tag-congreso-slp","post_format-post-format-video","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Legisladores aprueban incremento a la tarifa del servicio de agua potable para uso industrial y comercial. - Canal 7 SLP - 2021<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2021\/legisladores-aprueban-incremento-a-la-tarifa-del-servicio-de-agua-potable-para-uso-industrial-y-comercial\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Legisladores aprueban incremento a la tarifa del servicio de agua potable para uso industrial y comercial. - Canal 7 SLP - 2021\" \/>\n<meta property=\"og:description\" content=\"SLP.- Con 24 votos a favor, una abstenci\u00f3n y dos votos en contra en Sesi\u00f3n Ordinaria del Pleno diputados del Congreso aprobaron un incremento del 6.9 por ciento a la tarifa del agua potable para usuarios industriales y comerciales, tal como se hab\u00eda acordado en comisiones. Sin embargo, la tarifa para usuarios dom\u00e9sticos se mantiene igual pero se advirti\u00f3 que tendr\u00e1 actualizaciones de acuerdo a los niveles de inflaci\u00f3n. Asimismo, en esta iniciativa se implementa el programa \u201cCuenta Nueva y Borr\u00f3n\u201d para la eliminaci\u00f3n de adeudos anteriores a usuarios morosos, siempre y cuando est\u00e9n al corriente en el pago puntual [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2021\/legisladores-aprueban-incremento-a-la-tarifa-del-servicio-de-agua-potable-para-uso-industrial-y-comercial\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2021\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanalsiete\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-15T03:43:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/12\/Claudio01Autorizado.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"888\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/legisladores-aprueban-incremento-a-la-tarifa-del-servicio-de-agua-potable-para-uso-industrial-y-comercial\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/legisladores-aprueban-incremento-a-la-tarifa-del-servicio-de-agua-potable-para-uso-industrial-y-comercial\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#\\\/schema\\\/person\\\/28a12b0491d3b6f41a854d062961bdc7\"},\"headline\":\"Legisladores aprueban incremento a la tarifa del servicio de agua potable para uso industrial y comercial.\",\"datePublished\":\"2021-12-15T03:43:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/legisladores-aprueban-incremento-a-la-tarifa-del-servicio-de-agua-potable-para-uso-industrial-y-comercial\\\/\"},\"wordCount\":310,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/legisladores-aprueban-incremento-a-la-tarifa-del-servicio-de-agua-potable-para-uso-industrial-y-comercial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Claudio01Autorizado.jpg\",\"keywords\":[\"Congreso SLP\"],\"articleSection\":[\"CONGRESO\",\"DESTACADAS\",\"LOCALES Y REGIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/legisladores-aprueban-incremento-a-la-tarifa-del-servicio-de-agua-potable-para-uso-industrial-y-comercial\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/legisladores-aprueban-incremento-a-la-tarifa-del-servicio-de-agua-potable-para-uso-industrial-y-comercial\\\/\",\"name\":\"Legisladores aprueban incremento a la tarifa del servicio de agua potable para uso industrial y comercial. - Canal 7 SLP - 2021\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/legisladores-aprueban-incremento-a-la-tarifa-del-servicio-de-agua-potable-para-uso-industrial-y-comercial\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/legisladores-aprueban-incremento-a-la-tarifa-del-servicio-de-agua-potable-para-uso-industrial-y-comercial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Claudio01Autorizado.jpg\",\"datePublished\":\"2021-12-15T03:43:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/legisladores-aprueban-incremento-a-la-tarifa-del-servicio-de-agua-potable-para-uso-industrial-y-comercial\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/legisladores-aprueban-incremento-a-la-tarifa-del-servicio-de-agua-potable-para-uso-industrial-y-comercial\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/legisladores-aprueban-incremento-a-la-tarifa-del-servicio-de-agua-potable-para-uso-industrial-y-comercial\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Claudio01Autorizado.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Claudio01Autorizado.jpg\",\"width\":888,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/legisladores-aprueban-incremento-a-la-tarifa-del-servicio-de-agua-potable-para-uso-industrial-y-comercial\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Legisladores aprueban incremento a la tarifa del servicio de agua potable para uso industrial y comercial.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanalsiete\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#\\\/schema\\\/person\\\/28a12b0491d3b6f41a854d062961bdc7\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Legisladores aprueban incremento a la tarifa del servicio de agua potable para uso industrial y comercial. - Canal 7 SLP - 2021","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2021\/legisladores-aprueban-incremento-a-la-tarifa-del-servicio-de-agua-potable-para-uso-industrial-y-comercial\/","og_locale":"es_ES","og_type":"article","og_title":"Legisladores aprueban incremento a la tarifa del servicio de agua potable para uso industrial y comercial. - Canal 7 SLP - 2021","og_description":"SLP.- Con 24 votos a favor, una abstenci\u00f3n y dos votos en contra en Sesi\u00f3n Ordinaria del Pleno diputados del Congreso aprobaron un incremento del 6.9 por ciento a la tarifa del agua potable para usuarios industriales y comerciales, tal como se hab\u00eda acordado en comisiones. Sin embargo, la tarifa para usuarios dom\u00e9sticos se mantiene igual pero se advirti\u00f3 que tendr\u00e1 actualizaciones de acuerdo a los niveles de inflaci\u00f3n. Asimismo, en esta iniciativa se implementa el programa \u201cCuenta Nueva y Borr\u00f3n\u201d para la eliminaci\u00f3n de adeudos anteriores a usuarios morosos, siempre y cuando est\u00e9n al corriente en el pago puntual [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2021\/legisladores-aprueban-incremento-a-la-tarifa-del-servicio-de-agua-potable-para-uso-industrial-y-comercial\/","og_site_name":"Canal 7 SLP - 2021","article_publisher":"https:\/\/www.facebook.com\/noticieroscanalsiete","article_published_time":"2021-12-15T03:43:08+00:00","og_image":[{"width":888,"height":500,"url":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/12\/Claudio01Autorizado.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2021\/legisladores-aprueban-incremento-a-la-tarifa-del-servicio-de-agua-potable-para-uso-industrial-y-comercial\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2021\/legisladores-aprueban-incremento-a-la-tarifa-del-servicio-de-agua-potable-para-uso-industrial-y-comercial\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2021\/#\/schema\/person\/28a12b0491d3b6f41a854d062961bdc7"},"headline":"Legisladores aprueban incremento a la tarifa del servicio de agua potable para uso industrial y comercial.","datePublished":"2021-12-15T03:43:08+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2021\/legisladores-aprueban-incremento-a-la-tarifa-del-servicio-de-agua-potable-para-uso-industrial-y-comercial\/"},"wordCount":310,"publisher":{"@id":"https:\/\/canal7slp.tv\/2021\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2021\/legisladores-aprueban-incremento-a-la-tarifa-del-servicio-de-agua-potable-para-uso-industrial-y-comercial\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/12\/Claudio01Autorizado.jpg","keywords":["Congreso SLP"],"articleSection":["CONGRESO","DESTACADAS","LOCALES Y REGIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2021\/legisladores-aprueban-incremento-a-la-tarifa-del-servicio-de-agua-potable-para-uso-industrial-y-comercial\/","url":"https:\/\/canal7slp.tv\/2021\/legisladores-aprueban-incremento-a-la-tarifa-del-servicio-de-agua-potable-para-uso-industrial-y-comercial\/","name":"Legisladores aprueban incremento a la tarifa del servicio de agua potable para uso industrial y comercial. - Canal 7 SLP - 2021","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2021\/legisladores-aprueban-incremento-a-la-tarifa-del-servicio-de-agua-potable-para-uso-industrial-y-comercial\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2021\/legisladores-aprueban-incremento-a-la-tarifa-del-servicio-de-agua-potable-para-uso-industrial-y-comercial\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/12\/Claudio01Autorizado.jpg","datePublished":"2021-12-15T03:43:08+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2021\/legisladores-aprueban-incremento-a-la-tarifa-del-servicio-de-agua-potable-para-uso-industrial-y-comercial\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2021\/legisladores-aprueban-incremento-a-la-tarifa-del-servicio-de-agua-potable-para-uso-industrial-y-comercial\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2021\/legisladores-aprueban-incremento-a-la-tarifa-del-servicio-de-agua-potable-para-uso-industrial-y-comercial\/#primaryimage","url":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/12\/Claudio01Autorizado.jpg","contentUrl":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/12\/Claudio01Autorizado.jpg","width":888,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2021\/legisladores-aprueban-incremento-a-la-tarifa-del-servicio-de-agua-potable-para-uso-industrial-y-comercial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2021\/"},{"@type":"ListItem","position":2,"name":"Legisladores aprueban incremento a la tarifa del servicio de agua potable para uso industrial y comercial."}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2021\/#website","url":"https:\/\/canal7slp.tv\/2021\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2021\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2021\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2021\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2021\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2021\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanalsiete","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2021\/#\/schema\/person\/28a12b0491d3b6f41a854d062961bdc7","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2021\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/posts\/45578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/comments?post=45578"}],"version-history":[{"count":2,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/posts\/45578\/revisions"}],"predecessor-version":[{"id":45603,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/posts\/45578\/revisions\/45603"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/media\/45602"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/media?parent=45578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/categories?post=45578"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/tags?post=45578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}