{"id":45294,"date":"2021-12-11T14:49:28","date_gmt":"2021-12-11T20:49:28","guid":{"rendered":"https:\/\/canal7slp.tv\/2021\/?p=45294"},"modified":"2021-12-11T14:49:28","modified_gmt":"2021-12-11T20:49:28","slug":"detuvieron-a-par-de-hombres-por-probable-robo-de-autopartes","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2021\/detuvieron-a-par-de-hombres-por-probable-robo-de-autopartes\/","title":{"rendered":"Detuvieron a par de hombres por probable robo de autopartes"},"content":{"rendered":"<ul>\n<li style=\"text-align: justify;\">Fueron sorprendidos en la colonia Sim\u00f3n D\u00edaz en SLP<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">SLP.- Por su probable participaci\u00f3n en el delito de robo equiparado en la ciudad de San Luis Potos\u00ed, elementos de la Polic\u00eda de Investigaci\u00f3n (PDI) realizaron la detenci\u00f3n de dos hombres de 42 y 27 a\u00f1os de edad.<\/p>\n<p style=\"text-align: justify;\">En atenci\u00f3n a diversas denuncias sobre el hurto de autopartes de veh\u00edculos de la colonia Sim\u00f3n D\u00edaz, la PDI realiz\u00f3 un operativo en la zona y al circular sobre la calle Cuba tuvieron a la vista una camioneta con las puertas abiertas y a un lado dos personas manipulando el catalizador de un veh\u00edculo.<\/p>\n<p style=\"text-align: justify;\">Al realizar una inspecci\u00f3n encontraron dos catalizadores m\u00e1s y varios tubos que los conectan cortados por la mitad.<\/p>\n<p style=\"text-align: justify;\">Las personas no lograron acreditar la procedencia de las piezas y por ese motivo fueron llevados ante el agente del Ministerio P\u00fablico de la Fiscal\u00eda General del Estado (FGESLP), donde resolver\u00e1 su situaci\u00f3n legal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fueron sorprendidos en la colonia Sim\u00f3n D\u00edaz en SLP SLP.- Por su probable participaci\u00f3n en el delito de robo equiparado en la ciudad de San Luis Potos\u00ed, elementos de la Polic\u00eda de Investigaci\u00f3n (PDI) realizaron la detenci\u00f3n de dos hombres de 42 y 27 a\u00f1os de edad. En atenci\u00f3n a diversas denuncias sobre el hurto de autopartes de veh\u00edculos de la colonia Sim\u00f3n D\u00edaz, la PDI realiz\u00f3 un operativo en la zona y al circular sobre la calle Cuba tuvieron a la vista una camioneta con las puertas abiertas y a un lado dos personas manipulando el catalizador de un [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":45295,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-45294","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reporte7","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Detuvieron a par de hombres por probable robo de autopartes - Canal 7 SLP - 2021<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2021\/detuvieron-a-par-de-hombres-por-probable-robo-de-autopartes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Detuvieron a par de hombres por probable robo de autopartes - Canal 7 SLP - 2021\" \/>\n<meta property=\"og:description\" content=\"Fueron sorprendidos en la colonia Sim\u00f3n D\u00edaz en SLP SLP.- Por su probable participaci\u00f3n en el delito de robo equiparado en la ciudad de San Luis Potos\u00ed, elementos de la Polic\u00eda de Investigaci\u00f3n (PDI) realizaron la detenci\u00f3n de dos hombres de 42 y 27 a\u00f1os de edad. En atenci\u00f3n a diversas denuncias sobre el hurto de autopartes de veh\u00edculos de la colonia Sim\u00f3n D\u00edaz, la PDI realiz\u00f3 un operativo en la zona y al circular sobre la calle Cuba tuvieron a la vista una camioneta con las puertas abiertas y a un lado dos personas manipulando el catalizador de un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2021\/detuvieron-a-par-de-hombres-por-probable-robo-de-autopartes\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2021\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanalsiete\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-11T20:49:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/12\/zz2-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"792\" \/>\n\t<meta property=\"og:image:height\" content=\"554\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/detuvieron-a-par-de-hombres-por-probable-robo-de-autopartes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/detuvieron-a-par-de-hombres-por-probable-robo-de-autopartes\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#\\\/schema\\\/person\\\/28a12b0491d3b6f41a854d062961bdc7\"},\"headline\":\"Detuvieron a par de hombres por probable robo de autopartes\",\"datePublished\":\"2021-12-11T20:49:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/detuvieron-a-par-de-hombres-por-probable-robo-de-autopartes\\\/\"},\"wordCount\":179,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/detuvieron-a-par-de-hombres-por-probable-robo-de-autopartes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/zz2-2.jpg\",\"articleSection\":[\"REPORTE 7\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/detuvieron-a-par-de-hombres-por-probable-robo-de-autopartes\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/detuvieron-a-par-de-hombres-por-probable-robo-de-autopartes\\\/\",\"name\":\"Detuvieron a par de hombres por probable robo de autopartes - Canal 7 SLP - 2021\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/detuvieron-a-par-de-hombres-por-probable-robo-de-autopartes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/detuvieron-a-par-de-hombres-por-probable-robo-de-autopartes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/zz2-2.jpg\",\"datePublished\":\"2021-12-11T20:49:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/detuvieron-a-par-de-hombres-por-probable-robo-de-autopartes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/detuvieron-a-par-de-hombres-por-probable-robo-de-autopartes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/detuvieron-a-par-de-hombres-por-probable-robo-de-autopartes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/zz2-2.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/zz2-2.jpg\",\"width\":792,\"height\":554},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/detuvieron-a-par-de-hombres-por-probable-robo-de-autopartes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Detuvieron a par de hombres por probable robo de autopartes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanalsiete\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#\\\/schema\\\/person\\\/28a12b0491d3b6f41a854d062961bdc7\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Detuvieron a par de hombres por probable robo de autopartes - Canal 7 SLP - 2021","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2021\/detuvieron-a-par-de-hombres-por-probable-robo-de-autopartes\/","og_locale":"es_ES","og_type":"article","og_title":"Detuvieron a par de hombres por probable robo de autopartes - Canal 7 SLP - 2021","og_description":"Fueron sorprendidos en la colonia Sim\u00f3n D\u00edaz en SLP SLP.- Por su probable participaci\u00f3n en el delito de robo equiparado en la ciudad de San Luis Potos\u00ed, elementos de la Polic\u00eda de Investigaci\u00f3n (PDI) realizaron la detenci\u00f3n de dos hombres de 42 y 27 a\u00f1os de edad. En atenci\u00f3n a diversas denuncias sobre el hurto de autopartes de veh\u00edculos de la colonia Sim\u00f3n D\u00edaz, la PDI realiz\u00f3 un operativo en la zona y al circular sobre la calle Cuba tuvieron a la vista una camioneta con las puertas abiertas y a un lado dos personas manipulando el catalizador de un [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2021\/detuvieron-a-par-de-hombres-por-probable-robo-de-autopartes\/","og_site_name":"Canal 7 SLP - 2021","article_publisher":"https:\/\/www.facebook.com\/noticieroscanalsiete","article_published_time":"2021-12-11T20:49:28+00:00","og_image":[{"width":792,"height":554,"url":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/12\/zz2-2.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2021\/detuvieron-a-par-de-hombres-por-probable-robo-de-autopartes\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2021\/detuvieron-a-par-de-hombres-por-probable-robo-de-autopartes\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2021\/#\/schema\/person\/28a12b0491d3b6f41a854d062961bdc7"},"headline":"Detuvieron a par de hombres por probable robo de autopartes","datePublished":"2021-12-11T20:49:28+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2021\/detuvieron-a-par-de-hombres-por-probable-robo-de-autopartes\/"},"wordCount":179,"publisher":{"@id":"https:\/\/canal7slp.tv\/2021\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2021\/detuvieron-a-par-de-hombres-por-probable-robo-de-autopartes\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/12\/zz2-2.jpg","articleSection":["REPORTE 7"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2021\/detuvieron-a-par-de-hombres-por-probable-robo-de-autopartes\/","url":"https:\/\/canal7slp.tv\/2021\/detuvieron-a-par-de-hombres-por-probable-robo-de-autopartes\/","name":"Detuvieron a par de hombres por probable robo de autopartes - Canal 7 SLP - 2021","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2021\/detuvieron-a-par-de-hombres-por-probable-robo-de-autopartes\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2021\/detuvieron-a-par-de-hombres-por-probable-robo-de-autopartes\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/12\/zz2-2.jpg","datePublished":"2021-12-11T20:49:28+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2021\/detuvieron-a-par-de-hombres-por-probable-robo-de-autopartes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2021\/detuvieron-a-par-de-hombres-por-probable-robo-de-autopartes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2021\/detuvieron-a-par-de-hombres-por-probable-robo-de-autopartes\/#primaryimage","url":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/12\/zz2-2.jpg","contentUrl":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/12\/zz2-2.jpg","width":792,"height":554},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2021\/detuvieron-a-par-de-hombres-por-probable-robo-de-autopartes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2021\/"},{"@type":"ListItem","position":2,"name":"Detuvieron a par de hombres por probable robo de autopartes"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2021\/#website","url":"https:\/\/canal7slp.tv\/2021\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2021\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2021\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2021\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2021\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2021\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanalsiete","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2021\/#\/schema\/person\/28a12b0491d3b6f41a854d062961bdc7","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2021\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/posts\/45294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/comments?post=45294"}],"version-history":[{"count":1,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/posts\/45294\/revisions"}],"predecessor-version":[{"id":45296,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/posts\/45294\/revisions\/45296"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/media\/45295"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/media?parent=45294"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/categories?post=45294"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/tags?post=45294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}