{"id":25944,"date":"2021-07-24T14:26:27","date_gmt":"2021-07-24T20:26:27","guid":{"rendered":"https:\/\/canal7slp.tv\/2021\/?p=25944"},"modified":"2021-07-24T14:26:27","modified_gmt":"2021-07-24T20:26:27","slug":"ine-concluye-fiscalizacion-del-proceso-electoral-2021","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2021\/ine-concluye-fiscalizacion-del-proceso-electoral-2021\/","title":{"rendered":"INE concluye fiscalizaci\u00f3n del Proceso Electoral 2021"},"content":{"rendered":"<p style=\"text-align: justify;\">M\u00e9xico.- El Consejo General del Instituto Nacional Electoral concluy\u00f3 la fiscalizaci\u00f3n de los procesos electorales locales y federal de este 2021, en los cuales se impuso un total de 203 MDP como sanciones a todos los partidos pol\u00edticos.<\/p>\n<p style=\"text-align: justify;\">Ciro Murayama Rend\u00f3n, Consejero del INE, se\u00f1al\u00f3 que a nivel federal se acredit\u00f3 que los Partidos Pol\u00edticos no reportaron 80 MDP de gasto. Aunado, expres\u00f3 que considerando el monto que s\u00ed fue reportado, lo que no se inform\u00f3 a la autoridad representa 6% de los recursos, esto quiere decir que 94% del gasto s\u00ed se inform\u00f3 a la autoridad.<\/p>\n<p style=\"text-align: justify;\">Cabe se\u00f1alar, que MORENA fue el partido m\u00e1s sancionado, el cual recibi\u00f3 una multa total de 373 MDP.<\/p>\n<p style=\"text-align: justify;\">Murayama Rend\u00f3n declar\u00f3 que durante la fiscalizaci\u00f3n se dieron cuenta de ingresos durante las campa\u00f1as por 5 mil 644 MDP, mismos que fueron auditados y un monto de gastos por 5 mil 702 MDP. En total, la Unidad T\u00e9cnica de Fiscalizaci\u00f3n analiz\u00f3 un total de 11 mil 346 MDP.<\/p>\n<p style=\"text-align: justify;\">As\u00ed mismo, coment\u00f3 que las sanciones de campa\u00f1a ascienden a 1 mil 203 MDP, del cual, el 91%\u00a0 est\u00e1 concentrado en partidos pol\u00edticos nacionales y en partidos pol\u00edticos nacionales con acreditaci\u00f3n local, el 8% en partidos locales y s\u00f3lo el 1% en los candidatos independientes.<\/p>\n<p style=\"text-align: justify;\">Cabe se\u00f1alar que a dichas cifras se tienen que sumar sanciones por 96.8 MDP correspondientes a partidos pol\u00edticos locales y 6 MDP m\u00e1s a candidatos independientes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e9xico.- El Consejo General del Instituto Nacional Electoral concluy\u00f3 la fiscalizaci\u00f3n de los procesos electorales locales y federal de este 2021, en los cuales se impuso un total de 203 MDP como sanciones a todos los partidos pol\u00edticos. Ciro Murayama Rend\u00f3n, Consejero del INE, se\u00f1al\u00f3 que a nivel federal se acredit\u00f3 que los Partidos Pol\u00edticos no reportaron 80 MDP de gasto. Aunado, expres\u00f3 que considerando el monto que s\u00ed fue reportado, lo que no se inform\u00f3 a la autoridad representa 6% de los recursos, esto quiere decir que 94% del gasto s\u00ed se inform\u00f3 a la autoridad. Cabe se\u00f1alar, que [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":25956,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[],"class_list":["post-25944","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>INE concluye fiscalizaci\u00f3n del Proceso Electoral 2021 - Canal 7 SLP - 2021<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2021\/ine-concluye-fiscalizacion-del-proceso-electoral-2021\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"INE concluye fiscalizaci\u00f3n del Proceso Electoral 2021 - Canal 7 SLP - 2021\" \/>\n<meta property=\"og:description\" content=\"M\u00e9xico.- El Consejo General del Instituto Nacional Electoral concluy\u00f3 la fiscalizaci\u00f3n de los procesos electorales locales y federal de este 2021, en los cuales se impuso un total de 203 MDP como sanciones a todos los partidos pol\u00edticos. Ciro Murayama Rend\u00f3n, Consejero del INE, se\u00f1al\u00f3 que a nivel federal se acredit\u00f3 que los Partidos Pol\u00edticos no reportaron 80 MDP de gasto. Aunado, expres\u00f3 que considerando el monto que s\u00ed fue reportado, lo que no se inform\u00f3 a la autoridad representa 6% de los recursos, esto quiere decir que 94% del gasto s\u00ed se inform\u00f3 a la autoridad. Cabe se\u00f1alar, que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2021\/ine-concluye-fiscalizacion-del-proceso-electoral-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2021\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanalsiete\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-24T20:26:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/07\/01-21.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"675\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/ine-concluye-fiscalizacion-del-proceso-electoral-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/ine-concluye-fiscalizacion-del-proceso-electoral-2021\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#\\\/schema\\\/person\\\/28a12b0491d3b6f41a854d062961bdc7\"},\"headline\":\"INE concluye fiscalizaci\u00f3n del Proceso Electoral 2021\",\"datePublished\":\"2021-07-24T20:26:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/ine-concluye-fiscalizacion-del-proceso-electoral-2021\\\/\"},\"wordCount\":245,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/ine-concluye-fiscalizacion-del-proceso-electoral-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/01-21.jpg\",\"articleSection\":[\"NACIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/ine-concluye-fiscalizacion-del-proceso-electoral-2021\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/ine-concluye-fiscalizacion-del-proceso-electoral-2021\\\/\",\"name\":\"INE concluye fiscalizaci\u00f3n del Proceso Electoral 2021 - Canal 7 SLP - 2021\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/ine-concluye-fiscalizacion-del-proceso-electoral-2021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/ine-concluye-fiscalizacion-del-proceso-electoral-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/01-21.jpg\",\"datePublished\":\"2021-07-24T20:26:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/ine-concluye-fiscalizacion-del-proceso-electoral-2021\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/ine-concluye-fiscalizacion-del-proceso-electoral-2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/ine-concluye-fiscalizacion-del-proceso-electoral-2021\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/01-21.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/01-21.jpg\",\"width\":675,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/ine-concluye-fiscalizacion-del-proceso-electoral-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"INE concluye fiscalizaci\u00f3n del Proceso Electoral 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanalsiete\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#\\\/schema\\\/person\\\/28a12b0491d3b6f41a854d062961bdc7\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"INE concluye fiscalizaci\u00f3n del Proceso Electoral 2021 - Canal 7 SLP - 2021","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2021\/ine-concluye-fiscalizacion-del-proceso-electoral-2021\/","og_locale":"es_ES","og_type":"article","og_title":"INE concluye fiscalizaci\u00f3n del Proceso Electoral 2021 - Canal 7 SLP - 2021","og_description":"M\u00e9xico.- El Consejo General del Instituto Nacional Electoral concluy\u00f3 la fiscalizaci\u00f3n de los procesos electorales locales y federal de este 2021, en los cuales se impuso un total de 203 MDP como sanciones a todos los partidos pol\u00edticos. Ciro Murayama Rend\u00f3n, Consejero del INE, se\u00f1al\u00f3 que a nivel federal se acredit\u00f3 que los Partidos Pol\u00edticos no reportaron 80 MDP de gasto. Aunado, expres\u00f3 que considerando el monto que s\u00ed fue reportado, lo que no se inform\u00f3 a la autoridad representa 6% de los recursos, esto quiere decir que 94% del gasto s\u00ed se inform\u00f3 a la autoridad. Cabe se\u00f1alar, que [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2021\/ine-concluye-fiscalizacion-del-proceso-electoral-2021\/","og_site_name":"Canal 7 SLP - 2021","article_publisher":"https:\/\/www.facebook.com\/noticieroscanalsiete","article_published_time":"2021-07-24T20:26:27+00:00","og_image":[{"width":675,"height":450,"url":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/07\/01-21.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2021\/ine-concluye-fiscalizacion-del-proceso-electoral-2021\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2021\/ine-concluye-fiscalizacion-del-proceso-electoral-2021\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2021\/#\/schema\/person\/28a12b0491d3b6f41a854d062961bdc7"},"headline":"INE concluye fiscalizaci\u00f3n del Proceso Electoral 2021","datePublished":"2021-07-24T20:26:27+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2021\/ine-concluye-fiscalizacion-del-proceso-electoral-2021\/"},"wordCount":245,"publisher":{"@id":"https:\/\/canal7slp.tv\/2021\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2021\/ine-concluye-fiscalizacion-del-proceso-electoral-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/07\/01-21.jpg","articleSection":["NACIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2021\/ine-concluye-fiscalizacion-del-proceso-electoral-2021\/","url":"https:\/\/canal7slp.tv\/2021\/ine-concluye-fiscalizacion-del-proceso-electoral-2021\/","name":"INE concluye fiscalizaci\u00f3n del Proceso Electoral 2021 - Canal 7 SLP - 2021","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2021\/ine-concluye-fiscalizacion-del-proceso-electoral-2021\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2021\/ine-concluye-fiscalizacion-del-proceso-electoral-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/07\/01-21.jpg","datePublished":"2021-07-24T20:26:27+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2021\/ine-concluye-fiscalizacion-del-proceso-electoral-2021\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2021\/ine-concluye-fiscalizacion-del-proceso-electoral-2021\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2021\/ine-concluye-fiscalizacion-del-proceso-electoral-2021\/#primaryimage","url":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/07\/01-21.jpg","contentUrl":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/07\/01-21.jpg","width":675,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2021\/ine-concluye-fiscalizacion-del-proceso-electoral-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2021\/"},{"@type":"ListItem","position":2,"name":"INE concluye fiscalizaci\u00f3n del Proceso Electoral 2021"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2021\/#website","url":"https:\/\/canal7slp.tv\/2021\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2021\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2021\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2021\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2021\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2021\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanalsiete","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2021\/#\/schema\/person\/28a12b0491d3b6f41a854d062961bdc7","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2021\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/posts\/25944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/comments?post=25944"}],"version-history":[{"count":3,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/posts\/25944\/revisions"}],"predecessor-version":[{"id":25968,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/posts\/25944\/revisions\/25968"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/media\/25956"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/media?parent=25944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/categories?post=25944"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/tags?post=25944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}