{"id":24314,"date":"2021-07-13T12:49:25","date_gmt":"2021-07-13T18:49:25","guid":{"rendered":"https:\/\/canal7slp.tv\/2021\/?p=24314"},"modified":"2021-07-13T12:49:25","modified_gmt":"2021-07-13T18:49:25","slug":"aumenta-a-95-las-muertes-confirmadas-por-derrumbe-de-edificio-en-florida","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2021\/aumenta-a-95-las-muertes-confirmadas-por-derrumbe-de-edificio-en-florida\/","title":{"rendered":"Aumenta a 95 las muertes confirmadas por derrumbe de edificio en Florida"},"content":{"rendered":"<p style=\"text-align: justify;\">EUA.- Autoridades confirmaron que los equipos de b\u00fasqueda de v\u00edctimas bajo los escombros del edificio que se colapso en Surfside han logrado localizar a 95 v\u00edctimas fatales del incidente.<\/p>\n<p style=\"text-align: justify;\">Aunado, el n\u00famero de personas que no han podido ser localizadas ha disminuido hasta las 14.<\/p>\n<p style=\"text-align: justify;\">De acuerdo con Daniella Levine Cava, alcaldesa de Miami-Dade, 85 de los 95 cuerpos recuperados han sido identificados hasta ahora.<\/p>\n<p style=\"text-align: justify;\">Cabe se\u00f1alar, que entre las v\u00edctimas hab\u00eda estadounidenses argentinos, cubanos, uruguayos, colombianos, chilenos, venezolanos, paraguayos e israel\u00edes, ente otras nacionalidades.<\/p>\n<p style=\"text-align: justify;\">La investigaci\u00f3n de las causas del derrumbe del ala noreste del edificio Champlain Towers South, en la que hab\u00eda 55 apartamentos, ya se inici\u00f3, pero se da por seguro que ser\u00e1 larga y compleja.<\/p>\n<p style=\"text-align: justify;\">As\u00ed mismo, en tribunales ya hay por lo menos media decena de demandas presentadas contra la asociaci\u00f3n del condominio, que ten\u00eda problemas estructurales desde por lo menos 2018, de acuerdo con datos de una firma de ingenieros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>EUA.- Autoridades confirmaron que los equipos de b\u00fasqueda de v\u00edctimas bajo los escombros del edificio que se colapso en Surfside han logrado localizar a 95 v\u00edctimas fatales del incidente. Aunado, el n\u00famero de personas que no han podido ser localizadas ha disminuido hasta las 14. De acuerdo con Daniella Levine Cava, alcaldesa de Miami-Dade, 85 de los 95 cuerpos recuperados han sido identificados hasta ahora. Cabe se\u00f1alar, que entre las v\u00edctimas hab\u00eda estadounidenses argentinos, cubanos, uruguayos, colombianos, chilenos, venezolanos, paraguayos e israel\u00edes, ente otras nacionalidades. La investigaci\u00f3n de las causas del derrumbe del ala noreste del edificio Champlain Towers South, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":24323,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[44],"tags":[],"class_list":["post-24314","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aumenta a 95 las muertes confirmadas por derrumbe de edificio en Florida - Canal 7 SLP - 2021<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2021\/aumenta-a-95-las-muertes-confirmadas-por-derrumbe-de-edificio-en-florida\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aumenta a 95 las muertes confirmadas por derrumbe de edificio en Florida - Canal 7 SLP - 2021\" \/>\n<meta property=\"og:description\" content=\"EUA.- Autoridades confirmaron que los equipos de b\u00fasqueda de v\u00edctimas bajo los escombros del edificio que se colapso en Surfside han logrado localizar a 95 v\u00edctimas fatales del incidente. Aunado, el n\u00famero de personas que no han podido ser localizadas ha disminuido hasta las 14. De acuerdo con Daniella Levine Cava, alcaldesa de Miami-Dade, 85 de los 95 cuerpos recuperados han sido identificados hasta ahora. Cabe se\u00f1alar, que entre las v\u00edctimas hab\u00eda estadounidenses argentinos, cubanos, uruguayos, colombianos, chilenos, venezolanos, paraguayos e israel\u00edes, ente otras nacionalidades. La investigaci\u00f3n de las causas del derrumbe del ala noreste del edificio Champlain Towers South, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2021\/aumenta-a-95-las-muertes-confirmadas-por-derrumbe-de-edificio-en-florida\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2021\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanalsiete\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-13T18:49:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/07\/04-11.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"591\" \/>\n\t<meta property=\"og:image:height\" content=\"410\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/aumenta-a-95-las-muertes-confirmadas-por-derrumbe-de-edificio-en-florida\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/aumenta-a-95-las-muertes-confirmadas-por-derrumbe-de-edificio-en-florida\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#\\\/schema\\\/person\\\/28a12b0491d3b6f41a854d062961bdc7\"},\"headline\":\"Aumenta a 95 las muertes confirmadas por derrumbe de edificio en Florida\",\"datePublished\":\"2021-07-13T18:49:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/aumenta-a-95-las-muertes-confirmadas-por-derrumbe-de-edificio-en-florida\\\/\"},\"wordCount\":174,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/aumenta-a-95-las-muertes-confirmadas-por-derrumbe-de-edificio-en-florida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/04-11.jpg\",\"articleSection\":[\"INTERNACIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/aumenta-a-95-las-muertes-confirmadas-por-derrumbe-de-edificio-en-florida\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/aumenta-a-95-las-muertes-confirmadas-por-derrumbe-de-edificio-en-florida\\\/\",\"name\":\"Aumenta a 95 las muertes confirmadas por derrumbe de edificio en Florida - Canal 7 SLP - 2021\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/aumenta-a-95-las-muertes-confirmadas-por-derrumbe-de-edificio-en-florida\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/aumenta-a-95-las-muertes-confirmadas-por-derrumbe-de-edificio-en-florida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/04-11.jpg\",\"datePublished\":\"2021-07-13T18:49:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/aumenta-a-95-las-muertes-confirmadas-por-derrumbe-de-edificio-en-florida\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/aumenta-a-95-las-muertes-confirmadas-por-derrumbe-de-edificio-en-florida\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/aumenta-a-95-las-muertes-confirmadas-por-derrumbe-de-edificio-en-florida\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/04-11.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/04-11.jpg\",\"width\":591,\"height\":410},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/aumenta-a-95-las-muertes-confirmadas-por-derrumbe-de-edificio-en-florida\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aumenta a 95 las muertes confirmadas por derrumbe de edificio en Florida\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanalsiete\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#\\\/schema\\\/person\\\/28a12b0491d3b6f41a854d062961bdc7\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aumenta a 95 las muertes confirmadas por derrumbe de edificio en Florida - Canal 7 SLP - 2021","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2021\/aumenta-a-95-las-muertes-confirmadas-por-derrumbe-de-edificio-en-florida\/","og_locale":"es_ES","og_type":"article","og_title":"Aumenta a 95 las muertes confirmadas por derrumbe de edificio en Florida - Canal 7 SLP - 2021","og_description":"EUA.- Autoridades confirmaron que los equipos de b\u00fasqueda de v\u00edctimas bajo los escombros del edificio que se colapso en Surfside han logrado localizar a 95 v\u00edctimas fatales del incidente. Aunado, el n\u00famero de personas que no han podido ser localizadas ha disminuido hasta las 14. De acuerdo con Daniella Levine Cava, alcaldesa de Miami-Dade, 85 de los 95 cuerpos recuperados han sido identificados hasta ahora. Cabe se\u00f1alar, que entre las v\u00edctimas hab\u00eda estadounidenses argentinos, cubanos, uruguayos, colombianos, chilenos, venezolanos, paraguayos e israel\u00edes, ente otras nacionalidades. La investigaci\u00f3n de las causas del derrumbe del ala noreste del edificio Champlain Towers South, [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2021\/aumenta-a-95-las-muertes-confirmadas-por-derrumbe-de-edificio-en-florida\/","og_site_name":"Canal 7 SLP - 2021","article_publisher":"https:\/\/www.facebook.com\/noticieroscanalsiete","article_published_time":"2021-07-13T18:49:25+00:00","og_image":[{"width":591,"height":410,"url":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/07\/04-11.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2021\/aumenta-a-95-las-muertes-confirmadas-por-derrumbe-de-edificio-en-florida\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2021\/aumenta-a-95-las-muertes-confirmadas-por-derrumbe-de-edificio-en-florida\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2021\/#\/schema\/person\/28a12b0491d3b6f41a854d062961bdc7"},"headline":"Aumenta a 95 las muertes confirmadas por derrumbe de edificio en Florida","datePublished":"2021-07-13T18:49:25+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2021\/aumenta-a-95-las-muertes-confirmadas-por-derrumbe-de-edificio-en-florida\/"},"wordCount":174,"publisher":{"@id":"https:\/\/canal7slp.tv\/2021\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2021\/aumenta-a-95-las-muertes-confirmadas-por-derrumbe-de-edificio-en-florida\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/07\/04-11.jpg","articleSection":["INTERNACIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2021\/aumenta-a-95-las-muertes-confirmadas-por-derrumbe-de-edificio-en-florida\/","url":"https:\/\/canal7slp.tv\/2021\/aumenta-a-95-las-muertes-confirmadas-por-derrumbe-de-edificio-en-florida\/","name":"Aumenta a 95 las muertes confirmadas por derrumbe de edificio en Florida - Canal 7 SLP - 2021","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2021\/aumenta-a-95-las-muertes-confirmadas-por-derrumbe-de-edificio-en-florida\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2021\/aumenta-a-95-las-muertes-confirmadas-por-derrumbe-de-edificio-en-florida\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/07\/04-11.jpg","datePublished":"2021-07-13T18:49:25+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2021\/aumenta-a-95-las-muertes-confirmadas-por-derrumbe-de-edificio-en-florida\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2021\/aumenta-a-95-las-muertes-confirmadas-por-derrumbe-de-edificio-en-florida\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2021\/aumenta-a-95-las-muertes-confirmadas-por-derrumbe-de-edificio-en-florida\/#primaryimage","url":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/07\/04-11.jpg","contentUrl":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/07\/04-11.jpg","width":591,"height":410},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2021\/aumenta-a-95-las-muertes-confirmadas-por-derrumbe-de-edificio-en-florida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2021\/"},{"@type":"ListItem","position":2,"name":"Aumenta a 95 las muertes confirmadas por derrumbe de edificio en Florida"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2021\/#website","url":"https:\/\/canal7slp.tv\/2021\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2021\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2021\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2021\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2021\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2021\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanalsiete","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2021\/#\/schema\/person\/28a12b0491d3b6f41a854d062961bdc7","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2021\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/posts\/24314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/comments?post=24314"}],"version-history":[{"count":2,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/posts\/24314\/revisions"}],"predecessor-version":[{"id":24329,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/posts\/24314\/revisions\/24329"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/media\/24323"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/media?parent=24314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/categories?post=24314"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/tags?post=24314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}