{"id":23064,"date":"2021-07-02T15:09:42","date_gmt":"2021-07-02T21:09:42","guid":{"rendered":"https:\/\/canal7slp.tv\/2021\/?p=23064"},"modified":"2021-07-02T15:09:42","modified_gmt":"2021-07-02T21:09:42","slug":"fgeslp-logra-prision-preventiva-para-2-policias-municipales-por-presunta-desaparicion-forzada","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2021\/fgeslp-logra-prision-preventiva-para-2-policias-municipales-por-presunta-desaparicion-forzada\/","title":{"rendered":"FGESLP logra prisi\u00f3n preventiva para 2 polic\u00edas municipales por presunta desaparici\u00f3n forzada"},"content":{"rendered":"<div style=\"text-align: justify;\">\u2022 Permanecer\u00e1n recluidos en el centro de reinserci\u00f3n social de La Pila<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">SLP. \u2013 Litigadores de la Unidad para la Atenci\u00f3n de Personas Desaparecidas o Extraviadas de la Fiscal\u00eda Especializada en Materia de Derechos Humanos, lograron la vinculaci\u00f3n a proceso de dos agentes activos de la Direcci\u00f3n General de Seguridad P\u00fablica de la Capital, por su presunta participaci\u00f3n en la desaparici\u00f3n de dos personas.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Despu\u00e9s de que venciera la ampliaci\u00f3n del t\u00e9rmino constitucional solicitado por la defensa, se dio la continuaci\u00f3n de la audiencia inicial en la cual Israel \u201cN\u201d y Jos\u00e9 Agust\u00edn \u201cN\u201d fueron informados que permanecer\u00e1n en bajo la medida cautelar de prisi\u00f3n preventiva oficiosa, recluidos en el centro de reinserci\u00f3n social de La Pila.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Adem\u00e1s, el Juez de Control estableci\u00f3 cuatro meses para el cierre de la investigaci\u00f3n complementaria, tiempo en el que las partes involucradas tendr\u00e1 que aportar m\u00e1s datos de prueba.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">La Fiscal\u00eda General del Estado de San Luis Potos\u00ed (FGESLP) inform\u00f3 que los hechos de los que se deriva este proceso, ocurrieron el 9 de septiembre del 2017, cuando presuntamente los se\u00f1alados habr\u00edan privado de la libertad a dos hombres en el fraccionamiento El Sauzalito.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Posteriormente, los cuerpos de las v\u00edctimas fueron encontrados sin vida en Anillo Perif\u00e9rico a la altura de la colonia La Virgen en el municipio de Soledad de Graciano S\u00e1nchez, al interior de bolsas negras y horas m\u00e1s tarde en la calle Valent\u00edn Amador en la zona Centro de San Luis Potos\u00ed, en la caja de una camioneta fueron localizadas las extremidades cef\u00e1licas de los occisos con una cartulina alusiva a un presunto grupo delictivo.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Tras las indagaciones, los elementos de la PDI lograron obtener datos de prueba en contra de los presuntos, con los que el agente del Ministerio P\u00fablico Especializado, integr\u00f3 debidamente la carpeta de investigaci\u00f3n y acudi\u00f3 ante el Juez de Control quien obsequi\u00f3 la orden de aprehensi\u00f3n.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Los se\u00f1alados fueron detenidos al oriente de la Capital potosina hace unos d\u00edas y conducidos a la audiencia inicial con los resultados antes mencionados.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u2022 Permanecer\u00e1n recluidos en el centro de reinserci\u00f3n social de La Pila SLP. \u2013 Litigadores de la Unidad para la Atenci\u00f3n de Personas Desaparecidas o Extraviadas de la Fiscal\u00eda Especializada en Materia de Derechos Humanos, lograron la vinculaci\u00f3n a proceso de dos agentes activos de la Direcci\u00f3n General de Seguridad P\u00fablica de la Capital, por su presunta participaci\u00f3n en la desaparici\u00f3n de dos personas. Despu\u00e9s de que venciera la ampliaci\u00f3n del t\u00e9rmino constitucional solicitado por la defensa, se dio la continuaci\u00f3n de la audiencia inicial en la cual Israel \u201cN\u201d y Jos\u00e9 Agust\u00edn \u201cN\u201d fueron informados que permanecer\u00e1n en bajo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":23068,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-23064","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reporte7","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FGESLP logra prisi\u00f3n preventiva para 2 polic\u00edas municipales por presunta desaparici\u00f3n forzada - Canal 7 SLP - 2021<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2021\/fgeslp-logra-prision-preventiva-para-2-policias-municipales-por-presunta-desaparicion-forzada\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FGESLP logra prisi\u00f3n preventiva para 2 polic\u00edas municipales por presunta desaparici\u00f3n forzada - Canal 7 SLP - 2021\" \/>\n<meta property=\"og:description\" content=\"\u2022 Permanecer\u00e1n recluidos en el centro de reinserci\u00f3n social de La Pila SLP. \u2013 Litigadores de la Unidad para la Atenci\u00f3n de Personas Desaparecidas o Extraviadas de la Fiscal\u00eda Especializada en Materia de Derechos Humanos, lograron la vinculaci\u00f3n a proceso de dos agentes activos de la Direcci\u00f3n General de Seguridad P\u00fablica de la Capital, por su presunta participaci\u00f3n en la desaparici\u00f3n de dos personas. Despu\u00e9s de que venciera la ampliaci\u00f3n del t\u00e9rmino constitucional solicitado por la defensa, se dio la continuaci\u00f3n de la audiencia inicial en la cual Israel \u201cN\u201d y Jos\u00e9 Agust\u00edn \u201cN\u201d fueron informados que permanecer\u00e1n en bajo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2021\/fgeslp-logra-prision-preventiva-para-2-policias-municipales-por-presunta-desaparicion-forzada\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2021\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanalsiete\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-02T21:09:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/07\/zz3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"792\" \/>\n\t<meta property=\"og:image:height\" content=\"554\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/fgeslp-logra-prision-preventiva-para-2-policias-municipales-por-presunta-desaparicion-forzada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/fgeslp-logra-prision-preventiva-para-2-policias-municipales-por-presunta-desaparicion-forzada\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#\\\/schema\\\/person\\\/28a12b0491d3b6f41a854d062961bdc7\"},\"headline\":\"FGESLP logra prisi\u00f3n preventiva para 2 polic\u00edas municipales por presunta desaparici\u00f3n forzada\",\"datePublished\":\"2021-07-02T21:09:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/fgeslp-logra-prision-preventiva-para-2-policias-municipales-por-presunta-desaparicion-forzada\\\/\"},\"wordCount\":379,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/fgeslp-logra-prision-preventiva-para-2-policias-municipales-por-presunta-desaparicion-forzada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/zz3.jpg\",\"articleSection\":[\"REPORTE 7\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/fgeslp-logra-prision-preventiva-para-2-policias-municipales-por-presunta-desaparicion-forzada\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/fgeslp-logra-prision-preventiva-para-2-policias-municipales-por-presunta-desaparicion-forzada\\\/\",\"name\":\"FGESLP logra prisi\u00f3n preventiva para 2 polic\u00edas municipales por presunta desaparici\u00f3n forzada - Canal 7 SLP - 2021\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/fgeslp-logra-prision-preventiva-para-2-policias-municipales-por-presunta-desaparicion-forzada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/fgeslp-logra-prision-preventiva-para-2-policias-municipales-por-presunta-desaparicion-forzada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/zz3.jpg\",\"datePublished\":\"2021-07-02T21:09:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/fgeslp-logra-prision-preventiva-para-2-policias-municipales-por-presunta-desaparicion-forzada\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/fgeslp-logra-prision-preventiva-para-2-policias-municipales-por-presunta-desaparicion-forzada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/fgeslp-logra-prision-preventiva-para-2-policias-municipales-por-presunta-desaparicion-forzada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/zz3.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/zz3.jpg\",\"width\":792,\"height\":554},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/fgeslp-logra-prision-preventiva-para-2-policias-municipales-por-presunta-desaparicion-forzada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FGESLP logra prisi\u00f3n preventiva para 2 polic\u00edas municipales por presunta desaparici\u00f3n forzada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanalsiete\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#\\\/schema\\\/person\\\/28a12b0491d3b6f41a854d062961bdc7\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FGESLP logra prisi\u00f3n preventiva para 2 polic\u00edas municipales por presunta desaparici\u00f3n forzada - Canal 7 SLP - 2021","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2021\/fgeslp-logra-prision-preventiva-para-2-policias-municipales-por-presunta-desaparicion-forzada\/","og_locale":"es_ES","og_type":"article","og_title":"FGESLP logra prisi\u00f3n preventiva para 2 polic\u00edas municipales por presunta desaparici\u00f3n forzada - Canal 7 SLP - 2021","og_description":"\u2022 Permanecer\u00e1n recluidos en el centro de reinserci\u00f3n social de La Pila SLP. \u2013 Litigadores de la Unidad para la Atenci\u00f3n de Personas Desaparecidas o Extraviadas de la Fiscal\u00eda Especializada en Materia de Derechos Humanos, lograron la vinculaci\u00f3n a proceso de dos agentes activos de la Direcci\u00f3n General de Seguridad P\u00fablica de la Capital, por su presunta participaci\u00f3n en la desaparici\u00f3n de dos personas. Despu\u00e9s de que venciera la ampliaci\u00f3n del t\u00e9rmino constitucional solicitado por la defensa, se dio la continuaci\u00f3n de la audiencia inicial en la cual Israel \u201cN\u201d y Jos\u00e9 Agust\u00edn \u201cN\u201d fueron informados que permanecer\u00e1n en bajo [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2021\/fgeslp-logra-prision-preventiva-para-2-policias-municipales-por-presunta-desaparicion-forzada\/","og_site_name":"Canal 7 SLP - 2021","article_publisher":"https:\/\/www.facebook.com\/noticieroscanalsiete","article_published_time":"2021-07-02T21:09:42+00:00","og_image":[{"width":792,"height":554,"url":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/07\/zz3.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2021\/fgeslp-logra-prision-preventiva-para-2-policias-municipales-por-presunta-desaparicion-forzada\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2021\/fgeslp-logra-prision-preventiva-para-2-policias-municipales-por-presunta-desaparicion-forzada\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2021\/#\/schema\/person\/28a12b0491d3b6f41a854d062961bdc7"},"headline":"FGESLP logra prisi\u00f3n preventiva para 2 polic\u00edas municipales por presunta desaparici\u00f3n forzada","datePublished":"2021-07-02T21:09:42+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2021\/fgeslp-logra-prision-preventiva-para-2-policias-municipales-por-presunta-desaparicion-forzada\/"},"wordCount":379,"publisher":{"@id":"https:\/\/canal7slp.tv\/2021\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2021\/fgeslp-logra-prision-preventiva-para-2-policias-municipales-por-presunta-desaparicion-forzada\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/07\/zz3.jpg","articleSection":["REPORTE 7"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2021\/fgeslp-logra-prision-preventiva-para-2-policias-municipales-por-presunta-desaparicion-forzada\/","url":"https:\/\/canal7slp.tv\/2021\/fgeslp-logra-prision-preventiva-para-2-policias-municipales-por-presunta-desaparicion-forzada\/","name":"FGESLP logra prisi\u00f3n preventiva para 2 polic\u00edas municipales por presunta desaparici\u00f3n forzada - Canal 7 SLP - 2021","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2021\/fgeslp-logra-prision-preventiva-para-2-policias-municipales-por-presunta-desaparicion-forzada\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2021\/fgeslp-logra-prision-preventiva-para-2-policias-municipales-por-presunta-desaparicion-forzada\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/07\/zz3.jpg","datePublished":"2021-07-02T21:09:42+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2021\/fgeslp-logra-prision-preventiva-para-2-policias-municipales-por-presunta-desaparicion-forzada\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2021\/fgeslp-logra-prision-preventiva-para-2-policias-municipales-por-presunta-desaparicion-forzada\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2021\/fgeslp-logra-prision-preventiva-para-2-policias-municipales-por-presunta-desaparicion-forzada\/#primaryimage","url":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/07\/zz3.jpg","contentUrl":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/07\/zz3.jpg","width":792,"height":554},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2021\/fgeslp-logra-prision-preventiva-para-2-policias-municipales-por-presunta-desaparicion-forzada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2021\/"},{"@type":"ListItem","position":2,"name":"FGESLP logra prisi\u00f3n preventiva para 2 polic\u00edas municipales por presunta desaparici\u00f3n forzada"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2021\/#website","url":"https:\/\/canal7slp.tv\/2021\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2021\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2021\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2021\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2021\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2021\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanalsiete","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2021\/#\/schema\/person\/28a12b0491d3b6f41a854d062961bdc7","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2021\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/posts\/23064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/comments?post=23064"}],"version-history":[{"count":1,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/posts\/23064\/revisions"}],"predecessor-version":[{"id":23065,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/posts\/23064\/revisions\/23065"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/media\/23068"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/media?parent=23064"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/categories?post=23064"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/tags?post=23064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}