{"id":1534,"date":"2021-01-19T20:23:34","date_gmt":"2021-01-19T20:23:34","guid":{"rendered":"https:\/\/canal7slp.tv\/2021\/enrique-baca-va-por-la-corona-del-2021\/"},"modified":"2021-01-19T20:23:34","modified_gmt":"2021-01-19T20:23:34","slug":"enrique-baca-va-por-la-corona-del-2021","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2021\/enrique-baca-va-por-la-corona-del-2021\/","title":{"rendered":"Enrique Baca va por la corona del 2021."},"content":{"rendered":"<div>\n<p style=\"text-align: justify\">SLP.- Enrique Baca que finaliz\u00f3 la temporada en la tercera posici\u00f3n general de los Tractocamiones, espera este a\u00f1o salir desde la primera fecha a buscar la corona de la categor\u00eda.<\/p>\n<p style=\"text-align: justify\">Baca aclar\u00f3 que en el 2021 el objetivo est\u00e1 puesto en el campeonato y que agradece la oportunidad poder participar en una categor\u00eda tan espectacular como la de los tractocamiones.<\/p>\n<p style=\"text-align: justify\">Hubo tres carreras que marcaron la posibilidad de pelear el campeonato, la primera de Quer\u00e9taro, Monterrey y Guadalajara, donde no sum\u00e9 una buena cantidad de puntos. Pero estoy conforme de haber finalizado entre los tres mejores y de haber figurado en la lista de los que ganaron carreras, Es por ello que tengo mucha confianza que este 2021 se pueden hacer cosas muy buenas entre todos, aclar\u00f3 el piloto<\/p>\n<p>&#13;<br \/>\n\t\t\t\t<span class=\"post-views-icon dashicons dashicons-chart-bar\"\/>&#13;<br \/>\n\t\t\t\t<span class=\"post-views-label\">Post Views: <\/span>&#13;<br \/>\n\t\t\t\t<span class=\"post-views-count\">10<\/span>&#13;\n\t\t\t<\/p>\n<\/div>\n<p><script type=\"text\/javascript\" id='beeteam368_obj_wes-js-extra'>\n\/* <![CDATA[ *\/\nvar vidorev_jav_plugin_js_object = {\"youtube_library_url\":\"https:\/\/www.youtube.com\/iframe_api\",\"vimeo_library_url\":\"https:\/\/player.vimeo.com\/api\/player.js\",\"dailymotion_library_url\":\"https:\/\/api.dmcdn.net\/all.js\",\"facebook_library_url\":\"https:\/\/connect.facebook.net\/en_US\/sdk.js?ver=6.0#xfbml=1&#038;version=v6.0\",\"twitch_library_url\":\"https:\/\/player.twitch.tv\/js\/embed\/v1.js\",\"google_ima_library_url\":\"https:\/\/imasdk.googleapis.com\/js\/sdkloader\/ima3.js\",\"google_adsense_library_url\":\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\",\"jwplayer_library_url\":\"\",\"mediaelement_library_url\":\"https:\/\/canal7slp.tv\/2020\/wp-content\/plugins\/vidorev-extensions\/assets\/front-end\/mediaelement\/mediaelement.all.js\",\"plyr_library_url\":\"https:\/\/canal7slp.tv\/2020\/wp-content\/plugins\/vidorev-extensions\/assets\/front-end\/plyr\/plyr.min.js\",\"imdb_logo_url\":\"https:\/\/canal7slp.tv\/2020\/wp-content\/plugins\/vidorev-extensions\/assets\/front-end\/img\/IMDB_Logo\",\"youtube_rel\":\"no\",\"youtube_modestbranding\":\"yes\",\"youtube_showinfo\":\"no\",\"youtube_broadcasts_params\":[]};\nvar vidorev_jav_plugin_video_ads_object = {\"vid_ads_m_video_ads\":\"no\",\"vid_ads_m_video_ads_type\":\"google_ima\",\"vid_ads_m_group_google_ima\":[],\"vid_ads_m_group_image\":[{\"vid_ads_m_image_source_id\":4702,\"vid_ads_m_image_source\":\"https:\/\/canal7slp.tv\/2020\/wp-content\/uploads\/2019\/05\/01.png\",\"vid_ads_m_image_link\":\"https:\/\/trackhoundgps.com\"}],\"vid_ads_m_group_html5_video\":[],\"vid_ads_m_group_html\":[],\"vid_ads_m_vast_preroll\":[],\"vid_ads_m_vast_postroll\":[],\"vid_ads_m_vast_pauseroll\":[],\"vid_ads_m_vast_midroll\":[{\"vid_ads_m_vast_timer_seconds\":\"50\"}]};\nvar vidorev_jav_plugin_video_ads_object_post = {\"vid_ads_m_video_ads\":\"\",\"vid_ads_m_video_ads_type\":\"\",\"vid_ads_m_group_google_ima\":\"\",\"vid_ads_m_group_image\":\"\",\"vid_ads_m_group_html5_video\":\"\",\"vid_ads_m_group_html\":\"\",\"vid_ads_m_group_dynamic\":[{\"vid_ads_m_dynamic_type\":\"image\",\"vid_ads_m_dynamic_size_desktop\":\"336x280\",\"vid_ads_m_dynamic_size_mobile\":\"300x250\",\"vid_ads_m_dynamic_vertial_align\":\"bottom\"}],\"vid_ads_m_time_to_show_ads\":\"\",\"vid_ads_m_time_skip_ads\":\"\",\"vid_ads_m_time_to_hide_ads\":\"\"};\nvar vidorev_jav_js_object = {\"admin_ajax\":\"https:\/\/canal7slp.tv\/2020\/wp-admin\/admin-ajax.php\",\"query_vars\":{\"page\":0,\"name\":\"enrique-baca-va-por-la-corona-del-2021\",\"error\":\"\",\"m\":\"\",\"p\":0,\"post_parent\":\"\",\"subpost\":\"\",\"subpost_id\":\"\",\"attachment\":\"\",\"attachment_id\":0,\"pagename\":\"\",\"page_id\":0,\"second\":\"\",\"minute\":\"\",\"hour\":\"\",\"day\":0,\"monthnum\":0,\"year\":0,\"w\":0,\"category_name\":\"\",\"tag\":\"\",\"cat\":\"\",\"tag_id\":\"\",\"author\":\"\",\"author_name\":\"\",\"feed\":\"\",\"tb\":\"\",\"paged\":0,\"meta_key\":\"\",\"meta_value\":\"\",\"preview\":\"\",\"s\":\"\",\"sentence\":\"\",\"title\":\"\",\"fields\":\"\",\"menu_order\":\"\",\"embed\":\"\",\"category__in\":[],\"category__not_in\":[],\"category__and\":[],\"post__in\":[],\"post__not_in\":[],\"post_name__in\":[],\"tag__in\":[],\"tag__not_in\":[],\"tag__and\":[],\"tag_slug__in\":[],\"tag_slug__and\":[],\"post_parent__in\":[],\"post_parent__not_in\":[],\"author__in\":[],\"author__not_in\":[],\"ignore_sticky_posts\":false,\"suppress_filters\":false,\"cache_results\":true,\"update_post_term_cache\":true,\"lazy_load_term_meta\":true,\"update_post_meta_cache\":true,\"post_type\":\"\",\"posts_per_page\":20,\"nopaging\":false,\"comments_per_page\":\"50\",\"no_found_rows\":false,\"order\":\"DESC\"},\"video_auto_play\":\"off\",\"vid_auto_play_mute\":\"off\",\"number_format\":\"short\",\"single_post_comment_type\":\"wp\",\"origin_url\":\"https:\/\/canal7slp.tv\/2020\",\"is_user_logged_in\":\"\",\"video_lightbox_suggested\":\"on\",\"video_lightbox_comments\":\"off\",\"translate_close\":\"Cerrar\",\"translate_suggested\":\"Te Recomendamos\",\"translate_comments\":\"Live comments\",\"translate_auto_next\":\"Auto Play\",\"translate_loading\":\"Loading\",\"translate_public_comment\":\"Add a public comment\",\"translate_post_comment\":\"Post comment\",\"translate_reset\":\"Reset\",\"translate_login_comment\":\"Please login to post a comment\",\"translate_text_load_ad\":\"Loading advertisement...\",\"translate_skip_ad\":\"Skip Ad\",\"translate_skip_ad_in\":\"Skip ad in\",\"translate_up_next\":\"Siguiente\",\"translate_cancel\":\"cancel\",\"translate_reported\":\"Reported\",\"translate_confirm_delete\":\"Are you sure you want to delete this item?\",\"translate_delete_success\":\"The post has been deleted.\",\"translate_loading_preview\":\"Loading Preview\",\"translate_currently_offline\":\"Currently Offline\",\"translate_live_or_ended\":\"Live Streaming or Ended\",\"theme_image_ratio\":\"\",\"single_video_network\":\"youtube\",\"single_video_source\":\"FPM6HcDqhYE\",\"single_video_youtube_playlist_id\":\"\",\"single_video_url\":\"https:\/\/youtu.be\/FPM6HcDqhYE\",\"player_library\":\"vp\",\"plyr_player\":\"off\",\"single_video_streaming\":\"\",\"vm_video_ratio\":\"16:9\",\"vm_video_ratio_mobile\":\"16:9\",\"single_video_network_library_setup\":\"yes\",\"security\":\"d72d59008a\",\"login_url\":\"\",\"scrollbar_library\":\"malihu\"};\nvar vidorev_jav_js_preview = [];\n\/* ]]> *\/\n<\/script><script type=\"text\/javascript\">\n!function(f,b,e,v,n,t,s){if(f.fbq)return;n=f.fbq=function(){n.callMethod?\nn.callMethod.apply(n,arguments):n.queue.push(arguments)};if(!f._fbq)f._fbq=n;\nn.push=n;n.loaded=!0;n.version='2.0';n.queue=[];t=b.createElement(e);t.async=!0;\nt.src=v;s=b.getElementsByTagName(e)[0];s.parentNode.insertBefore(t,s)}(window,\ndocument,'script','https:\/\/connect.facebook.net\/en_US\/fbevents.js');\n<\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>SLP.- Enrique Baca que finaliz\u00f3 la temporada en la tercera posici\u00f3n general de los Tractocamiones, espera este a\u00f1o salir desde la primera fecha a buscar la corona de la categor\u00eda. Baca aclar\u00f3 que en el 2021 el objetivo est\u00e1 puesto en el campeonato y que agradece la oportunidad poder participar en una categor\u00eda tan espectacular como la de los tractocamiones. Hubo tres carreras que marcaron la posibilidad de pelear el campeonato, la primera de Quer\u00e9taro, Monterrey y Guadalajara, donde no sum\u00e9 una buena cantidad de puntos. Pero estoy conforme de haber finalizado entre los tres mejores y de haber figurado [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1535,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-1534","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Enrique Baca va por la corona del 2021. - Canal 7 SLP - 2021<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2021\/enrique-baca-va-por-la-corona-del-2021\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Enrique Baca va por la corona del 2021. - Canal 7 SLP - 2021\" \/>\n<meta property=\"og:description\" content=\"SLP.- Enrique Baca que finaliz\u00f3 la temporada en la tercera posici\u00f3n general de los Tractocamiones, espera este a\u00f1o salir desde la primera fecha a buscar la corona de la categor\u00eda. Baca aclar\u00f3 que en el 2021 el objetivo est\u00e1 puesto en el campeonato y que agradece la oportunidad poder participar en una categor\u00eda tan espectacular como la de los tractocamiones. Hubo tres carreras que marcaron la posibilidad de pelear el campeonato, la primera de Quer\u00e9taro, Monterrey y Guadalajara, donde no sum\u00e9 una buena cantidad de puntos. Pero estoy conforme de haber finalizado entre los tres mejores y de haber figurado [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2021\/enrique-baca-va-por-la-corona-del-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2021\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanalsiete\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-19T20:23:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/01\/baca.png\" \/>\n\t<meta property=\"og:image:width\" content=\"894\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/enrique-baca-va-por-la-corona-del-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/enrique-baca-va-por-la-corona-del-2021\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#\\\/schema\\\/person\\\/28a12b0491d3b6f41a854d062961bdc7\"},\"headline\":\"Enrique Baca va por la corona del 2021.\",\"datePublished\":\"2021-01-19T20:23:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/enrique-baca-va-por-la-corona-del-2021\\\/\"},\"wordCount\":142,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/enrique-baca-va-por-la-corona-del-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/baca.png\",\"articleSection\":[\"DEPORTES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/enrique-baca-va-por-la-corona-del-2021\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/enrique-baca-va-por-la-corona-del-2021\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/enrique-baca-va-por-la-corona-del-2021\\\/\",\"name\":\"Enrique Baca va por la corona del 2021. - Canal 7 SLP - 2021\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/enrique-baca-va-por-la-corona-del-2021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/enrique-baca-va-por-la-corona-del-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/baca.png\",\"datePublished\":\"2021-01-19T20:23:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/enrique-baca-va-por-la-corona-del-2021\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/enrique-baca-va-por-la-corona-del-2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/enrique-baca-va-por-la-corona-del-2021\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/baca.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/baca.png\",\"width\":894,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/enrique-baca-va-por-la-corona-del-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Enrique Baca va por la corona del 2021.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanalsiete\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#\\\/schema\\\/person\\\/28a12b0491d3b6f41a854d062961bdc7\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Enrique Baca va por la corona del 2021. - Canal 7 SLP - 2021","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2021\/enrique-baca-va-por-la-corona-del-2021\/","og_locale":"es_ES","og_type":"article","og_title":"Enrique Baca va por la corona del 2021. - Canal 7 SLP - 2021","og_description":"SLP.- Enrique Baca que finaliz\u00f3 la temporada en la tercera posici\u00f3n general de los Tractocamiones, espera este a\u00f1o salir desde la primera fecha a buscar la corona de la categor\u00eda. Baca aclar\u00f3 que en el 2021 el objetivo est\u00e1 puesto en el campeonato y que agradece la oportunidad poder participar en una categor\u00eda tan espectacular como la de los tractocamiones. Hubo tres carreras que marcaron la posibilidad de pelear el campeonato, la primera de Quer\u00e9taro, Monterrey y Guadalajara, donde no sum\u00e9 una buena cantidad de puntos. Pero estoy conforme de haber finalizado entre los tres mejores y de haber figurado [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2021\/enrique-baca-va-por-la-corona-del-2021\/","og_site_name":"Canal 7 SLP - 2021","article_publisher":"https:\/\/www.facebook.com\/noticieroscanalsiete","article_published_time":"2021-01-19T20:23:34+00:00","og_image":[{"width":894,"height":500,"url":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/01\/baca.png","type":"image\/png"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2021\/enrique-baca-va-por-la-corona-del-2021\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2021\/enrique-baca-va-por-la-corona-del-2021\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2021\/#\/schema\/person\/28a12b0491d3b6f41a854d062961bdc7"},"headline":"Enrique Baca va por la corona del 2021.","datePublished":"2021-01-19T20:23:34+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2021\/enrique-baca-va-por-la-corona-del-2021\/"},"wordCount":142,"commentCount":0,"publisher":{"@id":"https:\/\/canal7slp.tv\/2021\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2021\/enrique-baca-va-por-la-corona-del-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/01\/baca.png","articleSection":["DEPORTES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/canal7slp.tv\/2021\/enrique-baca-va-por-la-corona-del-2021\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2021\/enrique-baca-va-por-la-corona-del-2021\/","url":"https:\/\/canal7slp.tv\/2021\/enrique-baca-va-por-la-corona-del-2021\/","name":"Enrique Baca va por la corona del 2021. - Canal 7 SLP - 2021","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2021\/enrique-baca-va-por-la-corona-del-2021\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2021\/enrique-baca-va-por-la-corona-del-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/01\/baca.png","datePublished":"2021-01-19T20:23:34+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2021\/enrique-baca-va-por-la-corona-del-2021\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2021\/enrique-baca-va-por-la-corona-del-2021\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2021\/enrique-baca-va-por-la-corona-del-2021\/#primaryimage","url":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/01\/baca.png","contentUrl":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/01\/baca.png","width":894,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2021\/enrique-baca-va-por-la-corona-del-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2021\/"},{"@type":"ListItem","position":2,"name":"Enrique Baca va por la corona del 2021."}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2021\/#website","url":"https:\/\/canal7slp.tv\/2021\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2021\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2021\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2021\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2021\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2021\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanalsiete","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2021\/#\/schema\/person\/28a12b0491d3b6f41a854d062961bdc7","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2021\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/posts\/1534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/comments?post=1534"}],"version-history":[{"count":0,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/posts\/1534\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/media\/1535"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/media?parent=1534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/categories?post=1534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/tags?post=1534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}