{"id":12294,"date":"2021-04-20T08:47:42","date_gmt":"2021-04-20T14:47:42","guid":{"rendered":"https:\/\/canal7slp.tv\/2021\/?p=12294"},"modified":"2021-04-20T08:47:42","modified_gmt":"2021-04-20T14:47:42","slug":"advierte-cepc-altas-temperaturas-para-slp-en-los-proximos-dias","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2021\/advierte-cepc-altas-temperaturas-para-slp-en-los-proximos-dias\/","title":{"rendered":"Advierte CEPC altas temperaturas para SLP en los pr\u00f3ximos d\u00edas"},"content":{"rendered":"<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><strong>\u00a0<\/strong><\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>La temperatura m\u00e1s alta en los \u00faltimos d\u00edas la registr\u00f3 Tamu\u00edn en donde se alcanz\u00f3 los 45 gracos cent\u00edgrados.<\/strong><\/li>\n<li><strong>Adem\u00e1s, la dependencia inform\u00f3 que el incendio en El Milagro, Guadalc\u00e1zar tiene un 85 por ciento de control y 80 de liquidaci\u00f3n.<\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong>\u00a0SLP.- De acuerdo con informaci\u00f3n del Servicio Meteorol\u00f3gico Nacional (SMN), en San Luis Potos\u00ed continuar\u00e1n las altas tempraturas en los siguientes d\u00edas, con ma\u00f1anas y tardes frescas, pero con pocas probabilidades de lluvia, dio a conocer la Coordinaci\u00f3n Estatal de Protecci\u00f3n Civil (CEPC).<\/strong><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><strong>La dependencia inform\u00f3 que en la \u00faltima semana se han registrado muy altas temperaturas, sobre todo en la zonas Huasteca y Media.<\/strong><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><strong>Detall\u00f3 que la m\u00e1s alta registrada en los \u00faltimos d\u00edas se present\u00f3 en Tamu\u00edn el d\u00eda 17 de abril, donde el term\u00f3metro alcanz\u00f3 los 45 grados cent\u00edgrados (45\u00baC); en San Ciro y El Naranjo lleg\u00f3 a los 44 grados cent\u00edgrados (44\u00baC), al igual que en Valles el d\u00eda 16 de abril.<\/strong><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><strong>De acuerdo el SMN para las pr\u00f3ximas horas se espera un cielo despejado por la ma\u00f1ana e incremento de nubosidad hacia la tarde con lluvias aisladas. Ambiente fresco por la ma\u00f1ana y c\u00e1lido por la tarde. Viento de direcci\u00f3n variable de 25 a 40 kil\u00f3metros por hora (km\/h) con rachas de 60 a 70 km\/h y tolvaneras.<\/strong><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><strong>Protecci\u00f3n Civil hizo un llamado a la poblaci\u00f3n a tomar algunas medidas preventivas como tratar de no estar demasiado tiempo realizando actividades a la luz solar, no dejar personas ni animales dentro de veh\u00edculos con las ventanas cerradas debajo del sol, tomar muchos l\u00edquidos a\u00fan y cuando no se tenga sed, extremar cuidados con los alimentos tratando de no dejarlos sin refrigeraci\u00f3n por mucho tiempo, entre otras.<\/strong><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><strong>Finalmente, la dependencia actualiz\u00f3 el estado del incendio en la comunidad El Milagro, en el municipio de Guadalc\u00e1zar, el cual lleva un control del 85 por ciento y una liquidaci\u00f3n del 80 por ciento, gracias al intenso trabajo de brigadistas y voluntarios, as\u00ed como de los tres \u00f3rdenes de gobierno.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 La temperatura m\u00e1s alta en los \u00faltimos d\u00edas la registr\u00f3 Tamu\u00edn en donde se alcanz\u00f3 los 45 gracos cent\u00edgrados. Adem\u00e1s, la dependencia inform\u00f3 que el incendio en El Milagro, Guadalc\u00e1zar tiene un 85 por ciento de control y 80 de liquidaci\u00f3n. \u00a0SLP.- De acuerdo con informaci\u00f3n del Servicio Meteorol\u00f3gico Nacional (SMN), en San Luis Potos\u00ed continuar\u00e1n las altas tempraturas en los siguientes d\u00edas, con ma\u00f1anas y tardes frescas, pero con pocas probabilidades de lluvia, dio a conocer la Coordinaci\u00f3n Estatal de Protecci\u00f3n Civil (CEPC). La dependencia inform\u00f3 que en la \u00faltima semana se han registrado muy altas temperaturas, sobre [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":12295,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[45],"tags":[],"class_list":["post-12294","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-localesyregionales","post--single"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Advierte CEPC altas temperaturas para SLP en los pr\u00f3ximos d\u00edas - Canal 7 SLP - 2021<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2021\/advierte-cepc-altas-temperaturas-para-slp-en-los-proximos-dias\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Advierte CEPC altas temperaturas para SLP en los pr\u00f3ximos d\u00edas - Canal 7 SLP - 2021\" \/>\n<meta property=\"og:description\" content=\"\u00a0 La temperatura m\u00e1s alta en los \u00faltimos d\u00edas la registr\u00f3 Tamu\u00edn en donde se alcanz\u00f3 los 45 gracos cent\u00edgrados. Adem\u00e1s, la dependencia inform\u00f3 que el incendio en El Milagro, Guadalc\u00e1zar tiene un 85 por ciento de control y 80 de liquidaci\u00f3n. \u00a0SLP.- De acuerdo con informaci\u00f3n del Servicio Meteorol\u00f3gico Nacional (SMN), en San Luis Potos\u00ed continuar\u00e1n las altas tempraturas en los siguientes d\u00edas, con ma\u00f1anas y tardes frescas, pero con pocas probabilidades de lluvia, dio a conocer la Coordinaci\u00f3n Estatal de Protecci\u00f3n Civil (CEPC). La dependencia inform\u00f3 que en la \u00faltima semana se han registrado muy altas temperaturas, sobre [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2021\/advierte-cepc-altas-temperaturas-para-slp-en-los-proximos-dias\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2021\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noticieroscanalsiete\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-20T14:47:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/04\/CEPC.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"666\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edici\u00f3n Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:site\" content=\"@NOTICIEROS7\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edici\u00f3n Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/advierte-cepc-altas-temperaturas-para-slp-en-los-proximos-dias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/advierte-cepc-altas-temperaturas-para-slp-en-los-proximos-dias\\\/\"},\"author\":{\"name\":\"Edici\u00f3n Web\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#\\\/schema\\\/person\\\/28a12b0491d3b6f41a854d062961bdc7\"},\"headline\":\"Advierte CEPC altas temperaturas para SLP en los pr\u00f3ximos d\u00edas\",\"datePublished\":\"2021-04-20T14:47:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/advierte-cepc-altas-temperaturas-para-slp-en-los-proximos-dias\\\/\"},\"wordCount\":369,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/advierte-cepc-altas-temperaturas-para-slp-en-los-proximos-dias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/CEPC.jpg\",\"articleSection\":[\"LOCALES Y REGIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/advierte-cepc-altas-temperaturas-para-slp-en-los-proximos-dias\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/advierte-cepc-altas-temperaturas-para-slp-en-los-proximos-dias\\\/\",\"name\":\"Advierte CEPC altas temperaturas para SLP en los pr\u00f3ximos d\u00edas - Canal 7 SLP - 2021\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/advierte-cepc-altas-temperaturas-para-slp-en-los-proximos-dias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/advierte-cepc-altas-temperaturas-para-slp-en-los-proximos-dias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/CEPC.jpg\",\"datePublished\":\"2021-04-20T14:47:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/advierte-cepc-altas-temperaturas-para-slp-en-los-proximos-dias\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/advierte-cepc-altas-temperaturas-para-slp-en-los-proximos-dias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/advierte-cepc-altas-temperaturas-para-slp-en-los-proximos-dias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/CEPC.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/CEPC.jpg\",\"width\":666,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/advierte-cepc-altas-temperaturas-para-slp-en-los-proximos-dias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Advierte CEPC altas temperaturas para SLP en los pr\u00f3ximos d\u00edas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/\",\"name\":\"N7 - Noticieros Canal 7\",\"description\":\"Somos Televisi\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#organization\",\"name\":\"Noticieros Canal 7\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-noticieros@2x.png\",\"width\":1017,\"height\":268,\"caption\":\"Noticieros Canal 7\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/noticieroscanalsiete\",\"https:\\\/\\\/x.com\\\/NOTICIEROS7\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCliiYs-gP3JfJeqdPrNdd5A\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/#\\\/schema\\\/person\\\/28a12b0491d3b6f41a854d062961bdc7\",\"name\":\"Edici\u00f3n Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"Edici\u00f3n Web\"},\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2021\\\/author\\\/edicionweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Advierte CEPC altas temperaturas para SLP en los pr\u00f3ximos d\u00edas - Canal 7 SLP - 2021","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2021\/advierte-cepc-altas-temperaturas-para-slp-en-los-proximos-dias\/","og_locale":"es_ES","og_type":"article","og_title":"Advierte CEPC altas temperaturas para SLP en los pr\u00f3ximos d\u00edas - Canal 7 SLP - 2021","og_description":"\u00a0 La temperatura m\u00e1s alta en los \u00faltimos d\u00edas la registr\u00f3 Tamu\u00edn en donde se alcanz\u00f3 los 45 gracos cent\u00edgrados. Adem\u00e1s, la dependencia inform\u00f3 que el incendio en El Milagro, Guadalc\u00e1zar tiene un 85 por ciento de control y 80 de liquidaci\u00f3n. \u00a0SLP.- De acuerdo con informaci\u00f3n del Servicio Meteorol\u00f3gico Nacional (SMN), en San Luis Potos\u00ed continuar\u00e1n las altas tempraturas en los siguientes d\u00edas, con ma\u00f1anas y tardes frescas, pero con pocas probabilidades de lluvia, dio a conocer la Coordinaci\u00f3n Estatal de Protecci\u00f3n Civil (CEPC). La dependencia inform\u00f3 que en la \u00faltima semana se han registrado muy altas temperaturas, sobre [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2021\/advierte-cepc-altas-temperaturas-para-slp-en-los-proximos-dias\/","og_site_name":"Canal 7 SLP - 2021","article_publisher":"https:\/\/www.facebook.com\/noticieroscanalsiete","article_published_time":"2021-04-20T14:47:42+00:00","og_image":[{"width":666,"height":500,"url":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/04\/CEPC.jpg","type":"image\/jpeg"}],"author":"Edici\u00f3n Web","twitter_card":"summary_large_image","twitter_creator":"@NOTICIEROS7","twitter_site":"@NOTICIEROS7","twitter_misc":{"Escrito por":"Edici\u00f3n Web","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2021\/advierte-cepc-altas-temperaturas-para-slp-en-los-proximos-dias\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2021\/advierte-cepc-altas-temperaturas-para-slp-en-los-proximos-dias\/"},"author":{"name":"Edici\u00f3n Web","@id":"https:\/\/canal7slp.tv\/2021\/#\/schema\/person\/28a12b0491d3b6f41a854d062961bdc7"},"headline":"Advierte CEPC altas temperaturas para SLP en los pr\u00f3ximos d\u00edas","datePublished":"2021-04-20T14:47:42+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2021\/advierte-cepc-altas-temperaturas-para-slp-en-los-proximos-dias\/"},"wordCount":369,"publisher":{"@id":"https:\/\/canal7slp.tv\/2021\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2021\/advierte-cepc-altas-temperaturas-para-slp-en-los-proximos-dias\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/04\/CEPC.jpg","articleSection":["LOCALES Y REGIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2021\/advierte-cepc-altas-temperaturas-para-slp-en-los-proximos-dias\/","url":"https:\/\/canal7slp.tv\/2021\/advierte-cepc-altas-temperaturas-para-slp-en-los-proximos-dias\/","name":"Advierte CEPC altas temperaturas para SLP en los pr\u00f3ximos d\u00edas - Canal 7 SLP - 2021","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2021\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2021\/advierte-cepc-altas-temperaturas-para-slp-en-los-proximos-dias\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2021\/advierte-cepc-altas-temperaturas-para-slp-en-los-proximos-dias\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/04\/CEPC.jpg","datePublished":"2021-04-20T14:47:42+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2021\/advierte-cepc-altas-temperaturas-para-slp-en-los-proximos-dias\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2021\/advierte-cepc-altas-temperaturas-para-slp-en-los-proximos-dias\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2021\/advierte-cepc-altas-temperaturas-para-slp-en-los-proximos-dias\/#primaryimage","url":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/04\/CEPC.jpg","contentUrl":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/04\/CEPC.jpg","width":666,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2021\/advierte-cepc-altas-temperaturas-para-slp-en-los-proximos-dias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canal7slp.tv\/2021\/"},{"@type":"ListItem","position":2,"name":"Advierte CEPC altas temperaturas para SLP en los pr\u00f3ximos d\u00edas"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2021\/#website","url":"https:\/\/canal7slp.tv\/2021\/","name":"N7 - Noticieros Canal 7","description":"Somos Televisi\u00f3n","publisher":{"@id":"https:\/\/canal7slp.tv\/2021\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2021\/#organization","name":"Noticieros Canal 7","url":"https:\/\/canal7slp.tv\/2021\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2021\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","contentUrl":"https:\/\/canal7slp.tv\/2021\/wp-content\/uploads\/2021\/01\/logo-noticieros@2x.png","width":1017,"height":268,"caption":"Noticieros Canal 7"},"image":{"@id":"https:\/\/canal7slp.tv\/2021\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/noticieroscanalsiete","https:\/\/x.com\/NOTICIEROS7","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/channel\/UCliiYs-gP3JfJeqdPrNdd5A"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2021\/#\/schema\/person\/28a12b0491d3b6f41a854d062961bdc7","name":"Edici\u00f3n Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"Edici\u00f3n Web"},"url":"https:\/\/canal7slp.tv\/2021\/author\/edicionweb\/"}]}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/posts\/12294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/comments?post=12294"}],"version-history":[{"count":1,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/posts\/12294\/revisions"}],"predecessor-version":[{"id":12296,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/posts\/12294\/revisions\/12296"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/media\/12295"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/media?parent=12294"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/categories?post=12294"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2021\/wp-json\/wp\/v2\/tags?post=12294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}