{"id":121903,"date":"2020-03-29T18:32:54","date_gmt":"2020-03-30T00:32:54","guid":{"rendered":"https:\/\/canal7slp.tv\/2020\/?p=121903"},"modified":"2020-03-29T18:32:54","modified_gmt":"2020-03-30T00:32:54","slug":"casos-de-covid-19-en-el-mundo-rebasan-los-700-mil","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2020\/casos-de-covid-19-en-el-mundo-rebasan-los-700-mil\/","title":{"rendered":"Casos de Covid-19 en el mundo rebasan los 700 mil"},"content":{"rendered":"<ul>\n<li style=\"text-align: justify\">La enfermedad provocada por el nuevo coronavirus ha dejado ya 33 mil 551 fallecidos en todo el mundo<\/li>\n<\/ul>\n<p style=\"text-align: justify\">Ginebra.-El aumento de los casos reportados por coronavirus Covid-19 sigue a la alza con 713 mil 171 infectados por el nuevo pat\u00f3geno, de acuerdo con el aproximado que ofrece la universidad de John Hopkins, en 174 pa\u00edses.<\/p>\n<p style=\"text-align: justify\">Por otra parte, la enfermedad provocada por el nuevo coronavirus ha dejado ya 33 mil 551 fallecidos en todo el mundo.<\/p>\n<p style=\"text-align: justify\">Los pacientes m\u00e1s vulnerables siguen estando en la poblaci\u00f3n de la tercera edad, con factores de riesgo como cardiopat\u00edas, diabetes o asma.<\/p>\n<p style=\"text-align: justify\">En tanto, Estados Unidos, que recientemente debut\u00f3 como la naci\u00f3n m\u00e1s afectada y nuevo epicentro de contagios sum\u00f3 135 mil casos reportados de coronavirus, mientras las muertes siguen a la alza en Nueva York con dos mil 402 bajas.<\/p>\n<p style=\"text-align: justify\">Ahora, los estadunidenses cuentan con poco m\u00e1s de una s\u00e9ptima parte de los contagios en todo el mundo, con su capital, Washington, como la siguiente m\u00e1s afectada en el pa\u00eds.<\/p>\n<p style=\"text-align: justify\">Por otra parte, Italia es el segundo pa\u00eds m\u00e1s golpeado por la pandemia en cuanto infectados, pero sigue con el mayor n\u00famero de muertes con 97 mil 689 y 10 mil 779, respectivamente.<\/p>\n<p style=\"text-align: justify\">China se ubica en la posici\u00f3n n\u00famero tres de las naciones m\u00e1s afectadas. El gigante asi\u00e1tico, que alguna vez fue el epicentro de la enfermedad, originada en la provincia de Hubei, report\u00f3 este domingo 82 mil 122 casos de la enfermedad y tres mil 304 fallecimientos desde el origen del nuevo tipo de neumon\u00eda.<\/p>\n<p style=\"text-align: justify\">Sin embargo, de acuerdo con el mapeo de los universitarios de Mayland, Espa\u00f1a est\u00e1 s\u00f3lo a poco m\u00e1s de cinco mil casos m\u00e1s de configurarse en el tercer lugar de los pa\u00edses afectados por el coronavirus. Los especialistas indican que la cifra de infectados asciende a 78 mil 779 casos registrado y seis mil 606 muertes.<\/p>\n<p style=\"text-align: justify\">En Francia, hoy, se evacu\u00f3 hoy a tres docenas de enfermos de coronavirus del este del pa\u00eds, muy golpeado por la pandemia, hacia otras regiones y tambi\u00e9n a hospitales alemanes, con el fin de descongestionar sus centros m\u00e9dicos.<\/p>\n<p style=\"text-align: justify\">Los 36 pacientes fueron trasladados en trenes de alta velocidad medicalizados desde las localidades de Mulhouse y de Nancy hacia el oeste.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La enfermedad provocada por el nuevo coronavirus ha dejado ya 33 mil 551 fallecidos en todo el mundo Ginebra.-El aumento de los casos reportados por coronavirus Covid-19 sigue a la alza con 713 mil 171 infectados por el nuevo pat\u00f3geno, de acuerdo con el aproximado que ofrece la universidad de John Hopkins, en 174 pa\u00edses. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":121904,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1671,18],"tags":[],"class_list":["post-121903","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-covid-19","category-internacional"],"amp_enabled":true,"cmb2":{"video_ids_in_playlist":{"vid_p_videos":""},"video_ids_in_channel":{"vid_c_videos":""},"playlist_ids_in_channel":{"vid_c_playlists":""},"series_ids_in_channel":{"vid_c_series":""},"channel_images":{"vid_c_logo":"","vid_c_banner":""},"poster_feature_image":{"vid_m_poster_image":""},"gif_feature_image":{"vid_m_gif_image":""},"video_movie_settings":{"vid_m_director":"","vid_m_actor":"","vid_m_imdb_ratings":"","vid_m_amazon_associates":""},"vid_youtube_broadcasts_settings":{"vid_yb_broadcast_title":"","vid_yb_q":"","vid_yb_channelid":"","vid_yb_videocategoryid":"","vid_yb_maxresults":"","vid_yb_order":"","vid_yb_regioncode":"","vid_yb_videosyndicated":"","vid_yb_style":"","vid_yb_reload_first":""},"video_series_settings":{"vid_m_director":"","vid_m_actor":"","vid_m_imdb_ratings":"","video_series_group":""},"amazon_associates_settings":{"amazon_associates":"","amazon_native_ad":""},"vid_youtube_automatic_settings":{"vid_ya_youtube_source":"","vid_ya_update_every":"","vid_ya_update_unit":"","vid_ya_categories":"","vid_ya_published_after":"","vid_ya_published_before":"","vid_ya_playlists":"","vid_ya_channels":"","vid_ya_director":"","vid_ya_actor":"","vid_ya_author":"","vid_ya_import_post_date":"","vid_ya_status":"","vid_ya_sub_api_key":""},"vid_ads_m_videoads_settings_post":{"vid_ads_m_video_ads":"","vid_ads_m_video_ads_type":"","vid_ads_m_group_google_ima":"","vid_ads_m_group_image":"","vid_ads_m_group_html5_video":"","vid_ads_m_group_html":"","vid_ads_m_vast_preroll":"","vid_ads_m_vast_postroll":"","vid_ads_m_vast_pauseroll":"","vid_ads_m_vast_midroll":[{"vid_ads_m_vast_timer_seconds":"50"}],"vid_ads_m_time_to_show_ads":"","vid_ads_m_time_skip_ads":"","vid_ads_m_time_to_hide_ads":""},"page_slider_settings":{"display_slider_group":"","page_slider_group":""},"blog_page_settings":{"blog_page_title":"","blog_page_heading":"","blog_page_ic":"","blog_page_it":"","blog_page_ec":"","blog_page_ip":"","archive_loop_style":"","blog_image_ratio":"","blog_show_categories":"","blog_show_excerpt":"","blog_show_author":"","blog_show_date":"","blog_show_comment_count":"","blog_show_view_count":"","blog_show_like_count":"","blog_show_dislike_count":"","blog_items_per_page":"","blog_pag_type":""},"page_options":{"get_page_template":"","color_mode":"","main_layout":"","main_layout_full_with":"","main_logo":"","main_logo_retina":"","main_logo_mobile":"","main_logo_mobile_retina":"","sticky_logo":"","sticky_logo_retina":"","main_nav_layout":"","ajax_search":"","header_background":"","theme_sidebar":"","instagram_feed":"","instagram_feed_position":"","popular_videos":"","popular_videos_title_1":"","popular_videos_title_2":"","popular_videos_ic":"","popular_videos_it":"","theme_background":"","page_custom_css":""},"feature_image_settings":{"feature_image_position":""},"video_player_settings":{"single_video_style":"","video_player_position":"","vm_video_url":"","video_player_library":"","video_streaming":"","vm_media_sources":"","vid_auto_play":"","vm_video_shortcode":"","vid_p_sync_playlist":"","vid_c_sync_channel":"","get_post_format":"","multiple_links_structure":"default","multi_links_title":"","vm_video_multi_links":"","vm_duration":"","vid_social_locker":"off","vid_social_locker_id":"","vid_membership_action":"content-video","vm_video_trailer_url":"","vid_download_type":"free","vid_download_target":"download","vid_woo_product":"","vm_media_download":"","user_rating":"","user_rating_position":"","user_rating_mode":"","user_rating_multi_sets":""},"video_auto_fetch_settings":{"vm_video_fetch":"on"},"video_fake_views_likes":{"vm_fake_views":"","vm_fake_likes":"","vm_fake_dislikes":""},"gallery_settings":{"gallery_position":""},"quote_settings":{"quote_position":""},"post_options":{"main_layout":"","main_logo":"","main_logo_retina":"","main_logo_mobile":"","main_logo_mobile_retina":"","sticky_logo":"","sticky_logo_retina":"","main_nav_layout":"","header_background":"","theme_sidebar":"","single_post_comment_type":"","theme_background":""}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2020\/wp-json\/wp\/v2\/posts\/121903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2020\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2020\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2020\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2020\/wp-json\/wp\/v2\/comments?post=121903"}],"version-history":[{"count":0,"href":"https:\/\/canal7slp.tv\/2020\/wp-json\/wp\/v2\/posts\/121903\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2020\/wp-json\/wp\/v2\/media\/121904"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2020\/wp-json\/wp\/v2\/media?parent=121903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2020\/wp-json\/wp\/v2\/categories?post=121903"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2020\/wp-json\/wp\/v2\/tags?post=121903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}