{"id":84617,"date":"2019-11-27T12:53:39","date_gmt":"2019-11-27T18:53:39","guid":{"rendered":"https:\/\/canal7slp.tv\/2019\/?p=84617"},"modified":"2019-11-27T12:53:39","modified_gmt":"2019-11-27T18:53:39","slug":"la-tasa-de-desempleo-en-mexico-llega-al-3-6-en-octubre","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2019\/la-tasa-de-desempleo-en-mexico-llega-al-3-6-en-octubre\/","title":{"rendered":"La tasa de desempleo en M\u00e9xico llega al 3.6% en octubre"},"content":{"rendered":"<ul>\n<li style=\"text-align: justify\">Se ubica 0.1 puntos porcentuales por arriba de la cifra del mes previo, informa el Inegi<\/li>\n<\/ul>\n<p style=\"text-align: justify\">M\u00e9xico.- El desempleo en M\u00e9xico alcanz\u00f3 al 3.6% de la poblaci\u00f3n econ\u00f3micamente activa (PEA) en octubre pasado, superior al 3.2% del mismo mes de 2018, seg\u00fan las cifras publicadas este mi\u00e9rcoles por el Instituto Nacional de Estad\u00edstica y Geograf\u00eda (Inegi).<\/p>\n<p style=\"text-align: justify\">Seg\u00fan datos ajustados por estacionalidad, el nivel de desempleo se situ\u00f3 en 3.6% en el d\u00e9cimo mes del a\u00f1o, una tasa 0.1 puntos porcentuales superior a septiembre pasado, indic\u00f3 la instituci\u00f3n en un comunicado.<\/p>\n<p style=\"text-align: justify\">La poblaci\u00f3n subempleada, la que declar\u00f3 tener necesidad y disponibilidad para ofertar m\u00e1s horas de trabajo que las que su ocupaci\u00f3n actual le permite, fue del 7.8 %, una proporci\u00f3n mayor al 7% registrado un a\u00f1o antes, en cifras originales.<\/p>\n<p style=\"text-align: justify\">El Inegi, que considera empleadas a las personas mayores de 14 a\u00f1os que trabajan al menos seis horas a la semana y en cualquier puesto, situ\u00f3 la tasa de ocupaci\u00f3n en 96.4% de la PEA en octubre.<\/p>\n<p style=\"text-align: justify\">Las personas en la econom\u00eda sumergida representaron el 56.3% del total de la poblaci\u00f3n ocupada, por arriba del 56% que hab\u00eda en el mismo mes de 2018.<\/p>\n<p style=\"text-align: justify\">El 43.4% de la poblaci\u00f3n ocupada se concentr\u00f3 en el sector servicios, el 19.8% en el comercio, el 16.5 % en la industria manufacturera y el 11.6 % en las actividades agropecuarias.<\/p>\n<p style=\"text-align: justify\">Otro 7.4 % en la construcci\u00f3n, 0.7 % en otros sectores como la miner\u00eda, la electricidad, el agua y el suministro de gas, y el 0.6 % restante no especific\u00f3 su actividad.<\/p>\n<p style=\"text-align: justify\">El 67.9% de los trabajadores son asalariados, 23.1% aut\u00f3nomos, 4.6% empleadores o patrones y 4.4% son personas sin pago fijo que trabajan en negocios o parcelas familiares.<\/p>\n<p style=\"text-align: justify\">La tasa de desempleo en M\u00e9xico cerr\u00f3 2018 en 3.3 % de la PEA, dato id\u00e9ntico al del final de 2017, situ\u00e1ndose en las 1.82 millones de personas desocupadas.<\/p>\n<p style=\"text-align: justify\">M\u00e9xico cuenta con alrededor de 126 millones de habitantes, seg\u00fan las proyecciones demogr\u00e1ficas realizadas a partir del \u00faltimo censo de poblaci\u00f3n (2010) para 2019.<\/p>\n<p style=\"text-align: justify\">El pa\u00eds registr\u00f3 52.4 millones de habitantes en situaci\u00f3n de pobreza en 2018, un dato menor a los 53.4 millones de 2016 y que representa el 41.9 % del total de la poblaci\u00f3n, seg\u00fan los datos m\u00e1s recientes del Consejo Nacional de Evaluaci\u00f3n de la Pol\u00edtica de Desarrollo Social (Coneval).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se ubica 0.1 puntos porcentuales por arriba de la cifra del mes previo, informa el Inegi M\u00e9xico.- El desempleo en M\u00e9xico alcanz\u00f3 al 3.6% de la poblaci\u00f3n econ\u00f3micamente activa (PEA) en octubre pasado, superior al 3.2% del mismo mes de 2018, seg\u00fan las cifras publicadas este mi\u00e9rcoles por el Instituto Nacional de Estad\u00edstica y Geograf\u00eda [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":84618,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[98],"tags":[],"class_list":["post-84617","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-finanzas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La tasa de desempleo en M\u00e9xico llega al 3.6% en octubre - Canal 7 SLP - 2019<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2019\/la-tasa-de-desempleo-en-mexico-llega-al-3-6-en-octubre\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La tasa de desempleo en M\u00e9xico llega al 3.6% en octubre - Canal 7 SLP - 2019\" \/>\n<meta property=\"og:description\" content=\"Se ubica 0.1 puntos porcentuales por arriba de la cifra del mes previo, informa el Inegi M\u00e9xico.- El desempleo en M\u00e9xico alcanz\u00f3 al 3.6% de la poblaci\u00f3n econ\u00f3micamente activa (PEA) en octubre pasado, superior al 3.2% del mismo mes de 2018, seg\u00fan las cifras publicadas este mi\u00e9rcoles por el Instituto Nacional de Estad\u00edstica y Geograf\u00eda [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2019\/la-tasa-de-desempleo-en-mexico-llega-al-3-6-en-octubre\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2019\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CANAL7SLP\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-27T18:53:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2019\/wp-content\/uploads\/2019\/11\/1320-18.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"770\" \/>\n\t<meta property=\"og:image:height\" content=\"485\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"edicionweb\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@canal7_slp\" \/>\n<meta name=\"twitter:site\" content=\"@canal7_slp\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"edicionweb\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/la-tasa-de-desempleo-en-mexico-llega-al-3-6-en-octubre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/la-tasa-de-desempleo-en-mexico-llega-al-3-6-en-octubre\\\/\"},\"author\":{\"name\":\"edicionweb\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/#\\\/schema\\\/person\\\/11d941c1c6ca30ac0a46b95fa37aa2e3\"},\"headline\":\"La tasa de desempleo en M\u00e9xico llega al 3.6% en octubre\",\"datePublished\":\"2019-11-27T18:53:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/la-tasa-de-desempleo-en-mexico-llega-al-3-6-en-octubre\\\/\"},\"wordCount\":396,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/la-tasa-de-desempleo-en-mexico-llega-al-3-6-en-octubre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/1320-18.jpg\",\"articleSection\":[\"FINANZAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/la-tasa-de-desempleo-en-mexico-llega-al-3-6-en-octubre\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/la-tasa-de-desempleo-en-mexico-llega-al-3-6-en-octubre\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/la-tasa-de-desempleo-en-mexico-llega-al-3-6-en-octubre\\\/\",\"name\":\"La tasa de desempleo en M\u00e9xico llega al 3.6% en octubre - Canal 7 SLP - 2019\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/la-tasa-de-desempleo-en-mexico-llega-al-3-6-en-octubre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/la-tasa-de-desempleo-en-mexico-llega-al-3-6-en-octubre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/1320-18.jpg\",\"datePublished\":\"2019-11-27T18:53:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/la-tasa-de-desempleo-en-mexico-llega-al-3-6-en-octubre\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/la-tasa-de-desempleo-en-mexico-llega-al-3-6-en-octubre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/la-tasa-de-desempleo-en-mexico-llega-al-3-6-en-octubre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/1320-18.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/1320-18.jpg\",\"width\":770,\"height\":485},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/la-tasa-de-desempleo-en-mexico-llega-al-3-6-en-octubre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La tasa de desempleo en M\u00e9xico llega al 3.6% en octubre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/\",\"name\":\"Canal 7 SLP - Somos TV\",\"description\":\"Somos un Canal de 10\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/#organization\",\"name\":\"Comunicaci\u00f3n 2000 S.A. de C.V.\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/logo-c7.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/logo-c7.png\",\"width\":220,\"height\":60,\"caption\":\"Comunicaci\u00f3n 2000 S.A. de C.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CANAL7SLP\\\/\",\"https:\\\/\\\/x.com\\\/canal7_slp\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/NOTICIEROSCANAL7SLP\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/#\\\/schema\\\/person\\\/11d941c1c6ca30ac0a46b95fa37aa2e3\",\"name\":\"edicionweb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"edicionweb\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La tasa de desempleo en M\u00e9xico llega al 3.6% en octubre - Canal 7 SLP - 2019","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2019\/la-tasa-de-desempleo-en-mexico-llega-al-3-6-en-octubre\/","og_locale":"es_ES","og_type":"article","og_title":"La tasa de desempleo en M\u00e9xico llega al 3.6% en octubre - Canal 7 SLP - 2019","og_description":"Se ubica 0.1 puntos porcentuales por arriba de la cifra del mes previo, informa el Inegi M\u00e9xico.- El desempleo en M\u00e9xico alcanz\u00f3 al 3.6% de la poblaci\u00f3n econ\u00f3micamente activa (PEA) en octubre pasado, superior al 3.2% del mismo mes de 2018, seg\u00fan las cifras publicadas este mi\u00e9rcoles por el Instituto Nacional de Estad\u00edstica y Geograf\u00eda [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2019\/la-tasa-de-desempleo-en-mexico-llega-al-3-6-en-octubre\/","og_site_name":"Canal 7 SLP - 2019","article_publisher":"https:\/\/www.facebook.com\/CANAL7SLP\/","article_published_time":"2019-11-27T18:53:39+00:00","og_image":[{"width":770,"height":485,"url":"https:\/\/canal7slp.tv\/2019\/wp-content\/uploads\/2019\/11\/1320-18.jpg","type":"image\/jpeg"}],"author":"edicionweb","twitter_card":"summary_large_image","twitter_creator":"@canal7_slp","twitter_site":"@canal7_slp","twitter_misc":{"Escrito por":"edicionweb","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2019\/la-tasa-de-desempleo-en-mexico-llega-al-3-6-en-octubre\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2019\/la-tasa-de-desempleo-en-mexico-llega-al-3-6-en-octubre\/"},"author":{"name":"edicionweb","@id":"https:\/\/canal7slp.tv\/2019\/#\/schema\/person\/11d941c1c6ca30ac0a46b95fa37aa2e3"},"headline":"La tasa de desempleo en M\u00e9xico llega al 3.6% en octubre","datePublished":"2019-11-27T18:53:39+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2019\/la-tasa-de-desempleo-en-mexico-llega-al-3-6-en-octubre\/"},"wordCount":396,"commentCount":0,"publisher":{"@id":"https:\/\/canal7slp.tv\/2019\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2019\/la-tasa-de-desempleo-en-mexico-llega-al-3-6-en-octubre\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2019\/wp-content\/uploads\/2019\/11\/1320-18.jpg","articleSection":["FINANZAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/canal7slp.tv\/2019\/la-tasa-de-desempleo-en-mexico-llega-al-3-6-en-octubre\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2019\/la-tasa-de-desempleo-en-mexico-llega-al-3-6-en-octubre\/","url":"https:\/\/canal7slp.tv\/2019\/la-tasa-de-desempleo-en-mexico-llega-al-3-6-en-octubre\/","name":"La tasa de desempleo en M\u00e9xico llega al 3.6% en octubre - Canal 7 SLP - 2019","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2019\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2019\/la-tasa-de-desempleo-en-mexico-llega-al-3-6-en-octubre\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2019\/la-tasa-de-desempleo-en-mexico-llega-al-3-6-en-octubre\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2019\/wp-content\/uploads\/2019\/11\/1320-18.jpg","datePublished":"2019-11-27T18:53:39+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2019\/la-tasa-de-desempleo-en-mexico-llega-al-3-6-en-octubre\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2019\/la-tasa-de-desempleo-en-mexico-llega-al-3-6-en-octubre\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2019\/la-tasa-de-desempleo-en-mexico-llega-al-3-6-en-octubre\/#primaryimage","url":"https:\/\/canal7slp.tv\/2019\/wp-content\/uploads\/2019\/11\/1320-18.jpg","contentUrl":"https:\/\/canal7slp.tv\/2019\/wp-content\/uploads\/2019\/11\/1320-18.jpg","width":770,"height":485},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2019\/la-tasa-de-desempleo-en-mexico-llega-al-3-6-en-octubre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/canal7slp.tv\/2019\/"},{"@type":"ListItem","position":2,"name":"La tasa de desempleo en M\u00e9xico llega al 3.6% en octubre"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2019\/#website","url":"https:\/\/canal7slp.tv\/2019\/","name":"Canal 7 SLP - Somos TV","description":"Somos un Canal de 10","publisher":{"@id":"https:\/\/canal7slp.tv\/2019\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2019\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2019\/#organization","name":"Comunicaci\u00f3n 2000 S.A. de C.V.","url":"https:\/\/canal7slp.tv\/2019\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2019\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2019\/wp-content\/uploads\/2019\/07\/logo-c7.png","contentUrl":"https:\/\/canal7slp.tv\/2019\/wp-content\/uploads\/2019\/07\/logo-c7.png","width":220,"height":60,"caption":"Comunicaci\u00f3n 2000 S.A. de C.V."},"image":{"@id":"https:\/\/canal7slp.tv\/2019\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CANAL7SLP\/","https:\/\/x.com\/canal7_slp","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/user\/NOTICIEROSCANAL7SLP\/"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2019\/#\/schema\/person\/11d941c1c6ca30ac0a46b95fa37aa2e3","name":"edicionweb","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"edicionweb"}}]}},"amp_enabled":true,"cmb2":{"video_ids_in_playlist":{"vid_p_videos":""},"video_ids_in_channel":{"vid_c_videos":""},"playlist_ids_in_channel":{"vid_c_playlists":""},"series_ids_in_channel":{"vid_c_series":""},"channel_images":{"vid_c_logo":"","vid_c_banner":""},"poster_feature_image":{"vid_m_poster_image":""},"gif_feature_image":{"vid_m_gif_image":""},"video_movie_settings":{"vid_m_director":"","vid_m_actor":"","vid_m_imdb_ratings":"","vid_m_amazon_associates":""},"vid_youtube_broadcasts_settings":{"vid_yb_broadcast_title":"","vid_yb_q":"","vid_yb_channelid":"","vid_yb_videocategoryid":"","vid_yb_maxresults":"","vid_yb_order":"","vid_yb_regioncode":"","vid_yb_videosyndicated":"","vid_yb_style":"","vid_yb_reload_first":""},"video_series_settings":{"vid_m_director":"","vid_m_actor":"","vid_m_imdb_ratings":"","video_series_group":""},"amazon_associates_settings":{"amazon_associates":"","amazon_native_ad":""},"vid_youtube_automatic_settings":{"vid_ya_youtube_source":"","vid_ya_update_every":"","vid_ya_update_unit":"","vid_ya_categories":"","vid_ya_published_after":"","vid_ya_published_before":"","vid_ya_playlists":"","vid_ya_channels":"","vid_ya_director":"","vid_ya_actor":"","vid_ya_author":"","vid_ya_import_post_date":"","vid_ya_status":"","vid_ya_sub_api_key":""},"vid_ads_m_videoads_settings_post":{"vid_ads_m_video_ads":"","vid_ads_m_video_ads_type":"","vid_ads_m_group_google_ima":"","vid_ads_m_group_image":"","vid_ads_m_group_html5_video":"","vid_ads_m_group_html":"","vid_ads_m_vast_preroll":"","vid_ads_m_vast_postroll":"","vid_ads_m_vast_pauseroll":"","vid_ads_m_vast_midroll":[{"vid_ads_m_vast_timer_seconds":"50"}],"vid_ads_m_time_to_show_ads":"","vid_ads_m_time_skip_ads":"","vid_ads_m_time_to_hide_ads":""},"page_slider_settings":{"display_slider_group":"","page_slider_group":""},"blog_page_settings":{"blog_page_title":"","blog_page_heading":"","blog_page_ic":"","blog_page_it":"","blog_page_ec":"","blog_page_ip":"","archive_loop_style":"","blog_image_ratio":"","blog_show_categories":"","blog_show_excerpt":"","blog_show_author":"","blog_show_date":"","blog_show_comment_count":"","blog_show_view_count":"","blog_show_like_count":"","blog_show_dislike_count":"","blog_items_per_page":"","blog_pag_type":""},"page_options":{"get_page_template":"","color_mode":"","main_layout":"","main_layout_full_with":"","main_logo":"","main_logo_retina":"","main_logo_mobile":"","main_logo_mobile_retina":"","sticky_logo":"","sticky_logo_retina":"","main_nav_layout":"","ajax_search":"","header_background":"","theme_sidebar":"","instagram_feed":"","instagram_feed_position":"","popular_videos":"","popular_videos_title_1":"","popular_videos_title_2":"","popular_videos_ic":"","popular_videos_it":"","theme_background":"","page_custom_css":""},"feature_image_settings":{"feature_image_position":""},"video_player_settings":{"single_video_style":"","video_player_position":"","vm_video_url":"","video_player_library":"","video_streaming":"","vm_media_sources":"","vid_auto_play":"","vm_video_shortcode":"","vid_p_sync_playlist":"","vid_c_sync_channel":"","get_post_format":"","multiple_links_structure":"default","multi_links_title":"","vm_video_multi_links":"","vm_duration":"","vid_social_locker":"off","vid_social_locker_id":"","vid_membership_action":"content-video","vm_video_trailer_url":"","vid_download_type":"free","vid_download_target":"download","vid_woo_product":"","vm_media_download":"","user_rating":"","user_rating_position":"","user_rating_mode":"","user_rating_multi_sets":""},"video_auto_fetch_settings":{"vm_video_fetch":"on"},"video_fake_views_likes":{"vm_fake_views":"","vm_fake_likes":"","vm_fake_dislikes":""},"gallery_settings":{"gallery_position":""},"quote_settings":{"quote_position":""},"post_options":{"main_layout":"","main_logo":"","main_logo_retina":"","main_logo_mobile":"","main_logo_mobile_retina":"","sticky_logo":"","sticky_logo_retina":"","main_nav_layout":"","header_background":"","theme_sidebar":"","single_post_comment_type":"","theme_background":""}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/posts\/84617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/comments?post=84617"}],"version-history":[{"count":0,"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/posts\/84617\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/media\/84618"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/media?parent=84617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/categories?post=84617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/tags?post=84617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}