{"id":71153,"date":"2019-09-27T09:14:58","date_gmt":"2019-09-27T14:14:58","guid":{"rendered":"https:\/\/canal7slp.tv\/2019\/?p=71153"},"modified":"2019-09-27T11:29:18","modified_gmt":"2019-09-27T16:29:18","slug":"la-desesperanza-juvenil-no-es-exclusiva-de-mexico-gael-garcia","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2019\/la-desesperanza-juvenil-no-es-exclusiva-de-mexico-gael-garcia\/","title":{"rendered":"La desesperanza juvenil no es exclusiva de M\u00e9xico: Gael Garc\u00eda"},"content":{"rendered":"<ul>\n<li>El actor presenta &#8220;Chicuarotes&#8221; en el Festival de cine de San Sebasti\u00e1n<\/li>\n<\/ul>\n<p>El mexicano Gael Garc\u00eda Bernal ha asegurado hoy en San Sebasti\u00e1n, donde ha presentado su segundo largometraje como director, &#8220;Chicuarotes&#8221;, que &#8220;la desesperanza juvenil no es exclusiva de M\u00e9xico&#8221;.<\/p>\n<p>Ese es el tema principal de &#8220;Chicuarotes&#8221;, una pel\u00edcula que se ha proyectado en la secci\u00f3n Horizontes Latinos del 67 Festival de Cine de San Sebasti\u00e1n, junto al de la violencia intrafamiliar, seg\u00fan ha explicado el protagonista de &#8220;Amores perros&#8221;.<\/p>\n<p>&#8220;La violencia en la familia es el n\u00facleo del ciclo de violencia en el que vivimos en nuestros pa\u00edses&#8221;, ha se\u00f1alado. &#8220;Cuando se crece en una situaci\u00f3n as\u00ed no es extra\u00f1o acabar convertido en un soci\u00f3pata funcional, alguien que deja de sentir para sobrevivir&#8221;.<\/p>\n<p>https:\/\/www.instagram.com\/p\/B203RNqlmaM\/?utm_source=ig_web_button_share_sheet<\/p>\n<p>La pel\u00edcula, rodada en San Gregorio Atlapulco, un pueblo &#8220;olvidado&#8221; en las afueras de la capital mexicana, sigue a Cagalera y Moloteco, dos adolescentes que ven en la compra de una plaza en el sindicato de electricistas una v\u00eda de escape para la pobreza.<\/p>\n<p>Pero en su intento por conseguir los 20.000 pesos necesarios para ello caen en una espiral de violencia con consecuencias imprevistas.<\/p>\n<p>Pese a la crudeza del entorno y de los acontecimientos, el guion y la puesta en escena adoptan un tono de f\u00e1bula y un humor &#8220;de carnaval&#8221; que aligeran el relato.<\/p>\n<p>&#8220;Chicuarotes&#8221; llega doce a\u00f1os despu\u00e9s de su opera prima, &#8220;Deficit&#8221;, estrenada en la Semana de la Cr\u00edtica de Cannes en 2007.<\/p>\n<p>&#8220;Tard\u00e9 porque no lo pens\u00e9 antes, porque me gusta hacer las cosas despacio y porque la pel\u00edcula requer\u00eda un gran trabajo de investigaci\u00f3n previa&#8221;, ha explicado.<\/p>\n<p>&#8220;Tanto la historia como la generaci\u00f3n que retrata me resultaban ajenas, tuve que navegar despacio para encontrar la pel\u00edcula&#8221;, ha precisado Garc\u00eda Bernal que se considera, por encima de todo, actor, la profesi\u00f3n que eligi\u00f3 y de la que se siente &#8220;orgulloso&#8221;.<\/p>\n<p>Como director dice que espera hacer a lo sumo &#8220;seis o siete pel\u00edculas&#8221; porque &#8220;no hay tanto que contar y finalmente las pel\u00edculas que trascienden son muy pocas&#8221;.<\/p>\n<p>Aunque los protagonistas de esta historia son masculinos, las mujeres tienen un rol determinante en el desarrollo de la trama. &#8220;Las ni\u00f1as contrarrestan la violencia, son las que est\u00e1n cambiando el rollo&#8221;, ha dicho.<\/p>\n<p>De hecho, ha confesado que ya est\u00e1 pensando en una continuaci\u00f3n de esta pel\u00edcula que se llamar\u00eda &#8220;Chicuarotas&#8221;: &#8220;Empez\u00f3 como un chiste, pero s\u00ed, me intriga qu\u00e9 pasar\u00e1 con ellas&#8221;.<\/p>\n<p>Adem\u00e1s de presentar su segundo largometraje como director, Garc\u00eda Bernal tiene dos pel\u00edculas como actor en este festival: &#8220;Ema&#8221;, de Pablo Larra\u00edn, proyectada hace unos d\u00edas en la secci\u00f3n Perlas, y &#8220;La red avispa&#8221;, protagonizada por Pen\u00e9lope Cruz, quien ma\u00f1ana recibe el tercer y \u00faltimo Premio Donostia de esta edici\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El actor presenta &#8220;Chicuarotes&#8221; en el Festival de cine de San Sebasti\u00e1n El mexicano Gael Garc\u00eda Bernal ha asegurado hoy en San Sebasti\u00e1n, donde ha presentado su segundo largometraje como director, &#8220;Chicuarotes&#8221;, que &#8220;la desesperanza juvenil no es exclusiva de M\u00e9xico&#8221;. Ese es el tema principal de &#8220;Chicuarotes&#8221;, una pel\u00edcula que se ha proyectado en [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":71155,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-71153","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espectaculos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La desesperanza juvenil no es exclusiva de M\u00e9xico: Gael Garc\u00eda - Canal 7 SLP - 2019<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2019\/la-desesperanza-juvenil-no-es-exclusiva-de-mexico-gael-garcia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La desesperanza juvenil no es exclusiva de M\u00e9xico: Gael Garc\u00eda - Canal 7 SLP - 2019\" \/>\n<meta property=\"og:description\" content=\"El actor presenta &#8220;Chicuarotes&#8221; en el Festival de cine de San Sebasti\u00e1n El mexicano Gael Garc\u00eda Bernal ha asegurado hoy en San Sebasti\u00e1n, donde ha presentado su segundo largometraje como director, &#8220;Chicuarotes&#8221;, que &#8220;la desesperanza juvenil no es exclusiva de M\u00e9xico&#8221;. Ese es el tema principal de &#8220;Chicuarotes&#8221;, una pel\u00edcula que se ha proyectado en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2019\/la-desesperanza-juvenil-no-es-exclusiva-de-mexico-gael-garcia\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2019\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CANAL7SLP\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-27T14:14:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-09-27T16:29:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2019\/wp-content\/uploads\/2019\/09\/1145-25.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"624\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"edicionweb\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@canal7_slp\" \/>\n<meta name=\"twitter:site\" content=\"@canal7_slp\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"edicionweb\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/la-desesperanza-juvenil-no-es-exclusiva-de-mexico-gael-garcia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/la-desesperanza-juvenil-no-es-exclusiva-de-mexico-gael-garcia\\\/\"},\"author\":{\"name\":\"edicionweb\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/#\\\/schema\\\/person\\\/11d941c1c6ca30ac0a46b95fa37aa2e3\"},\"headline\":\"La desesperanza juvenil no es exclusiva de M\u00e9xico: Gael Garc\u00eda\",\"datePublished\":\"2019-09-27T14:14:58+00:00\",\"dateModified\":\"2019-09-27T16:29:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/la-desesperanza-juvenil-no-es-exclusiva-de-mexico-gael-garcia\\\/\"},\"wordCount\":518,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/la-desesperanza-juvenil-no-es-exclusiva-de-mexico-gael-garcia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/1145-25.jpg\",\"articleSection\":[\"ESPECTACULOS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/la-desesperanza-juvenil-no-es-exclusiva-de-mexico-gael-garcia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/la-desesperanza-juvenil-no-es-exclusiva-de-mexico-gael-garcia\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/la-desesperanza-juvenil-no-es-exclusiva-de-mexico-gael-garcia\\\/\",\"name\":\"La desesperanza juvenil no es exclusiva de M\u00e9xico: Gael Garc\u00eda - Canal 7 SLP - 2019\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/la-desesperanza-juvenil-no-es-exclusiva-de-mexico-gael-garcia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/la-desesperanza-juvenil-no-es-exclusiva-de-mexico-gael-garcia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/1145-25.jpg\",\"datePublished\":\"2019-09-27T14:14:58+00:00\",\"dateModified\":\"2019-09-27T16:29:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/la-desesperanza-juvenil-no-es-exclusiva-de-mexico-gael-garcia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/la-desesperanza-juvenil-no-es-exclusiva-de-mexico-gael-garcia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/la-desesperanza-juvenil-no-es-exclusiva-de-mexico-gael-garcia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/1145-25.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/1145-25.jpg\",\"width\":1080,\"height\":624},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/la-desesperanza-juvenil-no-es-exclusiva-de-mexico-gael-garcia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La desesperanza juvenil no es exclusiva de M\u00e9xico: Gael Garc\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/\",\"name\":\"Canal 7 SLP - Somos TV\",\"description\":\"Somos un Canal de 10\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/#organization\",\"name\":\"Comunicaci\u00f3n 2000 S.A. de C.V.\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/logo-c7.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/logo-c7.png\",\"width\":220,\"height\":60,\"caption\":\"Comunicaci\u00f3n 2000 S.A. de C.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CANAL7SLP\\\/\",\"https:\\\/\\\/x.com\\\/canal7_slp\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/NOTICIEROSCANAL7SLP\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/#\\\/schema\\\/person\\\/11d941c1c6ca30ac0a46b95fa37aa2e3\",\"name\":\"edicionweb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"edicionweb\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La desesperanza juvenil no es exclusiva de M\u00e9xico: Gael Garc\u00eda - Canal 7 SLP - 2019","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2019\/la-desesperanza-juvenil-no-es-exclusiva-de-mexico-gael-garcia\/","og_locale":"es_ES","og_type":"article","og_title":"La desesperanza juvenil no es exclusiva de M\u00e9xico: Gael Garc\u00eda - Canal 7 SLP - 2019","og_description":"El actor presenta &#8220;Chicuarotes&#8221; en el Festival de cine de San Sebasti\u00e1n El mexicano Gael Garc\u00eda Bernal ha asegurado hoy en San Sebasti\u00e1n, donde ha presentado su segundo largometraje como director, &#8220;Chicuarotes&#8221;, que &#8220;la desesperanza juvenil no es exclusiva de M\u00e9xico&#8221;. Ese es el tema principal de &#8220;Chicuarotes&#8221;, una pel\u00edcula que se ha proyectado en [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2019\/la-desesperanza-juvenil-no-es-exclusiva-de-mexico-gael-garcia\/","og_site_name":"Canal 7 SLP - 2019","article_publisher":"https:\/\/www.facebook.com\/CANAL7SLP\/","article_published_time":"2019-09-27T14:14:58+00:00","article_modified_time":"2019-09-27T16:29:18+00:00","og_image":[{"width":1080,"height":624,"url":"https:\/\/canal7slp.tv\/2019\/wp-content\/uploads\/2019\/09\/1145-25.jpg","type":"image\/jpeg"}],"author":"edicionweb","twitter_card":"summary_large_image","twitter_creator":"@canal7_slp","twitter_site":"@canal7_slp","twitter_misc":{"Escrito por":"edicionweb","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2019\/la-desesperanza-juvenil-no-es-exclusiva-de-mexico-gael-garcia\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2019\/la-desesperanza-juvenil-no-es-exclusiva-de-mexico-gael-garcia\/"},"author":{"name":"edicionweb","@id":"https:\/\/canal7slp.tv\/2019\/#\/schema\/person\/11d941c1c6ca30ac0a46b95fa37aa2e3"},"headline":"La desesperanza juvenil no es exclusiva de M\u00e9xico: Gael Garc\u00eda","datePublished":"2019-09-27T14:14:58+00:00","dateModified":"2019-09-27T16:29:18+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2019\/la-desesperanza-juvenil-no-es-exclusiva-de-mexico-gael-garcia\/"},"wordCount":518,"commentCount":0,"publisher":{"@id":"https:\/\/canal7slp.tv\/2019\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2019\/la-desesperanza-juvenil-no-es-exclusiva-de-mexico-gael-garcia\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2019\/wp-content\/uploads\/2019\/09\/1145-25.jpg","articleSection":["ESPECTACULOS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/canal7slp.tv\/2019\/la-desesperanza-juvenil-no-es-exclusiva-de-mexico-gael-garcia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2019\/la-desesperanza-juvenil-no-es-exclusiva-de-mexico-gael-garcia\/","url":"https:\/\/canal7slp.tv\/2019\/la-desesperanza-juvenil-no-es-exclusiva-de-mexico-gael-garcia\/","name":"La desesperanza juvenil no es exclusiva de M\u00e9xico: Gael Garc\u00eda - Canal 7 SLP - 2019","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2019\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2019\/la-desesperanza-juvenil-no-es-exclusiva-de-mexico-gael-garcia\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2019\/la-desesperanza-juvenil-no-es-exclusiva-de-mexico-gael-garcia\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2019\/wp-content\/uploads\/2019\/09\/1145-25.jpg","datePublished":"2019-09-27T14:14:58+00:00","dateModified":"2019-09-27T16:29:18+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2019\/la-desesperanza-juvenil-no-es-exclusiva-de-mexico-gael-garcia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2019\/la-desesperanza-juvenil-no-es-exclusiva-de-mexico-gael-garcia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2019\/la-desesperanza-juvenil-no-es-exclusiva-de-mexico-gael-garcia\/#primaryimage","url":"https:\/\/canal7slp.tv\/2019\/wp-content\/uploads\/2019\/09\/1145-25.jpg","contentUrl":"https:\/\/canal7slp.tv\/2019\/wp-content\/uploads\/2019\/09\/1145-25.jpg","width":1080,"height":624},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2019\/la-desesperanza-juvenil-no-es-exclusiva-de-mexico-gael-garcia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/canal7slp.tv\/2019\/"},{"@type":"ListItem","position":2,"name":"La desesperanza juvenil no es exclusiva de M\u00e9xico: Gael Garc\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2019\/#website","url":"https:\/\/canal7slp.tv\/2019\/","name":"Canal 7 SLP - Somos TV","description":"Somos un Canal de 10","publisher":{"@id":"https:\/\/canal7slp.tv\/2019\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2019\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2019\/#organization","name":"Comunicaci\u00f3n 2000 S.A. de C.V.","url":"https:\/\/canal7slp.tv\/2019\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2019\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2019\/wp-content\/uploads\/2019\/07\/logo-c7.png","contentUrl":"https:\/\/canal7slp.tv\/2019\/wp-content\/uploads\/2019\/07\/logo-c7.png","width":220,"height":60,"caption":"Comunicaci\u00f3n 2000 S.A. de C.V."},"image":{"@id":"https:\/\/canal7slp.tv\/2019\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CANAL7SLP\/","https:\/\/x.com\/canal7_slp","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/user\/NOTICIEROSCANAL7SLP\/"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2019\/#\/schema\/person\/11d941c1c6ca30ac0a46b95fa37aa2e3","name":"edicionweb","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"edicionweb"}}]}},"amp_enabled":true,"cmb2":{"video_ids_in_playlist":{"vid_p_videos":""},"video_ids_in_channel":{"vid_c_videos":""},"playlist_ids_in_channel":{"vid_c_playlists":""},"series_ids_in_channel":{"vid_c_series":""},"channel_images":{"vid_c_logo":"","vid_c_banner":""},"poster_feature_image":{"vid_m_poster_image":""},"gif_feature_image":{"vid_m_gif_image":""},"video_movie_settings":{"vid_m_director":"","vid_m_actor":"","vid_m_imdb_ratings":"","vid_m_amazon_associates":""},"vid_youtube_broadcasts_settings":{"vid_yb_broadcast_title":"","vid_yb_q":"","vid_yb_channelid":"","vid_yb_videocategoryid":"","vid_yb_maxresults":"","vid_yb_order":"","vid_yb_regioncode":"","vid_yb_videosyndicated":"","vid_yb_style":"","vid_yb_reload_first":""},"video_series_settings":{"vid_m_director":"","vid_m_actor":"","vid_m_imdb_ratings":"","video_series_group":""},"amazon_associates_settings":{"amazon_associates":"","amazon_native_ad":""},"vid_youtube_automatic_settings":{"vid_ya_youtube_source":"","vid_ya_update_every":"","vid_ya_update_unit":"","vid_ya_categories":"","vid_ya_published_after":"","vid_ya_published_before":"","vid_ya_playlists":"","vid_ya_channels":"","vid_ya_director":"","vid_ya_actor":"","vid_ya_author":"","vid_ya_import_post_date":"","vid_ya_status":"","vid_ya_sub_api_key":""},"vid_ads_m_videoads_settings_post":{"vid_ads_m_video_ads":"","vid_ads_m_video_ads_type":"","vid_ads_m_group_google_ima":"","vid_ads_m_group_image":"","vid_ads_m_group_html5_video":"","vid_ads_m_group_html":"","vid_ads_m_vast_preroll":"","vid_ads_m_vast_postroll":"","vid_ads_m_vast_pauseroll":"","vid_ads_m_vast_midroll":[{"vid_ads_m_vast_timer_seconds":"50"}],"vid_ads_m_time_to_show_ads":"","vid_ads_m_time_skip_ads":"","vid_ads_m_time_to_hide_ads":""},"page_slider_settings":{"display_slider_group":"","page_slider_group":""},"blog_page_settings":{"blog_page_title":"","blog_page_heading":"","blog_page_ic":"","blog_page_it":"","blog_page_ec":"","blog_page_ip":"","archive_loop_style":"","blog_image_ratio":"","blog_show_categories":"","blog_show_excerpt":"","blog_show_author":"","blog_show_date":"","blog_show_comment_count":"","blog_show_view_count":"","blog_show_like_count":"","blog_show_dislike_count":"","blog_items_per_page":"","blog_pag_type":""},"page_options":{"get_page_template":"","color_mode":"","main_layout":"","main_layout_full_with":"","main_logo":"","main_logo_retina":"","main_logo_mobile":"","main_logo_mobile_retina":"","sticky_logo":"","sticky_logo_retina":"","main_nav_layout":"","ajax_search":"","header_background":"","theme_sidebar":"","instagram_feed":"","instagram_feed_position":"","popular_videos":"","popular_videos_title_1":"","popular_videos_title_2":"","popular_videos_ic":"","popular_videos_it":"","theme_background":"","page_custom_css":""},"feature_image_settings":{"feature_image_position":""},"video_player_settings":{"single_video_style":"","video_player_position":"","vm_video_url":"","video_player_library":"","video_streaming":"","vm_media_sources":"","vid_auto_play":"","vm_video_shortcode":"","vid_p_sync_playlist":"","vid_c_sync_channel":"","get_post_format":"","multiple_links_structure":"default","multi_links_title":"","vm_video_multi_links":"","vm_duration":"","vid_social_locker":"off","vid_social_locker_id":"","vid_membership_action":"content-video","vm_video_trailer_url":"","vid_download_type":"free","vid_download_target":"download","vid_woo_product":"","vm_media_download":"","user_rating":"","user_rating_position":"","user_rating_mode":"","user_rating_multi_sets":""},"video_auto_fetch_settings":{"vm_video_fetch":"on"},"video_fake_views_likes":{"vm_fake_views":"","vm_fake_likes":"","vm_fake_dislikes":""},"gallery_settings":{"gallery_position":""},"quote_settings":{"quote_position":""},"post_options":{"main_layout":"","main_logo":"","main_logo_retina":"","main_logo_mobile":"","main_logo_mobile_retina":"","sticky_logo":"","sticky_logo_retina":"","main_nav_layout":"","header_background":"","theme_sidebar":"","single_post_comment_type":"","theme_background":""}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/posts\/71153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/comments?post=71153"}],"version-history":[{"count":0,"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/posts\/71153\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/media\/71155"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/media?parent=71153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/categories?post=71153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/tags?post=71153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}