{"id":54069,"date":"2019-08-22T20:05:40","date_gmt":"2019-08-23T01:05:40","guid":{"rendered":"https:\/\/canal7slp.tv\/2019\/?p=54069"},"modified":"2019-08-22T20:05:40","modified_gmt":"2019-08-23T01:05:40","slug":"compras-institucionales-a-productoras-y-productores-en-pequeno-ya-son-politica-publica-en-slp","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2019\/compras-institucionales-a-productoras-y-productores-en-pequeno-ya-son-politica-publica-en-slp\/","title":{"rendered":"Compras institucionales a productoras y productores en peque\u00f1o, ya son pol\u00edtica p\u00fablica en SLP"},"content":{"rendered":"<ul>\n<li style=\"text-align: justify\">El programa beneficia actualmente a 328 productoras y productores de 10 Municipios.<\/li>\n<li style=\"text-align: justify\">La FAO se ha sumado a la estrategia en la ampliaci\u00f3n de la estrategia a los Municipios de Santa Catarina, Ray\u00f3n y Ciudad del Ma\u00edz.<\/li>\n<\/ul>\n<p style=\"text-align: justify\">SLP.- La estrategia de compras institucionales a productoras y productores en peque\u00f1o, que actualmente beneficia a 328 personas de 10 Municipios, se convirti\u00f3 en pol\u00edtica p\u00fablica, despu\u00e9s de que se emiti\u00f3 el decreto administrativo para la formalizaci\u00f3n del programa, creado con el prop\u00f3sito de fortalecer las acciones de acceso a la alimentaci\u00f3n y apoyar a familias de zonas rurales de San Luis Potos\u00ed.<\/p>\n<p style=\"text-align: justify\">Las acciones que vienen trabaj\u00e1ndose desde el inicio de la administraci\u00f3n del Gobernador Juan Manuel Carreras L\u00f3pez, se impulsaron de manera conjunta entre el Sistema Estatal para el Desarrollo Integral de la Familia (DIF) y la Secretar\u00eda de Desarrollo Agropecuario y Recursos Hidr\u00e1ulicos (Sedarh), a trav\u00e9s del Laboratorio de Cohesi\u00f3n Social II M\u00e9xico-Uni\u00f3n Europea, en donde participaron la Agencia Mexicana de Cooperaci\u00f3n Internacional para el Desarrollo de la Secretar\u00eda de Relaciones Exteriores y la Delegaci\u00f3n de la Uni\u00f3n Europea en M\u00e9xico.<\/p>\n<p style=\"text-align: justify\">Cabe resaltar que, en mayo pasado, la Organizaci\u00f3n de las Naciones Unidas para la Alimentaci\u00f3n y la Agricultura (FAO), se integr\u00f3 a la estrategia para fortalecer y documentar estas acciones. El organismo internacional trabaja en conjunto con DIF Estatal y Sedarh, en los Municipios de Ciudad del Ma\u00edz, Ray\u00f3n y Santa Catarina, en donde m\u00e1s productoras y productores se integrar\u00e1n a este programa, que ha dejado importantes beneficios a quienes ya participan.<\/p>\n<p style=\"text-align: justify\">Estas acciones surgen cuando beneficiarias y beneficiarios de proyectos productivos dedicados a la producci\u00f3n de hortalizas y huevos comenzaron a tener excedentes, por lo que surge la necesidad de apoyarles para que los comercialicen. En la b\u00fasqueda de alternativas para apoyar a las familias a tener alg\u00fan ingreso extra, se realiza el acercamiento con los Ayuntamientos y DIF Municipales, para que los espacios alimentarios adquieran la producci\u00f3n excedente.<\/p>\n<p style=\"text-align: justify\">En este sentido, se realiz\u00f3 un trabajo muy cercano con productoras y productores, para garantizar que sus huertos y granjas estuvieran consolidados, con la finalidad de que cumplan con las entregas de alimentos. De la misma forma, se les brind\u00f3 asesor\u00eda y acompa\u00f1amiento para el cumplimiento de las obligaciones fiscales.<br \/>\nEs importante resaltar que el 95 por ciento del total de 328 participantes en este programa son mujeres. Los Municipios en donde la estrategia ya funciona son: Aquism\u00f3n, Coxcatl\u00e1n, Huehuetl\u00e1n, Matlapa, San Antonio, Tamasopo, Tampac\u00e1n, Tamazunchale, Tancanhuitz y Xilitla.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El programa beneficia actualmente a 328 productoras y productores de 10 Municipios. La FAO se ha sumado a la estrategia en la ampliaci\u00f3n de la estrategia a los Municipios de Santa Catarina, Ray\u00f3n y Ciudad del Ma\u00edz. SLP.- La estrategia de compras institucionales a productoras y productores en peque\u00f1o, que actualmente beneficia a 328 personas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":54070,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-54069","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-localesyregionales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Compras institucionales a productoras y productores en peque\u00f1o, ya son pol\u00edtica p\u00fablica en SLP - Canal 7 SLP - 2019<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2019\/compras-institucionales-a-productoras-y-productores-en-pequeno-ya-son-politica-publica-en-slp\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Compras institucionales a productoras y productores en peque\u00f1o, ya son pol\u00edtica p\u00fablica en SLP - Canal 7 SLP - 2019\" \/>\n<meta property=\"og:description\" content=\"El programa beneficia actualmente a 328 productoras y productores de 10 Municipios. La FAO se ha sumado a la estrategia en la ampliaci\u00f3n de la estrategia a los Municipios de Santa Catarina, Ray\u00f3n y Ciudad del Ma\u00edz. SLP.- La estrategia de compras institucionales a productoras y productores en peque\u00f1o, que actualmente beneficia a 328 personas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2019\/compras-institucionales-a-productoras-y-productores-en-pequeno-ya-son-politica-publica-en-slp\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2019\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CANAL7SLP\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-23T01:05:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2019\/wp-content\/uploads\/2019\/08\/g8-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"546\" \/>\n\t<meta property=\"og:image:height\" content=\"410\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"edicionweb\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@canal7_slp\" \/>\n<meta name=\"twitter:site\" content=\"@canal7_slp\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"edicionweb\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/compras-institucionales-a-productoras-y-productores-en-pequeno-ya-son-politica-publica-en-slp\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/compras-institucionales-a-productoras-y-productores-en-pequeno-ya-son-politica-publica-en-slp\\\/\"},\"author\":{\"name\":\"edicionweb\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/#\\\/schema\\\/person\\\/11d941c1c6ca30ac0a46b95fa37aa2e3\"},\"headline\":\"Compras institucionales a productoras y productores en peque\u00f1o, ya son pol\u00edtica p\u00fablica en SLP\",\"datePublished\":\"2019-08-23T01:05:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/compras-institucionales-a-productoras-y-productores-en-pequeno-ya-son-politica-publica-en-slp\\\/\"},\"wordCount\":462,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/compras-institucionales-a-productoras-y-productores-en-pequeno-ya-son-politica-publica-en-slp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/g8-3.jpg\",\"articleSection\":[\"LOCALES Y REGIONALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/compras-institucionales-a-productoras-y-productores-en-pequeno-ya-son-politica-publica-en-slp\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/compras-institucionales-a-productoras-y-productores-en-pequeno-ya-son-politica-publica-en-slp\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/compras-institucionales-a-productoras-y-productores-en-pequeno-ya-son-politica-publica-en-slp\\\/\",\"name\":\"Compras institucionales a productoras y productores en peque\u00f1o, ya son pol\u00edtica p\u00fablica en SLP - Canal 7 SLP - 2019\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/compras-institucionales-a-productoras-y-productores-en-pequeno-ya-son-politica-publica-en-slp\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/compras-institucionales-a-productoras-y-productores-en-pequeno-ya-son-politica-publica-en-slp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/g8-3.jpg\",\"datePublished\":\"2019-08-23T01:05:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/compras-institucionales-a-productoras-y-productores-en-pequeno-ya-son-politica-publica-en-slp\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/compras-institucionales-a-productoras-y-productores-en-pequeno-ya-son-politica-publica-en-slp\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/compras-institucionales-a-productoras-y-productores-en-pequeno-ya-son-politica-publica-en-slp\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/g8-3.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/g8-3.jpg\",\"width\":546,\"height\":410},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/compras-institucionales-a-productoras-y-productores-en-pequeno-ya-son-politica-publica-en-slp\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Compras institucionales a productoras y productores en peque\u00f1o, ya son pol\u00edtica p\u00fablica en SLP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/\",\"name\":\"Canal 7 SLP - Somos TV\",\"description\":\"Somos un Canal de 10\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/#organization\",\"name\":\"Comunicaci\u00f3n 2000 S.A. de C.V.\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/logo-c7.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/logo-c7.png\",\"width\":220,\"height\":60,\"caption\":\"Comunicaci\u00f3n 2000 S.A. de C.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CANAL7SLP\\\/\",\"https:\\\/\\\/x.com\\\/canal7_slp\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/NOTICIEROSCANAL7SLP\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/#\\\/schema\\\/person\\\/11d941c1c6ca30ac0a46b95fa37aa2e3\",\"name\":\"edicionweb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"edicionweb\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Compras institucionales a productoras y productores en peque\u00f1o, ya son pol\u00edtica p\u00fablica en SLP - Canal 7 SLP - 2019","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2019\/compras-institucionales-a-productoras-y-productores-en-pequeno-ya-son-politica-publica-en-slp\/","og_locale":"es_ES","og_type":"article","og_title":"Compras institucionales a productoras y productores en peque\u00f1o, ya son pol\u00edtica p\u00fablica en SLP - Canal 7 SLP - 2019","og_description":"El programa beneficia actualmente a 328 productoras y productores de 10 Municipios. La FAO se ha sumado a la estrategia en la ampliaci\u00f3n de la estrategia a los Municipios de Santa Catarina, Ray\u00f3n y Ciudad del Ma\u00edz. SLP.- La estrategia de compras institucionales a productoras y productores en peque\u00f1o, que actualmente beneficia a 328 personas [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2019\/compras-institucionales-a-productoras-y-productores-en-pequeno-ya-son-politica-publica-en-slp\/","og_site_name":"Canal 7 SLP - 2019","article_publisher":"https:\/\/www.facebook.com\/CANAL7SLP\/","article_published_time":"2019-08-23T01:05:40+00:00","og_image":[{"width":546,"height":410,"url":"https:\/\/canal7slp.tv\/2019\/wp-content\/uploads\/2019\/08\/g8-3.jpg","type":"image\/jpeg"}],"author":"edicionweb","twitter_card":"summary_large_image","twitter_creator":"@canal7_slp","twitter_site":"@canal7_slp","twitter_misc":{"Escrito por":"edicionweb","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2019\/compras-institucionales-a-productoras-y-productores-en-pequeno-ya-son-politica-publica-en-slp\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2019\/compras-institucionales-a-productoras-y-productores-en-pequeno-ya-son-politica-publica-en-slp\/"},"author":{"name":"edicionweb","@id":"https:\/\/canal7slp.tv\/2019\/#\/schema\/person\/11d941c1c6ca30ac0a46b95fa37aa2e3"},"headline":"Compras institucionales a productoras y productores en peque\u00f1o, ya son pol\u00edtica p\u00fablica en SLP","datePublished":"2019-08-23T01:05:40+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2019\/compras-institucionales-a-productoras-y-productores-en-pequeno-ya-son-politica-publica-en-slp\/"},"wordCount":462,"commentCount":0,"publisher":{"@id":"https:\/\/canal7slp.tv\/2019\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2019\/compras-institucionales-a-productoras-y-productores-en-pequeno-ya-son-politica-publica-en-slp\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2019\/wp-content\/uploads\/2019\/08\/g8-3.jpg","articleSection":["LOCALES Y REGIONALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/canal7slp.tv\/2019\/compras-institucionales-a-productoras-y-productores-en-pequeno-ya-son-politica-publica-en-slp\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2019\/compras-institucionales-a-productoras-y-productores-en-pequeno-ya-son-politica-publica-en-slp\/","url":"https:\/\/canal7slp.tv\/2019\/compras-institucionales-a-productoras-y-productores-en-pequeno-ya-son-politica-publica-en-slp\/","name":"Compras institucionales a productoras y productores en peque\u00f1o, ya son pol\u00edtica p\u00fablica en SLP - Canal 7 SLP - 2019","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2019\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2019\/compras-institucionales-a-productoras-y-productores-en-pequeno-ya-son-politica-publica-en-slp\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2019\/compras-institucionales-a-productoras-y-productores-en-pequeno-ya-son-politica-publica-en-slp\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2019\/wp-content\/uploads\/2019\/08\/g8-3.jpg","datePublished":"2019-08-23T01:05:40+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2019\/compras-institucionales-a-productoras-y-productores-en-pequeno-ya-son-politica-publica-en-slp\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2019\/compras-institucionales-a-productoras-y-productores-en-pequeno-ya-son-politica-publica-en-slp\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2019\/compras-institucionales-a-productoras-y-productores-en-pequeno-ya-son-politica-publica-en-slp\/#primaryimage","url":"https:\/\/canal7slp.tv\/2019\/wp-content\/uploads\/2019\/08\/g8-3.jpg","contentUrl":"https:\/\/canal7slp.tv\/2019\/wp-content\/uploads\/2019\/08\/g8-3.jpg","width":546,"height":410},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2019\/compras-institucionales-a-productoras-y-productores-en-pequeno-ya-son-politica-publica-en-slp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/canal7slp.tv\/2019\/"},{"@type":"ListItem","position":2,"name":"Compras institucionales a productoras y productores en peque\u00f1o, ya son pol\u00edtica p\u00fablica en SLP"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2019\/#website","url":"https:\/\/canal7slp.tv\/2019\/","name":"Canal 7 SLP - Somos TV","description":"Somos un Canal de 10","publisher":{"@id":"https:\/\/canal7slp.tv\/2019\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2019\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2019\/#organization","name":"Comunicaci\u00f3n 2000 S.A. de C.V.","url":"https:\/\/canal7slp.tv\/2019\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2019\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2019\/wp-content\/uploads\/2019\/07\/logo-c7.png","contentUrl":"https:\/\/canal7slp.tv\/2019\/wp-content\/uploads\/2019\/07\/logo-c7.png","width":220,"height":60,"caption":"Comunicaci\u00f3n 2000 S.A. de C.V."},"image":{"@id":"https:\/\/canal7slp.tv\/2019\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CANAL7SLP\/","https:\/\/x.com\/canal7_slp","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/user\/NOTICIEROSCANAL7SLP\/"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2019\/#\/schema\/person\/11d941c1c6ca30ac0a46b95fa37aa2e3","name":"edicionweb","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"edicionweb"}}]}},"amp_enabled":true,"cmb2":{"video_ids_in_playlist":{"vid_p_videos":""},"video_ids_in_channel":{"vid_c_videos":""},"playlist_ids_in_channel":{"vid_c_playlists":""},"series_ids_in_channel":{"vid_c_series":""},"channel_images":{"vid_c_logo":"","vid_c_banner":""},"poster_feature_image":{"vid_m_poster_image":""},"gif_feature_image":{"vid_m_gif_image":""},"video_movie_settings":{"vid_m_director":"","vid_m_actor":"","vid_m_imdb_ratings":"","vid_m_amazon_associates":""},"vid_youtube_broadcasts_settings":{"vid_yb_broadcast_title":"","vid_yb_q":"","vid_yb_channelid":"","vid_yb_videocategoryid":"","vid_yb_maxresults":"","vid_yb_order":"","vid_yb_regioncode":"","vid_yb_videosyndicated":"","vid_yb_style":"","vid_yb_reload_first":""},"video_series_settings":{"vid_m_director":"","vid_m_actor":"","vid_m_imdb_ratings":"","video_series_group":""},"amazon_associates_settings":{"amazon_associates":"","amazon_native_ad":""},"vid_youtube_automatic_settings":{"vid_ya_youtube_source":"","vid_ya_update_every":"","vid_ya_update_unit":"","vid_ya_categories":"","vid_ya_published_after":"","vid_ya_published_before":"","vid_ya_playlists":"","vid_ya_channels":"","vid_ya_director":"","vid_ya_actor":"","vid_ya_author":"","vid_ya_import_post_date":"","vid_ya_status":"","vid_ya_sub_api_key":""},"vid_ads_m_videoads_settings_post":{"vid_ads_m_video_ads":"","vid_ads_m_video_ads_type":"","vid_ads_m_group_google_ima":"","vid_ads_m_group_image":"","vid_ads_m_group_html5_video":"","vid_ads_m_group_html":"","vid_ads_m_vast_preroll":"","vid_ads_m_vast_postroll":"","vid_ads_m_vast_pauseroll":"","vid_ads_m_vast_midroll":[{"vid_ads_m_vast_timer_seconds":"50"}],"vid_ads_m_time_to_show_ads":"","vid_ads_m_time_skip_ads":"","vid_ads_m_time_to_hide_ads":""},"page_slider_settings":{"display_slider_group":"","page_slider_group":""},"blog_page_settings":{"blog_page_title":"","blog_page_heading":"","blog_page_ic":"","blog_page_it":"","blog_page_ec":"","blog_page_ip":"","archive_loop_style":"","blog_image_ratio":"","blog_show_categories":"","blog_show_excerpt":"","blog_show_author":"","blog_show_date":"","blog_show_comment_count":"","blog_show_view_count":"","blog_show_like_count":"","blog_show_dislike_count":"","blog_items_per_page":"","blog_pag_type":""},"page_options":{"get_page_template":"","color_mode":"","main_layout":"","main_layout_full_with":"","main_logo":"","main_logo_retina":"","main_logo_mobile":"","main_logo_mobile_retina":"","sticky_logo":"","sticky_logo_retina":"","main_nav_layout":"","ajax_search":"","header_background":"","theme_sidebar":"","instagram_feed":"","instagram_feed_position":"","popular_videos":"","popular_videos_title_1":"","popular_videos_title_2":"","popular_videos_ic":"","popular_videos_it":"","theme_background":"","page_custom_css":""},"feature_image_settings":{"feature_image_position":""},"video_player_settings":{"single_video_style":"","video_player_position":"","vm_video_url":"","video_player_library":"","video_streaming":"","vm_media_sources":"","vid_auto_play":"","vm_video_shortcode":"","vid_p_sync_playlist":"","vid_c_sync_channel":"","get_post_format":"","multiple_links_structure":"default","multi_links_title":"","vm_video_multi_links":"","vm_duration":"","vid_social_locker":"off","vid_social_locker_id":"","vid_membership_action":"content-video","vm_video_trailer_url":"","vid_download_type":"free","vid_download_target":"download","vid_woo_product":"","vm_media_download":"","user_rating":"","user_rating_position":"","user_rating_mode":"","user_rating_multi_sets":""},"video_auto_fetch_settings":{"vm_video_fetch":"on"},"video_fake_views_likes":{"vm_fake_views":"","vm_fake_likes":"","vm_fake_dislikes":""},"gallery_settings":{"gallery_position":""},"quote_settings":{"quote_position":""},"post_options":{"main_layout":"","main_logo":"","main_logo_retina":"","main_logo_mobile":"","main_logo_mobile_retina":"","sticky_logo":"","sticky_logo_retina":"","main_nav_layout":"","header_background":"","theme_sidebar":"","single_post_comment_type":"","theme_background":""}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/posts\/54069","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/comments?post=54069"}],"version-history":[{"count":0,"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/posts\/54069\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/media\/54070"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/media?parent=54069"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/categories?post=54069"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/tags?post=54069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}