{"id":22122,"date":"2019-06-25T15:18:39","date_gmt":"2019-06-25T20:18:39","guid":{"rendered":"https:\/\/canal7slp.tv\/2019\/?p=22122"},"modified":"2019-07-15T11:35:14","modified_gmt":"2019-07-15T16:35:14","slug":"se-disputo-la-7a-fecha-de-la-liga-de-handbol-potosinos-ilustres","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2019\/se-disputo-la-7a-fecha-de-la-liga-de-handbol-potosinos-ilustres\/","title":{"rendered":"Se disputo la 7\u00aa. Fecha de la Liga de H\u00e1ndbol Potosinos Ilustres."},"content":{"rendered":"<p style=\"text-align: justify;\">SLP.-\u00a0Finaliz\u00f3 la s\u00e9ptima fecha dentro de las actividades de la Liga de H\u00e1ndbol Potosinos Ilustres que cont\u00f3 nuevamente con una gran cantidad de partidos y de buenos juegos en la competencia que busca promover y fomentar \u00e9sta disciplina.<\/p>\n<p style=\"text-align: justify;\">Equipos en la rama varonil y femenil mostraron su talento para seguir cosechando triunfos, y as\u00ed llegar a situarse en la parte alta de la tabla general.<\/p>\n<p style=\"text-align: justify;\">En algunos de los resultados la UASLP derrot\u00f3 20-5 a la BECENE; el COBACH #25 cay\u00f3 5-9 ante Colegio Potosinos Ilustres y las Cazadoras le pegaron 14-4 a Soledad de Graciano S\u00e1nchez.<\/p>\n<p style=\"text-align: justify;\">En la varonil el Colegio Potosinos Ilustres gan\u00f3 19-6 a Lobos; Cedral se impuso 19-6 a Soledad de Graciano S\u00e1nchez; F\u00e9nix Negros vencieron 23-9 a la Universidad Jos\u00e9 Vasconcelos; Cedral aplast\u00f3 32-1 a la Preparatoria Silva Herzog y el COBACH 25 sucumbi\u00f3 13-26 ante la UASLP.<\/p>\n<p style=\"text-align: justify;\">Por: Eduardo Mart\u00ednez Tapia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SLP.-\u00a0Finaliz\u00f3 la s\u00e9ptima fecha dentro de las actividades de la Liga de H\u00e1ndbol Potosinos Ilustres que cont\u00f3 nuevamente con una gran cantidad de partidos y de buenos juegos en la competencia que busca promover y fomentar \u00e9sta disciplina. Equipos en la rama varonil y femenil mostraron su talento para seguir cosechando triunfos, y as\u00ed llegar [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":22147,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"footnotes":""},"categories":[96],"tags":[1069],"class_list":["post-22122","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-deportes","tag-liga-de-handbol-potosinos","post_format-post-format-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Se disputo la 7\u00aa. Fecha de la Liga de H\u00e1ndbol Potosinos Ilustres. - Canal 7 SLP - 2019<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2019\/se-disputo-la-7a-fecha-de-la-liga-de-handbol-potosinos-ilustres\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se disputo la 7\u00aa. Fecha de la Liga de H\u00e1ndbol Potosinos Ilustres. - Canal 7 SLP - 2019\" \/>\n<meta property=\"og:description\" content=\"SLP.-\u00a0Finaliz\u00f3 la s\u00e9ptima fecha dentro de las actividades de la Liga de H\u00e1ndbol Potosinos Ilustres que cont\u00f3 nuevamente con una gran cantidad de partidos y de buenos juegos en la competencia que busca promover y fomentar \u00e9sta disciplina. Equipos en la rama varonil y femenil mostraron su talento para seguir cosechando triunfos, y as\u00ed llegar [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2019\/se-disputo-la-7a-fecha-de-la-liga-de-handbol-potosinos-ilustres\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2019\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CANAL7SLP\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-25T20:18:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-15T16:35:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2019\/wp-content\/uploads\/2019\/06\/hadball.png\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"418\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"edicionweb\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@canal7_slp\" \/>\n<meta name=\"twitter:site\" content=\"@canal7_slp\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"edicionweb\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/se-disputo-la-7a-fecha-de-la-liga-de-handbol-potosinos-ilustres\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/se-disputo-la-7a-fecha-de-la-liga-de-handbol-potosinos-ilustres\\\/\"},\"author\":{\"name\":\"edicionweb\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/#\\\/schema\\\/person\\\/11d941c1c6ca30ac0a46b95fa37aa2e3\"},\"headline\":\"Se disputo la 7\u00aa. Fecha de la Liga de H\u00e1ndbol Potosinos Ilustres.\",\"datePublished\":\"2019-06-25T20:18:39+00:00\",\"dateModified\":\"2019-07-15T16:35:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/se-disputo-la-7a-fecha-de-la-liga-de-handbol-potosinos-ilustres\\\/\"},\"wordCount\":165,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/se-disputo-la-7a-fecha-de-la-liga-de-handbol-potosinos-ilustres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/hadball.png\",\"keywords\":[\"Liga de H\u00e1ndbol Potosinos\"],\"articleSection\":[\"DEPORTES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/se-disputo-la-7a-fecha-de-la-liga-de-handbol-potosinos-ilustres\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/se-disputo-la-7a-fecha-de-la-liga-de-handbol-potosinos-ilustres\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/se-disputo-la-7a-fecha-de-la-liga-de-handbol-potosinos-ilustres\\\/\",\"name\":\"Se disputo la 7\u00aa. Fecha de la Liga de H\u00e1ndbol Potosinos Ilustres. - Canal 7 SLP - 2019\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/se-disputo-la-7a-fecha-de-la-liga-de-handbol-potosinos-ilustres\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/se-disputo-la-7a-fecha-de-la-liga-de-handbol-potosinos-ilustres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/hadball.png\",\"datePublished\":\"2019-06-25T20:18:39+00:00\",\"dateModified\":\"2019-07-15T16:35:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/se-disputo-la-7a-fecha-de-la-liga-de-handbol-potosinos-ilustres\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/se-disputo-la-7a-fecha-de-la-liga-de-handbol-potosinos-ilustres\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/se-disputo-la-7a-fecha-de-la-liga-de-handbol-potosinos-ilustres\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/hadball.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/hadball.png\",\"width\":750,\"height\":418},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/se-disputo-la-7a-fecha-de-la-liga-de-handbol-potosinos-ilustres\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se disputo la 7\u00aa. Fecha de la Liga de H\u00e1ndbol Potosinos Ilustres.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/\",\"name\":\"Canal 7 SLP - Somos TV\",\"description\":\"Somos un Canal de 10\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/#organization\",\"name\":\"Comunicaci\u00f3n 2000 S.A. de C.V.\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/logo-c7.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/logo-c7.png\",\"width\":220,\"height\":60,\"caption\":\"Comunicaci\u00f3n 2000 S.A. de C.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CANAL7SLP\\\/\",\"https:\\\/\\\/x.com\\\/canal7_slp\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/NOTICIEROSCANAL7SLP\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/#\\\/schema\\\/person\\\/11d941c1c6ca30ac0a46b95fa37aa2e3\",\"name\":\"edicionweb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"edicionweb\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se disputo la 7\u00aa. Fecha de la Liga de H\u00e1ndbol Potosinos Ilustres. - Canal 7 SLP - 2019","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2019\/se-disputo-la-7a-fecha-de-la-liga-de-handbol-potosinos-ilustres\/","og_locale":"es_ES","og_type":"article","og_title":"Se disputo la 7\u00aa. Fecha de la Liga de H\u00e1ndbol Potosinos Ilustres. - Canal 7 SLP - 2019","og_description":"SLP.-\u00a0Finaliz\u00f3 la s\u00e9ptima fecha dentro de las actividades de la Liga de H\u00e1ndbol Potosinos Ilustres que cont\u00f3 nuevamente con una gran cantidad de partidos y de buenos juegos en la competencia que busca promover y fomentar \u00e9sta disciplina. Equipos en la rama varonil y femenil mostraron su talento para seguir cosechando triunfos, y as\u00ed llegar [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2019\/se-disputo-la-7a-fecha-de-la-liga-de-handbol-potosinos-ilustres\/","og_site_name":"Canal 7 SLP - 2019","article_publisher":"https:\/\/www.facebook.com\/CANAL7SLP\/","article_published_time":"2019-06-25T20:18:39+00:00","article_modified_time":"2019-07-15T16:35:14+00:00","og_image":[{"width":750,"height":418,"url":"https:\/\/canal7slp.tv\/2019\/wp-content\/uploads\/2019\/06\/hadball.png","type":"image\/png"}],"author":"edicionweb","twitter_card":"summary_large_image","twitter_creator":"@canal7_slp","twitter_site":"@canal7_slp","twitter_misc":{"Escrito por":"edicionweb","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2019\/se-disputo-la-7a-fecha-de-la-liga-de-handbol-potosinos-ilustres\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2019\/se-disputo-la-7a-fecha-de-la-liga-de-handbol-potosinos-ilustres\/"},"author":{"name":"edicionweb","@id":"https:\/\/canal7slp.tv\/2019\/#\/schema\/person\/11d941c1c6ca30ac0a46b95fa37aa2e3"},"headline":"Se disputo la 7\u00aa. Fecha de la Liga de H\u00e1ndbol Potosinos Ilustres.","datePublished":"2019-06-25T20:18:39+00:00","dateModified":"2019-07-15T16:35:14+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2019\/se-disputo-la-7a-fecha-de-la-liga-de-handbol-potosinos-ilustres\/"},"wordCount":165,"commentCount":0,"publisher":{"@id":"https:\/\/canal7slp.tv\/2019\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2019\/se-disputo-la-7a-fecha-de-la-liga-de-handbol-potosinos-ilustres\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2019\/wp-content\/uploads\/2019\/06\/hadball.png","keywords":["Liga de H\u00e1ndbol Potosinos"],"articleSection":["DEPORTES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/canal7slp.tv\/2019\/se-disputo-la-7a-fecha-de-la-liga-de-handbol-potosinos-ilustres\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2019\/se-disputo-la-7a-fecha-de-la-liga-de-handbol-potosinos-ilustres\/","url":"https:\/\/canal7slp.tv\/2019\/se-disputo-la-7a-fecha-de-la-liga-de-handbol-potosinos-ilustres\/","name":"Se disputo la 7\u00aa. Fecha de la Liga de H\u00e1ndbol Potosinos Ilustres. - Canal 7 SLP - 2019","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2019\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2019\/se-disputo-la-7a-fecha-de-la-liga-de-handbol-potosinos-ilustres\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2019\/se-disputo-la-7a-fecha-de-la-liga-de-handbol-potosinos-ilustres\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2019\/wp-content\/uploads\/2019\/06\/hadball.png","datePublished":"2019-06-25T20:18:39+00:00","dateModified":"2019-07-15T16:35:14+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2019\/se-disputo-la-7a-fecha-de-la-liga-de-handbol-potosinos-ilustres\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2019\/se-disputo-la-7a-fecha-de-la-liga-de-handbol-potosinos-ilustres\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2019\/se-disputo-la-7a-fecha-de-la-liga-de-handbol-potosinos-ilustres\/#primaryimage","url":"https:\/\/canal7slp.tv\/2019\/wp-content\/uploads\/2019\/06\/hadball.png","contentUrl":"https:\/\/canal7slp.tv\/2019\/wp-content\/uploads\/2019\/06\/hadball.png","width":750,"height":418},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2019\/se-disputo-la-7a-fecha-de-la-liga-de-handbol-potosinos-ilustres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/canal7slp.tv\/2019\/"},{"@type":"ListItem","position":2,"name":"Se disputo la 7\u00aa. Fecha de la Liga de H\u00e1ndbol Potosinos Ilustres."}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2019\/#website","url":"https:\/\/canal7slp.tv\/2019\/","name":"Canal 7 SLP - Somos TV","description":"Somos un Canal de 10","publisher":{"@id":"https:\/\/canal7slp.tv\/2019\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2019\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2019\/#organization","name":"Comunicaci\u00f3n 2000 S.A. de C.V.","url":"https:\/\/canal7slp.tv\/2019\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2019\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2019\/wp-content\/uploads\/2019\/07\/logo-c7.png","contentUrl":"https:\/\/canal7slp.tv\/2019\/wp-content\/uploads\/2019\/07\/logo-c7.png","width":220,"height":60,"caption":"Comunicaci\u00f3n 2000 S.A. de C.V."},"image":{"@id":"https:\/\/canal7slp.tv\/2019\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CANAL7SLP\/","https:\/\/x.com\/canal7_slp","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/user\/NOTICIEROSCANAL7SLP\/"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2019\/#\/schema\/person\/11d941c1c6ca30ac0a46b95fa37aa2e3","name":"edicionweb","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"edicionweb"}}]}},"amp_enabled":true,"cmb2":{"video_ids_in_playlist":{"vid_p_videos":""},"video_ids_in_channel":{"vid_c_videos":""},"playlist_ids_in_channel":{"vid_c_playlists":""},"series_ids_in_channel":{"vid_c_series":""},"channel_images":{"vid_c_logo":"","vid_c_banner":""},"poster_feature_image":{"vid_m_poster_image":""},"gif_feature_image":{"vid_m_gif_image":""},"video_movie_settings":{"vid_m_director":"","vid_m_actor":"","vid_m_imdb_ratings":"","vid_m_amazon_associates":""},"vid_youtube_broadcasts_settings":{"vid_yb_broadcast_title":"","vid_yb_q":"","vid_yb_channelid":"","vid_yb_videocategoryid":"","vid_yb_maxresults":"","vid_yb_order":"","vid_yb_regioncode":"","vid_yb_videosyndicated":"","vid_yb_style":"","vid_yb_reload_first":""},"video_series_settings":{"vid_m_director":"","vid_m_actor":"","vid_m_imdb_ratings":"","video_series_group":""},"amazon_associates_settings":{"amazon_associates":"","amazon_native_ad":""},"vid_youtube_automatic_settings":{"vid_ya_youtube_source":"","vid_ya_update_every":"","vid_ya_update_unit":"","vid_ya_categories":"","vid_ya_published_after":"","vid_ya_published_before":"","vid_ya_playlists":"","vid_ya_channels":"","vid_ya_director":"","vid_ya_actor":"","vid_ya_author":"","vid_ya_import_post_date":"","vid_ya_status":"","vid_ya_sub_api_key":""},"vid_ads_m_videoads_settings_post":{"vid_ads_m_video_ads":"","vid_ads_m_video_ads_type":"","vid_ads_m_group_google_ima":"","vid_ads_m_group_image":"","vid_ads_m_group_html5_video":"","vid_ads_m_group_html":"","vid_ads_m_vast_preroll":"","vid_ads_m_vast_postroll":"","vid_ads_m_vast_pauseroll":"","vid_ads_m_vast_midroll":[{"vid_ads_m_vast_timer_seconds":"50"}],"vid_ads_m_time_to_show_ads":"","vid_ads_m_time_skip_ads":"","vid_ads_m_time_to_hide_ads":""},"page_slider_settings":{"display_slider_group":"","page_slider_group":""},"blog_page_settings":{"blog_page_title":"","blog_page_heading":"","blog_page_ic":"","blog_page_it":"","blog_page_ec":"","blog_page_ip":"","archive_loop_style":"","blog_image_ratio":"","blog_show_categories":"","blog_show_excerpt":"","blog_show_author":"","blog_show_date":"","blog_show_comment_count":"","blog_show_view_count":"","blog_show_like_count":"","blog_show_dislike_count":"","blog_items_per_page":"","blog_pag_type":""},"page_options":{"get_page_template":"","color_mode":"","main_layout":"","main_layout_full_with":"","main_logo":"","main_logo_retina":"","main_logo_mobile":"","main_logo_mobile_retina":"","sticky_logo":"","sticky_logo_retina":"","main_nav_layout":"","ajax_search":"","header_background":"","theme_sidebar":"","instagram_feed":"","instagram_feed_position":"","popular_videos":"","popular_videos_title_1":"","popular_videos_title_2":"","popular_videos_ic":"","popular_videos_it":"","theme_background":"","page_custom_css":""},"feature_image_settings":{"feature_image_position":""},"video_player_settings":{"single_video_style":"","video_player_position":"special","vm_video_url":"https:\/\/youtu.be\/1pvycPhSWc4","video_player_library":"","video_streaming":"","vm_media_sources":"","vid_auto_play":"","vm_video_shortcode":"","vid_p_sync_playlist":"","vid_c_sync_channel":"","get_post_format":"","multiple_links_structure":"default","multi_links_title":"","vm_video_multi_links":"","vm_duration":"","vid_social_locker":"off","vid_social_locker_id":"","vid_membership_action":"content-video","vm_video_trailer_url":"","vid_download_type":"free","vid_download_target":"download","vid_woo_product":"","vm_media_download":"","user_rating":"","user_rating_position":"","user_rating_mode":"","user_rating_multi_sets":""},"video_auto_fetch_settings":{"vm_video_fetch":"off"},"video_fake_views_likes":{"vm_fake_views":"","vm_fake_likes":"","vm_fake_dislikes":""},"gallery_settings":{"gallery_position":""},"quote_settings":{"quote_position":""},"post_options":{"main_layout":"","main_logo":"","main_logo_retina":"","main_logo_mobile":"","main_logo_mobile_retina":"","sticky_logo":"","sticky_logo_retina":"","main_nav_layout":"","header_background":"","theme_sidebar":"","single_post_comment_type":"","theme_background":""}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/posts\/22122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/comments?post=22122"}],"version-history":[{"count":0,"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/posts\/22122\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/media\/22147"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/media?parent=22122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/categories?post=22122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/tags?post=22122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}