{"id":13115,"date":"2019-06-11T22:12:04","date_gmt":"2019-06-12T03:12:04","guid":{"rendered":"https:\/\/canal7slp.tv\/2019\/?p=13115"},"modified":"2019-06-12T10:51:54","modified_gmt":"2019-06-12T15:51:54","slug":"inaugura-xavier-azuara-su-casa-de-enlace-ciudadano","status":"publish","type":"post","link":"https:\/\/canal7slp.tv\/2019\/inaugura-xavier-azuara-su-casa-de-enlace-ciudadano\/","title":{"rendered":"Inaugura Xavier Azuara su casa de Enlace Ciudadano"},"content":{"rendered":"<p style=\"text-align: justify\">\u2022 El diputado federal dijo que ese ser\u00e1 espacio de transformaci\u00f3n donde se impulsen las ideas y propuestas de la ciudadan\u00eda.<\/p>\n<p style=\"text-align: justify\">\u2022 Present\u00f3 junto al vicecoordinador, Jorge Romero una iniciativa que busca garantizar las propuestas ciudadanas en la C\u00e1mara de Diputados.<\/p>\n<p style=\"text-align: justify\">SLP.- Este ser\u00e1 un espacio para las y los ciudadanos, que no s\u00f3lo apoye con gestiones, tramites y asesor\u00edas, sino que tambi\u00e9n sea un lugar de transformaci\u00f3n, donde las ideas y propuestas para mejorar la calidad de vida de toda la ciudadan\u00eda ser\u00e1n bienvenidas.<\/p>\n<p style=\"text-align: justify\">As\u00ed present\u00f3 el diputado federal Xavier Azuara Z\u00fa\u00f1iga su Casa de Enlace Ciudadano, la cual est\u00e1 ubicada en la calle Juventino Rosas #709, Col. Jardines del Estadio en la capital del Estado y estar\u00e1 abierta para atender a la ciudadan\u00eda a partir del d\u00eda de hoy.<\/p>\n<p style=\"text-align: justify\">Durante el evento de inauguraci\u00f3n, Azuara Z\u00fa\u00f1iga destac\u00f3 que el M\u00e9xico y el San Luis Potos\u00ed con mayores oportunidades, mejores empleos y mayor igualdad est\u00e1 a su alcance y se debe luchar por \u00e9l, ya que la tarea se debe hacer en conjunto con las y los ciudadanos.<\/p>\n<p style=\"text-align: justify\">En este sentido, dio a conocer una iniciativa conjunta con el vicecoordinador del Grupo Parlamentario del PAN en San L\u00e1zaro, el diputado Jorge Romero Herrera, la cual destac\u00f3 como una herramienta que garantice las propuestas ciudadanas en la C\u00e1mara de Diputados.<\/p>\n<p style=\"text-align: justify\">Con la cual remarc\u00f3 se tendr\u00e1n que discutir las iniciativas ciudadanas en el mismo mes donde sean presentadas, sin importar el tema sobre el cual se presenten, ya sea en salud, en educaci\u00f3n, en transporte, en vivienda o en cualquier otro \u00e1mbito para que se puedan convertir en una Ley que beneficie no s\u00f3lo a sus comunidades, sino a todas las mexicanas y mexicanos.<\/p>\n<p style=\"text-align: justify\">Sobre esto el vicecoordinador, Jorge Romero apunt\u00f3 que estas acciones est\u00e1n enfocadas en mantener el contacto con la ciudadan\u00eda ante la realidad del pa\u00eds, pues se demuestra con hechos la disposici\u00f3n para estar en contacto con todas y todos quienes requieren de la atenci\u00f3n de sus representantes.<\/p>\n<p style=\"text-align: justify\">Por su parte, el dirigente nacional, Marko Cort\u00e9s Mendoza quien acompa\u00f1\u00f3 al diputado en la inauguraci\u00f3n dijo que la casa de Enlace representa un acto de responsabilidad para estar pendiente sobre las demandas de la ciudadanas, para escuchar sus necesidades.<\/p>\n<p style=\"text-align: justify\">Asimismo, el dirigente estatal panista, Juan Francisco Aguilar Hern\u00e1ndez resalt\u00f3 que este espacio es una muestra del trabajo que est\u00e1 realizando Acci\u00f3n Nacional en San Luis Potos\u00ed para servir a la ciudadan\u00eda no s\u00f3lo a trav\u00e9s de la gesti\u00f3n, sino que tambi\u00e9n mediante la legislaci\u00f3n.<\/p>\n<p style=\"text-align: justify\">Finalmente el legislador hizo un llamado a la colaboraci\u00f3n y unidad, \u201cporque en estos tiempos de polarizaci\u00f3n y divisi\u00f3n, debemos estar m\u00e1s unidos, tenemos la obligaci\u00f3n de unir esfuerzos legisladores y ciudadanos como siempre lo hemos hecho, con la finalidad de realizar las mejores propuestas\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2022 El diputado federal dijo que ese ser\u00e1 espacio de transformaci\u00f3n donde se impulsen las ideas y propuestas de la ciudadan\u00eda. \u2022 Present\u00f3 junto al vicecoordinador, Jorge Romero una iniciativa que busca garantizar las propuestas ciudadanas en la C\u00e1mara de Diputados. SLP.- Este ser\u00e1 un espacio para las y los ciudadanos, que no s\u00f3lo apoye [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":13116,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-13115","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-localesyregionales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Inaugura Xavier Azuara su casa de Enlace Ciudadano - Canal 7 SLP - 2019<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canal7slp.tv\/2019\/inaugura-xavier-azuara-su-casa-de-enlace-ciudadano\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inaugura Xavier Azuara su casa de Enlace Ciudadano - Canal 7 SLP - 2019\" \/>\n<meta property=\"og:description\" content=\"\u2022 El diputado federal dijo que ese ser\u00e1 espacio de transformaci\u00f3n donde se impulsen las ideas y propuestas de la ciudadan\u00eda. \u2022 Present\u00f3 junto al vicecoordinador, Jorge Romero una iniciativa que busca garantizar las propuestas ciudadanas en la C\u00e1mara de Diputados. SLP.- Este ser\u00e1 un espacio para las y los ciudadanos, que no s\u00f3lo apoye [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canal7slp.tv\/2019\/inaugura-xavier-azuara-su-casa-de-enlace-ciudadano\/\" \/>\n<meta property=\"og:site_name\" content=\"Canal 7 SLP - 2019\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CANAL7SLP\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-12T03:12:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-12T15:51:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canal7slp.tv\/2019\/wp-content\/uploads\/2019\/06\/panazuara.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"edicionweb\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@canal7_slp\" \/>\n<meta name=\"twitter:site\" content=\"@canal7_slp\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"edicionweb\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/inaugura-xavier-azuara-su-casa-de-enlace-ciudadano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/inaugura-xavier-azuara-su-casa-de-enlace-ciudadano\\\/\"},\"author\":{\"name\":\"edicionweb\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/#\\\/schema\\\/person\\\/11d941c1c6ca30ac0a46b95fa37aa2e3\"},\"headline\":\"Inaugura Xavier Azuara su casa de Enlace Ciudadano\",\"datePublished\":\"2019-06-12T03:12:04+00:00\",\"dateModified\":\"2019-06-12T15:51:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/inaugura-xavier-azuara-su-casa-de-enlace-ciudadano\\\/\"},\"wordCount\":507,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/inaugura-xavier-azuara-su-casa-de-enlace-ciudadano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/panazuara.jpg\",\"articleSection\":[\"LOCALES Y REGIONALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/inaugura-xavier-azuara-su-casa-de-enlace-ciudadano\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/inaugura-xavier-azuara-su-casa-de-enlace-ciudadano\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/inaugura-xavier-azuara-su-casa-de-enlace-ciudadano\\\/\",\"name\":\"Inaugura Xavier Azuara su casa de Enlace Ciudadano - Canal 7 SLP - 2019\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/inaugura-xavier-azuara-su-casa-de-enlace-ciudadano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/inaugura-xavier-azuara-su-casa-de-enlace-ciudadano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/panazuara.jpg\",\"datePublished\":\"2019-06-12T03:12:04+00:00\",\"dateModified\":\"2019-06-12T15:51:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/inaugura-xavier-azuara-su-casa-de-enlace-ciudadano\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/inaugura-xavier-azuara-su-casa-de-enlace-ciudadano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/inaugura-xavier-azuara-su-casa-de-enlace-ciudadano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/panazuara.jpg\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/panazuara.jpg\",\"width\":800,\"height\":533},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/inaugura-xavier-azuara-su-casa-de-enlace-ciudadano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inaugura Xavier Azuara su casa de Enlace Ciudadano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/#website\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/\",\"name\":\"Canal 7 SLP - Somos TV\",\"description\":\"Somos un Canal de 10\",\"publisher\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/#organization\",\"name\":\"Comunicaci\u00f3n 2000 S.A. de C.V.\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/logo-c7.png\",\"contentUrl\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/logo-c7.png\",\"width\":220,\"height\":60,\"caption\":\"Comunicaci\u00f3n 2000 S.A. de C.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CANAL7SLP\\\/\",\"https:\\\/\\\/x.com\\\/canal7_slp\",\"https:\\\/\\\/www.instagram.com\\\/canal7_slp\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/NOTICIEROSCANAL7SLP\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canal7slp.tv\\\/2019\\\/#\\\/schema\\\/person\\\/11d941c1c6ca30ac0a46b95fa37aa2e3\",\"name\":\"edicionweb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g\",\"caption\":\"edicionweb\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inaugura Xavier Azuara su casa de Enlace Ciudadano - Canal 7 SLP - 2019","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canal7slp.tv\/2019\/inaugura-xavier-azuara-su-casa-de-enlace-ciudadano\/","og_locale":"es_ES","og_type":"article","og_title":"Inaugura Xavier Azuara su casa de Enlace Ciudadano - Canal 7 SLP - 2019","og_description":"\u2022 El diputado federal dijo que ese ser\u00e1 espacio de transformaci\u00f3n donde se impulsen las ideas y propuestas de la ciudadan\u00eda. \u2022 Present\u00f3 junto al vicecoordinador, Jorge Romero una iniciativa que busca garantizar las propuestas ciudadanas en la C\u00e1mara de Diputados. SLP.- Este ser\u00e1 un espacio para las y los ciudadanos, que no s\u00f3lo apoye [&hellip;]","og_url":"https:\/\/canal7slp.tv\/2019\/inaugura-xavier-azuara-su-casa-de-enlace-ciudadano\/","og_site_name":"Canal 7 SLP - 2019","article_publisher":"https:\/\/www.facebook.com\/CANAL7SLP\/","article_published_time":"2019-06-12T03:12:04+00:00","article_modified_time":"2019-06-12T15:51:54+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/canal7slp.tv\/2019\/wp-content\/uploads\/2019\/06\/panazuara.jpg","type":"image\/jpeg"}],"author":"edicionweb","twitter_card":"summary_large_image","twitter_creator":"@canal7_slp","twitter_site":"@canal7_slp","twitter_misc":{"Escrito por":"edicionweb","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canal7slp.tv\/2019\/inaugura-xavier-azuara-su-casa-de-enlace-ciudadano\/#article","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2019\/inaugura-xavier-azuara-su-casa-de-enlace-ciudadano\/"},"author":{"name":"edicionweb","@id":"https:\/\/canal7slp.tv\/2019\/#\/schema\/person\/11d941c1c6ca30ac0a46b95fa37aa2e3"},"headline":"Inaugura Xavier Azuara su casa de Enlace Ciudadano","datePublished":"2019-06-12T03:12:04+00:00","dateModified":"2019-06-12T15:51:54+00:00","mainEntityOfPage":{"@id":"https:\/\/canal7slp.tv\/2019\/inaugura-xavier-azuara-su-casa-de-enlace-ciudadano\/"},"wordCount":507,"commentCount":0,"publisher":{"@id":"https:\/\/canal7slp.tv\/2019\/#organization"},"image":{"@id":"https:\/\/canal7slp.tv\/2019\/inaugura-xavier-azuara-su-casa-de-enlace-ciudadano\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2019\/wp-content\/uploads\/2019\/06\/panazuara.jpg","articleSection":["LOCALES Y REGIONALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/canal7slp.tv\/2019\/inaugura-xavier-azuara-su-casa-de-enlace-ciudadano\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/canal7slp.tv\/2019\/inaugura-xavier-azuara-su-casa-de-enlace-ciudadano\/","url":"https:\/\/canal7slp.tv\/2019\/inaugura-xavier-azuara-su-casa-de-enlace-ciudadano\/","name":"Inaugura Xavier Azuara su casa de Enlace Ciudadano - Canal 7 SLP - 2019","isPartOf":{"@id":"https:\/\/canal7slp.tv\/2019\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canal7slp.tv\/2019\/inaugura-xavier-azuara-su-casa-de-enlace-ciudadano\/#primaryimage"},"image":{"@id":"https:\/\/canal7slp.tv\/2019\/inaugura-xavier-azuara-su-casa-de-enlace-ciudadano\/#primaryimage"},"thumbnailUrl":"https:\/\/canal7slp.tv\/2019\/wp-content\/uploads\/2019\/06\/panazuara.jpg","datePublished":"2019-06-12T03:12:04+00:00","dateModified":"2019-06-12T15:51:54+00:00","breadcrumb":{"@id":"https:\/\/canal7slp.tv\/2019\/inaugura-xavier-azuara-su-casa-de-enlace-ciudadano\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canal7slp.tv\/2019\/inaugura-xavier-azuara-su-casa-de-enlace-ciudadano\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2019\/inaugura-xavier-azuara-su-casa-de-enlace-ciudadano\/#primaryimage","url":"https:\/\/canal7slp.tv\/2019\/wp-content\/uploads\/2019\/06\/panazuara.jpg","contentUrl":"https:\/\/canal7slp.tv\/2019\/wp-content\/uploads\/2019\/06\/panazuara.jpg","width":800,"height":533},{"@type":"BreadcrumbList","@id":"https:\/\/canal7slp.tv\/2019\/inaugura-xavier-azuara-su-casa-de-enlace-ciudadano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/canal7slp.tv\/2019\/"},{"@type":"ListItem","position":2,"name":"Inaugura Xavier Azuara su casa de Enlace Ciudadano"}]},{"@type":"WebSite","@id":"https:\/\/canal7slp.tv\/2019\/#website","url":"https:\/\/canal7slp.tv\/2019\/","name":"Canal 7 SLP - Somos TV","description":"Somos un Canal de 10","publisher":{"@id":"https:\/\/canal7slp.tv\/2019\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canal7slp.tv\/2019\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/canal7slp.tv\/2019\/#organization","name":"Comunicaci\u00f3n 2000 S.A. de C.V.","url":"https:\/\/canal7slp.tv\/2019\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/canal7slp.tv\/2019\/#\/schema\/logo\/image\/","url":"https:\/\/canal7slp.tv\/2019\/wp-content\/uploads\/2019\/07\/logo-c7.png","contentUrl":"https:\/\/canal7slp.tv\/2019\/wp-content\/uploads\/2019\/07\/logo-c7.png","width":220,"height":60,"caption":"Comunicaci\u00f3n 2000 S.A. de C.V."},"image":{"@id":"https:\/\/canal7slp.tv\/2019\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CANAL7SLP\/","https:\/\/x.com\/canal7_slp","https:\/\/www.instagram.com\/canal7_slp","https:\/\/www.youtube.com\/user\/NOTICIEROSCANAL7SLP\/"]},{"@type":"Person","@id":"https:\/\/canal7slp.tv\/2019\/#\/schema\/person\/11d941c1c6ca30ac0a46b95fa37aa2e3","name":"edicionweb","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eee448fc3f7164808013b816ba91ac7e43bbe82a70bebac296f8bc6f0addaa1a?s=96&d=mm&r=g","caption":"edicionweb"}}]}},"amp_enabled":true,"cmb2":{"video_ids_in_playlist":{"vid_p_videos":""},"video_ids_in_channel":{"vid_c_videos":""},"playlist_ids_in_channel":{"vid_c_playlists":""},"series_ids_in_channel":{"vid_c_series":""},"channel_images":{"vid_c_logo":"","vid_c_banner":""},"poster_feature_image":{"vid_m_poster_image":""},"gif_feature_image":{"vid_m_gif_image":""},"video_movie_settings":{"vid_m_director":"","vid_m_actor":"","vid_m_imdb_ratings":"","vid_m_amazon_associates":""},"vid_youtube_broadcasts_settings":{"vid_yb_broadcast_title":"","vid_yb_q":"","vid_yb_channelid":"","vid_yb_videocategoryid":"","vid_yb_maxresults":"","vid_yb_order":"","vid_yb_regioncode":"","vid_yb_videosyndicated":"","vid_yb_style":"","vid_yb_reload_first":""},"video_series_settings":{"vid_m_director":"","vid_m_actor":"","vid_m_imdb_ratings":"","video_series_group":""},"amazon_associates_settings":{"amazon_associates":"","amazon_native_ad":""},"vid_youtube_automatic_settings":{"vid_ya_youtube_source":"","vid_ya_update_every":"","vid_ya_update_unit":"","vid_ya_categories":"","vid_ya_published_after":"","vid_ya_published_before":"","vid_ya_playlists":"","vid_ya_channels":"","vid_ya_director":"","vid_ya_actor":"","vid_ya_author":"","vid_ya_import_post_date":"","vid_ya_status":"","vid_ya_sub_api_key":""},"vid_ads_m_videoads_settings_post":{"vid_ads_m_video_ads":"","vid_ads_m_video_ads_type":"","vid_ads_m_group_google_ima":"","vid_ads_m_group_image":"","vid_ads_m_group_html5_video":"","vid_ads_m_group_html":"","vid_ads_m_vast_preroll":"","vid_ads_m_vast_postroll":"","vid_ads_m_vast_pauseroll":"","vid_ads_m_vast_midroll":[{"vid_ads_m_vast_timer_seconds":"50"}],"vid_ads_m_time_to_show_ads":"","vid_ads_m_time_skip_ads":"","vid_ads_m_time_to_hide_ads":""},"page_slider_settings":{"display_slider_group":"","page_slider_group":""},"blog_page_settings":{"blog_page_title":"","blog_page_heading":"","blog_page_ic":"","blog_page_it":"","blog_page_ec":"","blog_page_ip":"","archive_loop_style":"","blog_image_ratio":"","blog_show_categories":"","blog_show_excerpt":"","blog_show_author":"","blog_show_date":"","blog_show_comment_count":"","blog_show_view_count":"","blog_show_like_count":"","blog_show_dislike_count":"","blog_items_per_page":"","blog_pag_type":""},"page_options":{"get_page_template":"","color_mode":"","main_layout":"","main_layout_full_with":"","main_logo":"","main_logo_retina":"","main_logo_mobile":"","main_logo_mobile_retina":"","sticky_logo":"","sticky_logo_retina":"","main_nav_layout":"","ajax_search":"","header_background":"","theme_sidebar":"","instagram_feed":"","instagram_feed_position":"","popular_videos":"","popular_videos_title_1":"","popular_videos_title_2":"","popular_videos_ic":"","popular_videos_it":"","theme_background":"","page_custom_css":""},"feature_image_settings":{"feature_image_position":""},"video_player_settings":{"single_video_style":"","video_player_position":"","vm_video_url":"","video_player_library":"","video_streaming":"","vm_media_sources":"","vid_auto_play":"","vm_video_shortcode":"","vid_p_sync_playlist":"","vid_c_sync_channel":"","get_post_format":"","multiple_links_structure":"default","multi_links_title":"","vm_video_multi_links":"","vm_duration":"","vid_social_locker":"off","vid_social_locker_id":"","vid_membership_action":"content-video","vm_video_trailer_url":"","vid_download_type":"free","vid_download_target":"download","vid_woo_product":"","vm_media_download":"","user_rating":"","user_rating_position":"","user_rating_mode":"","user_rating_multi_sets":""},"video_auto_fetch_settings":{"vm_video_fetch":"on"},"video_fake_views_likes":{"vm_fake_views":"","vm_fake_likes":"","vm_fake_dislikes":""},"gallery_settings":{"gallery_position":""},"quote_settings":{"quote_position":""},"post_options":{"main_layout":"","main_logo":"","main_logo_retina":"","main_logo_mobile":"","main_logo_mobile_retina":"","sticky_logo":"","sticky_logo_retina":"","main_nav_layout":"","header_background":"","theme_sidebar":"","single_post_comment_type":"","theme_background":""}},"_links":{"self":[{"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/posts\/13115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/comments?post=13115"}],"version-history":[{"count":0,"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/posts\/13115\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/media\/13116"}],"wp:attachment":[{"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/media?parent=13115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/categories?post=13115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canal7slp.tv\/2019\/wp-json\/wp\/v2\/tags?post=13115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}